{"id":823,"date":"2010-04-05T12:15:17","date_gmt":"2010-04-05T17:15:17","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/photos\/?p=823"},"modified":"2012-01-11T11:11:14","modified_gmt":"2012-01-11T16:11:14","slug":"the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/","title":{"rendered":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica"},"content":{"rendered":"<h5><a title=\"Bas\u00edlica de Nuestra Se\u00f1ora de Los \u00c1ngeles en Cartago, Costa Rica\" href=\"https:\/\/www.costaricainfolink.com\/fotos\/basilica-de-nuestra-senora-de-los-angeles-en-cartago-costa-rica\/\">Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol<\/a><\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2068\" data-permalink=\"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/basilica-de-nuestra-senora-de-los-angeles-church-cartago-costa-rica\/#main\" data-orig-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg\" data-orig-size=\"504,371\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"The Our Lady of los Angeles Basilica (Basilica de Nuestra Se\u00f1ora de los Angeles) in Cartago, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg\" class=\"alignnone size-full wp-image-2068\" title=\"The Our Lady of los Angeles Basilica (Basilica de Nuestra Se\u00f1ora de los Angeles) in Cartago, Costa Rica\" src=\"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg\" alt=\"\" width=\"504\" height=\"371\" srcset=\"https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg 504w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica-150x110.jpg 150w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica-300x220.jpg 300w, https:\/\/costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica-400x294.jpg 400w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[51,65],"tags":[],"class_list":["post-823","post","type-post","status-publish","format-standard","hentry","category-cartago","category-churches"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos\" \/>\n<meta property=\"og:description\" content=\"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Rica Photos\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-05T17:15:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-01-11T16:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Costa Rica Info Link\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Costa Rica Info Link\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/\"},\"author\":{\"name\":\"Costa Rica Info Link\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"headline\":\"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica\",\"datePublished\":\"2010-04-05T17:15:17+00:00\",\"dateModified\":\"2012-01-11T16:11:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/\"},\"wordCount\":23,\"commentCount\":0,\"articleSection\":[\"Cartago\",\"Churches\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/\",\"name\":\"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\"},\"datePublished\":\"2010-04-05T17:15:17+00:00\",\"dateModified\":\"2012-01-11T16:11:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/\",\"name\":\"Costa Rica Photos\",\"description\":\"Beautiful photos from beautiful Costa Rica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/#\\\/schema\\\/person\\\/74cfe7eea26ea47a4dad189e44ff48b8\",\"name\":\"Costa Rica Info Link\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Costa Rica Info Link\"},\"sameAs\":[\"http:\\\/\\\/www.costaricainfolink.com\"],\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/photos\\\/author\\\/costaricainfolink\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/","og_locale":"en_US","og_type":"article","og_title":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos","og_description":"Click aqu\u00ed para ver esta p\u00e1gina en Espa\u00f1ol","og_url":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/","og_site_name":"Costa Rica Photos","article_published_time":"2010-04-05T17:15:17+00:00","article_modified_time":"2012-01-11T16:11:14+00:00","og_image":[{"url":"https:\/\/www.costaricainfolink.com\/photos\/wp-content\/uploads\/2010\/04\/basilica-de-nuestra-se\u00f1ora-de-los-angeles-church-cartago-costa-rica.jpg","type":"","width":"","height":""}],"author":"Costa Rica Info Link","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Costa Rica Info Link"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/"},"author":{"name":"Costa Rica Info Link","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"headline":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica","datePublished":"2010-04-05T17:15:17+00:00","dateModified":"2012-01-11T16:11:14+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/"},"wordCount":23,"commentCount":0,"articleSection":["Cartago","Churches"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/","url":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/","name":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica - Costa Rica Photos","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/photos\/#website"},"datePublished":"2010-04-05T17:15:17+00:00","dateModified":"2012-01-11T16:11:14+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/photos\/the-basilica-de-nuestra-senora-de-los-angeles-in-cartago-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costaricainfolink.com\/photos\/"},{"@type":"ListItem","position":2,"name":"The Basilica de Nuestra Se\u00f1ora de los Angeles in Cartago, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/photos\/#website","url":"https:\/\/costaricainfolink.com\/photos\/","name":"Costa Rica Photos","description":"Beautiful photos from beautiful Costa Rica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/photos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/photos\/#\/schema\/person\/74cfe7eea26ea47a4dad189e44ff48b8","name":"Costa Rica Info Link","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Costa Rica Info Link"},"sameAs":["http:\/\/www.costaricainfolink.com"],"url":"https:\/\/costaricainfolink.com\/photos\/author\/costaricainfolink\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p1lm9J-dh","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":4,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/823\/revisions"}],"predecessor-version":[{"id":2067,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/posts\/823\/revisions\/2067"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/categories?post=823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/photos\/wp-json\/wp\/v2\/tags?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}