{"id":358,"count":1,"description":"","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/","name":"Tacos y Antojitos Mexicanos","slug":"tacos-y-antojitos-mexicanos","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/category\\\/tacos-y-antojitos-mexicanos\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/category\\\/tacos-y-antojitos-mexicanos\\\/\",\"name\":\"Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/category\\\/tacos-y-antojitos-mexicanos\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/category\\\/tacos-y-antojitos-mexicanos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tacos y Antojitos Mexicanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/","og_site_name":"Restaurantes Costa Rica","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/","name":"Tacos y Antojitos Mexicanos Archivos - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/category\/tacos-y-antojitos-mexicanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Tacos y Antojitos Mexicanos"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts?categories=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}