{"id":6389,"date":"2018-03-02T19:03:04","date_gmt":"2018-03-03T00:03:04","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg"},"modified":"2018-03-02T19:04:11","modified_gmt":"2018-03-03T00:04:11","slug":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/restaurantes\/la-divina-comida\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920\/#main","title":{"rendered":"Risotto Paisano &#8211; Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica"},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-6389","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-03T00:04:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg\",\"name\":\"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2018-03-03T00:03:04+00:00\",\"dateModified\":\"2018-03-03T00:04:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante La Divina Comida Avenida Escaz\u00fa\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-divina-comida\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Risotto Paisano &#8211; Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2018-03-03T00:04:11+00:00","og_image":[{"width":1920,"height":1440,"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","name":"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2018-03-03T00:03:04+00:00","dateModified":"2018-03-03T00:04:11+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante La Divina Comida Avenida Escaz\u00fa","item":"https:\/\/costaricainfolink.com\/restaurantes\/la-divina-comida\/"},{"@type":"ListItem","position":3,"name":"Risotto Paisano &#8211; Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a5i3XU-1F3","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=160%2C120&amp;ssl=1 160w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"6389\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/la-divina-comida\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1516034357&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.0666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Risotto Paisano &amp;#8211; Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Risotto Paisano - Restaurante La Divina Comida, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":1440,"file":"2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","sizes":{"thumbnail":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=300%2C225&ssl=1"},"medium_large":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=768%2C576&ssl=1"},"large":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=1024%2C768&ssl=1"},"1_column":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-560x420.jpg","width":560,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-560x420.jpg"},"2_column":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-260x195.jpg","width":260,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-260x195.jpg"},"3_column":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-160x120.jpg","width":160,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920-160x120.jpg"},"full":{"file":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=1920%2C1440&ssl=1","width":1920,"height":1440,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg?fit=1920%2C1440&ssl=1"}},"image_meta":{"aperture":"1.8","credit":"","camera":"iPhone 8","caption":"","created_timestamp":"1516034357","copyright":"","focal_length":"3.99","iso":"64","shutter_speed":"0.0666666666667","title":"","orientation":"1","keywords":[]}},"post":295,"source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","filename":"risotto-paisano-restaurante-la-divina-comida-san-rafael-escazu-san-jose-costa-rica-1920.jpg","filesize":1499133,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media\/6389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=6389"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":295,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}