{"id":8918,"date":"2020-11-06T14:25:07","date_gmt":"2020-11-06T19:25:07","guid":{"rendered":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg"},"modified":"2020-11-06T14:25:40","modified_gmt":"2020-11-06T19:25:40","slug":"restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1\/#main","title":{"rendered":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica"},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-8918","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T19:25:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"505\" \/>\n\t<meta property=\"og:image:height\" content=\"444\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg\",\"name\":\"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2020-11-06T19:25:07+00:00\",\"dateModified\":\"2020-11-06T19:25:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trattor\u00eda il gusto Toscano\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tratoria-il-gusto-toscano\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica","og_description":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2020-11-06T19:25:40+00:00","og_image":[{"width":505,"height":444,"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","name":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2020-11-06T19:25:07+00:00","dateModified":"2020-11-06T19:25:40+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Trattor\u00eda il gusto Toscano","item":"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/"},{"@type":"ListItem","position":3,"name":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a5i3XU-2jQ","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"264\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=300%2C264&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?w=505&amp;ssl=1 505w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?resize=300%2C264&amp;ssl=1 300w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"8918\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=505%2C444&amp;ssl=1\" data-orig-size=\"505,444\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=505%2C444&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":505,"height":444,"file":"2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","sizes":{"medium":{"file":"restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1-300x264.jpg","width":300,"height":264,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=300%2C264&ssl=1"},"thumbnail":{"file":"restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?resize=150%2C150&ssl=1"},"full":{"file":"restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=505%2C444&ssl=1","width":505,"height":444,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg?fit=505%2C444&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":8840,"source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","filename":"restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1.jpg","filesize":14966,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media\/8918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=8918"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8840,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/8840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}