{"id":8922,"date":"2020-11-06T14:35:44","date_gmt":"2020-11-06T19:35:44","guid":{"rendered":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg"},"modified":"2020-11-06T14:36:08","modified_gmt":"2020-11-06T19:36:08","slug":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica","status":"inherit","type":"attachment","link":"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica\/#main","title":{"rendered":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano"},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_jetpack_social_image_focal_point":{"x":0.5,"y":0.5}},"class_list":["post-8922","attachment","type-attachment","status-inherit","hentry","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T19:36:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg\",\"name\":\"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2020-11-06T19:35:44+00:00\",\"dateModified\":\"2020-11-06T19:36:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trattor\u00eda il gusto Toscano\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tratoria-il-gusto-toscano\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica","robots":{"index":"noindex","follow":"follow"},"og_locale":"es_ES","og_type":"article","og_title":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2020-11-06T19:36:08+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","name":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2020-11-06T19:35:44+00:00","dateModified":"2020-11-06T19:36:08+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Trattor\u00eda il gusto Toscano","item":"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/"},{"@type":"ListItem","position":3,"name":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/a5i3XU-2jU","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?w=2560&amp;ssl=1 2560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=1536%2C1152&amp;ssl=1 1536w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=2048%2C1536&amp;ssl=1 2048w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"8922\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=1024%2C768&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Carpaccio de Salm\u00f3n Trattoria Il Gusto Toscano","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1920,"file":"2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","sizes":{"medium":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=300%2C225&ssl=1"},"large":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-1024x768.jpg","width":1024,"height":768,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=1024%2C768&ssl=1"},"thumbnail":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?resize=150%2C150&ssl=1"},"medium_large":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=768%2C576&ssl=1"},"1536x1536":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-1536x1152.jpg","width":1536,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=1536%2C1152&ssl=1"},"2048x2048":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica-2048x1536.jpg","width":2048,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=2048%2C1536&ssl=1"},"full":{"file":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=2560%2C1920&ssl=1","width":2560,"height":1920,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg?fit=2560%2C1920&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":8840,"source_url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","filename":"carpaccio-de-salmon-restaurante-il-gusto-toscano-san-isidro-heredia-costa-rica.jpg","filesize":445010,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media\/8922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=8922"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":8840,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/8840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}