{"id":1167,"date":"2014-04-25T09:54:30","date_gmt":"2014-04-25T14:54:30","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?page_id=1167"},"modified":"2014-04-25T09:58:28","modified_gmt":"2014-04-25T14:58:28","slug":"mapa-con-la-direccion-al-restaurante-family-pizza","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","title":{"rendered":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza"},"content":{"rendered":"<p><strong>Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Guadalupe, San Jos\u00e9, Costa Rica<\/strong><\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m26!1m12!1m3!1d31438.854567331968!2d-84.06602132847307!3d9.945868696236717!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m11!1i0!3e6!4m3!3m2!1d9.9370095!2d-84.09829979999999!4m4!2s9.947653%2C-84.053172!3m2!1d9.947652999999999!2d-84.05317199999999!5e0!3m2!1ses-419!2s!4v1398437612881\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><strong>Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Currdidabat, San Jos\u00e9, Costa Rica<\/strong><\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m26!1m12!1m3!1d31440.74191868429!2d-84.08327628502103!3d9.926234186754169!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m11!1i0!3e6!4m3!3m2!1d9.9370095!2d-84.09829979999999!4m4!2s9.918158%2C-84.033925!3m2!1d9.918158!2d-84.033925!5e0!3m2!1ses-419!2s!4v1398437650641\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-family-pizza\/\">Para m\u00e1s informaci\u00f3n acerca del Restaurante Family Pizza en San Jos\u00e9, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Guadalupe, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Currdidabat, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Family Pizza en San Jos\u00e9, haga click aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-1167","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Guadalupe, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Currdidabat, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Family Pizza en San Jos\u00e9, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2014-04-25T14:58:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-family-pizza\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-family-pizza\\\/\",\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2014-04-25T14:54:30+00:00\",\"dateModified\":\"2014-04-25T14:58:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-family-pizza\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-family-pizza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-family-pizza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Family Pizza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica","og_description":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Guadalupe, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Currdidabat, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Family Pizza en San Jos\u00e9, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2014-04-25T14:58:28+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","name":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2014-04-25T14:54:30+00:00","dateModified":"2014-04-25T14:58:28+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-iP","jetpack-related-posts":[{"id":2503,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-pizza-mym\/","url_meta":{"origin":1167,"position":0},"title":"Mapa con la Direcci\u00f3n al Restaurante Pizza MYM","author":"Restaurantes Costa Rica","date":"20 septiembre 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Pizza MYM en San Antonio de Bel\u00e9n, Heredia, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Pizza MYM en San Antonio de Bel\u00e9n, Heredia, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Pizza\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1857,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-pollos-y-pizza-del-monte-de-la-cruz\/","url_meta":{"origin":1167,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante Pollos y Pizza del Monte de La Cruz","author":"Restaurantes Costa Rica","date":"27 septiembre 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Pollos y Pizza del Monte de La Cruz en San Rafael de Heredia, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Pollos y Pizza del Monte de La Cruz en San Rafael\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1253,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-tacobar\/","url_meta":{"origin":1167,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante TacoBar","author":"Restaurantes Costa Rica","date":"22 julio 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Pinares, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3747,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-cosi\/","url_meta":{"origin":1167,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante Cos\u00ec","author":"Restaurantes Costa Rica","date":"8 mayo 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Cos\u00ec en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":435,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-churrascaria-fogo-brasil\/","url_meta":{"origin":1167,"position":4},"title":"Mapa con la Direcci\u00f3n al Restaurante Churrascaria Fogo Brasil","author":"Restaurantes Costa Rica","date":"18 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Churrascaria Fogo Brasil, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Churrascaria Fogo Brasil en La Sabana, San Jos\u00e9, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1214,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chagos\/","url_meta":{"origin":1167,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Chagos","author":"Restaurantes Costa Rica","date":"21 mayo 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Chagos en San Jos\u00e9 de la Monta\u00f1a, Heredia, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Chagos en San Jos\u00e9 de la Monta\u00f1a, Heredia, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/1167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=1167"}],"version-history":[{"count":6,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/1167\/revisions"}],"predecessor-version":[{"id":3707,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/1167\/revisions\/3707"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=1167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}