{"id":2520,"date":"2012-09-23T10:02:28","date_gmt":"2012-09-23T15:02:28","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?page_id=2520"},"modified":"2014-03-21T09:20:35","modified_gmt":"2014-03-21T14:20:35","slug":"mapa-con-la-direccion-al-restaurante-chubascos","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/","title":{"rendered":"Mapa con la Direcci\u00f3n al Restaurante Chubascos"},"content":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Chubascos en Fraijanes, Alajuela, Costa Rica<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m28!1m12!1m3!1d125708.5625554813!2d-84.267317818547!3d10.06688334451052!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m13!1i0!3e0!4m5!1s0x8fa0f9a3b2d2fb1d%3A0xaec408305a420af4!2sJuan+Santamaria+International+Airport%2C+Alajuela%2C+Costa+Rica!3m2!1d9.998237999999999!2d-84.20407999999999!4m4!2s10.133525%2C-84.191118!3m2!1d10.133524999999999!2d-84.191118!5e0!3m2!1sen!2s!4v1395411591407\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-chubascos\/\">Para m\u00e1s informaci\u00f3n acerca del Bar y Restaurante Chubascos en Alajuela, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Chubascos en Fraijanes, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Bar y Restaurante Chubascos en Alajuela, haga click aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2520","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Chubascos en Fraijanes, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Bar y Restaurante Chubascos en Alajuela, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-21T14:20:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-chubascos\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-chubascos\\\/\",\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2012-09-23T15:02:28+00:00\",\"dateModified\":\"2014-03-21T14:20:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-chubascos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-chubascos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-al-restaurante-chubascos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Chubascos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica","og_description":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Chubascos en Fraijanes, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Bar y Restaurante Chubascos en Alajuela, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2014-03-21T14:20:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/","name":"Mapa con la Direcci\u00f3n al Restaurante Chubascos - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2012-09-23T15:02:28+00:00","dateModified":"2014-03-21T14:20:35+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-chubascos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Mapa con la Direcci\u00f3n al Restaurante Chubascos"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-EE","jetpack-related-posts":[{"id":3946,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-katu\/","url_meta":{"origin":2520,"position":0},"title":"Mapa con la Direcci\u00f3n al Restaurante Kat\u00fa","author":"Restaurantes Costa Rica","date":"16 febrero 2015","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Kat\u00fa en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Kat\u00fa en Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Kat\u00fa en Alajuela, Costa Rica, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3564,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-bri-art-cafe\/","url_meta":{"origin":2520,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante BRI Art Caf\u00e9","author":"Restaurantes Costa Rica","date":"24 abril 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante BRI Art Caf\u00e9 en Alajuela, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante BRI Art Caf\u00e9 en La Gu\u00e1cima, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante BRI Art Caf\u00e9 en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3856,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-abgb\/","url_meta":{"origin":2520,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante ABGB","author":"Restaurantes Costa Rica","date":"11 noviembre 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante ABGB en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante ABGB en Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n haga click en el siguiente enlace: Hamburguesas ABGB en Alajuela, Costa Rica: informaci\u00f3n,\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/11\/abgb-restaurante-costa-rica001.jpg?fit=500%2C375&ssl=1&resize=350%2C200","width":350,"height":200},"classes":[]},{"id":2902,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-antigua-hacienda\/","url_meta":{"origin":2520,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante Antigua Hacienda","author":"Restaurantes Costa Rica","date":"14 abril 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Antigua Hacienda en Orotina, Alajuela, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional de Liberia Daniel Oduber, Guanacaste, Costa Rica al Restaurante Antigua Hacienda en Orotina, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Antigua Hacienda en Orotina,\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3210,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-japan-tico\/","url_meta":{"origin":2520,"position":4},"title":"Mapa con la Direcci\u00f3n al Restaurante Japan Tico","author":"Restaurantes Costa Rica","date":"17 marzo 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Japan Tico en Alajuela, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Japan Tico en Alajuela, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3212,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-jalapenos-central\/","url_meta":{"origin":2520,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Jalape\u00f1os Central","author":"Restaurantes Costa Rica","date":"13 marzo 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Jalape\u00f1os Central en Alajuela, Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Jalape\u00f1os Central en Alajuela, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=2520"}],"version-history":[{"count":5,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2520\/revisions"}],"predecessor-version":[{"id":3441,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2520\/revisions\/3441"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=2520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}