{"id":2778,"date":"2013-03-24T23:04:33","date_gmt":"2013-03-25T04:04:33","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?page_id=2778"},"modified":"2019-08-26T07:19:00","modified_gmt":"2019-08-26T12:19:00","slug":"restaurantes-en-costa-rica","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/","title":{"rendered":"Restaurantes en Costa Rica"},"content":{"rendered":"<form role=\"search\" method=\"get\" action=\"https:\/\/costaricainfolink.com\/restaurantes\/\" class=\"wp-block-search__button-outside wp-block-search__text-button wp-block-search\" ><label class=\"wp-block-search__label\" for=\"wp-block-search__input-1\" >Buscar<\/label><div class=\"wp-block-search__inside-wrapper\" ><input class=\"wp-block-search__input\" id=\"wp-block-search__input-1\" placeholder=\"\" value=\"\" type=\"search\" name=\"s\" required \/><button aria-label=\"Buscar\" class=\"wp-block-search__button wp-element-button\" type=\"submit\" >Buscar<\/button><\/div><\/form>\n\n<p><strong>Restaurantes en Costa Rica:<\/strong>Si hace click sobre el nombre de cada restaurante, el sitio lo llevara a otra p\u00e1gina con informaci\u00f3n m\u00e1s detallada sobre su selecci\u00f3n, como: ubicaci\u00f3n ,coordenadas para GPS, mapa con direcci\u00f3n, horario, tel\u00e9fono, descripci\u00f3n y fotograf\u00edas.<\/p>\n<p><script><br \/>\n  (function() {<br \/>\n    var cx = 'partner-pub-6211205276133643:1269416813';<br \/>\n    var gcse = document.createElement('script');<br \/>\n    gcse.type = 'text\/javascript';<br \/>\n    gcse.async = true;<br \/>\n    gcse.src = 'https:\/\/cse.google.com\/cse.js?cx=' + cx;<br \/>\n    var s = document.getElementsByTagName('script')[0];<br \/>\n    s.parentNode.insertBefore(gcse, s);<br \/>\n  })();<br \/>\n<\/script><\/p>\n<table border=\"0\" width=\"100%\">\n<tbody>\n<tr>\n<td width=\"50%\">\n<h2><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/san-jose\/\" target=\"_blank\" rel=\"noopener noreferrer\">Restaurantes en San Jos\u00e9<\/a><\/h2>\n<\/td>\n<td width=\"50%\">\n<h2>Restaurantes en Alajuela<\/h2>\n<\/td>\n<\/tr>\n<tr>\n<td valign=\"top\" width=\"50%\">\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/al-masri\/\">Al Masri<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-pocket\/\">Bar y Restaurante Pocket<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bistro-tapas-buffet\/\">Bistro, Tapas &amp; Buffet<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-y-restaurante-il-panino\/\">Caf\u00e9 y Restaurante Il Panino<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/cafeteria-eco-tienda-amalur\/\">Cafeter\u00eda y Eco-Tienda Amalur<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-cosi\/\">Restaurante Cos\u00ed<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/gelateria-da-noi\/\">Gelateria Da Noi<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-lile-de-france\/\">L&#8217;Ile de France<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-alquimia-healthy\/\">Restaurante Alquimia Healthy<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-tin-jo\/\">Restaurante Asi\u00e1tico Tin Jo<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/\">Restaurante Asi\u00e1tico, Bar &amp; Grill Gan-Bei<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-bbq-los-anonos\/\">Restaurante BBQ Los Anonos<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-churrascaria-fogo-brasil\/\">Restaurante Churrascaria Fogo Brasil<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-damalfi\/\">Restaurante D&#8217;amalfi<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-de-comida-caribena-whapin\/\">Restaurante de comida Caribe\u00f1a Whapin<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-doris-metropolitan\/\">Restaurante Doris Metropolitan<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-divina-comida\/\">Restaurante La Divina Comida<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-las-bromelias\/\">Restaurante Las Bromelias<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/miraflores\/\">Restaurante Miraflores<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/family-pizza-costa-rica\/\">Restaurante Family Pizza<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-sabor-a-pueblo\/\">Restaurante Sabor a Pueblo<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/porkys\/\">PORKY&#8217;S<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-saga\/\">Restaurante Saga<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-samurai-fusion\/\">Restaurante Samurai Fusion<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-sushi-kai-bar-lounge\/\">Restaurante Sushi Kai Bar &amp; Lounge<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-tacobar\/\">Restaurante TacoBar<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-the-muse\/\">Restaurante The Muse<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafeteria-artesanal-wo-kapi\/\">Wo Kapi cafeteria artesanal<\/a><\/li>\n<\/ul>\n<h2>Restaurantes en Puntarenas<\/h2>\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-que-comemos\/\">Restaurante \u00bfQu\u00e9 Comemos? <\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-casa-del-mar\/\">Restaurante Casa del Mar<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-exotica\/\">Restaurante Ex\u00f3tica<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-outback-jacks-australian-\">Restaurante Outback Jack&#8217;s Australian Roadkill Grill<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-palenque-garabito\/\">Restaurante Palenque Garabito<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-pasta-basta\/\">Restaurante Pasta Basta<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-product-c\/\">Restaurante Product C<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-the-bakery\/\">Restaurante The Bakery<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafe-stellas-bakery\/\">Restaurante y Caf\u00e9 Stella&#8217;s Bakery<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-surf-dogs\/\">Bar y Restaurante Surf Dogs<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafe-tree-house\/\">Restaurante y Caf\u00e9 Tree House<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ristorante-e-pizzeria-tramonti\/\">Restaurante y Pizzeria Tramonti<\/a><\/li>\n<\/ul>\n<h2>Restaurantes en Cartago<\/h2>\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-el-rancho-del-sapito\/\">Restaurante El Rancho del Sapito<\/a><\/li>\n<\/ul>\n<\/td>\n<td valign=\"top\" width=\"50%\">\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-antigua-hacienda\/\">Restaurante Antigua Hacienda<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-bri-art-cafe\/\">Restaurante BRI Art Caf\u00e9<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-cosi\/\">Restaurante Cos\u00ed<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/hamburguesas-abgb\/\">Restaurante Hamburguesas ABGB<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-pizzeria-il-capriccio-en-san-rafael-alajuela\/\">Il Capriccio<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-quieres\/\">Bar &amp; Restaurante Quieres?<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-jalapenos-central\/\">Restaurante Jalape\u00f1os Central<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-japan-tico\/\">Japan tico: comida japonesa &#8211; sushi bar<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-katu\/\">Kat\u00fa<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-chubascos\/\">Restaurante Chubascos<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-el-descanso\/\">Restaurante El Descanso<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-el-chante-vegano\/\">Restaurante El Chante Vegano<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-caribbean-kid\/\">Restaurante Caribbean Kid<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/family-pizza-costa-rica\/\">Restaurante Family Pizza<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/la-choripaneria-ovizam\/\">La Choripaneria OVIZAM<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-focaccia-di-martino\/\">Restaurante La Focaccia di Martino<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-the-cakery\/\">The Cakery<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-ragu\/\">Rag\u00fa<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-sandwicheria\/\">Restaurante La Sandwicher\u00eda<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/pollos-del-este\/\">Pollos del Este<\/a><\/li>\n<\/ul>\n<h2>Restaurantes en Heredia<\/h2>\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-restaurante-bufalos-mojados\/\">Bufalos Mojados<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-restaurante-chagos\/\">Bar y Restaurante Chago&#8217;s<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-pianos\/\">Bar y Restaurante Pianos<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-restaurante-y-museo-anoranzas\/\">Bar, Restaurante y Museo A\u00f1oranzas<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-colbert\/\">Restaurante Colbert<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-el-banco-de-los-mariscos\/\">Restaurante El Banco de los Mariscos<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-deportiva-charlies-bar\/\">Restaurante La Deportiva Charlies Bar<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-focaccia-di-martino\/\">Restaurante La Focaccia di Martino<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/soda-gallito-pinto-en-belen-heredia\/\">Soda Gallito Pinto<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-maremmana\/\">Restaurante La Maremmana<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-marisqueria-el-dorado\/\">Restaurante Marisquer\u00eda El Dorado<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-palacio-real\/\">Restaurante Palacio Real<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-pizza-mym\/\">Restaurante Pizza MyM<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-pollos-del-monte\/\">Restaurante Pollos del Monte<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-pollos-raymi\/\">Restaurante Pollos RAYMI<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-pollos-y-pizza-del-monte-de-la-cruz\/\">Restaurante Pollos y Pizza Monte de La Cruz<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-restaurante-tierra-mar\/\">Tierra Mar<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-tiquicia\/\">Restaurante Tiquicia<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/las-orquideas-bar-y-restaurante\/\">Restaurante y Bar Las Orqu\u00eddeas<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-bar-los-tiroleses\/\">Restaurante y Bar Los Tiroleses<\/a><\/li>\n<\/ul>\n<h2>Restaurantes en Guanacaste<\/h2>\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-lolas\/\">Bar y Restaurante Lola&#8217;s<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-bamboo-sushi-club\/\">Restaurante Bamboo Sushi Club<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-sports-bar-kahiki\/\">Restaurante y Sports Bar KAHIKI<\/a><\/li>\n<\/ul>\n<h2>Restaurantes en Lim\u00f3n<\/h2>\n<ul>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafeteria-bread-chocolate\/\">Restaurante y Cafeter\u00eda Bread &amp; Chocolate<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-creperie-sel-sucre\/\">Restaurante Cr\u00eaperie Sel &amp; Sucre<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-pita-bonita\/\">Restaurante La Pita Bonita<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/le-numu-restaurante\/\">Restaurante Le Numu<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-maxis\/\">Restaurante Maxis<\/a><\/li>\n<li><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-stashus-con-fusion\/\">Restaurante Stashus Con Fusion<\/a><\/li>\n<\/ul>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>*** <a href=\"https:\/\/costaricainfolink.com\/es\/agregue-su-negocio\/\">Click aqu\u00ed para agregar su Restaurante<\/a> ***<\/h2>","protected":false},"excerpt":{"rendered":"<p>Restaurantes en Costa Rica:Si hace click sobre el nombre de cada restaurante, el sitio lo llevara a otra p\u00e1gina con informaci\u00f3n m\u00e1s detallada sobre su selecci\u00f3n, como: ubicaci\u00f3n ,coordenadas para GPS, mapa con direcci\u00f3n, horario, tel\u00e9fono, descripci\u00f3n y fotograf\u00edas. Restaurantes en San Jos\u00e9 Restaurantes en Alajuela Al Masri Bar y Restaurante Pocket Bistro, Tapas &amp; &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurantes en Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/#more-2778\" aria-label=\"Leer m\u00e1s sobre Restaurantes en Costa Rica\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-2778","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurantes en Costa Rica - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurantes en Costa Rica - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Restaurantes en Costa Rica:Si hace click sobre el nombre de cada restaurante, el sitio lo llevara a otra p\u00e1gina con informaci\u00f3n m\u00e1s detallada sobre su selecci\u00f3n, como: ubicaci\u00f3n ,coordenadas para GPS, mapa con direcci\u00f3n, horario, tel\u00e9fono, descripci\u00f3n y fotograf\u00edas. Restaurantes en San Jos\u00e9 Restaurantes en Alajuela Al Masri Bar y Restaurante Pocket Bistro, Tapas &amp; ... Ver Restaurante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-26T12:19:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes en Costa Rica - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2013-03-25T04:04:33+00:00\",\"dateModified\":\"2019-08-26T12:19:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurantes en Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurantes en Costa Rica - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurantes en Costa Rica - Restaurantes Costa Rica","og_description":"Restaurantes en Costa Rica:Si hace click sobre el nombre de cada restaurante, el sitio lo llevara a otra p\u00e1gina con informaci\u00f3n m\u00e1s detallada sobre su selecci\u00f3n, como: ubicaci\u00f3n ,coordenadas para GPS, mapa con direcci\u00f3n, horario, tel\u00e9fono, descripci\u00f3n y fotograf\u00edas. Restaurantes en San Jos\u00e9 Restaurantes en Alajuela Al Masri Bar y Restaurante Pocket Bistro, Tapas &amp; ... Ver Restaurante","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2019-08-26T12:19:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes en Costa Rica - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2013-03-25T04:04:33+00:00","dateModified":"2019-08-26T12:19:00+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurantes en Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-IO","jetpack-related-posts":[{"id":36,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-de-caciquita-mirador-bar-restaurante-y-lodge\/","url_meta":{"origin":2778,"position":0},"title":"Mapa de Caciquita Mirador, Bar, Restaurante y Lodge","author":"Restaurantes Costa Rica","date":"14 abril 2009","format":false,"excerpt":"","rel":"","context":"En \u00abGeneral\u00bb","block_context":{"text":"General","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/general\/"},"img":{"alt_text":"mapa-caciquita-bar-restaurant-vara-blanca-costa-rica1","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/mapa-caciquita-bar-restaurant-vara-blanca-costa-rica1-1024x1008.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/mapa-caciquita-bar-restaurant-vara-blanca-costa-rica1-1024x1008.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/mapa-caciquita-bar-restaurant-vara-blanca-costa-rica1-1024x1008.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/mapa-caciquita-bar-restaurant-vara-blanca-costa-rica1-1024x1008.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1253,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-tacobar\/","url_meta":{"origin":2778,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante TacoBar","author":"Restaurantes Costa Rica","date":"22 julio 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Pinares, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3946,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-katu\/","url_meta":{"origin":2778,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante Kat\u00fa","author":"Restaurantes Costa Rica","date":"16 febrero 2015","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Kat\u00fa en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Kat\u00fa en Alajuela, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Kat\u00fa en Alajuela, Costa Rica, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3747,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-cosi\/","url_meta":{"origin":2778,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante Cos\u00ec","author":"Restaurantes Costa Rica","date":"8 mayo 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Cos\u00ec en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2739,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-que-comemos\/","url_meta":{"origin":2778,"position":4},"title":"Mapa con la Direcci\u00f3n al Restaurante Que Comemos?","author":"Restaurantes Costa Rica","date":"3 abril 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Que Comemos? en Parrita, Puntarenas, Costa Rica > Direcci\u00f3n desde el Aeropuerto Quepos La Managua, Puntarenas Costa Rica al Restaurante Que Comemos? en Parrita, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Que Comemos? en Parrita, Puntarenas,\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":490,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-maxis\/","url_meta":{"origin":2778,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Maxis","author":"Restaurantes Costa Rica","date":"19 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Maxis, Lim\u00f3n, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Maxis en Santa Ana, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Maxis, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=2778"}],"version-history":[{"count":64,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2778\/revisions"}],"predecessor-version":[{"id":8185,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/2778\/revisions\/8185"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=2778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}