{"id":494,"date":"2010-10-19T09:40:42","date_gmt":"2010-10-19T14:40:42","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/"},"modified":"2014-03-20T11:33:14","modified_gmt":"2014-03-20T16:33:14","slug":"mapa-con-la-direccion-del-restaurante-creperie-sel-sucre","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/","title":{"rendered":"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel &#038; Sucre"},"content":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Cr\u00eaperie Sel &#038; Sucre, Lim\u00f3n, Costa Rica<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m26!1m12!1m3!1d1006083.3837932127!2d-84.02894449580289!3d9.932856742201265!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m11!1i0!3e0!4m3!3m2!1d9.9988862!2d-84.204144!4m4!2s9.655747%2C-82.754903!3m2!1d9.655747!2d-82.754903!5e0!3m2!1sen!2s!4v1395332980180\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-creperie-sel-sucre\/\">Para m\u00e1s informaci\u00f3n acerca del Restaurante Cr\u00eaperie Sel &#038; Sucre en Lim\u00f3n, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Cr\u00eaperie Sel &#038; Sucre, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Cr\u00eaperie Sel &#038; Sucre en Lim\u00f3n, haga click aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-494","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel &amp; Sucre - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel &amp; Sucre - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Cr\u00eaperie Sel &#038; Sucre, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Cr\u00eaperie Sel &#038; Sucre en Lim\u00f3n, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-20T16:33:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\\\/\",\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel & Sucre - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2010-10-19T14:40:42+00:00\",\"dateModified\":\"2014-03-20T16:33:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel &#038; Sucre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel & Sucre - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel & Sucre - Restaurantes Costa Rica","og_description":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Cr\u00eaperie Sel &#038; Sucre, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Cr\u00eaperie Sel &#038; Sucre en Lim\u00f3n, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2014-03-20T16:33:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/","name":"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel & Sucre - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2010-10-19T14:40:42+00:00","dateModified":"2014-03-20T16:33:14+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-creperie-sel-sucre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Mapa con la Direcci\u00f3n al Restaurante Cr\u00eaperie Sel &#038; Sucre"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-7Y","jetpack-related-posts":[{"id":2778,"url":"https:\/\/costaricainfolink.com\/restaurantes\/","url_meta":{"origin":494,"position":0},"title":"Restaurantes en Costa Rica","author":"Restaurantes Costa Rica","date":"24 marzo 2013","format":false,"excerpt":"Restaurantes en Costa Rica:Si hace click sobre el nombre de cada restaurante, el sitio lo llevara a otra p\u00e1gina con informaci\u00f3n m\u00e1s detallada sobre su selecci\u00f3n, como: ubicaci\u00f3n ,coordenadas para GPS, mapa con direcci\u00f3n, horario, tel\u00e9fono, descripci\u00f3n y fotograf\u00edas. Restaurantes en San Jos\u00e9 Restaurantes en Alajuela Al Masri Bar y\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":476,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-le-numu-2\/","url_meta":{"origin":494,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante Le Numu","author":"Restaurantes Costa Rica","date":"19 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela,, Costa Rica al Restaurante Le Numu, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Le Numu en Playa Cocles, Lim\u00f3n, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":498,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-la-paila-casera\/","url_meta":{"origin":494,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante La Paila Casera","author":"Restaurantes Costa Rica","date":"19 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante La Paila Casera, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante La Paila Casera en Lim\u00f3n, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3124,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-la-pita-bonita\/","url_meta":{"origin":494,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante La Pita Bonita","author":"Restaurantes Costa Rica","date":"16 octubre 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante La Pita Bonita en Punta Uva, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante La Pita Bonita en Punta Uva de Lim\u00f3n, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3142,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-stashus-con-fusion\/","url_meta":{"origin":494,"position":4},"title":"Mapa con la Direcci\u00f3n al Restaurante Stashus Con Fusion","author":"Restaurantes Costa Rica","date":"17 octubre 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Stashus Con Fusion en Puerto Viejo, Lim\u00f3n, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Stashus Con Fusion en Puerto Viejo de Lim\u00f3n, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":490,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-maxis\/","url_meta":{"origin":494,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Maxis","author":"Restaurantes Costa Rica","date":"19 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica al Restaurante Maxis, Lim\u00f3n, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Maxis en Santa Ana, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Maxis, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=494"}],"version-history":[{"count":5,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/494\/revisions"}],"predecessor-version":[{"id":3341,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/494\/revisions\/3341"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}