{"id":595,"date":"2011-01-24T23:05:29","date_gmt":"2011-01-25T04:05:29","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/"},"modified":"2014-03-20T16:59:37","modified_gmt":"2014-03-20T21:59:37","slug":"mapa-con-la-direccion-del-restaurante-y-cafe-tree-house","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/","title":{"rendered":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House"},"content":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m28!1m12!1m3!1d502779.21889595035!2d-84.80404461442895!3d10.102143307766433!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m13!1i0!3e0!4m5!1s0x8fa0f9a3b2d2fb1d%3A0xaec408305a420af4!2sJuan+Santamaria+International+Airport%2C+Alajuela%2C+Costa+Rica!3m2!1d9.998237999999999!2d-84.20407999999999!4m4!2s10.317361%2C-84.824375!3m2!1d10.317361!2d-84.82437499999999!5e0!3m2!1sen!2s!4v1395352756256\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafe-tree-house\/\">Para m\u00e1s informaci\u00f3n acerca del Restaurante y Caf\u00e9 Tree House en Monteverde, Puntarenas, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante y Caf\u00e9 Tree House en Monteverde, Puntarenas, haga click aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-595","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante y Caf\u00e9 Tree House en Monteverde, Puntarenas, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-20T21:59:37+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\\\/\",\"name\":\"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2011-01-25T04:05:29+00:00\",\"dateModified\":\"2014-03-20T21:59:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica","og_description":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante y Caf\u00e9 Tree House en Monteverde, Puntarenas, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2014-03-20T21:59:37+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/","name":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2011-01-25T04:05:29+00:00","dateModified":"2014-03-20T21:59:37+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-tree-house\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Tree House"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-9B","jetpack-related-posts":[{"id":564,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-cafe-stellas-bakery\/","url_meta":{"origin":595,"position":0},"title":"Mapa con la Direcci\u00f3n al Restaurante y Caf\u00e9 Stella&#8217;s Bakery","author":"Restaurantes Costa Rica","date":"20 enero 2011","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante y Caf\u00e9 Stella's Bakery en Monteverde, Puntarenas, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":577,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-y-pizzeria-tramonti\/","url_meta":{"origin":595,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante y Pizzer\u00eda Tramonti","author":"Restaurantes Costa Rica","date":"24 enero 2011","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamaria, Alajuela, Costa Rica a la entrada a Monteverde, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante y Pizzer\u00eda Tramonti en Monteverde, Puntarenas, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2739,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-que-comemos\/","url_meta":{"origin":595,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante Que Comemos?","author":"Restaurantes Costa Rica","date":"3 abril 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Que Comemos? en Parrita, Puntarenas, Costa Rica > Direcci\u00f3n desde el Aeropuerto Quepos La Managua, Puntarenas Costa Rica al Restaurante Que Comemos? en Parrita, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Que Comemos? en Parrita, Puntarenas,\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1775,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-palenque-garabito\/","url_meta":{"origin":595,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante Palenque Garabito","author":"Restaurantes Costa Rica","date":"3 septiembre 2012","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Palenque Garabito en Puntarenas, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional de Liberia Daniel Oduber, Guanacaste, Costa Rica al Restaurante Palenque Garabito en Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Palenque Garabito en Miramar, Puntarenas, haga\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2967,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-bar-y-restaurante-surf-dogs\/","url_meta":{"origin":595,"position":4},"title":"Mapa con la Direcci\u00f3n al Bar y Restaurante Surf Dogs","author":"Restaurantes Costa Rica","date":"16 abril 2013","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Bar y Restaurante Surf Dogs en Jac\u00f3, Puntarenas, Costa Rica Direcci\u00f3n desde el Aeropuerto Internacional de Liberia Daniel Oduber, Guanacaste, Costa Rica al Bar y Restaurante Surf Dogs en Jac\u00f3, Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Bar\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":508,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-exotica\/","url_meta":{"origin":595,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Ex\u00f3tica","author":"Restaurantes Costa Rica","date":"21 octubre 2010","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda (SJO), Alajuela, Costa Rica a Ojochal en Puntarenas, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ex\u00f3tica en Ojochal, Puntarenas, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=595"}],"version-history":[{"count":3,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/595\/revisions"}],"predecessor-version":[{"id":3369,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/595\/revisions\/3369"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}