{"id":696,"date":"2011-02-25T17:29:33","date_gmt":"2011-02-25T22:29:33","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?page_id=696"},"modified":"2014-03-20T17:53:47","modified_gmt":"2014-03-20T22:53:47","slug":"mapa-con-la-direccion-del-restaurante-ichiban-san-pedro","status":"publish","type":"page","link":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/","title":{"rendered":"Mapa con la Direcci\u00f3n al  Restaurante Ichiban San Pedro"},"content":{"rendered":"<p>Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban San Pedro, San Jos\u00e9, Costa Rica<\/p>\n<p><code><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m26!1m12!1m3!1d31440.080793149646!2d-84.09065178501845!3d9.933116385574724!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!4m11!1i0!3e0!4m3!3m2!1d9.936632!2d-84.0981773!4m4!2s9.931853%2C-84.048708!3m2!1d9.931853!2d-84.04870799999999!5e0!3m2!1sen!2s!4v1395356011057\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0\"><\/iframe><\/code><\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-ichiban\/\">Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban San Pedro, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-696","page","type-page","status-publish","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban San Pedro, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2014-03-20T22:53:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\\\/\",\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"datePublished\":\"2011-02-25T22:29:33+00:00\",\"dateModified\":\"2014-03-20T22:53:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/","og_locale":"es_ES","og_type":"article","og_title":"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica","og_description":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban San Pedro, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/","og_site_name":"Restaurantes Costa Rica","article_modified_time":"2014-03-20T22:53:47+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/","name":"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"datePublished":"2011-02-25T22:29:33+00:00","dateModified":"2014-03-20T22:53:47+00:00","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-san-pedro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Mapa con la Direcci\u00f3n al Restaurante Ichiban San Pedro"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"jetpack_shortlink":"https:\/\/wp.me\/P5i3XU-be","jetpack-related-posts":[{"id":694,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-rohrmoser\/","url_meta":{"origin":696,"position":0},"title":"Mapa con la Direcci\u00f3n al Restaurante Ichiban Rohrmoser","author":"Restaurantes Costa Rica","date":"25 febrero 2011","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban Rohrmoser, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":690,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-paseo-de-las-flores\/","url_meta":{"origin":696,"position":1},"title":"Mapa con la Direcci\u00f3n al Restaurante Ichiban Paseo de Las Flores","author":"Restaurantes Costa Rica","date":"25 febrero 2011","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban Paseo de Las Flores, Heredia, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":692,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-ichiban-real-cariari\/","url_meta":{"origin":696,"position":2},"title":"Mapa con la Direcci\u00f3n al Restaurante Ichiban Real Cariari","author":"Restaurantes Costa Rica","date":"25 febrero 2011","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Ichiban Real Cariari, Heredia, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Ichiban en Costa Rica, haga click aqu\u00ed","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3747,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-cosi\/","url_meta":{"origin":696,"position":3},"title":"Mapa con la Direcci\u00f3n al Restaurante Cos\u00ec","author":"Restaurantes Costa Rica","date":"8 mayo 2014","format":false,"excerpt":"Direcci\u00f3n desde el Aeropuerto Internacional Juan Santamar\u00eda, Alajuela, Costa Rica al Restaurante Cos\u00ec en Alajuela, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Cos\u00ec en\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1253,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-tacobar\/","url_meta":{"origin":696,"position":4},"title":"Mapa con la Direcci\u00f3n al Restaurante TacoBar","author":"Restaurantes Costa Rica","date":"22 julio 2012","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Escaz\u00fa, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante TacoBar en Pinares, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1167,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-family-pizza\/","url_meta":{"origin":696,"position":5},"title":"Mapa con la Direcci\u00f3n al Restaurante Family Pizza","author":"Restaurantes Costa Rica","date":"25 abril 2014","format":false,"excerpt":"Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Guadalupe, San Jos\u00e9, Costa Rica Direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Family Pizza en Currdidabat, San Jos\u00e9, Costa Rica Para m\u00e1s informaci\u00f3n acerca del Restaurante Family Pizza en San\u2026","rel":"","context":"Entrada similar","block_context":{"text":"Entrada similar","link":""},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=696"}],"version-history":[{"count":3,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/696\/revisions"}],"predecessor-version":[{"id":3388,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/pages\/696\/revisions\/3388"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}