{"id":1274,"date":"2012-06-01T18:44:57","date_gmt":"2012-06-01T23:44:57","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=1274"},"modified":"2024-04-25T07:42:42","modified_gmt":"2024-04-25T12:42:42","slug":"el-banco-de-los-mariscos","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","title":{"rendered":"Restaurante El Banco de los Mariscos"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1284\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1544%2C710&amp;ssl=1\" data-orig-size=\"1544,710\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante El Banco de los Mariscos en Santa B\u00e1rbara de Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1024%2C470&amp;ssl=1\" class=\"wp-image-1284 alignright\" title=\"Restaurante El Banco de los Mariscos en Santa B\u00e1rbara de Heredia, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=334%2C154&#038;ssl=1\" alt=\"Restaurante El Banco de los Mariscos en Santa B\u00e1rbara de Heredia, Costa Rica\" width=\"334\" height=\"154\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?w=1544&amp;ssl=1 1544w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=300%2C137&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=1024%2C470&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=150%2C68&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=400%2C183&amp;ssl=1 400w\" sizes=\"auto, (max-width: 334px) 100vw, 334px\" \/><strong>Horario:<\/strong><\/p>\n<p>De Lunes a S\u00e1bados de 11:30 a.m. a 10 p.m.<br \/>\nDomingos de 11:30 a.m. a 9 p.m.<\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> 600m al oeste del costado suroeste de la Iglesia de Santa B\u00e1rbara, distrito: San Pedro, cant\u00f3n: Santa Barbara, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40402.<br \/>\n<strong>Coordenadas para GPS<\/strong>: 10.034908,-84.163470 (10\u00b002&#8217;05.67&#8243;N, 84\u00b009&#8217;48.49&#8243;W)<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u1hfcsz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante El Banco de los Mariscos San Pedro, Santa Barbara, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Banco+de+Los+Mariscos\/@10.0352895,-84.1656777,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0f098b402d093:0x60e1a0ad9c42b86a!8m2!3d10.0352842!4d-84.163489\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante El Banco de los Mariscos San Pedro, Santa Barbara, Heredia, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono:<\/h2>\n<p><a href=\"tel:+5062269-9090\">+506 2269-9090<\/a> servicio express ( a domicilio )<\/p>\n<p><strong><a title=\"Men\u00fa del Restaurante Banco de los Mariscos\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#menu\">Men\u00fa de El Banco de los Mariscos<\/a><\/strong><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-el-banco-de-los-mariscos\">Haga click aqu\u00ed para ver la direcci\u00f3n al Restaurante El Banco de los Mariscos en Santa B\u00e1rbara de Heredia, Costa Rica.<\/a><\/p>\n<p>El Restaurante El Banco de los Mariscos es un acogedor restaurante con m\u00e1s de 25 a\u00f1os de experiencia, ubicado en San Pedro de Santa B\u00e1rbara, Heredia. En sus inicios, El Banco de los Mariscos estaba ubicado a un costado del parque de Santa B\u00e1rbara, pero gracias al \u00e9xito que tuvo, en 1996 decidieron ampliar su negocio y trasladarse al local que hoy d\u00eda es su casa.<\/p>\n<p>Ofrece un extenso men\u00fa que incluye mariscos, carnes, arroces, pastas y m\u00e1s, para satisfacer todos los gustos, siempre manteniendo la calidad y la frescura de sus productos. Dentro de sus platillos se destacan el ceviche de corvina, de camar\u00f3n o mixto, el filete de corvina empanizada o a la plancha, el arroz a la marinera o con camarones, el pescado entero frito y m\u00e1s! Para el Restaurante El Banco de los Mariscos, la frescura y calidad de sus productos son muy importantes.<\/p>\n<p>El Banco de los Mariscos es un amplio restaurante con capacidad para atender a unas 500 personas, toda su decoraci\u00f3n es alusiva al fondo del mar. Por otra parte, el restaurante tambi\u00e9n cuenta con varios salones, dos de los cuales pueden ser reservados para realizar sus actividades personales. Uno, se encuentra totalmente aislado del restaurante y cuenta con capacidad para 20 personas.<\/p>\n<p>El Restaurante El Banco de los Mariscos cuenta con un excelente servicio, precios, servicio de reservaciones y un amplio parqueo.<\/p>\n<p>En el Restaurante El Banco de los Mariscos los productos vienen del mar, directo a su mesa!<\/p>\n<h1 id=\"menu\">MEN\u00da<\/h1>\n<p>Precios con impuesto incluido.<\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#entradas\">Entradas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#especialidadenarroz\">Especialidad en Arroz<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#especialidadenmariscos\">Especialidad en Mariscos<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#polloycarne\">Pollo y Carne<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#adicionales\">Adicionales<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#postres\">Postres<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#bebidas\">Bebidas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#licores\">Licores<\/a><\/p>\n<h2 id=\"entradas\">ENTRADAS<\/h2>\n<ul>\n<li>Ceviche MEDIO \u20a12952 ENTERO \u20a14059<\/li>\n<li>Ceviche de Camar\u00f3n MEDIO \u20a13321 ENTERO \u20a14797<\/li>\n<li>Ceviche de Chuchecas MEDIO \u20a13198 ENTERO \u20a14428<\/li>\n<li>Ceviche Mixto \u20a14797<\/li>\n<li>Ceviche Vuelve a la Vida \u20a15289<\/li>\n<li>Ceviche con Aguacate \u20a15043<\/li>\n<li>Ceviche con Palmito \u20a15043<\/li>\n<li>Ensalada Verde, Palmito, C\u00e9sar, Pollo o At\u00fan \u20a14059<\/li>\n<li>Ensalada de Camarones Especial. \u20a18241 JUMBO. \u20a113530<\/li>\n<li>Coctel de Camarones Especial. \u20a18241 JUMBO \u20a113530<\/li>\n<li>Sopa de Mariscos \u20a14053<\/li>\n<li>Sopa Fiesta Marina \u20a15043<\/li>\n<\/ul>\n<p><strong>Aderezos: Mil Islas &#8211; Salsa T\u00e1rtara &#8211; Salsa Rosada<\/strong><\/p>\n<h2 id=\"especialidadenarroz\">ESPECIALIDAD EN ARROZ<\/h2>\n<ul>\n<li>Paella de la casa (para 2 personas) \u20a114760<\/li>\n<li>Paella de la Casa (para 4 personas) \u20a127050<\/li>\n<li>Camarones con Arroz PEQ. \u20a15904 MED. \u20a18856 JUMBO. \u20a115990<\/li>\n<li>Arroz a la Marinera * MEDIO \u20a15043 ENTERO \u20a17749<\/li>\n<li>Arroz con Camarones * MEDIO \u20a14797 ENTERO \u20a17380<\/li>\n<li>Arroz con Pulpo * MEDIO \u20a16150 ENTERO \u20a19963<\/li>\n<li>Arroz con Calamares * MEDIO \u20a15043 ENTERO \u20a17626<\/li>\n<li>Arroz con Pescado * MEDIO \u20a14059 ENTERO \u20a16273<\/li>\n<li>Arroz con At\u00fan * MEDIO \u20a14059 ENTERO \u20a16273<\/li>\n<li>Arroz con Pollo * MEDIO \u20a13936 ENTERO \u20a16150<\/li>\n<\/ul>\n<p><strong>* Acompa\u00f1ado con papas tostadas y ensalada<\/strong><\/p>\n<h2 id=\"especialidadenmariscos\">ESPECIALIDAD EN MARISCOS<\/h2>\n<ul>\n<li>Camarones Banco de los Mariscos PEQ. \u20a16027 Esp. \u20a18733 JUMBO \u20a115990<\/li>\n<li>Camarones Termidor PEQ. \u20a16027 Esp. \u20a18733 JUMBO \u20a115990<\/li>\n<li>Camarones a la Mantequilla, Ajillo, Empanizados o en Salsa de Tomate PEQ. \u20a15289 Esp. \u20a17872 JUMBO \u20a114145<\/li>\n<li>Camarones a la Plancha Esp. \u20a17872 JUMBO \u20a114145<\/li>\n<li>Brochetas de Camar\u00f3n Esp. \u20a17872 JUMBO \u20a114145<\/li>\n<li>Camarones en Crema de Hongos Gratinados Esp. \u20a19348 JUMBO \u20a117220<\/li>\n<li>Langosta al Ajillo o Mantequilla \u20a117220<\/li>\n<li>Langosta Empanizada \u20a117835<\/li>\n<li>Langosta a la Plancha \u20a117835<\/li>\n<li>Langosta Termidor \u20a119065<\/li>\n<li>Pulpo al Ajillo o Mantequilla \u20a19963<\/li>\n<li>Pulpo en Salsa de Tomate \u20a19963<\/li>\n<li>Calamares al Ajillo o Mantequilla \u20a16150<\/li>\n<li>Calamares en Salsa de Tomate \u20a16150<\/li>\n<li>Mariscada al Ajillo o Mantequilla \u20a18364<\/li>\n<li>Mariscada en Salsa de Tomate \u20a18364<\/li>\n<li>Filet Banco de Los Mariscos \u20a16150<\/li>\n<li>Filet con Camarones a la Reina \u20a16273<\/li>\n<li>Filet Empanizado \u20a14428<\/li>\n<li>Filet Ajillo, a la plancha, en Salsa de Tomate o a la Mantequilla o la Plancha \u20a15043<\/li>\n<li>Filet al Aguacate \u20a15781<\/li>\n<li>Filet al Aguacate Gratinado \u20a16519<\/li>\n<li>Filet en Crema de Hongos \u00f3 Esparragos \u20a15781<\/li>\n<li>Salm\u00f3n a la Plancha \u20a19840<\/li>\n<li>Espaguetti Frutti di Mare \u20a17011<\/li>\n<li>Espaguetti en Crema de Hongos \u20a15043<\/li>\n<li>Espaguetti en Salsa de Tomate \u00f3 Mantequilla \u20a14305<\/li>\n<li>Pescado Entero Frito o Empanizado (Precio Seg\u00fan Peso)<\/li>\n<li>Pescado Entero sin Espinas Frito o Empanizado (Precio Seg\u00fan Peso)<\/li>\n<li>Pescado Entero sin Espinas en Crema de Esp\u00e1rragos &#8211; Hongos (Precio Seg\u00fan Peso)<\/li>\n<li>Pescado Entero sin Espinas Relleno de Mariscos (Precio Seg\u00fan Peso)<\/li>\n<\/ul>\n<h2 id=\"polloycarne\">Pollo y Carne<\/h2>\n<ul>\n<li>Pollo Frito \u20a13813<\/li>\n<li>Pollo al Ajillo, Mantequilla o Salsa de Tomate \u20a14059<\/li>\n<li>Pechuga sin hueso a la Plancha, Mantequilla, Ajillo o Empanizada \u20a15043<\/li>\n<li>Pechuga en Crema de Hongos \u20a15289<\/li>\n<li>Lomito \u20a111808<\/li>\n<li>Lengua en Salsa de Tomate \u20a16888<\/li>\n<li>Hamburguesa con Papas a la Francesa \u20a13813<\/li>\n<li>Plato Surtido BM \u20a19000<\/li>\n<li>Alitas a la BBQ, Mostaza Miel o Buffalo \u20a15000<\/li>\n<\/ul>\n<h2 id=\"adicionales\">ADICIONALES<\/h2>\n<ul>\n<li>Plato Surtido Pa&#8217;Pikar \u20a18000<\/li>\n<li>Papas a la Francesa Peq. \u20a12829 Grnd. \u20a13567<\/li>\n<li>Aros de Cebolla \u20a13567<\/li>\n<li>Tortillas Tostadas \u20a11968<\/li>\n<li>Orden de Frijoles Molidos \u20a12829<\/li>\n<li>Orden de Guacamol \u20a13567<\/li>\n<li>Orden Patacones \u20a13198<\/li>\n<li>Orden Patacones MIxtos \u20a14428<\/li>\n<li>Orden Pan de Ajo \u20a12214<\/li>\n<li>Orden Pan de Ajo con Queso \u20a13321<\/li>\n<li>Orden de Chile Jalape\u00f1o \u00f3 Banano Verde \u20a11599<\/li>\n<li>Orden de Arroz Blanco Peq. \u20a11230 Grand. \u20a11845<\/li>\n<li>Orden Papa en Gajos \u20a13321<\/li>\n<li>Orden de Palitos de Queso \u20a13321<\/li>\n<li>Orden de Aros de Calamar \u20a13936<\/li>\n<\/ul>\n<h2 id=\"postres\">POSTRES<\/h2>\n<ul>\n<li>Tres Leches \u20a11722<\/li>\n<li>Flan de Coco \u20a1722<\/li>\n<li>Cheese Cake \u20a11845<\/li>\n<li>Pedacito de Cielo \u20a11968<\/li>\n<li>Tiramis\u00fa \u20a11968<\/li>\n<li>Fresas con Leche Condensada \u20a12214<\/li>\n<li>Helados con Gelatina (Copa) \u20a11722<\/li>\n<li>Copa de Helados \u20a11722<\/li>\n<li>Ensalada de Frutas \u20a13567<\/li>\n<\/ul>\n<h2 id=\"bebidas\">BEBIDAS<\/h2>\n<ul>\n<li>Coca Cola &#8211; Fanta Naranja &#8211; Fanta Kolita Peq. \u20a11722 Grnd. \u20a12214<\/li>\n<li>Ginger Ale &#8211; Soda &#8211; Sprite Peq. \u20a11722 Grnd. \u20a12214<\/li>\n<li>Naturales en Leche Peq. \u20a12091 Grnd. \u20a12337<\/li>\n<li>Naturales en Agua Peq. \u20a11722 Grnd. \u20a12091<\/li>\n<li>Jugo de Naranja \u20a11599<\/li>\n<li>Te Fr\u00edo \u20a11599<\/li>\n<li>Caf\u00e9 Negro \u20a11353<\/li>\n<li>Caf\u00e9 con Leche \u20a11476<\/li>\n<li>Caf\u00e9 Espresso \u20a11353<\/li>\n<li>Caf\u00e9 Capuchino \u20a11476<\/li>\n<li>Chocolate \u20a11476<\/li>\n<li>T\u00e9 Negro (caliente) \u20a11353<\/li>\n<li>T\u00e9 en Leche (caliente) \u20a11476<\/li>\n<li>N\u00e9ctar de Frutas del Prado \u20a11845<\/li>\n<li>Infusi\u00f3n (Twinnings) \u20a11353<\/li>\n<\/ul>\n<h2 id=\"licores\">LICORES<\/h2>\n<ul>\n<li>Cerveza Cruda (imperial) Jarra \u20a12214\u00a0Pichel Med. \u20a15412 Pichel Grnd. \u20a19225<\/li>\n<li>Cervezas: (Imperial &#8211; Pilsen &#8211; Rock Ice &#8211; Kaiser) \u20a12214<br \/>\n(Bavaria &#8211; Bavaria Light &#8211; Heineken) \u20a12460<\/li>\n<li>Extranjeras: (Corona) \u20a13567<\/li>\n<li>Vino de la Casa en Copa \u20a12460<\/li>\n<li>Vodka: Smirnoff &#8211; Absolut<\/li>\n<li>Ron: Bacardi &#8211; Centenario &#8211; Malib\u00fa<\/li>\n<li>Tequila: Cuervo<\/li>\n<li>Whisky: Johnnie Walker &#8211; Passport &#8211; Chivas Regal &#8211; Old Parr &#8211; J&amp;B<\/li>\n<li>Brandy: Valdespino<\/li>\n<li>Cognac: Henessy<\/li>\n<\/ul>\n<p>Variedad en Cremas y Digestivos<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horario: De Lunes a S\u00e1bados de 11:30 a.m. a 10 p.m. Domingos de 11:30 a.m. a 9 p.m. Ubicaci\u00f3n: 600m al oeste del costado suroeste de la Iglesia de Santa B\u00e1rbara, distrito: San Pedro, cant\u00f3n: Santa Barbara, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40402. Coordenadas para GPS: 10.034908,-84.163470 (10\u00b002&#8217;05.67&#8243;N, 84\u00b009&#8217;48.49&#8243;W) Tel\u00e9fono: +506 &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante El Banco de los Mariscos\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#more-1274\" aria-label=\"Leer m\u00e1s sobre Restaurante El Banco de los Mariscos\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[107,3,72,74],"tags":[],"class_list":["post-1274","post","type-post","status-publish","format-standard","hentry","category-107","category-heredia","category-mariscos","category-santa-barbara","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono<\/title>\n<meta name=\"description\" content=\"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono\" \/>\n<meta property=\"og:description\" content=\"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-01T23:44:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-25T12:42:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante El Banco de los Mariscos\",\"datePublished\":\"2012-06-01T23:44:57+00:00\",\"dateModified\":\"2024-04-25T12:42:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/\"},\"wordCount\":983,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg\",\"articleSection\":[\"40402\",\"Heredia\",\"Mariscos\",\"Santa B\u00e1rbara\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/\",\"name\":\"Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg\",\"datePublished\":\"2012-06-01T23:44:57+00:00\",\"dateModified\":\"2024-04-25T12:42:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1544%2C710&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/02\\\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1544%2C710&ssl=1\",\"width\":\"1544\",\"height\":\"710\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-banco-de-los-mariscos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante El Banco de los Mariscos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono","description":"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono","og_description":"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2012-06-01T23:44:57+00:00","article_modified_time":"2024-04-25T12:42:42+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante El Banco de los Mariscos","datePublished":"2012-06-01T23:44:57+00:00","dateModified":"2024-04-25T12:42:42+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/"},"wordCount":983,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg","articleSection":["40402","Heredia","Mariscos","Santa B\u00e1rbara"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","name":"Restaurante El Banco de los Mariscos Costa Rica - Men\u00fa, Tel\u00e9fono","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg","datePublished":"2012-06-01T23:44:57+00:00","dateModified":"2024-04-25T12:42:42+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Restaurante El Banco de los Mariscos Costa Rica en Heredia: men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1544%2C710&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?fit=1544%2C710&ssl=1","width":"1544","height":"710"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante El Banco de los Mariscos"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-ky","jetpack-related-posts":[{"id":6806,"url":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","url_meta":{"origin":1274,"position":0},"title":"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara","author":"Restaurantes Costa Rica","date":"9 agosto 2018","format":false,"excerpt":"Tel\u00e9fono +506 2269-9369 Servicio a domicilio ( express ). Horario De Martes a Domingo de 12md a 8pm. Direcci\u00f3n 150 metros oeste del parque de Santa Barbara, sobre Av 2 entre calles 4 y 6. Distrito: Santa Barbara, cant\u00f3n: Santa Barbara, provincia: Heredia. C\u00f3digo postal de la zona: 40401. M\u00fasica\u2026","rel":"","context":"En \u00ab40401\u00bb","block_context":{"text":"40401","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40401\/"},"img":{"alt_text":"Ubicaci\u00f3n WAZE de Restaurante Marisquer\u00eda Rancho Santa Barbara, Heredia, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1623,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-pianos\/","url_meta":{"origin":1274,"position":1},"title":"Bar y Restaurante Pianos","author":"Restaurantes Costa Rica","date":"27 julio 2012","format":false,"excerpt":"Horario: De Martes a Domingo de 2 p.m. a 12 mn. Karaoke Viernes de 7pm a 11pm. Lunes Cerrado MEN\u00da Ubicaci\u00f3n: 1.5 km noreste de la plaza de Birr\u00ed, distrito: Jes\u00fas, cant\u00f3n: Santa B\u00e1rbara, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40404 Coordenadas para GPS: 10.065206,-84.128408 (10\u00b003'54.74\"N, 84\u00b007'42.27\"W) Tel\u00e9fono: +506 2269-8051\u2026","rel":"","context":"En \u00ab40404\u00bb","block_context":{"text":"40404","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40404\/"},"img":{"alt_text":"Mirador Pianos Bar y Restaurante en Birri, Santa Barbara, Heredia, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/mirador-pianos-bar-restaurante-birri-santa-barbara-heredia-costa-rica-300x207.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1788,"url":"https:\/\/costaricainfolink.com\/restaurantes\/gelateria-da-noi\/","url_meta":{"origin":1274,"position":2},"title":"Gelateria Da Noi","author":"Restaurantes Costa Rica","date":"27 agosto 2012","format":false,"excerpt":"Click the following link to read this page in English: Da Noi Gelateria El Caf\u00e9 y Gelateria Da Noi, que significa \u201cDonde nosotros\u201d en italiano, es una gelater\u00eda artesanal italiana que abri\u00f3 sus puertas en el a\u00f1o 2008 en San Jos\u00e9, gracias al sue\u00f1o de Elena Barnab\u00f3 y Marcello Polinaris,\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Gelateria Da Noi en Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/da-noi-gelateria-cafe-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1245,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tacobar\/","url_meta":{"origin":1274,"position":3},"title":"TacoBar","author":"Restaurantes Costa Rica","date":"22 julio 2012","format":false,"excerpt":"Restaurante TacoBar en Santa Ana: Ubicaci\u00f3n: 350m al norte de la Cruz Roja, frente de Mas x Menos en Santa Ana, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10901. Coordenadas para GPS: 9.937425,-84.188756 (9\u00b056'14.73\"N, 84\u00b011'19.52\"W) Tel\u00e9fono: +506 2282-4863 Horario: de Lunes\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/01\/taco-bar-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6858,"url":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","url_meta":{"origin":1274,"position":4},"title":"Spoon","author":"Restaurantes Costa Rica","date":"2 septiembre 2018","format":false,"excerpt":"Tel\u00e9fono Servicio a Domicilio ( express ) +506 2259-6000 MEN\u00da Ubicaciones ALAJUELA: Plaza Real - City Mall - SAN JOS\u00c9: Los Laureles - Distrito 4 - Multiplaza Escaz\u00fa - Escaz\u00fa Village - Sabana - Pavas - Cl\u00ednica B\u00edblica - Avenida Central - Calle Central - Yoses - Mall San Pedro\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Spoon Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":112,"url":"https:\/\/costaricainfolink.com\/restaurantes\/maxis\/","url_meta":{"origin":1274,"position":5},"title":"Restaurante Maxis","author":"Restaurantes Costa Rica","date":"27 mayo 2009","format":false,"excerpt":"Restaurante Maxis en Manzanillo, Lim\u00f3n: Ubicaci\u00f3n: sobre la carretera principal en Manzanillo centro junto a la playa, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. Coordenadas para GPS: 9.632503,-82.657817 (9\u00b037'57.01\"N, 82\u00b039'28.14\"W) Tel\u00e9fono: +506 2798-3740 \/ +506 2759-9073 Horario: todos los d\u00edas de 11 a.m.\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=1274"}],"version-history":[{"count":47,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1274\/revisions"}],"predecessor-version":[{"id":12187,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1274\/revisions\/12187"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=1274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=1274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=1274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}