{"id":1507,"date":"2012-07-10T07:56:31","date_gmt":"2012-07-10T12:56:31","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=1507"},"modified":"2019-09-23T18:29:30","modified_gmt":"2019-09-23T23:29:30","slug":"bamboo-sushi-club-tamarindo","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/","title":{"rendered":"Restaurante Bamboo Sushi Club"},"content":{"rendered":"<p><strong><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1548\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/bamboo-sushi-club-restaurante-costa-rica-logos\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&amp;ssl=1\" data-orig-size=\"720,423\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante Bamboo Sushi Club en Tamarindo, Guanacaste, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&amp;ssl=1\" class=\"alignright wp-image-1548\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?resize=400%2C235&#038;ssl=1\" alt=\"\" width=\"400\" height=\"235\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?resize=300%2C176&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?resize=150%2C88&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?resize=400%2C235&amp;ssl=1 400w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?w=720&amp;ssl=1 720w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>Horario:<\/strong><br>De Lunes a Sabados de 11 a.m. a 10 p.m.<br>Domingos de 11 a.m. a 10 p.m.<\/p>\n<h2>Tel\u00e9fono<br><a href=\"tel:+5062653-4519\">+506 2653-4519<\/a><\/h2>\n<p><strong>Ubicaci\u00f3n:<\/strong> 4.5km al noroeste de la entrada de Tamarindo, frente a Century 21, distrito: Tamarindo, Cant\u00f3n: Santa Cruz, provincia: Guanacaste, Costa Rica. C\u00f3digo Postal: 50309.<br><strong>Coordenadas para GPS<\/strong>: 10.299677,-85.841289 (10\u00b017&#8217;58.84&#8243;N, 85\u00b050&#8217;28.64&#8243;W)<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1ffwdur9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante Bamboo Sushi Club Tamarindo Santa Cruz Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/ZuVeWnRui2NjTQuY8\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante Bamboo Sushi Club Tamarindo Santa Cruz Guanacaste Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-bamboo-sushi-club\">Haga click aqu\u00ed para ver la direcci\u00f3n al Restaurante Bamboo Sushi Club Tamarindo, Costa Rica<\/a><\/p>\n<h2><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#menu\">MEN\u00da<\/a><\/h2>\n<p>Bamboo Sushi Club es un acogedor restaurante al aire libre, situado a 100 metros de la espectacular playa de Tamarindo en Guanacaste, Costa Rica. El restaurante cuenta con lugares privados y un jard\u00edn tropical japon\u00e9s donde se ofrece un sabroso men\u00fa de sushi y bocadillos estilo asi\u00e1tico. Con su exclusivo dise\u00f1o Japon\u00e9s, el restaurante Bamboo Sushi Club le garantiza la experiencia culinaria m\u00e1s memorable de la zona con sus muy creativas recetas, servidas en un ambiente extraordinario.<\/p>\n<p>Cuando el Restaurant Bamboo Sushi Club Tamarindo abri\u00f3 sus puertas en marzo del 2009, se convirti\u00f3 en un \u00e9xito total, y ahora, cuenta con m\u00e1s de 60 diferentes tipos de platillos variados para servir a sus clientes, seg\u00fan su fundador, propietario y chef, el argentino Mauro Camera. Este restaurante es fant\u00e1stico para una comida ligera, sana y deliciosa.<\/p>\n<p>El Restaurant Bamboo Sushi Club cuenta con una amplia variedad de comida siempre fresca, famoso por sus combinaciones de sushi, as\u00ed como su diversidad en bowls de arroz y ensaladas. Aqu\u00ed los visitantes pueden comer algunos deliciosos wontons de camarones con salsa picante, pastel de cangrejo, s\u00e1ndwich de at\u00fan, ravioles de salm\u00f3n con salsa de asi\u00e1tica y eneldo, as\u00ed como un exquisito cheesecake de maracuy\u00e1, por nombrar s\u00f3lo algunos de sus platillos. Adem\u00e1s, el Restaurante Bamboo Sushi Club es el lugar ideal para los vegetarianos, ya que ofrecen muchas opciones para ellos. El restaurante tambi\u00e9n ofrece servicio para llevar y de reservaciones, personal biling\u00fce, cuenta con estacionamiento y acepta tarjetas de cr\u00e9dito. Este restaurante es la opci\u00f3n perfecta para aquellos que buscan encontrar un lugar tranquilo, con comida incre\u00edble dentro de un ambiente equilibrado, o simplemente para disfrutar de un refrescante Mojito frozen o el que m\u00e1s le guste, ya que el restaurante cuenta con numerosos c\u00f3cteles exclusivos para acompa\u00f1ar sus platos.<\/p>\n<p>El Restaurante Bamboo Sushi Club es sin duda el mejor lugar para disfrutar de una cena de sushi incre\u00edble, compartir con amigos y tener una gran noche!<\/p>\n<h2 id=\"menu\">MEN\u00da<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#entradas\">Entradas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#ensaladas\">Ensaladas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#sopas\">Sopas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#pokebowl\">Poke Bowl<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#sashimis\">Sashimis<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#nigiris\">Nigiris<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#gunkans\">Gunkans<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#makis\">Makis<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#handrolls\">Hand Rolls<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#uramakis\">Uramakis<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#sushicombos\">Sushi Combos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#platosfuertes\">Platos Fuertes<\/a><\/p>\n<h2>Entradas<\/h2>\n<p><strong>Edamames<\/strong> $5.54<\/p>\n<p><strong>Edamames Picantes<\/strong> $5.66<\/p>\n<p><strong>Rollo Primavera<\/strong> $5.66<br>Servido con Salsa Mae Ploi<\/p>\n<p><strong>Gyosas<\/strong> $7.38<br>Cerdo, Pollo o Camaron. Fritas o al vapor.<\/p>\n<p><strong>Wantan de Camarones<\/strong> $6.15<\/p>\n<p><strong>Korokes de Salm\u00f3n<\/strong> $7.38<br>Bolitas fritas de salm\u00f3n y papa con salsa picante casera.<\/p>\n<p><strong>At\u00fan Tataki<\/strong> $9.84<br>At\u00fan sellado con semillas de ajonjol\u00ed, salsa crujiente y picante de ajo servido sobre ar\u00fagula fresca.<\/p>\n<p><strong>Tiradito de Dorado<\/strong> $8.61<br>Finas lonjas de salm\u00f3n servido con salsa de Maracuy\u00e1 y fideos de wantan fritos.<\/p>\n<p><strong>Tempura de Vegetales<\/strong> $6.15<\/p>\n<p><strong>Tempura de Camarones<\/strong> $9.23<\/p>\n<p><strong>Tempura de Calamares<\/strong> $9.23<\/p>\n<p><strong>Tempura Mixto<\/strong> $14.76<\/p>\n<h2 id=\"ensaladas\">Ensaladas<\/h2>\n<p><strong>Club Salad<\/strong> $5.54<br>Mixto verde y cebolla morada con vinagreta asi\u00e1tica casera.<\/p>\n<p><strong>Pollo Teriyaki<\/strong> $8<br>Pollo con salsa teriyaki, mixto verde, cebolla, tomate y brotes de soja.<\/p>\n<p><strong>Smoke Salada<\/strong> $9.23<br>Salm\u00f3n ahumado, mixto verde, huevo, aguacate y cebolla morada con Vinagreta casera.<\/p>\n<p><strong>At\u00fan Tataki<\/strong> $10.46<br>At\u00fan sellado con semillas de ajonjol\u00ed, mixto verde, cebolla morada y tomates cherry.<\/p>\n<p><strong>Salm\u00f3n Tataki<\/strong> $11.69<br>Salm\u00f3n sellado con semillas de ajonjol\u00ed, mixto verde, cebolla morada y tomates cherry.<\/p>\n<p><strong>Ensalada de Algas<\/strong> $8.61<\/p>\n<p><strong>Ensalada de Algas con Tartar de At\u00fan<\/strong> $10.46<\/p>\n<p><strong>Ensalada de Algas con Tartar de At\u00fan picante<\/strong> $12.30<\/p>\n<h2 id=\"sopas\">Sopas<\/h2>\n<p><strong>Sopa Miso<\/strong> $6.15<br>Con Nori, Wakame, Tofu y ceboll\u00edn.<\/p>\n<p><strong>Sopa Bamboo<\/strong> $8<br>Caldo a base de soya con vegetales, huevo y fideos soba.<\/p>\n<h2 id=\"pokebowl\">Poke Bowl<\/h2>\n<p><strong>Vegetariano<\/strong> $10.21<br>Zanahoria, pepino, aguacate, tofu especiado, cebollin y brotes con una vinagreta de ajonjol\u00ed y miso.<\/p>\n<p><strong>Maruja Bamboo<\/strong> $11.69<br>Tartar de At\u00fan con mango, zanahoria, pepino y aguacate con Vinagreta de Soya y aceite de ajonjol\u00ed.<\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/atun-poke-bowl-maruja-bamboo-sushi-club-tamarindo-1\/#main\" rel=\"attachment wp-att-8246\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8246\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/atun-poke-bowl-maruja-bamboo-sushi-club-tamarindo-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Maruja Bamboo Poke Bowl de At\u00fan\" data-image-description=\"&lt;p&gt;Maruja Bamboo Poke Bowl de At\u00fan&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-8246\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?resize=533%2C400&#038;ssl=1\" alt=\"\" width=\"533\" height=\"400\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/atun-poke-bowl-Maruja-Bamboo-sushi-club-tamarindo-1.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 533px) 100vw, 533px\" \/><\/a><\/p>\n<p><strong>Camar\u00f3n<\/strong> $13.53<br>Camarones, lechuga, aguacate, pi\u00f1a y rabano con vinagreta de wasabi.<\/p>\n<h2 id=\"sashimis\">Sashimis 7 piezas<\/h2>\n<p><strong>Maguro<\/strong> $9.23<br>At\u00fan.<\/p>\n<p><strong>Sake<\/strong> $10.46<br>Salm\u00f3n.<\/p>\n<p><strong>Unagi<\/strong> $12.92<br>Anguila.<\/p>\n<p><strong>EBI<\/strong> $6.77<br>Camar\u00f3n.<\/p>\n<p><strong>Shimisaba<\/strong> $9.23<br>Macarela.<\/p>\n<p><strong>Hamachi<\/strong> $14.76<br>At\u00fan Cola Amarilla.<\/p>\n<h2 id=\"gunkans\">Gunkans<\/h2>\n<p><strong>Maguro<\/strong> $9.23<br>At\u00fan, tartar de at\u00fan y arroz.<\/p>\n<p><strong>Sake<\/strong> $10.46<br>Salm\u00f3n, tartar de salm\u00f3n y arroz.<\/p>\n<p><strong>Scallops<\/strong> $11.69<br>At\u00fan, tartar de Vieyras y arroz.<\/p>\n<p><strong>Calamari Tempura<\/strong> $14.76<br>Salm\u00f3n o At\u00fan, calamar tempura con salsa de maracuy\u00e1.<\/p>\n<h2 id=\"makis\">Makis<\/h2>\n<p><strong>Pepino o Aguacate<\/strong> $6.77<\/p>\n<p><strong>Maguro<\/strong> $8<br>At\u00fan.<\/p>\n<p><strong>Sake<\/strong> $9.23<br>Salm\u00f3n.<\/p>\n<p><strong>Hamachi<\/strong> $15.99<br>At\u00fan Cola Amarilla.<\/p>\n<h2>Hand Rolls<\/h2>\n<p><strong>Temaki Hand Roll<\/strong><br>Cono Nori, eleg\u00ed un rollo uramaki y te lo convertimos en cono.<\/p>\n<h2 id=\"uramakis\">Uramakis<\/h2>\n<p>10 piezas, rollos tradicionales con arroz por fuera.<\/p>\n<p><strong>California Roll<\/strong> $7.38<br>Cangrejo, aguacate y pepino.<\/p>\n<p><strong>New York Roll<\/strong> $8<br>At\u00fan o salm\u00f3n, aguacate y pepino.<\/p>\n<p><strong>Vegetarian Roll<\/strong> $8<br>Zanahoria, lechuga, aguacate, pepino y mango.<\/p>\n<p><strong>Spicy Tuna Roll<\/strong> $9.23<br>At\u00fan, aguacate y pepino cubierto con diferentes pescados.<\/p>\n<p><strong>Rainbow Roll<\/strong> $11.69<br>Cangrejo, aguacate y pepino cubierto con diferentes pescados..<\/p>\n<p><strong>Tex Mex Roll<\/strong> $8<br>At\u00fan picante y pepino con fresco guacamole arriba.<\/p>\n<p><strong>Tico Roll<\/strong> $11.07<br>At\u00fan picante y pepino cubierto con pl\u00e1tano maduro.<\/p>\n<p><strong>Philadelphia Roll<\/strong> $11.07<br>At\u00fan o Salm\u00f3n, aguacate, pepino y queso crema.<\/p>\n<p><strong>Caterpillar Roll<\/strong> $11.07<br>Anguila horneada y pepino cubierto con pur\u00e9 de aguacate servido con salsa de Anguila.<\/p>\n<p><strong>Ebi Roll<\/strong> $11.69<br>Camar\u00f3n tempurizado y aguacate servido con salsa de osgras y acompa\u00f1ado por una salsa ponzu casera.<\/p>\n<p><strong>Smoke Roll<\/strong> $11.07<br>Salm\u00f3n ahumado, aguacate, pepino y queso crema.<\/p>\n<p><strong>Buenos aires Roll<\/strong> $11.69<br>Salm\u00f3n, aguacate, pepino, nira ( cebollin japones ) y queso crema.<\/p>\n<p><strong>Crunchi Roll<\/strong> $14.76<br>Rollo frito con at\u00fan, queso crema y ceboll\u00edn, servido con salsa teriyaki especial.<\/p>\n<p><strong>Kim Roll<\/strong> $12.92<br>Salm\u00f3n picante y pepino, cubierto con l\u00e1mnias de aguacate.<\/p>\n<p><strong>Sushi Club<\/strong> $14.76<br>Rollo frito con At\u00fan, aguacate, Nira ( cebollin japones ) y queso crema.<\/p>\n<p><strong>Tono Roll<\/strong> $15.99<br>Tartar de At\u00fan cubierto por l\u00e1minas de aguacate.<\/p>\n<p><strong>Dashi Roll<\/strong> $15.38<br>Salm\u00f3n, queso crema y tomate seco con ar\u00fagula fresca por arriba.<\/p>\n<p><strong>Pacific Roll<\/strong> $13.53<br>Camar\u00f3n tempura, aguacate y queso crema cubierto con pl\u00e1tano maduro frito.<\/p>\n<h2 id=\"sushicombos\">Sushi Combos<\/h2>\n<p><strong>Red Combo<\/strong> 20 piezas, 1 persona $25.22<br>5 piezas Sashimi de At\u00fan, 5 piezas Nigiri de at\u00fan, 5 piezas de spicy tuna, 5 piezas de philadelphia roll.<\/p>\n<p><strong>Pink Combo<\/strong> 20 piezas, 1 persona $27.68<br>5 piezas sashimi de salmon, 5 piezas nigiri de salm\u00f3n, 5 piezas de New York Roll, 5 piezas de buenos aires roll.<\/p>\n<p><strong>Love Boat<\/strong> 44 piezas, 2 personas $43.05<br>7 piezas de sashimi de at\u00fan, 7 piezas de nigiri de at\u00fan, 10 piezas maki de at\u00fan, 10 piezas de New York Roll y 10 piezas de California Roll.<\/p>\n<p><strong>Special Combo<\/strong> 43 piezas, 2 personas $60.27<br>5 piezas de sashimi de at\u00fan, 5 piezas de sashimi de salm\u00f3n, 5 piezas de nigiri de at\u00fan, 5 piezas de nigiri de salm\u00f3n, 3 piezas de nigiri de Anguila, 10 piezas de Tex Mex Roll, 10 piezas de Kari Roll.<\/p>\n<p><strong>Super Love Boat<\/strong> 60 piezas, 3 personas $78.72<br>5 piezas de sashimi de at\u00fan, 5 piezas de sashimi de salm\u00f3n, 5 piezas de sashimi de macarela, 5 piezas de nigiri de at\u00fan, 5 piezas de nigiri de salm\u00f3n, 5 piezas de nigiri de salm\u00f3n, 5 piezas de nigiri de macarela, 10 piezas de california roll, 10 piezas de new york roll, 10 piezas de Tex Mex Roll.<\/p>\n<h2 id=\"platosfuertes\">Platos Fuertes<\/h2>\n<p>Wok&#8217;s y M\u00e1s<\/p>\n<p><strong>Donburi de Vegetales<\/strong> $14.76<br>Vegetales salteados al wok con salsa hoisin servido sobre arroz japon\u00e9s.<\/p>\n<p><strong>Donburi de Pollo<\/strong> $15.99<br>Pollo y vegetales salteados al wok con salsa teriyaki servido sobre arroz japon\u00e9s y almendras.<\/p>\n<p><strong>Yakimeshi de Pollo<\/strong> $14.76<br>Arroz frito con pollo, zanahoria, cebollin y huevo cocinado con salsa de soya.<\/p>\n<p><strong>Yakimeshi de Camarones<\/strong> $17.22<br>Arroz frito con Camarones, zanahoria, cebollin y huevo cocinado con salsa de soya.<\/p>\n<p><strong>Salm\u00f3n Teriyaki<\/strong> $19.68<br>Servido con arroz frito y mixto de ensalada asi\u00e1tica.<\/p>\n<p><strong>Canasta Bamboo<\/strong> $18.45<br>Pollo y vegetales salteados al wok con salsa picante y agridulce servido en una canaste de yuca y tiquisque.<\/p>\n<p><strong>Torta de Cangrejo<\/strong> $11.69<br>Servido con ensalada mixta verde y guacamole picante.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horario:De Lunes a Sabados de 11 a.m. a 10 p.m.Domingos de 11 a.m. a 10 p.m. Tel\u00e9fono+506 2653-4519 Ubicaci\u00f3n: 4.5km al noroeste de la entrada de Tamarindo, frente a Century 21, distrito: Tamarindo, Cant\u00f3n: Santa Cruz, provincia: Guanacaste, Costa Rica. C\u00f3digo Postal: 50309.Coordenadas para GPS: 10.299677,-85.841289 (10\u00b017&#8217;58.84&#8243;N, 85\u00b050&#8217;28.64&#8243;W) &nbsp;&nbsp; Mapa con direcci\u00f3n: Haga click aqu\u00ed &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Bamboo Sushi Club\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#more-1507\" aria-label=\"Leer m\u00e1s sobre Restaurante Bamboo Sushi Club\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[83,34,16,51,32],"tags":[],"class_list":["post-1507","post","type-post","status-publish","format-standard","hentry","category-83","category-asiatico","category-de-playa","category-japones","category-sushi","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-10T12:56:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-23T23:29:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Bamboo Sushi Club\",\"datePublished\":\"2012-07-10T12:56:31+00:00\",\"dateModified\":\"2019-09-23T23:29:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/\"},\"wordCount\":1325,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg\",\"articleSection\":[\"50309\",\"Asi\u00e1tico\",\"De playa\",\"Japon\u00e9s\",\"Sushi\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/\",\"name\":\"Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg\",\"datePublished\":\"2012-07-10T12:56:31+00:00\",\"dateModified\":\"2019-09-23T23:29:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&ssl=1\",\"width\":\"720\",\"height\":\"423\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bamboo-sushi-club-tamarindo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Bamboo Sushi Club\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono","description":"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono","og_description":"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2012-07-10T12:56:31+00:00","article_modified_time":"2019-09-23T23:29:30+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Bamboo Sushi Club","datePublished":"2012-07-10T12:56:31+00:00","dateModified":"2019-09-23T23:29:30+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/"},"wordCount":1325,"commentCount":2,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg","articleSection":["50309","Asi\u00e1tico","De playa","Japon\u00e9s","Sushi"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/","name":"Restaurante Bamboo Sushi Club Tamarindo - Men\u00fa, Direcci\u00f3n, Tel\u00e9fono","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos-300x176.jpg","datePublished":"2012-07-10T12:56:31+00:00","dateModified":"2019-09-23T23:29:30+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Informaci\u00f3n del Restaurante Bamboo Sushi Club Tamarindo, Costa Rica: men\u00fa, ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/bamboo-sushi-club-restaurante-costa-rica-logos.jpg?fit=720%2C423&ssl=1","width":"720","height":"423"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bamboo-sushi-club-tamarindo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Bamboo Sushi Club"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-oj","jetpack-related-posts":[{"id":236,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-sushi-kai-bar-lounge\/","url_meta":{"origin":1507,"position":0},"title":"Restaurante Sushi Kai Bar &#038; Lounge","author":"Restaurantes Costa Rica","date":"15 abril 2013","format":false,"excerpt":"NEGOCIO CERRADO Click the following link to read this page in English: Sushi Kai Bar & Lounge Restaurant El Restaurante Sushi Kai Bar & Lounge, ubicado en Lindora entre Santa Ana y Bel\u00e9n, es el lugar ideal para todos los amantes de la buena cocina japonesa, ya que cuenta con\u2026","rel":"","context":"En \u00ab10903\u00bb","block_context":{"text":"10903","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10903\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/sushi-kai-restaurant-santa-ana-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/sushi-kai-restaurant-santa-ana-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/sushi-kai-restaurant-santa-ana-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3205,"url":"https:\/\/costaricainfolink.com\/restaurantes\/japan-tico\/","url_meta":{"origin":1507,"position":1},"title":"Restaurante Japan Tico","author":"Restaurantes Costa Rica","date":"17 marzo 2014","format":false,"excerpt":"Men\u00fa Direcci\u00f3n: en avenida 9, entre calles 10 y 8, distrito: Alajuela, cant\u00f3n: Alajuela, provincia: Alajuela. C\u00f3digo postal de la zona: 20101. Coordenadas para GPS: 10.019344,-84.218510 (10\u00b001'09.64\"N, 84\u00b013'06.63\"W) Tel\u00e9fono: +506 2430-1429 \/ +506 8627-4679 Horario: todos los dias de 11:30 a.m. a 10 p.m. Mapa con direcci\u00f3n: Haga click aqu\u00ed\u2026","rel":"","context":"En \u00ab20101\u00bb","block_context":{"text":"20101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/20101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/03\/restaurante-japan-tico-alajuela-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":807,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-sports-bar-kahiki\/","url_meta":{"origin":1507,"position":2},"title":"Restaurante y Sports Bar Kahiki","author":"Restaurantes Costa Rica","date":"11 agosto 2011","format":false,"excerpt":"Click the following link to read this page in English: Kahiki Sports Bar and Restaurant El Restaurante y Sports Bar Kahiki es un popular lugar para el desayuno o el brunch y tambi\u00e9n como bar durante la noche. El restaurante ofrece una selecci\u00f3n abundante de la Cuenca del Pac\u00edfico, desde\u2026","rel":"","context":"En \u00ab50309\u00bb","block_context":{"text":"50309","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/50309\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/06\/kahiki-restaurante-costa-rica-logo3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":538,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samurai-fusion\/","url_meta":{"origin":1507,"position":3},"title":"Restaurante Samurai Fusion","author":"Restaurantes Costa Rica","date":"20 diciembre 2012","format":false,"excerpt":"El Restaurante Samurai Fusion, como su nombre lo indica, propone una fusi\u00f3n entre la traidicional comida japonesa y un acento que remite a la gastronom\u00eda de otras culturas; el restaurante est\u00e1 ubicado en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Todo en el Restaurante Samurai es simplemente genial, el ambiente\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/11\/samurai-fusion-restaurante-escazu-costa-rica-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5450,"url":"https:\/\/costaricainfolink.com\/restaurantes\/genki-sushi-deli\/","url_meta":{"origin":1507,"position":4},"title":"Genki Sushi &#038; Deli","author":"Restaurantes Costa Rica","date":"27 febrero 2017","format":false,"excerpt":"Tel\u00e9fono: +506 2228-1710 Horario: Todos los d\u00edas de 11:45am a 9pm. Direcci\u00f3n Avenida Escaz\u00fa, en el Edificio Nova Repretel en el \u00e1rea Food Court, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Servicio Express y Catering Service De Lunes a S\u00e1bados de 11:45 am\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Genki Sushi & Deli Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/genki-sushi-deli-costa-rica-logo-sm.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/genki-sushi-deli-costa-rica-logo-sm.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/genki-sushi-deli-costa-rica-logo-sm.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/genki-sushi-deli-costa-rica-logo-sm.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":683,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-ichiban\/","url_meta":{"origin":1507,"position":5},"title":"Restaurante Ichiban","author":"Restaurantes Costa Rica","date":"27 mayo 2011","format":false,"excerpt":"NEGOCIO CERRADO Click the following link to read this page in English: Ichiban Restaurant El sushi se ha catalogado como una de las comidas m\u00e1s saludables del siglo, recorriendo con gran \u00e9xito infinidad de pa\u00edses, desde Oriente hasta Occidente. Es por esto que para el Restaurante de comida japonesa Ichiban,\u2026","rel":"","context":"En \u00abAsi\u00e1tico\u00bb","block_context":{"text":"Asi\u00e1tico","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-tipo-de-comida\/asiatico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=1507"}],"version-history":[{"count":50,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1507\/revisions"}],"predecessor-version":[{"id":8260,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1507\/revisions\/8260"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=1507"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=1507"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=1507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}