{"id":1604,"date":"2012-07-31T15:54:31","date_gmt":"2012-07-31T20:54:31","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=1604"},"modified":"2020-01-06T06:25:21","modified_gmt":"2020-01-06T11:25:21","slug":"restaurante-la-estancia","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/","title":{"rendered":"Restaurante La Estancia"},"content":{"rendered":"<h3>Click the following link to read this page in English: <a href=\"https:\/\/costaricainfolink.com\/restaurants\/la-estancia-restaurant\/\">La Estancia Restaurant<\/a><\/h3>\n<p><strong>Horario:<\/strong><\/p>\n<p>De Lunes a S\u00e1bados de 11:30 a.m. a 3 p.m.<br \/>\nDomingos Cerrado<\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong> 200 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701<br \/>\n<strong>Coordenadas para GPS<\/strong>: 9.979563,-84.184266 (9\u00b058&#8217;46.99&#8243;N, 84\u00b011&#8217;00.57&#8243;W)<br \/>\n<strong>Tel\u00e9fono:<\/strong> <a href=\"tel:+50622936867\">+506 2293-6867<\/a><\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-la-estancia\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante La Estancia San Antonio de Bel\u00e9n, Heredia, Costa Rica.<\/a><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restauranteswp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1688\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/la-estancia-restaurante-belen-costa-rica-logo-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&amp;ssl=1\" data-orig-size=\"300,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante La Estancia en San Antonio de Bel\u00e9n, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&amp;ssl=1\" class=\"aligncenter  wp-image-1688\" title=\"Restaurante La Estancia en San Antonio de Bel\u00e9n, Heredia, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?resize=270%2C140&#038;ssl=1\" alt=\"\" width=\"270\" height=\"140\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?resize=150%2C78&amp;ssl=1 150w\" sizes=\"auto, (max-width: 270px) 100vw, 270px\" \/><\/a><\/p>\n<p>El restaurante La Estancia, ubicado en San Antonio de Bel\u00e9n, Heredia, abri\u00f3 sus puertas en abril del a\u00f1o 2008 gracias al sue\u00f1o de don Miguel Barahona y su esposa Isabel S\u00e1nchez, de tener un restaurante con el fin de transmitir y no dejar perder el aut\u00e9ntico sabor peruano.<\/p>\n<p>El restaurante La Estancia se especializa en la cocina tradicional de Per\u00fa, y busca resaltar con sus creativas mezclas de ingredientes y sabores, dando como resultado una comida exquisita y variada que concentra ese sabor caracter\u00edsitico peruano de casa. Dentro de su men\u00fa, se destacan las diferentes variaciones del exquisito arroz chaufa, ya sea de pollo, carne o mariscos; as\u00ed como los tradicionales ceviches, papa a la huanca\u00edna, lomo saltado y aj\u00ed de gallina, entre otros, sin dejar de lado sus espectaculares postres, donde no pod\u00eda faltar el Suspiro Lime\u00f1o. Adem\u00e1s, a partir de este 15 de agosto, se incluir\u00e1 en el men\u00fa de los domingos una aut\u00e9ntica Parrillada Peruana con anticuchos, papa a la huanca\u00edna, salchich\u00f3n, pollo, chorizo, costilla de cerdo y carne, todo macerado al estilo peruano.<\/p>\n<p>En la comida peruana se encuentran al menos 5.000 a\u00f1os de historia Preinca, Inca, Colonial y Republicana. Ademas, como particularidad exclusiva de la gastronom\u00eda de Per\u00fa, existen comidas y sabores de cuatro continentes en un solo pa\u00eds, ya que se consideran casi tres siglos de aporte culinario Espa\u00f1ol, asi como las costumbres gastron\u00f3micas tra\u00eddas por esclavos de la costa Atl\u00e1ntica Africana y la fuerte influencia de los Chefs Franceses que huyeron de la revoluci\u00f3n en su pa\u00eds para radicarse, en buen n\u00famero, en la capital del virreinato del Per\u00fa. Igualmente trascendental es la influencia de los chinos-cantoneses, japoneses, italianos y otros europeos que emigraron a Per\u00fa desde el siglo XIX.<\/p>\n<p>El restaurante La Estancia es la aut\u00e9ntica cocina peruana casera, hecha con mucho amor!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: La Estancia Restaurant Horario: De Lunes a S\u00e1bados de 11:30 a.m. a 3 p.m. Domingos Cerrado Ubicaci\u00f3n: 200 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.979563,-84.184266 (9\u00b058&#8217;46.99&#8243;N, 84\u00b011&#8217;00.57&#8243;W) Tel\u00e9fono: +506 2293-6867 Mapa &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante La Estancia\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#more-1604\" aria-label=\"Leer m\u00e1s sobre Restaurante La Estancia\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[90,52,3,35],"tags":[],"class_list":["post-1604","post","type-post","status-publish","format-standard","hentry","category-90","category-belen","category-heredia","category-peruano","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante La Estancia - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante La Estancia - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Click the following link to read this page in English: La Estancia Restaurant Horario: De Lunes a S\u00e1bados de 11:30 a.m. a 3 p.m. Domingos Cerrado Ubicaci\u00f3n: 200 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.979563,-84.184266 (9\u00b058&#8217;46.99&#8243;N, 84\u00b011&#8217;00.57&#8243;W) Tel\u00e9fono: +506 2293-6867 Mapa ... Ver Restaurante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2012-07-31T20:54:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-06T11:25:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante La Estancia\",\"datePublished\":\"2012-07-31T20:54:31+00:00\",\"dateModified\":\"2020-01-06T11:25:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/\"},\"wordCount\":415,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/la-estancia-restaurante-belen-costa-rica-logo1.jpg\",\"articleSection\":[\"40701\",\"Bel\u00e9n\",\"Heredia\",\"Peruano\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/\",\"name\":\"Restaurante La Estancia - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/la-estancia-restaurante-belen-costa-rica-logo1.jpg\",\"datePublished\":\"2012-07-31T20:54:31+00:00\",\"dateModified\":\"2020-01-06T11:25:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2012\\\/07\\\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&ssl=1\",\"width\":\"300\",\"height\":\"156\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-la-estancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante La Estancia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante La Estancia - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante La Estancia - Restaurantes Costa Rica","og_description":"Click the following link to read this page in English: La Estancia Restaurant Horario: De Lunes a S\u00e1bados de 11:30 a.m. a 3 p.m. Domingos Cerrado Ubicaci\u00f3n: 200 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.979563,-84.184266 (9\u00b058&#8217;46.99&#8243;N, 84\u00b011&#8217;00.57&#8243;W) Tel\u00e9fono: +506 2293-6867 Mapa ... Ver Restaurante","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2012-07-31T20:54:31+00:00","article_modified_time":"2020-01-06T11:25:21+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante La Estancia","datePublished":"2012-07-31T20:54:31+00:00","dateModified":"2020-01-06T11:25:21+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/"},"wordCount":415,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg","articleSection":["40701","Bel\u00e9n","Heredia","Peruano"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/","name":"Restaurante La Estancia - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg","datePublished":"2012-07-31T20:54:31+00:00","dateModified":"2020-01-06T11:25:21+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/la-estancia-restaurante-belen-costa-rica-logo1.jpg?fit=300%2C156&ssl=1","width":"300","height":"156"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-la-estancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante La Estancia"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-pS","jetpack-related-posts":[{"id":4589,"url":"https:\/\/costaricainfolink.com\/restaurantes\/soda-gallito-pinto-en-belen-heredia\/","url_meta":{"origin":1604,"position":0},"title":"Soda Gallito Pinto en Bel\u00e9n, Heredia","author":"Restaurantes Costa Rica","date":"18 julio 2016","format":false,"excerpt":"Tel\u00e9fono: +506 2293-8965 Horario: Lunes a Viernes: 5am a 5pm S\u00e1bados: 5am 12md Direcci\u00f3n: Contiguo a Estaci\u00f3n de Combustible SHEYZA Provincia: Heredia, cant\u00f3n: Bel\u00e9n, distrito: San Antonio. C\u00f3digo Postal de la Zona: 40701 Men\u00fa\u00a0Soda Gallito Pinto Desayunos Pinto con: Huevos a su gusto, natilla Carne en salsa, Pollo en salsa,\u2026","rel":"","context":"En \u00ab40701\u00bb","block_context":{"text":"40701","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40701\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/07\/desayuno-gallo-pinto-carne-salsa-platanos-maduros-huevos-fritos-costaricainfolink-300x225.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1940,"url":"https:\/\/costaricainfolink.com\/restaurantes\/pollos-raymi\/","url_meta":{"origin":1604,"position":1},"title":"Pollos RAYMI","author":"Restaurantes Costa Rica","date":"17 septiembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: 150 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.979734,-84.183383 (9\u00b058'47.04\"N, 84\u00b011'00.18\"W) Servicio a domicilio a todo Bel\u00e9n (express)\u00a0\u20a1800 Tel\u00e9fono: +506 2239-2725 +506 4030-5777 Horario: todos los dias de 11 a.m. a 10 p.m. Men\u00fa Mapa con\u2026","rel":"","context":"En \u00ab40701\u00bb","block_context":{"text":"40701","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40701\/"},"img":{"alt_text":"Restaurante Pollos RAYMI en Bel\u00e9n, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/pollos-raymi-heredia-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2491,"url":"https:\/\/costaricainfolink.com\/restaurantes\/pizza-mym\/","url_meta":{"origin":1604,"position":2},"title":"Restaurante Pizza MYM","author":"Restaurantes Costa Rica","date":"20 septiembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: 350 oeste del supermercado Mas por Menos de Bel\u00e9n, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.980054,-84.181871 (9\u00b058'48.19\"N, 84\u00b010'54.73\"W) Tel\u00e9fono: +506 2293-0404 SERVICIO EXPRESS ( a domicilio ) Horario: todos los dias de 11:30 a.m. a 10 p.m. Mapa con direcci\u00f3n:\u2026","rel":"","context":"En \u00ab40701\u00bb","block_context":{"text":"40701","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40701\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/09\/pizza-mym-belen-heredia-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/09\/pizza-mym-belen-heredia-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/09\/pizza-mym-belen-heredia-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":3800,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-la-deportiva-charlies-bar\/","url_meta":{"origin":1604,"position":3},"title":"Restaurante La Deportiva Charlie&#8217;s Bar","author":"Restaurantes Costa Rica","date":"21 julio 2014","format":false,"excerpt":"Ubicaci\u00f3n: costado Este de la Plaza de Deportes de La Asunci\u00f3n de Bel\u00e9n, distrito: Asunci\u00f3n, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40703. Coordenadas para GPS: 9.979901,-84.169774 (9\u00b058'47.64\"N, 84\u00b010'11.18\"W) Tel\u00e9fono: +506 2293-6567 Horario: todos los d\u00edas de 11 a.m. a 12 a.m. Haga click en el\u2026","rel":"","context":"En \u00ab40703\u00bb","block_context":{"text":"40703","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40703\/"},"img":{"alt_text":"Restaurante La Deportiva Charlie's Bar en Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/07\/la-deportiva-charlies-bar-belen-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":683,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-ichiban\/","url_meta":{"origin":1604,"position":4},"title":"Restaurante Ichiban","author":"Restaurantes Costa Rica","date":"27 mayo 2011","format":false,"excerpt":"NEGOCIO CERRADO Click the following link to read this page in English: Ichiban Restaurant El sushi se ha catalogado como una de las comidas m\u00e1s saludables del siglo, recorriendo con gran \u00e9xito infinidad de pa\u00edses, desde Oriente hasta Occidente. Es por esto que para el Restaurante de comida japonesa Ichiban,\u2026","rel":"","context":"En \u00abAsi\u00e1tico\u00bb","block_context":{"text":"Asi\u00e1tico","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-tipo-de-comida\/asiatico\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/02\/ichiban-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":1374,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-y-cafeteria-apetito\/","url_meta":{"origin":1604,"position":5},"title":"Restaurante y Cafeter\u00eda Apetito","author":"Restaurantes Costa Rica","date":"20 junio 2012","format":false,"excerpt":"NEGOCIO CERRADO Click here to view this page in English Cafeter\u00eda Apetito, es un nuevo concepto de Cafeter\u00eda-Restaurante con mucho que ofrecer, donde todo es simplemente delicioso, est\u00e1 ubicado en el Centro Comercial La Ribera en Bel\u00e9n, a s\u00f3lo 5 minutos del Aeropuerto Internacional Juan Santamar\u00eda. Cafeter\u00eda Apetito ofrece desayunos,\u2026","rel":"","context":"En \u00ab40702\u00bb","block_context":{"text":"40702","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40702\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/06\/apetito-cafeteria-heredia-costa-rica006.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=1604"}],"version-history":[{"count":22,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1604\/revisions"}],"predecessor-version":[{"id":8457,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/1604\/revisions\/8457"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=1604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=1604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}