{"id":363,"date":"2010-07-28T10:29:55","date_gmt":"2010-07-28T15:29:55","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=363"},"modified":"2016-03-06T07:36:40","modified_gmt":"2016-03-06T12:36:40","slug":"restaurante-asiatico-bar-grill-gan-bei","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/","title":{"rendered":"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei"},"content":{"rendered":"<h1>NEGOCIO CERRADO<\/h1>\n<h3>Click the following link to read this page in English: <a href=\"https:\/\/costaricainfolink.com\/restaurants\/gan-bei-asian-restaurant-bar-grill\/\">Gan-Bei Asian Restaurant, Bar &amp; Grill<\/a><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"368\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/restaurante-gan-bei-costa-rica-logo2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&amp;ssl=1\" data-orig-size=\"414,152\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante Asiatico, Bar y Grill Gan-Bei en Santa Ana, San Jose, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&amp;ssl=1\" class=\"aligncenter wp-image-368\" title=\"Restaurante Asi\u00e1tico, Bar y Grill Gan-Bei en Santa Ana, San Jose, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?resize=290%2C106&#038;ssl=1\" alt=\"\" width=\"290\" height=\"106\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?w=414&amp;ssl=1 414w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?resize=300%2C110&amp;ssl=1 300w\" sizes=\"auto, (max-width: 290px) 100vw, 290px\" \/><\/p>\n<p>Gan-Bei, que significa \u00a1Salud!, es la nueva propuesta de comida asi\u00e1tica, con platillos de China, Tailandia, Vietnam, Corea y Jap\u00f3n, entre otros, que sin duda cautivar\u00e1 su paladar.<\/p>\n<table border=\"0\" width=\"530\" cellspacing=\"0\" cellpadding=\"0\" align=\"right\">\n<tbody>\n<tr>\n<td>[portfolio_slideshow id=2208]<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>El Chef Ejecutivo Edward Florian, experimentado en diversas culturas culinarias, hace realidad su verdadera pasi\u00f3n en Gan-Bei, con una cocina aut\u00f3ctona y contempor\u00e1nea a la vez, incorpor\u00e1ndole su expresi\u00f3n gastron\u00f3mica de primera calidad.<\/p>\n<p>Viaje por Asia con sus deliciosos platillos, desde un tradicional Pollo Kung Pao de China, un Pho Ga de Vietnam, un Curry Ind\u00fa, unos Fideos de Singapur, hasta una Berenjena a la Parrilla al mejor estilo Tailand\u00e9s. Adem\u00e1s, descubra el singular men\u00fa de t\u00e9 asi\u00e1tico del Restaurante Gan-Bei, con m\u00e1s de 20 combinaciones, as\u00ed como variados postres y helados de la casa.<\/p>\n<p>Gan-Bei Asian Bar and Grill, tiene un ambiente para cada personalidad, todos con una agradable atm\u00f3sfera y un excelente servicio. En la primera planta, disfrute del restaurante, con su entorno c\u00e1lido y elegante, con toda la esencia oriental, mientras que en el segundo piso, podr\u00e1 encontrar un ambiente m\u00e1s relajado, con pantallas gigantes y sof\u00e1s para tomarse su bebida favorita con amigos o familiares, acompa\u00f1ado de la gran variedad de platillos o bocas orientales. Adem\u00e1s el Restaurante Asi\u00e1tico Gan-Bei cuenta con el Koi Room, una sala de reuniones privada, con vista hacia una pescera en un jard\u00edn asi\u00e1tico, con total privacidad para manejar su evento empresarial, su cena ejecutiva para hacer una presentaci\u00f3n, o disfrutar de un partido.<\/p>\n<p>Disfrute adem\u00e1s de los eventos especiales, y men\u00fas ejecutivos, que ofrece el Restaurante Gan-Bei, una opci\u00f3n saludable y variada para los profesionales de la zona.<\/p>\n<p><strong>Horario:<\/strong><br \/>\nDe Lunes a Mi\u00e9rcoles de 11:30 a.m. a 10:00 p.m.<br \/>\nDe Jueves a S\u00e1bados de 11:30 a.m. a 2:00 a.m.<br \/>\nDomingos de 11:30 a.m. a 10:00 p.m.<\/p>\n<p><strong>Ubicaci\u00f3n:<\/strong>Centro Comercial Momentum en Lindora, distrito: Pozos, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10903.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.953181,-84.194744 (9\u00b057&#8217;11.45&#8243;N, 84\u00b011&#8217;41.08&#8243;O)<br \/>\n<strong>Tel\u00e9fono: <\/strong>+506 2203-2323<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-asiatico-gan-bei\/\">Haga click aqu\u00ed para ver la direcci\u00f3n desde el Parque La Sabana, San Jos\u00e9, Costa Rica al Restaurante Asi\u00e1tico Gan-Bei, San Jos\u00e9, Costa Rica.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NEGOCIO CERRADO Click the following link to read this page in English: Gan-Bei Asian Restaurant, Bar &amp; Grill Gan-Bei, que significa \u00a1Salud!, es la nueva propuesta de comida asi\u00e1tica, con platillos de China, Tailandia, Vietnam, Corea y Jap\u00f3n, entre otros, que sin duda cautivar\u00e1 su paladar. [portfolio_slideshow id=2208] El Chef Ejecutivo Edward Florian, experimentado en &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#more-363\" aria-label=\"Leer m\u00e1s sobre Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[84,34,26,27],"tags":[],"class_list":["post-363","post","type-post","status-publish","format-standard","hentry","category-84","category-asiatico","category-san-jose","category-santa-ana","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Asi\u00e1tico, Bar &amp; Grill Gan-Bei - Restaurantes Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Asi\u00e1tico, Bar &amp; Grill Gan-Bei - Restaurantes Costa Rica\" \/>\n<meta property=\"og:description\" content=\"NEGOCIO CERRADO Click the following link to read this page in English: Gan-Bei Asian Restaurant, Bar &amp; Grill Gan-Bei, que significa \u00a1Salud!, es la nueva propuesta de comida asi\u00e1tica, con platillos de China, Tailandia, Vietnam, Corea y Jap\u00f3n, entre otros, que sin duda cautivar\u00e1 su paladar. [portfolio_slideshow id=2208] El Chef Ejecutivo Edward Florian, experimentado en ... Ver Restaurante\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2010-07-28T15:29:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-06T12:36:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei\",\"datePublished\":\"2010-07-28T15:29:55+00:00\",\"dateModified\":\"2016-03-06T12:36:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/\"},\"wordCount\":410,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/restaurante-gan-bei-costa-rica-logo2.jpg\",\"articleSection\":[\"10903\",\"Asi\u00e1tico\",\"San Jos\u00e9\",\"Santa Ana\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/\",\"name\":\"Restaurante Asi\u00e1tico, Bar & Grill Gan-Bei - Restaurantes Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/restaurante-gan-bei-costa-rica-logo2.jpg\",\"datePublished\":\"2010-07-28T15:29:55+00:00\",\"dateModified\":\"2016-03-06T12:36:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2010\\\/07\\\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&ssl=1\",\"width\":\"414\",\"height\":\"152\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/restaurante-asiatico-bar-grill-gan-bei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Asi\u00e1tico, Bar & Grill Gan-Bei - Restaurantes Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Asi\u00e1tico, Bar & Grill Gan-Bei - Restaurantes Costa Rica","og_description":"NEGOCIO CERRADO Click the following link to read this page in English: Gan-Bei Asian Restaurant, Bar &amp; Grill Gan-Bei, que significa \u00a1Salud!, es la nueva propuesta de comida asi\u00e1tica, con platillos de China, Tailandia, Vietnam, Corea y Jap\u00f3n, entre otros, que sin duda cautivar\u00e1 su paladar. [portfolio_slideshow id=2208] El Chef Ejecutivo Edward Florian, experimentado en ... Ver Restaurante","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2010-07-28T15:29:55+00:00","article_modified_time":"2016-03-06T12:36:40+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei","datePublished":"2010-07-28T15:29:55+00:00","dateModified":"2016-03-06T12:36:40+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/"},"wordCount":410,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg","articleSection":["10903","Asi\u00e1tico","San Jos\u00e9","Santa Ana"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/","name":"Restaurante Asi\u00e1tico, Bar & Grill Gan-Bei - Restaurantes Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg","datePublished":"2010-07-28T15:29:55+00:00","dateModified":"2016-03-06T12:36:40+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/restaurante-gan-bei-costa-rica-logo2.jpg?fit=414%2C152&ssl=1","width":"414","height":"152"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-asiatico-bar-grill-gan-bei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Asi\u00e1tico, Bar &#038; Grill Gan-Bei"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-5R","jetpack-related-posts":[{"id":5383,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","url_meta":{"origin":363,"position":0},"title":"Bambuddha Restaurante y Bar Lounge","author":"Restaurantes Costa Rica","date":"19 febrero 2017","format":false,"excerpt":"Tel\u00e9fono: +506 4700-6821 Horario: De Domingo a Martes de 11am a 11pm. De Mi\u00e9rcoles a S\u00e1bados de 11am a 3 am. Direcci\u00f3n City Place, segundo piso locales 34 y 35, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. Bambuddha Restaurante & Bar es\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Bambuddha Restaurante y Bar Lounge Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":6314,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-la-muny\/","url_meta":{"origin":363,"position":1},"title":"La Muny Restaurante y Bar","author":"Restaurantes Costa Rica","date":"16 febrero 2018","format":false,"excerpt":"Tel\u00e9fono +506 2233-0279 Horario: Lunes, Martes, Mi\u00e9rcoles y Jueves de 9am a 11pm. Viernes de 9am a 12mn. S\u00e1bados de 10am a 11pm. Domingo de 10am a 6pm. Direcci\u00f3n: Sobre avenida 10, 300 metros este de la Municipalidad de San Jos\u00e9. Distrito: Hospital, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9. C\u00f3digo\u2026","rel":"","context":"En \u00ab10103\u00bb","block_context":{"text":"10103","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10103\/"},"img":{"alt_text":"La Muny ( Muni ) Bar y Restaurante San Jos\u00e9 Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/02\/la-muny-muni-bar-restaurante-san-jose-costa-rica-300x276.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1811,"url":"https:\/\/costaricainfolink.com\/restaurantes\/outback-jacks-australian-roadkill-grill\/","url_meta":{"origin":363,"position":2},"title":"Restaurante Outback Jacks Australian Roadkill Grill","author":"Restaurantes Costa Rica","date":"6 septiembre 2012","format":false,"excerpt":"Click the following link to read this page in English: Outback Jack's Restaurant El Restaurante y Bar de playa Outback Jacks Costa Rica, naci\u00f3 gracias al sue\u00f1o de \"Outback Jack\", un peregrino que andaba de paseo (walkabout) alrededor del mundo, creando una tormenta de sabores con su comida australiana, cuando\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":8755,"url":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","url_meta":{"origin":363,"position":3},"title":"Invictus Restaurant &#038; Sports Bar","author":"Restaurantes Costa Rica","date":"14 octubre 2020","format":false,"excerpt":"Tel\u00e9fono: +506 40015287 WhatsApp: 6362-0197 Direcci\u00f3n: Ruta 121, 90 metros noroeste del centro comercial paco, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. \u00a0\u00a0 Desayuno, Almuerzo, After office Sports, reuniones, cena. Horario: De Lunes a Viernes de 11am a 10pm. S\u00e1bados y\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Invictus Restaurant & Sports Bar San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Telefono, horario, menu, direccion, ubicacion WAZE y mapas de Google","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":169,"url":"https:\/\/costaricainfolink.com\/restaurantes\/los-tiroleses\/","url_meta":{"origin":363,"position":4},"title":"Restaurante &#038; Bar Los Tiroleses","author":"Restaurantes Costa Rica","date":"14 enero 2010","format":false,"excerpt":"Ubicaci\u00f3n: Hotel Chalet El Tirol, distrito: \u00c1ngeles, cant\u00f3n: San Rafael, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40504. Tel\u00e9fono: +506 2267-6222 Fax: +506 2267-6373 Coordenadas para GPS: 10.074817,-84.086128 (10\u00b004'29.34\"N, 84\u00b005'10.06\"W) Click aqu\u00ed para ver el Men\u00fa Mapa con la direcci\u00f3n: Haga click aqu\u00ed para ver la direcci\u00f3n al\u2026","rel":"","context":"En \u00ab40504\u00bb","block_context":{"text":"40504","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40504\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/01\/restaurante-el-tirol-costa-rica-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5036,"url":"https:\/\/costaricainfolink.com\/restaurantes\/fenix-dorado\/","url_meta":{"origin":363,"position":5},"title":"F\u00e9nix Dorado","author":"Restaurantes Costa Rica","date":"17 diciembre 2016","format":false,"excerpt":"Ubicaci\u00f3n: centro comercial Los Andres, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. T\u00e9lefonos: +506 2282-4189\u00a0+506 2282-42833 Horario: Todos los d\u00edas de 11am a 12pm. MEN\u00da Entradas \/ Appetizer \u00b7 Ensalada \/ Salad \u00b7 Sopas \/ Soups \u00b7 Especial De Arroz \/ Rice\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Ubicaci\u00f3n WAZE de Restaurante F\u00e9nix Dorado, Santa Ana, San Jose, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=363"}],"version-history":[{"count":26,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/363\/revisions"}],"predecessor-version":[{"id":4327,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/363\/revisions\/4327"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}