{"id":4132,"date":"2016-02-11T13:12:34","date_gmt":"2016-02-11T18:12:34","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=4132"},"modified":"2017-08-09T11:44:23","modified_gmt":"2017-08-09T16:44:23","slug":"el-rincon-casero","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","title":{"rendered":"Restaurante El Rinc\u00f3n Casero"},"content":{"rendered":"<h1 style=\"text-align: center;\">CERRADO<\/h1>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4134\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/restaurante-rincon-casero-costa-rica-logo\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&amp;ssl=1\" data-orig-size=\"300,300\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"restaurante-rincon-casero-costa-rica-logo\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&amp;ssl=1\" class=\"aligncenter wp-image-4134\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?resize=250%2C250&#038;ssl=1\" alt=\"Restaurante El Rinc\u00f3n Casero en Santa Ana, San Jos\u00e9, Costa Rica\" width=\"250\" height=\"250\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/p>\n<p>El Restaurante El Rinc\u00f3n Casero es una peque\u00f1a e innovadora soda, que goza de un ambiente tranquilo, ubicada en Santa Ana centro, operada en sus inicios familiarmente desde Octubre del 2011 por dos hermanos y su padre.<\/p>\n<table border=\"0\" width=\"502\" cellspacing=\"0\" cellpadding=\"0\" align=\"right\">\n<tbody>\n<tr>\n<td>[portfolio_slideshow id=4161]<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>El Rinc\u00f3n Casero y su men\u00fa, ha sido dise\u00f1ado pensando en la satisfacci\u00f3n de sus clientes, seleccionando cuidadosamente los productos que se usan en su cocina, pues saben que la calidad se ver\u00e1 reflejada en cada uno de sus platillos. Su propuesta es comida hecha como en casa, a lo tico, con la misma atenci\u00f3n, calidad y cuidado que se le pone a la comida hecha en nuestros hogares, incluyendo desde los famosos \u00abCasados\u00bb, sopas, arroz con pollo, empanadas, deliciosos desayunos completos con Gallo Pinto, carne en salsa, platanitos maduros y m\u00e1s, hasta hamburguesas, tacos, camarones empanizados, pasta alfredo, filet mignon, etc., con el fin de tener una amplia y adecuada selecci\u00f3n para sus comensales.<\/p>\n<p>Un men\u00fa completo a precios muy moderados, permite a sus clientes disfrutar de una rica comida en la cual disfrutar\u00e1 de una verdadera y completa experiencia gastron\u00f3mica costarricense.<\/p>\n<p>Su excelente ubicaci\u00f3n y caracter\u00edsticas lo convierten en un lugar ideal para compartir con compa\u00f1eros de trabajo, amigos y familiares, mientras se disfruta de una buena comida en un lugar de tranquilo, y ante todo, un lugar acogedor. Adem\u00e1s, El Rinc\u00f3n Casero tambi\u00e9n ofrece servicio a domicilio, para los que no quieran salir de su casa u oficina, pero quieran disfrutar de una buena comida.<\/p>\n<p>!Los invitamos a probar comida tica en Santa Ana con sabor a casita!<\/p>\n<p><strong>Direcci\u00f3n:<\/strong> 400 m Este de la Cruz Roja de Santa Ana, frente al S\u00faper El Roble, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10901.<br \/>\n<strong>Coordenadas para GPS:<\/strong> 9.931483, -84.184151 (N 9\u00b055.889, W 84\u00b011.049)<br \/>\n<strong>Tel\u00e9fono:<\/strong> <a href=\"callto:+5062282-8256\">+506 2282-8256<\/a><br \/>\n<strong>Horario:<\/strong> de Lunes a S\u00e1bados de 8 a.m. a 3 p.m.<\/p>\n<p><strong>Mapa con direcci\u00f3n:<\/strong> <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-al-restaurante-el-rincon-casero\/\">Haga click aqu\u00ed para ver la direcci\u00f3n al Restaurante y Soda El Rinc\u00f3n Casero en Santa Ana, San Jos\u00e9, Costa Rica.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CERRADO El Restaurante El Rinc\u00f3n Casero es una peque\u00f1a e innovadora soda, que goza de un ambiente tranquilo, ubicada en Santa Ana centro, operada en sus inicios familiarmente desde Octubre del 2011 por dos hermanos y su padre. [portfolio_slideshow id=4161] El Rinc\u00f3n Casero y su men\u00fa, ha sido dise\u00f1ado pensando en la satisfacci\u00f3n de sus &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante El Rinc\u00f3n Casero\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#more-4132\" aria-label=\"Leer m\u00e1s sobre Restaurante El Rinc\u00f3n Casero\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13,26,27,146,6],"tags":[],"class_list":["post-4132","post","type-post","status-publish","format-standard","hentry","category-internacional","category-san-jose","category-santa-ana","category-soda","category-tipica-costarricense","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante El Rinc\u00f3n Casero Costa Rica<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante El Rinc\u00f3n Casero Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-11T18:12:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-09T16:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante El Rinc\u00f3n Casero\",\"datePublished\":\"2016-02-11T18:12:34+00:00\",\"dateModified\":\"2017-08-09T16:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/\"},\"wordCount\":364,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/restaurante-rincon-casero-costa-rica-logo.jpg\",\"articleSection\":[\"Internacional\",\"San Jos\u00e9\",\"Santa Ana\",\"Soda\",\"T\u00edpica Costarricense\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/\",\"name\":\"Restaurante El Rinc\u00f3n Casero Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/restaurante-rincon-casero-costa-rica-logo.jpg\",\"datePublished\":\"2016-02-11T18:12:34+00:00\",\"dateModified\":\"2017-08-09T16:44:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2015\\\/11\\\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&ssl=1\",\"width\":300,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-rincon-casero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante El Rinc\u00f3n Casero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante El Rinc\u00f3n Casero Costa Rica","description":"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante El Rinc\u00f3n Casero Costa Rica","og_description":"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2016-02-11T18:12:34+00:00","article_modified_time":"2017-08-09T16:44:23+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante El Rinc\u00f3n Casero","datePublished":"2016-02-11T18:12:34+00:00","dateModified":"2017-08-09T16:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/"},"wordCount":364,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg","articleSection":["Internacional","San Jos\u00e9","Santa Ana","Soda","T\u00edpica Costarricense"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","name":"Restaurante El Rinc\u00f3n Casero Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg","datePublished":"2016-02-11T18:12:34+00:00","dateModified":"2017-08-09T16:44:23+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Informaci\u00f3n del Restaurante El Rinc\u00f3n Casero Costa Rica en Santa Ana: ubicaci\u00f3n, horario, tel\u00e9fono, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?fit=300%2C300&ssl=1","width":300,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante El Rinc\u00f3n Casero"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-14E","jetpack-related-posts":[{"id":5521,"url":"https:\/\/costaricainfolink.com\/restaurantes\/picnic\/","url_meta":{"origin":4132,"position":0},"title":"PICNIC","author":"Restaurantes Costa Rica","date":"26 marzo 2017","format":false,"excerpt":"Direcci\u00f3n: Plaza Futura, local #2. Distrito: Pozos, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10903. Tel\u00e9fono: +506 4033-4111 Horario: De Martes a Viernes de 7am a 7pm. S\u00e1bados y Domingos de 8am a 5pm. Lunes cerrado. Correo Electr\u00f3nico: MEN\u00da BATIDOS VITAMIX\u00a0\u20a12400 naranja, pi\u00f1a y albahaca. FRES-CO\u00a0\u20a12400\u2026","rel":"","context":"En \u00ab10903\u00bb","block_context":{"text":"10903","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10903\/"},"img":{"alt_text":"Restaurante PICNIC en Pozos, Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/03\/restaurante-picnic-pozos-santa-ana-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10661,"url":"https:\/\/costaricainfolink.com\/restaurantes\/pollos-salitral-soda-la-esquina\/","url_meta":{"origin":4132,"position":1},"title":"Pollos Salitral Soda La Esquina","author":"Restaurantes Costa Rica","date":"27 mayo 2022","format":false,"excerpt":"DIRECCI\u00d3N De la bomba hermanos montes 3 kil\u00f3metros al sur. Tambi\u00e9n puede ser de la iglesia de Salitral 500 metros al sur. Distrito: Salitral, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10902. \u00a0\u00a0 HORARIO De Lunes a Jueves de 11am a 10pm. Fin de\u2026","rel":"","context":"En \u00abEscaz\u00fa\u00bb","block_context":{"text":"Escaz\u00fa","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/san-jose\/escazu\/"},"img":{"alt_text":"Pollos Salitral Restaurante La Esquina, Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/05\/pollos-salitral-soda-la-esquina-santa-ana-san-jose-costa-rica-restaurante-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":81,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","url_meta":{"origin":4132,"position":2},"title":"Restaurante La Paila Casera","author":"Restaurantes Costa Rica","date":"25 mayo 2009","format":false,"excerpt":"Click the following link to read this page in English: La Paila Casera Restaurant Restaurante de comida caribe\u00f1a, ubicado en Puerto Viejo de Talamanca en la Costa del Caribe, directamente en Punta Uva, Lim\u00f3n, Costa Rica. Cuenta con parqueo, excelente servicio y rapidez. Tel\u00e9fono: +506 2759-9047 Coordenadas para GPS:9.637281,-82.691414 (9\u00b038'14.21\"N,\u2026","rel":"","context":"En \u00abCaribe\u00f1a\u00bb","block_context":{"text":"Caribe\u00f1a","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-tipo-de-comida\/caribena\/"},"img":{"alt_text":"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":342,"url":"https:\/\/costaricainfolink.com\/restaurantes\/doris-metropolitan\/","url_meta":{"origin":4132,"position":3},"title":"Restaurante Doris Metropolitan Santa Ana, Costa Rica","author":"Restaurantes Costa Rica","date":"19 agosto 2010","format":false,"excerpt":"Ubicaci\u00f3n: Costado Noreste de la Iglesia de Piedra de Santa Ana Centro, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10901. Coordenadas para GPS: 9.933189,-84.180053 (9\u00b055'59.48\"N, 84\u00b010'48.19\"W) Horario: todos los d\u00edas de 12 p.m. a 11 p.m. Tel\u00e9fono: +506 2282-2221 Men\u00fa Mapa\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Ravioli - Restaurante Doris Metropolitan Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/08\/ravioli-restaurante-doris-metropolitan-costa-rica.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10380,"url":"https:\/\/costaricainfolink.com\/restaurantes\/banana-beach\/","url_meta":{"origin":4132,"position":4},"title":"Banana Beach","author":"Restaurantes Costa Rica","date":"9 noviembre 2021","format":false,"excerpt":"Tel\u00e9fono: +506 2640 1117 Horario: De Lunes a Viernes de 7:30 am a 10pm. S\u00e1bados y Domingos de 7:30 am a 9pm. Direcci\u00f3n: 1km norte del cruce de Santa Teresa, distrito: C\u00f3bano, cant\u00f3n: Puntarenas, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 60111. \u00a0\u00a0 MENU Bebidas \u00b7 Entradas \u00b7\u2026","rel":"","context":"En \u00ab60111\u00bb","block_context":{"text":"60111","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/60111\/"},"img":{"alt_text":"Restaurante Banana Beach en Santa Teresa, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/11\/restaurante-banana-beach-santa-teresa-costa-rica-300x119.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10786,"url":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-porteno\/","url_meta":{"origin":4132,"position":5},"title":"El Rinc\u00f3n Porte\u00f1o","author":"Restaurantes Costa Rica","date":"12 octubre 2022","format":false,"excerpt":"Tel\u00e9fono: +506 8397-1348 Horario: Todos los d\u00edas de 7am a 9:30pm. Jueves CERRADO Direcci\u00f3n: Frente a la Entrada del Jaguar Rescue Center Cocles, Lim\u00f3n Province, Costa Rica, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. \u00a0\u00a0 MENU Bebidas \u00b7 Cervezas \u00b7 Cocktails \u00b7 Caf\u00e9\u2026","rel":"","context":"En \u00abCahuita\u00bb","block_context":{"text":"Cahuita","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/limon\/talamanca\/cahuita\/"},"img":{"alt_text":"Restaurante El Rinc\u00f3n Porte\u00f1o en Cocles, Lim\u00f3n","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/10\/el-rincon-porteno-puerto-viejo-limon-costa-rica-logo-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=4132"}],"version-history":[{"count":15,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4132\/revisions"}],"predecessor-version":[{"id":5807,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4132\/revisions\/5807"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=4132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=4132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=4132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}