{"id":4251,"date":"2016-02-28T12:36:25","date_gmt":"2016-02-28T17:36:25","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=4251"},"modified":"2023-02-14T08:02:50","modified_gmt":"2023-02-14T13:02:50","slug":"menu-hooligans-costa-rica","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/","title":{"rendered":"Men\u00fa Hooligans Costa Rica"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4863\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/bar-restaurante-hooligans-costa-rica-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&amp;ssl=1\" data-orig-size=\"622,622\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bar Restaurante Hooligans Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&amp;ssl=1\" class=\"alignright size-medium wp-image-4863\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=300%2C300&#038;ssl=1\" alt=\"Bar Restaurante Hooligans Costa Rica\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=560%2C560&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=260%2C260&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?resize=160%2C160&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?w=622&amp;ssl=1 622w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#menu\">Men\u00fa<\/a><\/h2>\n<p><strong>Multiplaza Escaz\u00fa<\/strong><\/p>\n<p>Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. Codigo postal de la zona: 10203. <strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062201-8261\">+506 2201-8261<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0t46m1\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Multiplaza, San Rafael, Escazu, San Jose, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@9.9446758,-84.1501714,20z\/data=!4m12!1m6!3m5!1s0x8fa0fc9ea8e64ebb:0xfccf800df0a45f58!2sHooligans!8m2!3d9.9348339!4d-84.1274462!3m4!1s0x0:0x4ff07c7b881370b!8m2!3d9.9445955!4d-84.1500136\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Multiplaza, San Rafael, Escazu, San Jose, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Plaza Lincoln<\/strong><\/p>\n<p>Distrito: San Vicente, cant\u00f3n: Moravia, provincia: San Jos\u00e9. Codigo postal de la zona: 11401.<strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+50625199506\">+506 2519-9506<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0xm8wx\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Plaza Lincoln, San Jose, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@9.9629701,-84.0575847,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e45e5ca76299:0x14e2d7226d533d8b!8m2!3d9.9629701!4d-84.055396\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Plaza Lincoln, San Jose, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Paseo de las Flores.<\/strong><\/p>\n<p>Distrito: San Francisco, cant\u00f3n: Heredia, provincia: Heredia. C\u00f3digo postal de la zona: 40103. <strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062262-5757\">+506 2262-5757<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0y19je\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Paseo de las Flores, San Francisco, Heredia, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@9.9846662,-84.1117385,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fad7d0f5165b:0x72d739e039df11ed!8m2!3d9.9846662!4d-84.1095498\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Paseo de las Flores, San Francisco, Heredia, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Trejos Montealegre<\/strong><\/p>\n<p>Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. Codigo postal de la zona: 10203. <strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062289-0908\">+506 2289-0908<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0t8s6b\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Trejos Montealegre, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@9.9348339,-84.1296349,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0fc9ea8e64ebb:0xfccf800df0a45f58!8m2!3d9.9348339!4d-84.1274462\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Trejos Montealegre, San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Plaza Carolina<\/strong><\/p>\n<p>Distrito: Mercedes, cant\u00f3n: Montes de Oca, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 11503.&nbsp;<strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062253-9740\">+506 2253-9740<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0x386n\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Plaza Carolina, Mercedes, Montes de Oca, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@9.9399517,-84.0585744,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e47f0a752689:0x45df00a7ea863f7a!8m2!3d9.9399517!4d-84.0563857\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Plaza Carolina, Mercedes, Montes de Oca, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Multiplaza del Este<\/strong><\/p>\n<p>Distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 11801. <strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062234-0756\">+506 2234-0756<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0rmx8c\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Multiplaza del Este, Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans+Winds+And+Beer+Sports\/@9.9173044,-84.0487545,397m\/data=!3m1!1e3!4m5!3m4!1s0x0:0xcf0885549a6df1a5!8m2!3d9.9169586!4d-84.0474265\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Multiplaza del Este, Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p><strong>Plaza Real<\/strong><br>Distrito: Alajuela, cant\u00f3n: Alajuela, provincia: Alajuela. C\u00f3digo postal de la zona: 20101. <strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062430-4595\">+506 2430-4595<\/a>.&nbsp;<strong>Horario<\/strong>: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0gydsq\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Hooligans Plaza Real, Alajuela, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Hooligans\/@10.0209578,-84.2450917,13z\/data=!4m8!1m2!2m1!1sHooligans,+Alajuela,+Alajuela!3m4!1s0x0:0xeb864eb299574799!8m2!3d10.012045!4d-84.2065144\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Hooligans Plaza Real, Alajuela, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2 id=\"menu\">MEN\u00da<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#appetizers\">Appetizers<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#chips\">Chips<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#platters\">Platters Para Compartir<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#sandwiches\">Sandwiches<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#tacosyquesadillas\">Tacos &amp; Quesadillas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#grilledburgers\">Grilled Burgers<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#wings\">Wings Your Way<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#salsas\">Salsas Para Elegir<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#grilled\">Grilled<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#sopas\">Sopas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#allbeefsuperbowls\">All Beef Super Bowls<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#salads\">Salads<\/a> \u00b7 Veggie: <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#veggiestarters\">Starters<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#vegetariansalads\">Salads<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#vegetarianmain\">Main<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#homemadesweets\">Homemade Sweets<\/a><\/p>\n<h2 id=\"appetizers\">APPETIZERS<\/h2>\n<p>Mientras llegan tus Alitas<\/p>\n<p><strong>Hooligans Onion Rings<\/strong> 6 Aros \u20a13550 12 Aros \u20a15250<br>Nuestros famosos Aros de Cebolla, los rebozamos en una mezcla de harina y especias. Te los servimos doraditos acompa\u00f1ados de aderezo Ranch.<\/p>\n<p><strong>Hoolipapas<\/strong> \u20a13250<\/p>\n<p><strong>Fries &amp; Spicy Queso<\/strong> \u20a12950<\/p>\n<p><strong>Mozzarellas<\/strong> 3 unds \u20a13250 5 unds \u20a15450<br>Doraditas barras de queso Mozzarella empanizadas, servidas con salsa Marinara hecha en casa.<\/p>\n<p><strong>Chili con carne<\/strong> Cup \u20a12550 Bowl \u20a13550<br>Tradicional cocido de res y cerdo, con frijoles y cerveza artesanal. Queso cheddar, ceboll\u00edn y natilla.<\/p>\n<p><strong>Re-loaded Nachos Pollo ( chicken )<\/strong> Peq. \u20a15250 Grnd. \u20a19850 <strong>Chili con Carne<\/strong> Peq. \u20a14350 Grnd. \u20a17350 Cerdo ( pulled pork ) Peq. \u20a14650 Grnd. \u20a18250<\/p>\n<h2 id=\"chips\">&#8230;.&amp; CHIPS<\/h2>\n<p><strong>Fresh Guacamole &amp; Chips<\/strong> \u20a14950 <strong>Jalape\u00f1o-Pico de gallo &amp; Chips<\/strong> \u20a12950 <strong>Spicy Queso &amp; Chips<\/strong> \u20a12550 <strong>Smoked Frijolitos &amp; Chips<\/strong> \u20a12950<\/p>\n<p><strong>Crispy Chicken Eggrolls<\/strong> 4 unds \u20a14850 6 unds \u20a16450<br>Crispy \u00abwraps\u00bb rellenos de pollo, queso, espinaca, frijoles y ma\u00edz dulce. Aderezo poblano para dipear.<\/p>\n<p><strong>Fried Pickles \u00abPepinillos\u00bb<\/strong> \u20a13950<br>Pepinillos pankonizados, acompa\u00f1ados con aderezo de eneldo para dipear.<\/p>\n<h2 id=\"platters\">PLATTERS \u00abPara Compartir\u00bb<\/h2>\n<p><strong>All Star<\/strong> \u20a115950<br>5 Alitas Mixtas con Ranch, 3 Bacon Potato Skins con natilla, 3 mozzarellas con marinara y 4 crispy Eggrolls con salsa Avocado-Ranch.<\/p>\n<p><strong>Beer Mates<\/strong> \u20a110500<br>Una combinaci\u00f3n de nuestros aperitivos que mejor acompa\u00f1an unas cervecitas! 4 Chicken Eggrolls, 4 Aros de Cebolla, 4 Fried Pickles y Chili con Carne.<\/p>\n<p><strong>Two for Two<\/strong> \u20a19750<br>Ideal para parejas o una persona de gran apetito. 2 beef sliders y una orden de nuestro populares Chicken Bites con papas fritas y salsa BBQ.<\/p>\n<p><strong>Threesome<\/strong> \u20a121500<br>Suficiente para tres personas. Este plat\u00f3n combina 3 Beef Sliders con papitas fritas, una orden de Bites, Aros de Cebolla y 10 Alitas mixtas ba\u00f1adas con tu salsa favorita.<\/p>\n<p><strong>Veggie Sampler<\/strong> \u20a16950<br>Quien dice que los vegetarianos no comen divertido? 3 coliflores Buffalo, 2 veggie potato skins, 3 aros de cebolla, apio y zanahoria. Boom!<\/p>\n<p><strong>Striptease<\/strong> 400g \u20a111750 600g \u20a115650<br>Doraditos chicken bites: estilo original, caj\u00fan y buffalo. Papas fritas, salsa mostaza miel y barbacoa.<\/p>\n<h2 id=\"sandwiches\">SANDWICHES en pan artesanal<\/h2>\n<p><strong>BBQ Pork Sandwich<\/strong> \u20a16650<br>Tierna y jugosa carne de cerdo ahumada y desmenuzada en nuestra salsa BBQ. La servimos sobre pan brioche artesanal con aguacate fresco, tomate y cebolla morada encurtida en casa. Papas fritas y ensalada de repollo al lado.<\/p>\n<p><strong>Grilled Turkey<\/strong> \u20a18950<br>Un \u00abstack\u00bb de rebanadas de pechuga de pavo con queso Suizo derretido, tocineta a la parrilla y tomate fresco sobre pan de Masa Madre. Lo servimos con papas country y 2 fried pickles.<\/p>\n<p><strong>Hooligan&#8217;s Pastrami \u00abReuben\u00bb Sandwich<\/strong> \u20a19750<br>Te traemos todo el sabor de esta sandwich Neoyorquina! Abundante Pastrami, queso suizo y Pepper Jack, Sauerkraut y aderezo Ruso. Le damos nuestro \u00abtwist\u00bb al agregarle cebolla caramelizada y ar\u00fagula. Delicioso!<\/p>\n<p><strong>Buffalo Burger<\/strong> \u20a16950<br>Pechuga de pollo empanizada, ba\u00f1ada con salsa Buffalo y cubierta de queso Pepperjack. Lechuga, tomate, cebolla morada y pepinillo. Servida sobre pan artesanal con aderezo Blue Cheese.<\/p>\n<h2 id=\"tacosyquesadillas\">TACOS &amp; QUESADILLAS<\/h2>\n<p><strong>Cajun Shrimp<\/strong> 2 Tacos \u20a15950<br>\u00abSoft tacos\u00bb de camarones caj\u00fan salteados con rajas de jalape\u00f1os, cebolla morada y queso pepper jack. Todo sobre una cama de repollo con Aderezo Chipotle-Ranch.<\/p>\n<p><strong>BBQ PORK<\/strong> 3 Tacos \u20a14950 6 Tacos \u20a18950<br>Crujientes tortillas de ma\u00edz, rellenas de cerdo mechado con BBQ, repollo morado, zanahoria, aguacate y cebollas encurtidas. Chipotle-Ranch.<\/p>\n<p><strong>JALAPE\u00d1O STEAK<\/strong> 3 Tacos \u20a16450<br>\u00abSoft tacos\u00bb de lomito a la parrilla, salteados con rajas de jalape\u00f1os y queso pepper jack. Todo sobre una cama de repollo con Aderezo&nbsp; Jalape\u00f1o-Ranch.<\/p>\n<p><strong>TACOMIX<\/strong> 3 BBQ Pork + 3 Steak \u20a110750 2 BBQ Pork + 2 Steak + 2 Shrimp \u20a112850<\/p>\n<p><strong>PHILLY STEAK Quesadilla<\/strong> \u20a17450<br>Philly style baby! Lomito salteado a la plancha con chile dulce, cebolla y hongos. Lo mezclamos con queso suizo y lo servimos entre tortillas de harina con aderezo poblano y papas country.<\/p>\n<p><strong>PORK CARNITAS<\/strong> Quesadilla \u20a16350<br>Quesadilla con carnitas de cerdo a la plancha, tomate, culantro, cebollita picada y unas gotas de lim\u00f3n. La acompa\u00f1amos con frijolitos y salsa Jalape\u00f1o-Ranch. Extra de Guacamole por \u20a1950 colones.<\/p>\n<p><strong>BUFFALO<\/strong> Quesadilla \u20a17650<br>Buffalo Bites picantes dentro de nuestra tradicional quesadilla. Si te gustan las alitas te fascinar\u00e1 este plato.<\/p>\n<p><strong>CHICKEN<\/strong> Quesadilla \u20a17950<br>Tortilla de harina rellena con pollo sazonado, queso mozzarella, hongos frescos, cebolla y tomate. Servida con lechuga, pico de gallo, natilla y guacamole.<\/p>\n<h2 id=\"grilledburgers\">GRILLED BURGERS<\/h2>\n<p>Hamburguesas a la parrilla<br>Nuestras tortas de hamburguesa las preparamos con carne de res importada 100% ANGUS. Las cocinas t\u00e9rmino \u00abtres cuartos\u00bb y las servimos sobre pan de hamburguesa artesanal acompa\u00f1adas de papas fritas. Las ofrecemos en tres tama\u00f1os para que decid\u00e1s cu\u00e1l se acomoda m\u00e1s a tu apetito. La opci\u00f3n \u00abNAKED\u00bb es nutra version sin carbohidratos, no trae pan, la torta es de 230 gramos y viene acompa\u00f1ada con ensalada Caesar en lugar de papas.<\/p>\n<p><strong>FRANCIA &#8217;98<\/strong> Regular 180g \u20a17950, Lunch 150g \u20a17450, Naked 230g \u20a17950<br>Queso suizo, hongos salteados y cebolla caramelizada sobre una cama de vegetales frescos.<\/p>\n<p><strong>MEXICO &#8217;86<\/strong> Regular 180g \u20a18550, Lunch 150g \u20a17950, Naked 230g \u20a18550<br>Queso pepper jack, jalape\u00f1os, tocineta y guacamole.<\/p>\n<p><strong>ANGUS CHEESE BURGER<\/strong> Regular 180g \u20a16850, Lunch 150g \u20a16250, Naked 230g \u20a16850<br>Tu elecci\u00f3n de queso Cheddar, Americano o Mozzarella.<\/p>\n<p><strong>ARGENTINA &#8217;78<\/strong> Regular 180g \u20a17950, Lunch 150g \u20a17550, Naked 230g \u20a17950<br>Queso mozzarella, tocineta a la parrilla y huevo frito.<\/p>\n<p><strong>USA &#8217;94<\/strong> Regular 180g \u20a17950, Lunch 150g \u20a17450, Naked 230g \u20a17950<br>Queso americano, tocineta, salsa BBQ y un aro de cebolla.<\/p>\n<p><strong>ALEMANIA &#8217;06<\/strong> Regular 180g \u20a19750, Lunch 150g \u20a19250, Naked 230g \u20a19750<br>Queso suizo, sauerkraut, pastrami, aderezo ruso, mostaza Alemana especial y ar\u00fagula sobre pan pretzel.<\/p>\n<p><strong>SLIDERS<\/strong> \u20a17650<br>3 Mini hamburguesas de tu elecci\u00f3n. Angus beef o Buffalo Chicken.<\/p>\n<p><strong>PORTOBELLO<\/strong> Veggie, solo hongo \u20a16750, Full, con carne \u20a18450<br>Hongo portobello relleno de queso Muenster y Cheddar. Pedila full con torta de 150g o versi\u00f3n Veggie, solo hongo.&nbsp;<\/p>\n<h2>EXTRAS<\/h2>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Cheddar<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Americano<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Mozzarella<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Queso suizo<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Pepper Jack<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Jalape\u00f1os<\/strong> \u20a1350<\/li>\n\n\n\n<li><strong>Chili c\/carne<\/strong> \u20a1650<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><strong>Cebolla caramelizada<\/strong> \u20a1550<\/li>\n\n\n\n<li><strong>Guacamole<\/strong> \u20a1950<\/li>\n\n\n\n<li><strong>Hongos salteados<\/strong> \u20a11250<\/li>\n\n\n\n<li><strong>Tocineta ahumada<\/strong> \u20a11350<\/li>\n\n\n\n<li><strong>Cerdo ( pulled pork )<\/strong> \u20a11350<\/li>\n\n\n\n<li><strong>Torta Angus 150g<\/strong> \u20a11950<\/li>\n\n\n\n<li><strong>Torta Angus 180g<\/strong> \u20a12350<\/li>\n<\/ul>\n<\/div>\n<\/div>\n\n\n<h2 id=\"wings\">WINGS YOUR WAY<\/h2>\n<p>Tus alitas, a tu manera<\/p>\n<p><strong>Flattie<\/strong> \u20a1450<\/p>\n<p><strong>Drumette<\/strong> \u20a11650<\/p>\n<p><strong>Apio y zanahoria<\/strong> \u20a11250<\/p>\n<p><strong>Rancho \/ Blue Cheese<\/strong> \u20a1650<\/p>\n<ul>\n<li>Precio por pieza, ba\u00f1adas ( o no ) con tu salsa favorita.<\/li>\n<li>Prices by piece with ( or without ) your favorite wing sauce.<\/li>\n<\/ul>\n<p>Vos decid\u00eds tu formula perfecta, pedilos en cualquiera de nuestras 11 salsas.<\/p>\n<p>Alitas mixtas, totally fresh, never frozen! <strong>5 alitas, 1 salsa<\/strong> \u20a15500 <strong>10 alitas, 2 salsas<\/strong> \u20a19950 <strong>15 alitas, 3 salsas<\/strong>&nbsp;\u20a114600 <strong>20 alitas, 4 salsas<\/strong> \u20a119500<\/p>\n<p>Nuestras ordenes mixtas se conforman de 3 flatties y 2 drumettes por cada 5 piezas. Incluye apio, zanahoria y aderezo ranch.<\/p>\n<p><strong>CHICKEN FINGERS<\/strong> \u20a16750<br>Nuestros famosos dedos de pechuga de pollo vienen acompa\u00f1ados con papas fritas y se sirven con aderezo mostaza-miel y salsa barbacoa o ba\u00f1ados en su salsa de elecci\u00f3n.<\/p>\n<p><strong>CHICKEN BITES<\/strong> \u20a17250<br>Doraditos trozos de pechuga de pollo ba\u00f1ados con la salsa de tu elecci\u00f3n. Acompa\u00f1ados de apio y aderezo ranch. Son como alitas sin el hueso.<\/p>\n<p><strong>GRILLED PARMESAN FLATTIES<\/strong> \u20a15950<br>10 flatties a la parrilla rebozadas con nuestra salsa ajo \/ parmesano, y terminadas con queso parmesano y perejil fresco. Tardan un poquito, pero son deliciosas!<\/p>\n<h2 id=\"salsas\">SALSAS PARA ELEGIR<\/h2>\n<ul>\n<li>Garlic Parmesan<\/li>\n<li>Honey Mustard<\/li>\n<li>Barbecue<\/li>\n<li>Sweet &amp; Chili<\/li>\n<li>Mr Miyagi<\/li>\n<li>Marley Mango<\/li>\n<li>Barbecue Chipotle<\/li>\n<li>Hooligan&#8217;s Buffalo<\/li>\n<li>TNT Marley Mango<\/li>\n<li>TNT Chipotle<\/li>\n<li>TNT Buffalo<\/li>\n<\/ul>\n<p><strong>FAJITA SKILLET<\/strong> <strong>Pollo<\/strong> \u20a17250 <strong>Lomito<\/strong> \u20a18950 <strong>Mixtas<\/strong> \u20a18650<br>Jugosas fajitas de lomito o pollo a la parrilla, salteadas a la plancha con chile dulce y cebolla. Servidas con arroz, tortillas de trigo, guacamole, jalape\u00f1o-pico y&nbsp; natilla. Tocineta adiciona \u20a11150 o Camarones \u20a12500<\/p>\n<h2 id=\"grilled\">GRILLED<\/h2>\n<p><strong>CHURRASCO 250GRS<\/strong> \u20a19250<br>Tierno corte a la parrilla, sazonado y aderezado con Chimichurri. Servido con papas country, chilli con carne y ensalada Caesar.<\/p>\n<p><strong>PECHUGA DE POLLO A LA PARRILLA<\/strong> \u20a16950<br>200 grs de pechuga de pollo grillada, acompa\u00f1ada de papas country, frijolitos molidos ahumados y ensalada Caesar.<\/p>\n<p><strong>Agregale Camarones por<\/strong>&nbsp;\u20a12500<\/p>\n<h2 id=\"sopas\">SOPAS<\/h2>\n<p><strong>CREMA DEL D\u00cdA<\/strong> Cup \u20a11950 Bowl \u20a14450<br>Pregunt\u00e1 por nuestra calientita crema del d\u00eda. Hecha en casa con ingredientes super frescos.<\/p>\n<p><strong>Broccoli &amp; Cheese<\/strong> Cup \u20a11950 Bowl \u20a14450<br>Crema de br\u00f3coli y queso sharp cheddar.<\/p>\n<p><strong>Potato &amp; Bacon<\/strong> Cup \u20a11950 Bowl \u20a14450<br>Crema de papa, queso cheddar, tocineta y cebollino.<\/p>\n<p><strong>SOPA DE TORTILLA<\/strong> Cup \u20a11950 Bowl \u20a14850<br>Nuestra versi\u00f3n de la cl\u00e1sica Sopa Azteca! Servida con pollo desmenuzado, queso rallado, tortillas fritas, aguacate y natilla.<\/p>\n<h2 id=\"allbeefsuperbowls\">ALL BEEF SUPER BOWLS<\/h2>\n<p><b>CHURRASCO BOWL<\/b> \u20a16950<br>Lomito de res a la parrilla con chimichurri sobre arroz de la casa, hoolipapas con salsa Chipotle Ranch y un huevo frito ( opcional ).<\/p>\n<p><b>FAJITA BOWL<\/b> \u20a16950<br>Lomito de res sazonado y cocinado estilo fajitas sobre una cama de arroz con guarnici\u00f3n de jalape\u00f1os, pico de gallo y guacamole.<\/p>\n<p><b>TICO BOWL<\/b> \u20a16450<br>Lomito de res encebollado, con ensalada, frijolitos y maduro sobre una cama de arroz.<\/p>\n<p><b>MR MIYAGI BOWL<\/b> \u20a16650<br>Lomito de res cocinado estilo oriental con cebollinos, chile dulce, ajonjol\u00ed y zanahoria tempura, todo sobre una cama de arroz.<\/p>\n<h2 id=\"salads\">SALADS<\/h2>\n<p><b>COBB<\/b> \u20a17750<br>Trocitos de pollo a la parrilla, huevo cocido, mix de quesos rallados, tocineta, aguacate y tomate. Todo sobre una cama de lechugas y acompa\u00f1ado de aderezo Ranch.<\/p>\n<p><b>ORIENTAL<\/b> \u20a17250<br>Combinaci\u00f3n de lechugas con pollo al grill, fideos de arroz, repollo morado, zanahoria, almendras, semillas de ajonjol\u00ed y mandarinas en conserva. Aderezo oriental.<\/p>\n<p><b>CAESAR<\/b> <strong>Original<\/strong> \u20a14150 <strong>Pollo al Grill<\/strong> \u20a17250 <strong>Crispy Buffalo<\/strong> \u20a16950 <strong>Camarones<\/strong> \u20a17650<br>Fresca lechuga romana con aderezo Caesar, parmesano reci\u00e9n rallado y croutones de pan con ajo.<\/p>\n<p><b>TACO SALAD<\/b> \u20a16950<br>Con alma de taco! Pollo al grill, mezcla de quesos, pico de gallo, ma\u00edz dulce, frijoles, aguacate, lechuga y tortilla strips. Viene acompa\u00f1ada de gajos de lim\u00f3n, jalape\u00f1os y aderezo Chipotle-ranch.<\/p>\n<h2 id=\"extrasparatuensalada\">EXTRAS PARA TU ENSALADA<\/h2>\n<ul>\n<li>Aguacate \u20a11250<\/li>\n<li>Huevo cocido \u20a1650<\/li>\n<li>Tocineta al grill \u20a11250<\/li>\n<li>Pollo al grill \u20a12250<\/li>\n<li>Chicken bites \u20a12250<\/li>\n<li>Tortilla strips \u20a1550<\/li>\n<li>Aderezo oriental \u20a11750<\/li>\n<li>Camarones \u20a12500<\/li>\n<\/ul>\n<p>En Hooligan&#8217;s nos sentimos muy orgullosos de nuestra cocina, solo utilizamos productos frescos y todos nuestros aderezos ( excepto ranch ) los hacemos desde cero aqu\u00ed en casa.<\/p>\n<h2>don&#8217;t put <strong>VEGGIE<\/strong> in the <strong>CORNER<\/strong><\/h2>\n<h2 id=\"veggiestarters\">STARTERS<\/h2>\n<p><strong>Sopa de tortilla<\/strong> ( sustancia de pollo ) \u20a13450<\/p>\n<p><strong>Apio y Zanahoria<\/strong> ( blue cheese ) \u20a12150<\/p>\n<p><strong>Fried Pickles<\/strong> \u20a13950<\/p>\n<p><strong>Mozzarellas<\/strong> ( 5 unds ) \u20a15450<\/p>\n<p><strong>Onion Rings<\/strong> ( 6 unds ) \u20a13550<\/p>\n<p><strong>Veggie Potato Skins<\/strong> ( 3 unds ) \u20a14550<\/p>\n<p><strong>Smoked frijolitos &amp; chips<\/strong> \u20a12950<\/p>\n<p><strong>Fresh Guacamole &amp; Chips<\/strong> \u20a14950<\/p>\n<p><strong>Jalape\u00f1o Pico &amp; Chips<\/strong> \u20a12950<\/p>\n<p><strong>Spicy Queso &amp; Chips<\/strong> \u20a12550<\/p>\n<p><strong>Hoolipapas<\/strong> \u20a13250<\/p>\n<p><strong>Fries &amp; Cheese<\/strong> \u20a12950<\/p>\n<h2 id=\"vegetariansalads\">SALADS<\/h2>\n<p><strong>Avocado Caesar Salad<\/strong> \u20a15350<\/p>\n<p><strong>Oriental con Zanahoria Tempura<\/strong> \u20a15250<\/p>\n<p><strong>Taco Salad<\/strong> \u20a15850<\/p>\n<h2 id=\"vegetarianmain\">MAIN<\/h2>\n<p><strong>Veggie Portobello Burger<\/strong> \u20a16650<\/p>\n<p><strong>Veggie Nachos<\/strong> \u20a14350<\/p>\n<p><strong>Veggie&nbsp; Quesadilla<\/strong> \u20a16150<\/p>\n<p><strong>Fajitas Portobello<\/strong> \u20a16950<\/p>\n<p><strong>Mr. Miyagi Portobello Bowl<\/strong> \u20a15550<\/p>\n<p><strong>Coliflores Buffalo<\/strong> \u20a14850<\/p>\n<p><strong>Veggie Sampler Platter<\/strong> \u20a16950<br>3 onion rings, 2 veggie potato skins, 3 coliflores buffalo, apio y zanahoria.<\/p>\n<h2 id=\"homemadesweets\">HOMEMADE SWEETS<\/h2>\n<p><strong>Chocolate Cluster<\/strong> \u20a13950<\/p>\n<p><strong>Carrot Cake Cheesecake<\/strong> \u20a13950<\/p>","protected":false},"excerpt":{"rendered":"<p>Men\u00fa Multiplaza Escaz\u00fa Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. Codigo postal de la zona: 10203. Tel\u00e9fono: +506 2201-8261.&nbsp;Horario: Lunes, Martes, Mi\u00e9rcoles y Domingo: 11am a 12am. Jueves: 11am a 1am. Viernes y S\u00e1bado de 11am a 2am. Plaza Lincoln Distrito: San Vicente, cant\u00f3n: Moravia, provincia: San Jos\u00e9. Codigo postal de la zona: 11401.Tel\u00e9fono: &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Men\u00fa Hooligans Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#more-4251\" aria-label=\"Leer m\u00e1s sobre Men\u00fa Hooligans Costa Rica\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[98,148,140,111,150,147],"tags":[250],"class_list":["post-4251","post","type-post","status-publish","format-standard","hentry","category-98","category-148","category-140","category-111","category-150","category-menus","tag-restaurantes-en-escazu","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE<\/title>\n<meta name=\"description\" content=\"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE\" \/>\n<meta property=\"og:description\" content=\"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-28T17:36:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T13:02:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Men\u00fa Hooligans Costa Rica\",\"datePublished\":\"2016-02-28T17:36:25+00:00\",\"dateModified\":\"2023-02-14T13:02:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/\"},\"wordCount\":1959,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg\",\"keywords\":[\"Restaurantes en Escazu\"],\"articleSection\":[\"10203\",\"11401\",\"11503\",\"11801\",\"40103\",\"Men\u00fas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/\",\"name\":\"Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg\",\"datePublished\":\"2016-02-28T17:36:25+00:00\",\"dateModified\":\"2023-02-14T13:02:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&ssl=1\",\"width\":622,\"height\":622,\"caption\":\"Bar Restaurante Hooligans Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/menu-hooligans-costa-rica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Men\u00fa Hooligans Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE","description":"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/","og_locale":"es_ES","og_type":"article","og_title":"Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE","og_description":"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2016-02-28T17:36:25+00:00","article_modified_time":"2023-02-14T13:02:50+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Men\u00fa Hooligans Costa Rica","datePublished":"2016-02-28T17:36:25+00:00","dateModified":"2023-02-14T13:02:50+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/"},"wordCount":1959,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg","keywords":["Restaurantes en Escazu"],"articleSection":["10203","11401","11503","11801","40103","Men\u00fas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/","name":"Hooligans Costa Rica - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n, WAZE","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1-300x300.jpg","datePublished":"2016-02-28T17:36:25+00:00","dateModified":"2023-02-14T13:02:50+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Men\u00fa, tel\u00e9fonos, horarios, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Hooligans Alajuela, San Jos\u00e9 y Heredia, Costa Rica.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/02\/bar-restaurante-hooligans-costa-rica-1.jpg?fit=622%2C622&ssl=1","width":622,"height":622,"caption":"Bar Restaurante Hooligans Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/menu-hooligans-costa-rica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Men\u00fa Hooligans Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-16z","jetpack-related-posts":[{"id":5398,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-modesta\/","url_meta":{"origin":4251,"position":0},"title":"La Modesta","author":"Restaurantes Costa Rica","date":"20 febrero 2017","format":false,"excerpt":"NEGOCIO CERRADO Tel\u00e9fono: +506 7293-7360 Horario: De Lunes a Viernes de 9am a 7pm. S\u00e1bados de 9am a 1pm. Domingo cerrado. Direcci\u00f3n De la salida a Multiplaza Escaz\u00fa en la autopista Prospero Fern\u00e1ndez, 800 mts norte frente a Crossfit 506, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante La Modesta, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/restaurante-la-modesta-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5512,"url":"https:\/\/costaricainfolink.com\/restaurantes\/rostipollos\/","url_meta":{"origin":4251,"position":1},"title":"RostiPollos","author":"Restaurantes Costa Rica","date":"4 junio 2017","format":false,"excerpt":"Tel\u00e9fono Servicio Express: +506 2217-8787 Men\u00fa SAN JOS\u00c9 Direcci\u00f3n: Diagonal al Cine Variedades. Distrito: Catedral, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10104. Tel\u00e9fono: +506 2258-1724 Horario: Todos los d\u00edas de 11am a 10pm. SABANA Direcci\u00f3n: Sabana Norte, 100 mts este del ICE. Distrito: Mata Redonda,\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"RostiPollos Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/03\/rostipollos-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5164,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-casona-laly\/","url_meta":{"origin":4251,"position":2},"title":"La Casona de Laly","author":"Restaurantes Costa Rica","date":"30 diciembre 2016","format":false,"excerpt":"Lo mejor de la comida t\u00edpica costarricense al alcance de todos! SANTA ANA Direcci\u00f3n: centro comercial Santa Ana 2000. Distrito: Pozos, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10903. Tel\u00e9fono: +506 2282-5504 Horario: de Lunes a S\u00e1bado de 11am a 12 mn. Domingos de 11am a\u2026","rel":"","context":"En \u00ab10903\u00bb","block_context":{"text":"10903","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10903\/"},"img":{"alt_text":"Restaurante La Casona de Laly en Escazu, San Pedro y Santa Ana","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/restaurante-la-casona-de-laly-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":956,"url":"https:\/\/costaricainfolink.com\/restaurantes\/lile-de-france\/","url_meta":{"origin":4251,"position":3},"title":"Restaurante L&#8217;Ile de France","author":"Restaurantes Costa Rica","date":"15 agosto 2011","format":false,"excerpt":"Horario: De Lunes a S\u00e1bados de 12 p.m. 11:30 p.m. Cerrado los Domingos. Ubicaci\u00f3n: 1er piso Hotel Marriott Residence Inn en Avenida Escaz\u00fa, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. Coordenadas para GPS: 9.938156,-84.142894 (9\u00b056'17.36\"N, 84\u00b008'34.42\"W) Reservaciones: +506 2289-7533 Tel\u00e9fono: +506\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/06\/lile-de-france-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1001,"url":"https:\/\/costaricainfolink.com\/restaurantes\/damalfi\/","url_meta":{"origin":4251,"position":4},"title":"Restaurante D&#8217;amalfi","author":"Restaurantes Costa Rica","date":"6 diciembre 2012","format":false,"excerpt":"Restaurante Cerrado Click the following link to read this page in English: D'amalfi Restaurant El Restaurante D'amalfi es el aut\u00e9ntico restaurante de comida italiana a cargo del reconocido Chef Giuseppe Galuppo, mejor conocido como Chef Pino, ubicado en Escaz\u00fa, el cual abri\u00f3 sus puertas en el a\u00f1o 2010. [portfolio_slideshow id=2406]\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9032,"url":"https:\/\/costaricainfolink.com\/restaurantes\/poke\/","url_meta":{"origin":4251,"position":5},"title":"Poke","author":"Restaurantes Costa Rica","date":"13 noviembre 2020","format":false,"excerpt":"Poke Escaz\u00fa Tel\u00e9fono:\u00a0+506 2228 2710 Horario: de Lunes a Domingo de 1130am a 9pm. Direcci\u00f3n: Plaza Tempo, distrito: San Rafel, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. \u00a0\u00a0 Poke To Go Lindora y San Pedro, solamente a tr\u00e1ves de Uber eats. MEN\u00da Signature Bowls\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante POKE Escazu, Lindora y Escazu Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/11\/restaurante-poke-escazu-lindora-san-pedro-costa-rica-300x300.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=4251"}],"version-history":[{"count":97,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4251\/revisions"}],"predecessor-version":[{"id":11136,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4251\/revisions\/11136"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=4251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=4251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=4251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}