{"id":4949,"date":"2016-12-02T10:29:48","date_gmt":"2016-12-02T15:29:48","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=4949"},"modified":"2017-10-05T07:14:56","modified_gmt":"2017-10-05T12:14:56","slug":"cafe-frances","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/","title":{"rendered":"Restaurante Caf\u00e9 Franc\u00e9s"},"content":{"rendered":"<p><strong>Ubicaci\u00f3n<\/strong>: Centro comercial Plaza del Sol, <strong>distrito<\/strong>: Curridabat, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><strong>Tel\u00e9fono<\/strong>: <a href=\"tel:+5062234-2709\">+506 2234-2709<\/a><\/p>\n<p><strong>Horario<\/strong>: de Lunes a S\u00e1bado de 9am a 8pm. Domingos de 10am a 7pm.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0rxdbj\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante Caf\u00e9 Franc\u00e9s en Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/Caf%C3%A9+Franc%C3%A9s\/@9.9289187,-84.04359,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0e38dbc775ba9:0x18f845842820d1bf!8m2!3d9.9289187!4d-84.0414013\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante Caf\u00e9 Franc\u00e9s en Curridabat, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Men\u00fa<\/h2>\n<h2>ENTRADAS<\/h2>\n<p>Sopa de pescado<br \/>\nEnsalada Verde<br \/>\nEnsalada de Pollo<br \/>\nEnsalda Mixta<br \/>\nCeviche<br \/>\nPate de la casa con pimienta verde<br \/>\nPapas Fritas<br \/>\nCroquetas (papa con queso y estrag\u00f3n)<br \/>\nQuiche de hongos o jam\u00f3n o palmito<\/p>\n<h2>PLATOS<\/h2>\n<p>Tilapia al ajillo<br \/>\nTilapia con hongos y crema<br \/>\nTilapia a la nicoise (light)<\/p>\n<h2>CHULETAS<\/h2>\n<p>Chuletas de Cerdo<br \/>\nChuletas dijonnaise<br \/>\nChuleta con hongos<\/p>\n<h2>TRUCHAS<\/h2>\n<p>Trucha a la francesa con pernod<br \/>\nTrucha con esparragos y crema<br \/>\nTrucha con crema y hierbas de provence<br \/>\nTrucha al ajillo<\/p>\n<p><strong>Todos estos platos van acompa\u00f1ados con ensalada, arroz o papas fritas o croquetas.<\/strong><\/p>\n<p>Fajitas de pollo a la mexicana (salsa de tomate y picante)<br \/>\nPollo a la plancha<br \/>\nPollo crema estrag\u00f3n<br \/>\nPollo crema con esparragos<br \/>\nPollo a la pimienta verde ( con salsa crema )<br \/>\nPollo con hongos y crema<br \/>\nPollo al Vermouth con pasas y hongos<br \/>\nPollo tropical (mermelada de frutas y crema)<br \/>\nPollo Jalape\u00f1o<br \/>\nPollo a la mexicana (salsa de tomate y picante)<\/p>\n<p>Camarones jumbo empanizados ( 12 unidades )<br \/>\nCamarones jumbo al ajillo ( 12 unidades )<br \/>\nCamarones Jumbo a la Provenzal ( 12 unidades )<br \/>\nCamarones jumbo al pernod ( licor de anis y crema ) ( 12 unidades )<\/p>\n<p>Corvina al ajillo<br \/>\nCorvina empanizada<br \/>\nCorvina caf\u00e9 franc\u00e9s (crema y estrag\u00f3n)<br \/>\nCorvina Hongos (crema y hongos)<br \/>\nCorvina a la mexicana ( salsa de tomate y picante )<br \/>\nCorvina al pernod \u00a0(licor de anis y crema)<br \/>\nCorvina a la nicoise con vegetales al vapor (light)<\/p>\n<p>Trocitos de lomito a la mexicana (salsa de tomate y picante)<br \/>\nLomito de res<br \/>\n<a href=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica\/\" rel=\"attachment wp-att-6027\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6027\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lomito de Res, Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-6027\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=500%2C375&#038;ssl=1\" alt=\"Lomito de Res, Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica\" width=\"500\" height=\"375\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/lomito-de-res-restaurante-cafe-frances-curridabat-san-jose-costa-rica.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><br \/>\nLomito encebollado<br \/>\nLomito a la mexicana ( salsa de tomate y picante )<br \/>\nLomito a la pimienta negra ( pimienta negra y crema )<br \/>\nLomito a la pimienta verde ( pimienta verde y crema )<br \/>\nLomito con hongos ( salteados a la mantequilla )<br \/>\nLomito rocquefort (queso y crema )<br \/>\nLomito dijonnaise con hongos ( mostaza y crema )<br \/>\nLomito especial ( whisky, hongos y crema )<br \/>\nLomito anchois ( anchoas salteadas )<br \/>\nLomito con esparragos ( mantequilla de ajo )<br \/>\nLomito Franc\u00e9s ( hongos, vino tinto y crema )<br \/>\nLomito a la Jalape\u00f1a ( jalape\u00f1o y crema )<\/p>\n<p>Conejo a la mostaza ( mostaza y crema )<br \/>\nConejo a la Belga con ciruelas ( cerveza y crema )<\/p>\n<p>Omelette de Jam\u00f3n<br \/>\nOmelette de espinaca<br \/>\nOmelette de queso<br \/>\nOmelette de hongos<br \/>\nOmelette de jam\u00f3n, queso y hongos<\/p>\n<p>Croissant Solo<br \/>\nCroissant con Jam\u00f3n y queso<br \/>\nCroissant de pollo y queso<br \/>\nSandwich de Jam\u00f3n y queso en pan cuadrado prensado<br \/>\nSandwich de Pollo y queso en pan cuadrado prensado<br \/>\nSandwich de Jam\u00f3n y queso en pan cuadrado integral prensado<br \/>\nSandwich de Pollo y queso en pan cuadrado integral prensado<br \/>\nSandwich de Jam\u00f3n y queso en pan\u00a0baguette<br \/>\nSandwich de Pollo y queso en pan baguette<br \/>\nSandwich de carne y queso en pan baguette<br \/>\nSandwich de Pate de la casa en pan baguette<br \/>\nTostadas<br \/>\nTostadas con queso<br \/>\nTostadas en pan integral<br \/>\nTostadas en pan integral con queso<br \/>\nCrepas con Jam\u00f3n y Hongos<br \/>\nCrepas con pollo y hongos<br \/>\nQuiche de Hongos<br \/>\nQuiche de palmito<br \/>\nQuiche de Jam\u00f3n ( lorraine )<br \/>\nCrepas dulces con nutella y helados<br \/>\nCrepas dulces con manzana<br \/>\nCrepas dulces con manzana y helados<br \/>\nCrepas dulces con helados ( de vainilla )<br \/>\nTarta Tatin sola ( manzana )<br \/>\nTarta Tatin con chantilly ( manzana )<br \/>\nTarta tatin con helados ( manzana )<br \/>\nReposter\u00eda<\/p>\n<h2>BEBIDAS CALIENTES<\/h2>\n<p>Caf\u00e9 Negro<br \/>\nCaf\u00e9 Negro Descafeinado<br \/>\nCaf\u00e9 con leche<br \/>\nCaf\u00e9 con leche descafeinado<br \/>\nCaf\u00e9 con leche delactomy<br \/>\nCaf\u00e9 espresso<br \/>\nCaf\u00e9 espresso cortado<br \/>\nCaf\u00e9 latte<br \/>\nCaf\u00e9 capuchino<br \/>\nCapuchino con licor de amaretto \/ macadamia \/ etc..<br \/>\nCapuchino con delactomy<br \/>\nCapuchino con Baileys (licor)<br \/>\nCaf\u00e9 Royal (chantilly)<br \/>\nChocolate<br \/>\nChocolate Delactomy<br \/>\nCaf\u00e9 glace con chantilly<\/p>\n<p>Te Negro<br \/>\nTe con Leche<br \/>\nTe con Leche Delactomy<br \/>\nTe dr Frutas<br \/>\nTe de Canela<br \/>\nTe Verde<br \/>\nTe de Manzanilla<br \/>\nTe de Menta<br \/>\nTe Blanco<br \/>\nTe Capuchino<\/p>\n<h2>BEBIDAS FR\u00cdAS<\/h2>\n<p>Manzana en agua<br \/>\nManzana en leche<br \/>\nManzana Delactomy<br \/>\nPapaya en agua<br \/>\nPapaya en leche<br \/>\nPapaya Delactomy<br \/>\nPi\u00f1a en agua<br \/>\nLimonada<br \/>\nGuanabana en agua<br \/>\nGuanabana en leche<br \/>\nGuanabana Delactomy<br \/>\nFruit Punch<br \/>\nTe Fr\u00edo de la casa<br \/>\nTropical de \u00a0lim\u00f3n \/ melocot\u00f3n \/ te verde<br \/>\nJugo de Naranja<br \/>\nChocolate Fr\u00edo<br \/>\nMilkshake de Fresa \/ Vainilla \/ Chocolate<br \/>\nJugo de Tomate<\/p>\n<h2>GASEOSAS<\/h2>\n<p>Coca Cola Cl\u00e1sica \/ Light \/ Zero<br \/>\nGinger Ale Regular \/ Light<br \/>\nSoda<br \/>\nSprite, Fresca, Fanta<br \/>\nQuinada<br \/>\nAgua Cristal 600ml<\/p>\n<h2>APERITIVOS<\/h2>\n<p>Whisky Johnnie Rojo<br \/>\nWhisky Highland Queen<br \/>\nJohnnie Negro<br \/>\nJ&amp;B<br \/>\nWhisky Old Parr<br \/>\nRon Bacardi<br \/>\nRon Centenario<br \/>\nRon Flor de Ca\u00f1a 18 a\u00f1os<br \/>\nVodka Smirnoff<br \/>\nVodka Absolut<br \/>\nTequila<br \/>\nAmaretto Dissarono<br \/>\nCognac Hennessy<br \/>\nGinebra Burneth<br \/>\nBrandy Napoleon<br \/>\nCointreau<br \/>\nCrema Baileys<br \/>\nGrand Marnier<\/p>\n<h2>Cervezas<\/h2>\n<p>Imperial, Pilsen, Bavaria Light, Bavaria Gold, Bavaria Dark, Heineken<\/p>\n<h2>Cervezas de B\u00e9lgica<\/h2>\n<p>Stella Artois, Leffe Rubia, Leffe Oscura<\/p>\n<h2>Especialidades<\/h2>\n<p>Irish Coffee<br \/>\nMargarita<br \/>\nKir<br \/>\nDaiquiri<br \/>\nBlack Russian<br \/>\nRuso Blanco<br \/>\nAlexander<br \/>\nBloody Mary<br \/>\nPi\u00f1a Colada<br \/>\nTom Collins<br \/>\nPlanter Ponche<\/p>\n<h2>VINOS<\/h2>\n<p>Copa de Vino Tinto, Blanco o Rosado<br \/>\nMaitres \u00a0viticulteurs frances tinto<br \/>\nFrontera Blanco Chileno<br \/>\nFrontera Tinto Chileno<br \/>\nFrontera Rosado Chileno<br \/>\nCasillero del diablo blanco chileno<br \/>\nCasillero del diablo tinto chileno<br \/>\nMarques de caceres espa\u00f1ol tinto<br \/>\nBeaujolais cuvee prestige franc\u00e9s tinto<\/p>\n<p>Gato Negro 1\/2 Botellas<\/p>\n<p>Lavi\u00f1a catalunya espa\u00f1ol blanco<br \/>\nLavi\u00f1a catalunya espa\u00f1ol\u00a0rosado<br \/>\nLavi\u00f1a catalunya espa\u00f1ol\u00a0tinto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ubicaci\u00f3n: Centro comercial Plaza del Sol, distrito: Curridabat, cant\u00f3n: Curridabat, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 11801. Tel\u00e9fono: +506 2234-2709 Horario: de Lunes a S\u00e1bado de 9am a 8pm. Domingos de 10am a 7pm. Men\u00fa ENTRADAS Sopa de pescado Ensalada Verde Ensalada de Pollo Ensalda Mixta Ceviche Pate de la casa con pimienta &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Caf\u00e9 Franc\u00e9s\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#more-4949\" aria-label=\"Leer m\u00e1s sobre Restaurante Caf\u00e9 Franc\u00e9s\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[111,69,26],"tags":[],"class_list":["post-4949","post","type-post","status-publish","format-standard","hentry","category-111","category-curridabat","category-san-jose","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-02T15:29:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-05T12:14:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Caf\u00e9 Franc\u00e9s\",\"datePublished\":\"2016-12-02T15:29:48+00:00\",\"dateModified\":\"2017-10-05T12:14:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/\"},\"wordCount\":869,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/waze.jpg\",\"articleSection\":[\"11801\",\"Curridabat\",\"San Jos\u00e9\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/\",\"name\":\"Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/waze.jpg\",\"datePublished\":\"2016-12-02T15:29:48+00:00\",\"dateModified\":\"2017-10-05T12:14:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/waze.jpg?fit=50%2C50&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/waze.jpg?fit=50%2C50&ssl=1\",\"width\":50,\"height\":50,\"caption\":\"Ubicaci\u00f3n WAZE de Restaurantes Il Cappricio, San Rafael, Alajuela, Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/cafe-frances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Caf\u00e9 Franc\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n","description":"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n","og_description":"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2016-12-02T15:29:48+00:00","article_modified_time":"2017-10-05T12:14:56+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Caf\u00e9 Franc\u00e9s","datePublished":"2016-12-02T15:29:48+00:00","dateModified":"2017-10-05T12:14:56+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/"},"wordCount":869,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg","articleSection":["11801","Curridabat","San Jos\u00e9"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/","name":"Restaurante Caf\u00e9 Franc\u00e9s - Men\u00fa, Tel\u00e9fono, Horario, Direcci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg","datePublished":"2016-12-02T15:29:48+00:00","dateModified":"2017-10-05T12:14:56+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Restaurante Caf\u00e9 Franc\u00e9s Curridabat, San Jos\u00e9, Costa Rica. Men\u00fa, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?fit=50%2C50&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?fit=50%2C50&ssl=1","width":50,"height":50,"caption":"Ubicaci\u00f3n WAZE de Restaurantes Il Cappricio, San Rafael, Alajuela, Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-frances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Caf\u00e9 Franc\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1hP","jetpack-related-posts":[{"id":1153,"url":"https:\/\/costaricainfolink.com\/restaurantes\/family-pizza-costa-rica\/","url_meta":{"origin":4949,"position":0},"title":"Family Pizza Costa Rica","author":"Restaurantes Costa Rica","date":"25 abril 2014","format":false,"excerpt":"Horario: De Lunes a Jueves de 11 a.m. 3 p.m. y de 6 p.m. 10:25 p.m. Viernes y S\u00e1bados de 11 a.m. 10:55 p.m. Domingos de 11 a.m. 9:55 p.m. Ubicaci\u00f3n: 75 m Norte del Banco de Costa Rica de Guadalupe, distrito: Guadalupe, cant\u00f3n: Goicoechea, provincia: San Jos\u00e9, Costa Rica.\u2026","rel":"","context":"En \u00ab10801\u00bb","block_context":{"text":"10801","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10801\/"},"img":{"alt_text":"Family Pizza Costa Rica en Curridabat, Guadalupe y Alajuela","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/12\/restaurante-family-pizza-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4783,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bistro-tapas-buffet\/","url_meta":{"origin":4949,"position":1},"title":"Bistro, Tapas &#038; Buffet","author":"Restaurantes Costa Rica","date":"4 noviembre 2016","format":false,"excerpt":"Horario: de Lunes a Viernes de 730am a 4pm. Tel\u00e9fono: +506 2271-5370 Direcci\u00f3n: de Servicentro La Galera 100 metros NE y 50 SE, Edificio BIOQUIM. Distrito: S\u00e1nchez, Cant\u00f3n: Curridabat, Provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 11804.","rel":"","context":"En \u00ab11804\u00bb","block_context":{"text":"11804","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/11804\/"},"img":{"alt_text":"Bistro, Tapas & Buffet Curridabat, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/11\/bistro-tapas-buffet-curridabat-san-jose-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6572,"url":"https:\/\/costaricainfolink.com\/restaurantes\/giacomin\/","url_meta":{"origin":4949,"position":2},"title":"Giacomin Pasteler\u00eda y Chocolater\u00eda","author":"Restaurantes Costa Rica","date":"5 abril 2018","format":false,"excerpt":"MULTIPLAZA ESCAZ\u00da - GUACHIPEL\u00cdN - HEREDIA - SAN PEDRO - CURRIDABAT - PINARES - TIB\u00c1S MEN\u00da MULTIPLAZA ESCAZ\u00daHORARIO De Lunes a Domingo de 10:00 a.m. a 7:00 p.m. TEL\u00c9FONO +506 4001-7304 DIRECCI\u00d3N En Multiplaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jose, Costa Rica. C\u00f3digo postal de la zona: 10203.\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Giacomin Pasteler\u00eda y Chocolater\u00eda en Santa Ana, Escaz\u00fa, Heredia y San Pedro, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/04\/giacomin-costa-rica-escazu-santa-ana-san-pedro-heredia-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/04\/giacomin-costa-rica-escazu-santa-ana-san-pedro-heredia-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/04\/giacomin-costa-rica-escazu-santa-ana-san-pedro-heredia-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/04\/giacomin-costa-rica-escazu-santa-ana-san-pedro-heredia-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1788,"url":"https:\/\/costaricainfolink.com\/restaurantes\/gelateria-da-noi\/","url_meta":{"origin":4949,"position":3},"title":"Gelateria Da Noi","author":"Restaurantes Costa Rica","date":"27 agosto 2012","format":false,"excerpt":"Click the following link to read this page in English: Da Noi Gelateria El Caf\u00e9 y Gelateria Da Noi, que significa \u201cDonde nosotros\u201d en italiano, es una gelater\u00eda artesanal italiana que abri\u00f3 sus puertas en el a\u00f1o 2008 en San Jos\u00e9, gracias al sue\u00f1o de Elena Barnab\u00f3 y Marcello Polinaris,\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Gelateria Da Noi en Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/da-noi-gelateria-cafe-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6858,"url":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","url_meta":{"origin":4949,"position":4},"title":"Spoon","author":"Restaurantes Costa Rica","date":"2 septiembre 2018","format":false,"excerpt":"Tel\u00e9fono Servicio a Domicilio ( express ) +506 2259-6000 MEN\u00da Ubicaciones ALAJUELA: Plaza Real - City Mall - SAN JOS\u00c9: Los Laureles - Distrito 4 - Multiplaza Escaz\u00fa - Escaz\u00fa Village - Sabana - Pavas - Cl\u00ednica B\u00edblica - Avenida Central - Calle Central - Yoses - Mall San Pedro\u2026","rel":"","context":"En \u00ab10101\u00bb","block_context":{"text":"10101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10101\/"},"img":{"alt_text":"Spoon Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5512,"url":"https:\/\/costaricainfolink.com\/restaurantes\/rostipollos\/","url_meta":{"origin":4949,"position":5},"title":"RostiPollos","author":"Restaurantes Costa Rica","date":"4 junio 2017","format":false,"excerpt":"Tel\u00e9fono Servicio Express: +506 2217-8787 Men\u00fa SAN JOS\u00c9 Direcci\u00f3n: Diagonal al Cine Variedades. Distrito: Catedral, cant\u00f3n: San Jos\u00e9, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10104. Tel\u00e9fono: +506 2258-1724 Horario: Todos los d\u00edas de 11am a 10pm. SABANA Direcci\u00f3n: Sabana Norte, 100 mts este del ICE. Distrito: Mata Redonda,\u2026","rel":"","context":"En \u00ab10104\u00bb","block_context":{"text":"10104","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10104\/"},"img":{"alt_text":"RostiPollos Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/03\/rostipollos-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=4949"}],"version-history":[{"count":20,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4949\/revisions"}],"predecessor-version":[{"id":6029,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/4949\/revisions\/6029"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=4949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=4949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=4949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}