{"id":5383,"date":"2017-02-19T11:35:35","date_gmt":"2017-02-19T16:35:35","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=5383"},"modified":"2017-02-20T09:17:04","modified_gmt":"2017-02-20T14:17:04","slug":"bambuddha-restaurante-bar-lounge","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","title":{"rendered":"Bambuddha Restaurante y Bar Lounge"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5390\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/bambuddha-restaurant-bar-costa-rica-logo-2\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&amp;ssl=1\" data-orig-size=\"743,740\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bambuddha Restaurant &amp;amp; Bar Lounge Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&amp;ssl=1\" class=\"alignright wp-image-5390\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=350%2C349&#038;ssl=1\" alt=\"Bambuddha Restaurant &amp; Bar Lounge Costa Rica\" width=\"350\" height=\"349\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?w=743&amp;ssl=1 743w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=560%2C558&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=260%2C259&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?resize=160%2C159&amp;ssl=1 160w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<h2>Tel\u00e9fono:<br \/>\n<a href=\"tel:+5064700-6821\">+506 4700-6821<\/a><\/h2>\n<h2>Horario:<\/h2>\n<p>De Domingo a Martes de 11am a 11pm.<br \/>\nDe Mi\u00e9rcoles a S\u00e1bados de 11am a 3 am.<\/p>\n<h2>Direcci\u00f3n<\/h2>\n<p>City Place, segundo piso locales 34 y 35, <strong>distrito<\/strong>: Santa Ana, <strong>cant\u00f3n<\/strong>: Santa Ana, <strong>provincia<\/strong>: San Jos\u00e9. C\u00f3digo postal de la zona: 10901.<\/p>\n<p><a href=\"https:\/\/waze.to\/lr\/hd1u0s0xx6\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Bambuddha Restaurante y Bar Lounge en Santa Ana, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/www.google.es\/maps\/place\/Bambuddha+Restaurant+And+Bar\/@9.9356938,-84.1910132,17z\/data=!3m1!4b1!4m5!3m4!1s0x8fa0feabd6d4b041:0x24f9c0636a9b87c5!8m2!3d9.9356885!4d-84.1888245\" target=\"_blank\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/08\/mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Bambuddha Restaurante y Bar Lounge en Santa Ana, San Jos\u00e9, Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<p>Bambuddha Restaurante &amp; Bar es un concepto \u00fanico en la regi\u00f3n, inspirado en La India, Tailandia y Singapur. Es una mezcla de cultura asi\u00e1tica en su m\u00e1ximo esplendor, donde se fusiona la m\u00fasica, el arte, las gastronom\u00eda, su cultura y sus aromas.<\/p>\n<p>Somos un Restaurante y Bar Lounge de deliciosa y exclusiva gastronom\u00eda fusi\u00f3n oriental, sabemos lo que hacemos y nos encanta entretener a nuestros exclusivos clientes.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5394\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/bambuddha-restaurant-bar-costa-rica001\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?fit=2500%2C1901&amp;ssl=1\" data-orig-size=\"2500,1901\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Bambuddha Restaurante y Bar Lounge Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?fit=1024%2C779&amp;ssl=1\" class=\"aligncenter size-full wp-image-5394\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=1200%2C912&#038;ssl=1\" alt=\"Bambuddha Restaurante y Bar Lounge Costa Rica\" width=\"1200\" height=\"912\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=300%2C228&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=768%2C584&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=1024%2C779&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=560%2C426&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=260%2C198&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?resize=160%2C122&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica001.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>MEN\u00da<\/h2>\n<h2>TAPAS<\/h2>\n<p><strong>Calamares \u20a15500<br \/>\nCazuela de Camar\u00f3n \u20a16500<br \/>\nAlmejas \u20a15900<br \/>\nFish and Chips \u20a15500<br \/>\nCeviche Fusion \u20a16500<br \/>\nMejillones \u20a15500<\/strong><\/p>\n<h2>ENTRADAS<\/h2>\n<p><strong>Gyosas \u20a14800<\/strong><br \/>\nFritas, rellenas de camar\u00f3n con una salsa thai.<\/p>\n<p><strong>Ceviche Bambuddha \u20a16500<\/strong><br \/>\nLenguado marinado en lim\u00f3n con julianas de cebolla morada, culantro coyote, reducci\u00f3n de maracuy\u00e1, chile paname\u00f1o y servido con patacones.<\/p>\n<p><strong>Tartar de At\u00fan \u20a16900<\/strong><br \/>\nAt\u00fan en cuadritos con mango, aguacate, cebolla morada, culantro, semillas de s\u00e9samo y aderezo oriental.<\/p>\n<p><strong>Tataki Salad \u20a15500<\/strong><br \/>\nAt\u00fan sellado servido con crostinis y pur\u00e9 de edamames.<\/p>\n<p><strong>Sashimi de Corvina \u20a16000<\/strong><br \/>\nLonjas de corvina con ensalada de algas y salsa ponzu.<\/p>\n<p><strong>Calamares Empanizados \u20a15500<\/strong><br \/>\nEmpanizados con nuestro mix de harinas y servidos con aioli de maracuy\u00e1.<\/p>\n<p><strong>Almejas al Ajillo \u20a15900<\/strong><br \/>\nFlambeadas con licor de an\u00eds, perejil y servidas pan grillado.<\/p>\n<p><strong>Rollos Primavera \u20a14800<\/strong><br \/>\nMix de vegetales salteados y servidos con nuestro aioli de sirasha.<\/p>\n<p><strong>Edamames \u20a14500<\/strong><br \/>\nAl vapor y servidos con sal marina.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5389\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/bambuddha-restaurant-bar-costa-rica003\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Ceviche de Bambuddha Restaurante y Bar Lounge\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-5389 size-full\" title=\"Ceviche Bambuddha\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=1200%2C900&#038;ssl=1\" alt=\"Ceviche de Bambuddha Restaurante y Bar Lounge\" width=\"1200\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica003.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>PLATOS FUERTES<\/h2>\n<p><strong>Mar y Tierra \u20a111500<\/strong><br \/>\nLomito y camarones servidos con fideos de arroz y salsa satay.<\/p>\n<p><strong>Wok Laos \u20a16500<\/strong><br \/>\nVegetales salteados con semillas de mara\u00f1\u00f3n y salsa de osti\u00f3n.<\/p>\n<p><strong>Burguer Gourmet \u20a19000<\/strong><br \/>\nMezcla de carne de res y chorizo, queso Gouda, cebolla caramelizada, lechuga, tomate, acompa\u00f1ada de papas fritas.<br \/>\nExtras: aguacate, hongos, tocineta.<\/p>\n<p><strong>Nasi Goreng \u20a16900<\/strong><br \/>\nArroz chaufa al wok, con una mezcla de vegetales, jengibre, ajo y aceite de s\u00e9samo y pollo.<\/p>\n<p><strong>Green Salad \u20a16000<\/strong><br \/>\nMix de lechugas, tomate, aguacate, cebolla morada, zanahoria en juliana, chayote rayado y aderezo thai.<\/p>\n<p><strong>Shrimp Wrap \u20a18000<\/strong><br \/>\nCamarones fritos, pepinos encurtidos, aguacate, cebolla morada y mayonesa chipotle.<\/p>\n<p><strong>Lomito \u20a19000<\/strong><br \/>\nServido con una croqueta de yuca y salsa BBQ de tamarindo.<\/p>\n<p><strong>Pollo Mok Kai \u20a17200<\/strong><br \/>\nPollo a la plancha servido con vegetales, arroz jazm\u00edn y nuestra salsa satay.<\/p>\n<p><strong>Salm\u00f3n Gravlax \u20a19500<\/strong><br \/>\nAcompa\u00f1ado con pur\u00e9 de pl\u00e1tano maduro y crema de eneldo.<\/p>\n<p><strong>Crusted Tuna \u20a18500<\/strong><br \/>\nSellado con una costra de semillas de culantro, mini vainicas, cherrys y salsa de tamarindo.<\/p>\n<p><strong>Grilled Octopus \u20a19000<\/strong><br \/>\nPulpo al ajillo, servido con una base de papas al vapor.<\/p>\n<p><strong>Han\u00f3i Tofu \u20a16900<\/strong><br \/>\nAcompa\u00f1ado con fideos de arroz aderezados con ponzu y salsa dulce.<\/p>\n<p><strong>Corvina al Estilo Szechuan \u20a19500<\/strong><br \/>\nSellada a la plancha y acompa\u00f1ada con arroz jazm\u00edn, vegetales y salsa thai.<\/p>\n<p><strong>Mariscada \u20a113500<\/strong><br \/>\nNuestros mariscos servidos con una salsa pomodoro o al ajillo y acompa\u00f1ada de arroz blanco.<\/p>\n<p><strong>Entra\u00f1a \u20a110500<\/strong><br \/>\nCon nuestro acompa\u00f1amiento a escoger y salsa bernesa.<br \/>\nPapas Fritas \/ Ensalada Thai \/ Vegetales Flambeados<\/p>\n<p><strong>Rib Eye \u20a114000<\/strong><br \/>\nNuestro corte gourmet con nuestros acompa\u00f1amientos a escoger y salsa bernesa.<br \/>\nPapas Fritas \/ Vegetales Flambeados \/ Ensalada Thai<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5391\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/bambuddha-restaurant-bar-costa-rica005\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lomito de Bambuddha Restaurant &amp;amp; Bar Lounge Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-5391 size-full\" title=\"Lomito\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=1200%2C900&#038;ssl=1\" alt=\"Lomito de Bambuddha Restaurant &amp; Bar Lounge Costa Rica\" width=\"1200\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica005.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<h2>SUSHI<\/h2>\n<p><strong>California Roll \u20a13900<\/strong><br \/>\nRelleno de aguacate, pepino y kanikama con una cubierta de ajonjol\u00ed.<\/p>\n<p><strong>Spicy Tuna Roll \u20a14200<\/strong><br \/>\nRelleno de at\u00fan picante, aguacate y pepino.<\/p>\n<p><strong>Filadelfia Roll \u20a14500<\/strong><br \/>\nRelleno de queso filadelfia, aguacate, pepino, salm\u00f3n ahumado y una cubierta de salm\u00f3n ahumado.<\/p>\n<p><strong>Shake Roll \u20a14500<\/strong><br \/>\nRelleno de salm\u00f3n fresco, aguacate, pepino y cubierto de ajonjol\u00ed.<\/p>\n<p><strong>Carpaccio Roll \u20a14200<\/strong><br \/>\nRelleno de carne marinada en nuestra salsa ponzu, ar\u00fagula, ceboll\u00edn y aderezo parmesano.<\/p>\n<p><strong>Shitake Vegan Roll \u20a14200<\/strong><br \/>\nRelleno de hongos shitake, esp\u00e1rragos, ar\u00fagula, chayote picado finamente y cubierto de quinoa.<\/p>\n<p><strong>Vancouver Roll \u20a14200<\/strong><br \/>\nRelleno de aguacate, pepino, kanikama y una cubierta de salm\u00f3n fresco.<\/p>\n<p><strong>Spicy Shrimp Roll \u20a15200<\/strong><br \/>\nRelleno de camar\u00f3n picante, pepino, aguacate y una cubierta de ajonjol\u00ed.<\/p>\n<h2>POSTRES<\/h2>\n<p><strong>Creme Brul\u00e9 de Lemongrass \u20a13900<\/strong><br \/>\nCrema con zacate de lim\u00f3n y quemada al momento.<\/p>\n<p><strong>Pisang Goreng \u20a13500<\/strong><br \/>\nBu\u00f1uelos de banano con helado de coco.<\/p>\n<p><strong>Brownie Bomba \u20a14800<\/strong><br \/>\nBrownie con helado de matcha.<\/p>\n<p><strong>Cheesecake de Guan\u00e1bana \u20a14600<\/strong><br \/>\nCheesecake al horno cubierto con mousse de guan\u00e1bana y salsa tropical de pi\u00f1a.<\/p>\n<p><strong>Pud\u00edn de Coco \u20a15200<\/strong><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5392\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/bambuddha-restaurant-bar-costa-rica006\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?fit=2500%2C1875&amp;ssl=1\" data-orig-size=\"2500,1875\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Cheesecake de Gun\u00e1bana de Lomito de Bambuddha Restaurant &amp;amp; Bar Lounge Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-5392 size-full\" title=\"Cheesecake de Guan\u00e1bana\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=1200%2C900&#038;ssl=1\" alt=\"Cheesecake de Gun\u00e1bana de Lomito de Bambuddha Restaurant &amp; Bar Lounge Costa Rica\" width=\"1200\" height=\"900\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?w=2500&amp;ssl=1 2500w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica006.jpg?w=2400&amp;ssl=1 2400w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 38px; left: 436px;\">Save<\/span><\/p>\n<p><span style=\"border-radius: 2px; text-indent: 20px; width: auto; padding: 0px 4px 0px 0px; text-align: center; font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif; color: #ffffff; background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px; position: absolute; opacity: 1; z-index: 8675309; display: none; cursor: pointer; top: 38px; left: 446px;\">Save<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel\u00e9fono: +506 4700-6821 Horario: De Domingo a Martes de 11am a 11pm. De Mi\u00e9rcoles a S\u00e1bados de 11am a 3 am. Direcci\u00f3n City Place, segundo piso locales 34 y 35, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. Bambuddha Restaurante &amp; Bar es un concepto \u00fanico en la &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Bambuddha Restaurante y Bar Lounge\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#more-5383\" aria-label=\"Leer m\u00e1s sobre Bambuddha Restaurante y Bar Lounge\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[91,34,142,13,26,27],"tags":[],"class_list":["post-5383","post","type-post","status-publish","format-standard","hentry","category-91","category-asiatico","category-bar","category-internacional","category-san-jose","category-santa-ana","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google<\/title>\n<meta name=\"description\" content=\"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google\" \/>\n<meta property=\"og:description\" content=\"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-19T16:35:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-20T14:17:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Bambuddha Restaurante y Bar Lounge\",\"datePublished\":\"2017-02-19T16:35:35+00:00\",\"dateModified\":\"2017-02-20T14:17:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/\"},\"wordCount\":712,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg\",\"articleSection\":[\"10901\",\"Asi\u00e1tico\",\"Bar\",\"Internacional\",\"San Jos\u00e9\",\"Santa Ana\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/\",\"name\":\"Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg\",\"datePublished\":\"2017-02-19T16:35:35+00:00\",\"dateModified\":\"2017-02-20T14:17:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&ssl=1\",\"width\":743,\"height\":740,\"caption\":\"Bambuddha Restaurant &amp; Bar Lounge Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/bambuddha-restaurante-bar-lounge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bambuddha Restaurante y Bar Lounge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google","description":"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","og_locale":"es_ES","og_type":"article","og_title":"Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google","og_description":"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2017-02-19T16:35:35+00:00","article_modified_time":"2017-02-20T14:17:04+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Bambuddha Restaurante y Bar Lounge","datePublished":"2017-02-19T16:35:35+00:00","dateModified":"2017-02-20T14:17:04+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/"},"wordCount":712,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg","articleSection":["10901","Asi\u00e1tico","Bar","Internacional","San Jos\u00e9","Santa Ana"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/","name":"Bambuddha Restaurante y Bar Lounge Costa Rica - Tel\u00e9fono, men\u00fa, WAZE, mapas de Google","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg","datePublished":"2017-02-19T16:35:35+00:00","dateModified":"2017-02-20T14:17:04+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Bambuddha Restaurante y Bar Lounge en City Place Santa Ana, San Jos\u00e9, Costa Rica. Horario, men\u00fa, tel\u00e9fono, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/bambuddha-restaurant-bar-costa-rica-logo-1.jpg?fit=743%2C740&ssl=1","width":743,"height":740,"caption":"Bambuddha Restaurant &amp; Bar Lounge Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/bambuddha-restaurante-bar-lounge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Bambuddha Restaurante y Bar Lounge"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1oP","jetpack-related-posts":[{"id":5714,"url":"https:\/\/costaricainfolink.com\/restaurantes\/we-love-pasta\/","url_meta":{"origin":5383,"position":0},"title":"WE LOVE PASTA","author":"Restaurantes Costa Rica","date":"4 julio 2017","format":false,"excerpt":"Direcci\u00f3n: Container Platz, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. Tel\u00e9fono: +506 8950-7697 Horario: De Lunes a Domingo de 11am a 10pm. MEN\u00da En combo +\u20a1500: pan de ajo + refresco. Bolognesa\u00a0\u20a13500 Pomodoro\u00a0\u20a13000 4 Quesos Bechamel \/ Pomodoro\u00a0\u20a13500 Hongos Bechamel \/ Pomodoro\u00a0\u20a14300\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Restaurante We Love Pasta en Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/07\/restaurante-we-love-pasta-santa-ana-san-jose-costa-rica-1-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5577,"url":"https:\/\/costaricainfolink.com\/restaurantes\/donde-totto\/","url_meta":{"origin":5383,"position":1},"title":"Restaurante Donde Totto","author":"Restaurantes Costa Rica","date":"10 abril 2017","format":false,"excerpt":"Direcci\u00f3n: Centro comercial Vindi, local n\u00famero 3, costado este de la Plaza de Deportes del INVU. Distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. Horario: De Lunes a S\u00e1bados de 11am a 1030pm. Domingos cerrrado. Tel\u00e9fono: +506 2203-3111 MEN\u00da PIZZAS Pizza Margherita\u00a0Peq. \u20a15169\u00a0Med.\u00a0\u20a15169\u00a0Grd.\u00a0\u20a17500\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Donde Totto Comida Italiana Artesanal -Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/04\/donde-totto-comida-italiana-artesanal-300x194.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4132,"url":"https:\/\/costaricainfolink.com\/restaurantes\/el-rincon-casero\/","url_meta":{"origin":5383,"position":2},"title":"Restaurante El Rinc\u00f3n Casero","author":"Restaurantes Costa Rica","date":"11 febrero 2016","format":false,"excerpt":"CERRADO El Restaurante El Rinc\u00f3n Casero es una peque\u00f1a e innovadora soda, que goza de un ambiente tranquilo, ubicada en Santa Ana centro, operada en sus inicios familiarmente desde Octubre del 2011 por dos hermanos y su padre. [portfolio_slideshow id=4161] El Rinc\u00f3n Casero y su men\u00fa, ha sido dise\u00f1ado pensando\u2026","rel":"","context":"En \u00abInternacional\u00bb","block_context":{"text":"Internacional","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-tipo-de-comida\/internacional\/"},"img":{"alt_text":"Restaurante El Rinc\u00f3n Casero en Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2015\/11\/restaurante-rincon-casero-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5164,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-casona-laly\/","url_meta":{"origin":5383,"position":3},"title":"La Casona de Laly","author":"Restaurantes Costa Rica","date":"30 diciembre 2016","format":false,"excerpt":"Lo mejor de la comida t\u00edpica costarricense al alcance de todos! SANTA ANA Direcci\u00f3n: centro comercial Santa Ana 2000. Distrito: Pozos, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10903. Tel\u00e9fono: +506 2282-5504 Horario: de Lunes a S\u00e1bado de 11am a 12 mn. Domingos de 11am a\u2026","rel":"","context":"En \u00ab10903\u00bb","block_context":{"text":"10903","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10903\/"},"img":{"alt_text":"Restaurante La Casona de Laly en Escazu, San Pedro y Santa Ana","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2016\/12\/restaurante-la-casona-de-laly-costa-rica-1.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5724,"url":"https:\/\/costaricainfolink.com\/restaurantes\/hoppys-place\/","url_meta":{"origin":5383,"position":4},"title":"Hoppy&#8217;s Place","author":"Restaurantes Costa Rica","date":"10 julio 2017","format":false,"excerpt":"Horario: De Martes a Jueves de 12md a 2pm y de 5pm a 11pm. Viernes 12md a 2pm y de 5pm a 12 mn. Domingo de 2pm a 10pm. Lunes cerrado. Tel\u00e9fono +506 2100-8960 Direcci\u00f3n: Plaza Kronos Distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Hoppy's Place Brewpub & Grill en Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/07\/hoppys-place-santa-ana-san-jose-costa-rica-1-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6086,"url":"https:\/\/costaricainfolink.com\/restaurantes\/restaurante-cebolla-verde\/","url_meta":{"origin":5383,"position":5},"title":"Restaurante Cebolla Verde","author":"Restaurantes Costa Rica","date":"31 octubre 2017","format":false,"excerpt":"Direcci\u00f3n Carretera Vieja Santa Ana Escaz\u00faDistrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10901. Tel\u00e9fono +506 2203-4493 Refrescos Naturales EN AGUA Mango, Mora, Cas, Guanabana, Fresa, Tamarindo, Pi\u00f1a\u00a0\u20a11100 EN LECHE Mora, Cas, Guanabana, Fresas\u00a0\u20a11350 Bebidas Calientes Caf\u00e9 Negro\u00a0\u20a1500 Caf\u00e9 con Leche\u00a0\u20a1750 Aguadulce Negra\u00a0\u20a1500 Aguadulce\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"Ubicaci\u00f3n WAZE de Restaurante Cebolla Verde en Santa Ana, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=5383"}],"version-history":[{"count":8,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5383\/revisions"}],"predecessor-version":[{"id":5396,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5383\/revisions\/5396"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=5383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=5383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=5383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}