{"id":5970,"date":"2017-09-08T20:20:33","date_gmt":"2017-09-09T01:20:33","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/?p=5970"},"modified":"2021-03-07T14:16:43","modified_gmt":"2021-03-07T19:16:43","slug":"el-churrasco","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/","title":{"rendered":"EL CHURRASCO"},"content":{"rendered":"<h2><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"5984\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&amp;ssl=1\" data-orig-size=\"792,612\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&amp;ssl=1\" class=\"alignright size-medium wp-image-5984\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=300%2C232&#038;ssl=1\" alt=\"Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica\" width=\"300\" height=\"232\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=300%2C232&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=768%2C593&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=560%2C433&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=260%2C201&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?resize=160%2C124&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?w=792&amp;ssl=1 792w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Direcci\u00f3n:<\/h2>\n<p>Poasito, <strong>distrito<\/strong>: Sabanilla, <strong>cant\u00f3n<\/strong>: Alajuela, <strong>provincia<\/strong>: Alajuela. C\u00f3digo postal de la zona: 20107.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u1u405v\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante El Churrasco en Poasito, Alajuela, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/www.google.co.cr\/maps\/place\/El+Churrasco\/@10.1627676,-84.1998397,18.79z\/data=!4m12!1m6!3m5!1s0x8fa0f46261165941:0x2b9c59eb71222429!2sEl+Churrasco+Hotel+Restaurante!8m2!3d10.162779!4d-84.19913!3m4!1s0x0:0xec23097a51e08dd0!8m2!3d10.1630877!4d-84.19897\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante El Churrasco en Poasito, Alajuela, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h2>Tel\u00e9fonos<\/h2>\n<p><a href=\"tel:+50624822135\">+506 2482-2135<\/a>, <a href=\"tel:+50688610902\">+506 8861-0902<\/a><\/p>\n<h2>Horario:<\/h2>\n<p>Lunes a Jueves de 730am a 8pm.<br \/>\nViernes y S\u00e1bado de 730am a 9pm.<br \/>\nDomingos de 730am a 8pm.<\/p>\n<h2><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#menu\">Men\u00fa<\/a><\/h2>\n<h2>Nuestra Historia<\/h2>\n<p>El 4 de Diciembre de 1987, el matrimonio conformado por Mario y Ady, con deseos de trabajar, gran voluntad y llenos de ilusiones, decidieron iniciar un sue\u00f1o gastr\u00f3nomico y fundar su propio negocio en la zona cercana al Volc\u00e1n Po\u00e1s.<\/p>\n<p>Fue as\u00ed como, con la ayuda de Dios, naci\u00f3 El Churrasco Hotel y Restaurante, sus orgullosos fundadores, trabajaron con ah\u00ednco y dedicaci\u00f3n para lograr abrirse espacio y consolidar un nombre, dentro del competitivo mercado de servicios y restaurantes de esta hermosa zona tur\u00edstica, tal y como sucede con las nuevas iniciativas empresariales, que se insertan en un ambiente de comercio de tales caracter\u00edsticas.<\/p>\n<p>Al comenzar, se trataba de un restaurante peque\u00f1o que ten\u00eda tan solo 8 mesas y una peque\u00f1a parrilla abierta; esto \u00faltimo, para dar sustento a la filosof\u00eda de Mario, en el sentido de que cada cliente tuviese el acceso y la posibilidad de observar la manipulaci\u00f3n de los alimentos, con los elevados requerimientos de higiene en el manejo de los productos, que posteriormente se servir\u00edan en la mesa de cada uno de los comensales. Est\u00e1 visi\u00f3n de integridad y transparencia ha permanecido a lo largo de los a\u00f1os y al d\u00eda de hoy, se constituye en uno de los pilares fundamentales sobre los que se sustenta el prestigio y la calidad del restaurante El Churrasco.<\/p>\n<p>Poco a poco esos est\u00e1ndares de calidad y servicio, fueron dando fama y reconocimiento al restaurante y con ello, el volumen de clientes aument\u00f3, acompa\u00f1ado de nuevas necesidades de adaptaci\u00f3n en cuanto a cantidad de mesas, espacio y particularmente en la ampliaci\u00f3n del men\u00fa, siempre dentro de los estrictos m\u00e1rgenes de calidad y sabor que son la base de nuestro restaurante.<\/p>\n<p>En la actualidad, adem\u00e1s de la experiencia gastronomica, Mario y Ady le ofrecen un comodo y c\u00e1lido hotel, que se conjuga como una perfecta alternativa para hacer turismo, sin dejar de lado las comodidades propias del hogar. Por ello, la invitaci\u00f3n de los propietarios, para visitar El Churrasco Hotel y Restaurante, quienes personalmente le atender\u00e1n mientras disfruta el hermoso paisaje que le ofrece el Volc\u00e1n Po\u00e1s.<\/p>\n<p>Entonces, venga&#8230;\u00a1descanse con nosotros, ser\u00e1 un placer atenderle!<\/p>\n<h2 id=\"menu\">MEN\u00da<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#desayunos\">Desayunos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#entradas\">Entradas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#arroces\">Arroces<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#cortesespeciales\">Cortes Especiales De La Casa<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#otrosplatos\">Otros Platos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#ni\u00f1os\">Menu De Ni\u00f1os<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#gallos\">Gallos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#emparedados\">Emparedados<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#postres\">Postres<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#bebidas\">Bebidas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#bebidascalientes\">Bebidas Calientes<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#cocteles\">Cocteles<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#cervezaslicoresgaseosas\">Cervezas, Licores Y Gaseosas<\/a><\/p>\n<h2 id=\"desayunos\">DESAYUNOS<\/h2>\n<p><b>Desayuno T\u00edpico<\/b>&nbsp;\u20a13400<br \/>\nGallo pinto, Huevos al gusto, Maduro Frito, Queso blanco, Jugo de Naranja y Caf\u00e9.<\/p>\n<p><b>Desayuno Continental<\/b>&nbsp;\u20a13200<br \/>\nTostadas, huevos al gusto, tocineta, jugo de naranja y caf\u00e9.<\/p>\n<h2 id=\"entradas\">ENTRADAS<\/h2>\n<p><b>Ensalada C\u00e9sar<\/b>&nbsp;\u20a14300<br \/>\nEnsalada a base de lechuga, crotones, queso parmesano, tomate, pollo a la parrilla y el cl\u00e1sico aderezo C\u00e9sar.<\/p>\n<p><b>Ensalada del Churrasco<\/b>&nbsp;\u20a13800<br \/>\nLechuga, repollo, tomate, aguacate, remolacha, queso parmesano, chile dulce y el aderezo de la casa.<\/p>\n<p><strong>Guacamole<\/strong>&nbsp;\u20a12460<\/p>\n<p><strong>Frijoles Molidos<\/strong>&nbsp;\u20a11600<\/p>\n<p><strong>Cazuela de Queso<\/strong>&nbsp;\u20a14449<\/p>\n<p><strong>Sopa Negra<\/strong>&nbsp;\u20a12300<\/p>\n<p><strong>Consom\u00e9 de Pollo<\/strong>&nbsp;\u20a12360<\/p>\n<p><strong>Crema de Ayote<\/strong>&nbsp;\u20a11950<\/p>\n<p><strong>Patacones<\/strong>&nbsp;\u20a11400<\/p>\n<h2 id=\"arroces\">ARROCES<\/h2>\n<p><b>Casado T\u00edpico<\/b>&nbsp;\u20a13995<br \/>\nAcompa\u00f1ado de arroz, frijoles, ensalada, maduro y picadillo, con una carne de su elecci\u00f3n: pollo, bistec o carne en salsa.<\/p>\n<p><b>Arroz con Camarones<\/b>&nbsp;\u20a14650<br \/>\nAcompa\u00f1ado de una ensalada verde.<\/p>\n<p><b>Arroz con Pollo<\/b>&nbsp;\u20a14200<br \/>\nAcompa\u00f1ado de una ensalada verde.<\/p>\n<h2 id=\"cortesespeciales\">CORTES ESPECIALES DE LA CASA<\/h2>\n<p><b>Churrasco<\/b>&nbsp;\u20a19980<br \/>\nCorte de Churrasco de 300g, acompa\u00f1ado de 2 guarniciones a su gusto.<\/p>\n<p><b>Lomito Encebollado<\/b>&nbsp;\u20a18945<br \/>\nCorte de lomito de 250g, acompa\u00f1ado de 2 guarniciones.<\/p>\n<p><b>Lomito Suizo<\/b>&nbsp;\u20a18846<br \/>\nCorte de lomito de 250g, acompa\u00f1ado de 2 guarniciones.<\/p>\n<p><b>Lomito en salsa de Jalape\u00f1os, Hongos o Pimienta Verde<\/b>&nbsp;\u20a13800<br \/>\nCorte de Lomito de 250g, acompa\u00f1ado de la salsa de su elecci\u00f3n y 2 guarniciones a elegir.<\/p>\n<p><b>Lomito Roquefort<\/b>&nbsp;\u20a19920<br \/>\nCorte de Lomito de 250g, ba\u00f1ado en salsa de queso Roquefort, acompa\u00f1ado de 2 guarniciones.<\/p>\n<p><b>Lomito Campesino<\/b>&nbsp;\u20a19745<br \/>\nCorte de Lomito 250g, con salsa de tomate criollo, gallo pinto, pl\u00e1tano maduro y picadillo de papa.<\/p>\n<p><b>Lomito a Caballo<\/b>&nbsp;\u20a18800<br \/>\nCorte de lomito de 250g, 2 huevos fritos acompa\u00f1ados de arroz y frijoles.<\/p>\n<p><b>Lomito a la Plancha<\/b>&nbsp;\u20a18800<br \/>\nCorte de lomito de 250g, acompa\u00f1ado de 2 guarniciones de su elecci\u00f3n.<\/p>\n<p><b>Filet Mignon<\/b>&nbsp;\u20a110885<br \/>\nUn medall\u00f3n de lomito de 250g, ba\u00f1ado en salsa de hongos y 2 guarniciones.<\/p>\n<p><b>Filet de Tilapia al gusto<\/b>&nbsp;\u20a16630<br \/>\nAcompa\u00f1ada de 2 guarniciones a su elecci\u00f3n.<\/p>\n<p><b>Filet de Tilapia en salsa de Camarones<\/b>&nbsp;\u20a18980<br \/>\nAcompa\u00f1ado de una salsa de camarones y 2 guarniciones a elegir.<\/p>\n<p><b>Fajitas Mixtas<\/b>&nbsp;\u20a17240<br \/>\nElaboradas a base de carne de lomito, pollo y cerdo a la plancha, cebolla y chile dulce.<\/p>\n<p><b>Lomo de Cerdo<\/b>&nbsp;\u20a17200<br \/>\nEn Salsa de miel y mostaza y 2 guarniciones a su elecci\u00f3n.<\/p>\n<p><b>Corte Delm\u00f3nico<\/b>&nbsp;\u20a19400<br \/>\nCorte de 300g, acompa\u00f1ado de 2 guarniciones a su gusto.<\/p>\n<p><b>Parrillada el Churrasco<\/b>&nbsp;\u20a117800<br \/>\nElaborada con pollo, chorizo, churrasco, cerdo, tortillas, pico de gallo, guacamole, frijoles molidos, jalape\u00f1os y chimichurri.<\/p>\n<h2 id=\"otrosplatos\">OTROS PLATOS<\/h2>\n<p><b>Pechuga de la Casa<\/b>&nbsp;\u20a18200<br \/>\nPechuga al vapor a base de jam\u00f3n, queso, salsa blanca con hongos y 2 guarniciones a su elecci\u00f3n.<\/p>\n<p><b>Fajitas de Pollo<\/b>&nbsp;\u20a16350<br \/>\nAcompa\u00f1adas de chile dulce y cebolla salteados, frijoles molidos y tortillas.<\/p>\n<p><b>Filet de Pehuga a la Plancha<\/b>&nbsp;\u20a16360<br \/>\nFilet de pechuga de pollo acompa\u00f1ado de 2 guarniciones de su elecci\u00f3n.<\/p>\n<p><b>Filet de Pehuga de Pollo en Salsa de Hongos<\/b>&nbsp;\u20a16700<br \/>\nBa\u00f1ada en salsa de hongos y acompa\u00f1ada de 2 guarniciones a elegir.<\/p>\n<p><b>Lengua en Salsa de Tomate<\/b>&nbsp;\u20a17400<br \/>\nAcompa\u00f1ada con arroz blanco.<\/p>\n<p><b>Hamburguesa<\/b>&nbsp;\u20a12750<br \/>\nAcompa\u00f1ada de papas fritas.<\/p>\n<p><b>Quesoburguesa<\/b>&nbsp;\u20a12900<br \/>\nAcompa\u00f1ada con papas fritas.<\/p>\n<p><b>Pl\u00e1tano maduro con queso al horno<\/b>&nbsp;\u20a13870<\/p>\n<p><b>Plato Vegetariano<\/b>&nbsp;\u20a14380<br \/>\nElaborado con vegetales salteados, pico de gallo, guacamole, frijoles y patacones.<\/p>\n<h2 id=\"ni\u00f1os\">MENU DE NI\u00d1OS<\/h2>\n<p><b>Deditos de Pollo<\/b>&nbsp;\u20a14400<br \/>\nAcompa\u00f1ado de papas fritas.<\/p>\n<p><b>Casadito<\/b>&nbsp;\u20a13400<br \/>\nAcompa\u00f1ado con arroz, frijoles y papas fritas; pollo, bistec o carne en salsa.<\/p>\n<h2 id=\"gallos\">GALLOS<\/h2>\n<p><b>Gallo de Bistec Encebollado<\/b>&nbsp;\u20a14320<br \/>\nAcompa\u00f1ado de papas fritas.<\/p>\n<p><b>Gallo de Lengua en Salsa de Tomate<\/b>&nbsp;\u20a13650<\/p>\n<p><b>Gallo de Carne en Salsa<\/b>&nbsp;\u20a11600<\/p>\n<p><b>Gallo de Queso<\/b>&nbsp;\u20a11300<\/p>\n<h2 id=\"emparedados\">EMPAREDADOS<\/h2>\n<p><b>Emparedado de Bistec<\/b>&nbsp;\u20a13400<br \/>\nAcompa\u00f1ado de papas fritas.<\/p>\n<p><b>Emparedado de Pollo<\/b>&nbsp;\u20a12400<\/p>\n<p><b>Emparedado Vegetariano<\/b>&nbsp;\u20a12850<\/p>\n<p><b>Emparedado de Jam\u00f3n y Queso<\/b>&nbsp;\u20a12400<\/p>\n<h2 id=\"postres\">POSTRES<\/h2>\n<p><b>Tiramis\u00fa<\/b>&nbsp;\u20a12900<\/p>\n<p><b>Pedacito de Cielo<\/b>&nbsp;\u20a11560<\/p>\n<p><b>Copa de Helado con Topping<\/b>&nbsp;\u20a11250<\/p>\n<h2 id=\"bebidas\">BEBIDAS<\/h2>\n<p><b>Bebidas Naturales en Leche<\/b>&nbsp;\u20a11500<br \/>\nMora, fresa, guanabana, pi\u00f1a, crema, papaya, cocoa.<\/p>\n<p><b>Bebidas Naturales en Agua<\/b>&nbsp;\u20a11300<br \/>\nMora, fresa, guanabana, pi\u00f1a, papaya, T\u00e9, Limonada.<\/p>\n<h2 id=\"bebidascalientes\">BEBIDAS CALIENTES<\/h2>\n<p><b>Caf\u00e9<\/b>&nbsp;\u20a1950<\/p>\n<p><b>Espresso<\/b>&nbsp;\u20a11500<\/p>\n<p><b>Capuccino<\/b>&nbsp;\u20a11400<\/p>\n<p><b>Capuccino con Sabor<\/b>&nbsp;\u20a11800<br \/>\nAmaretto, menta o licor de cafe.<\/p>\n<p><b>Mocaccino<\/b>&nbsp;\u20a11900<\/p>\n<p><b>Caf\u00e9 Cortado<\/b>&nbsp;\u20a11200<\/p>\n<p><b>T\u00e9 de Variedades de Sabores<\/b>&nbsp;\u20a1950<\/p>\n<p><b>Agua Dulce<\/b>&nbsp;\u20a1950<\/p>\n<p><b>T\u00e9 Chai<\/b>&nbsp;\u20a11600<\/p>\n<p><b>Chocolate<\/b>&nbsp;\u20a11400<\/p>\n<h2 id=\"cocteles\">COCTELES<\/h2>\n<p><b>Margarita<\/b>&nbsp;\u20a12900<\/p>\n<p><b>Ruso Negro<\/b>&nbsp;\u20a12300<\/p>\n<p><b>Ruso Blanco<\/b>&nbsp;\u20a12300<\/p>\n<p><b>Pi\u00f1a Colada<\/b>&nbsp;\u20a13200<\/p>\n<p><b>Daiquir\u00ed<\/b>&nbsp;\u20a12400<\/p>\n<p><b>Fruit Punch<\/b>&nbsp;\u20a11980<\/p>\n<p><b>Rum Punch<\/b>&nbsp;\u20a12600<\/p>\n<p><b>Bloody Mary<\/b>&nbsp;\u20a12200<\/p>\n<p><b>Coctel de la Casa<\/b>&nbsp;\u20a12600<\/p>\n<h2 id=\"cervezaslicoresgaseosas\">CERVEZAS, LICORES Y GASEOSAS<\/h2>\n<p><b>Cerveza Nacional<\/b>&nbsp;\u20a11600<\/p>\n<p><b>Importada<\/b><\/p>\n<p><b>Gaseosas<\/b>&nbsp;\u20a11450<\/p>\n<p><strong>Variedad de Vinos Argentina, Chile, Espa\u00f1a, Italia, Estados Unidos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Direcci\u00f3n: Poasito, distrito: Sabanilla, cant\u00f3n: Alajuela, provincia: Alajuela. C\u00f3digo postal de la zona: 20107. Tel\u00e9fonos +506 2482-2135, +506 8861-0902 Horario: Lunes a Jueves de 730am a 8pm. Viernes y S\u00e1bado de 730am a 9pm. Domingos de 730am a 8pm. Men\u00fa Nuestra Historia El 4 de Diciembre de 1987, el matrimonio conformado por Mario y Ady, &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"EL CHURRASCO\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#more-5970\" aria-label=\"Leer m\u00e1s sobre EL CHURRASCO\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[195,8,196,6],"tags":[],"class_list":["post-5970","post","type-post","status-publish","format-standard","hentry","category-195","category-alajuela","category-sabanilla","category-tipica-costarricense","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante El Churrasco en Poasito, Alajuela, Costa Rica<\/title>\n<meta name=\"description\" content=\"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante El Churrasco en Poasito, Alajuela, Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-09T01:20:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-07T19:16:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"EL CHURRASCO\",\"datePublished\":\"2017-09-09T01:20:33+00:00\",\"dateModified\":\"2021-03-07T19:16:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/\"},\"wordCount\":1205,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg\",\"articleSection\":[\"20107\",\"Alajuela\",\"Sabanilla\",\"T\u00edpica Costarricense\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/\",\"name\":\"Restaurante El Churrasco en Poasito, Alajuela, Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg\",\"datePublished\":\"2017-09-09T01:20:33+00:00\",\"dateModified\":\"2021-03-07T19:16:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&ssl=1\",\"width\":792,\"height\":612,\"caption\":\"Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/el-churrasco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EL CHURRASCO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante El Churrasco en Poasito, Alajuela, Costa Rica","description":"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante El Churrasco en Poasito, Alajuela, Costa Rica","og_description":"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2017-09-09T01:20:33+00:00","article_modified_time":"2021-03-07T19:16:43+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"EL CHURRASCO","datePublished":"2017-09-09T01:20:33+00:00","dateModified":"2021-03-07T19:16:43+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/"},"wordCount":1205,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg","articleSection":["20107","Alajuela","Sabanilla","T\u00edpica Costarricense"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/","name":"Restaurante El Churrasco en Poasito, Alajuela, Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1-300x232.jpg","datePublished":"2017-09-09T01:20:33+00:00","dateModified":"2021-03-07T19:16:43+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google. Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/09\/el-churrasco-restaurante-poasito-sabanilla-alajuela-costa-rica-1.jpg?fit=792%2C612&ssl=1","width":792,"height":612,"caption":"Restaurante El Churrasco en Poasito, Sabanilla, Alajuela, Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/el-churrasco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"EL CHURRASCO"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1yi","jetpack-related-posts":[{"id":10969,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-terraza-de-luna-volcan-poas\/","url_meta":{"origin":5970,"position":0},"title":"La Terraza de Luna Volc\u00e1n Po\u00e1s","author":"Restaurantes Costa Rica","date":"15 noviembre 2022","format":false,"excerpt":"Direcci\u00f3n Calle El Tirol, Po\u00e1s. Distrito: Sabana Redonda, cant\u00f3n: Po\u00e1s, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20805. \u00a0\u00a0 Horario Mi\u00e9rcoles y Jueves de 12md a 9pm, Viernes de 12md a 10pm. S\u00e1bado de 11am a 10pm. Domingos de 11am a 6pm. Lunes y Martes cerrado. MEN\u00da \u00b7\u2026","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/alajuela\/"},"img":{"alt_text":"Restaurante La Terraza de Luna Volc\u00e1n Po\u00e1s, Alajuela, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2022\/11\/restaurante-terraza-de-luna-volcan-poas-alajuela-costa-rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":3733,"url":"https:\/\/costaricainfolink.com\/restaurantes\/ragu\/","url_meta":{"origin":5970,"position":1},"title":"Restaurante Rag\u00fa","author":"Restaurantes Costa Rica","date":"3 mayo 2014","format":false,"excerpt":"Click the following link to read this page in English: Rag\u00fa Restaurant El Restaurante y Pizzeria Rag\u00fa, es un peque\u00f1o pero acogedor y exquisito restaurante ubicado en Alajuela, el cual abri\u00f3 sus puertas desde el a\u00f1o 2010, con la idea de ofrecer a todos los alajuelenses un verdadero restaurante italiano.\u2026","rel":"","context":"En \u00ab20101\u00bb","block_context":{"text":"20101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/20101\/"},"img":{"alt_text":"Restaurante Rag\u00fa Alajuela, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/04\/restaurante-ragu-alajuela-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3205,"url":"https:\/\/costaricainfolink.com\/restaurantes\/japan-tico\/","url_meta":{"origin":5970,"position":2},"title":"Restaurante Japan Tico","author":"Restaurantes Costa Rica","date":"17 marzo 2014","format":false,"excerpt":"Men\u00fa Direcci\u00f3n: en avenida 9, entre calles 10 y 8, distrito: Alajuela, cant\u00f3n: Alajuela, provincia: Alajuela. C\u00f3digo postal de la zona: 20101. Coordenadas para GPS: 10.019344,-84.218510 (10\u00b001'09.64\"N, 84\u00b013'06.63\"W) Tel\u00e9fono: +506 2430-1429 \/ +506 8627-4679 Horario: todos los dias de 11:30 a.m. a 10 p.m. Mapa con direcci\u00f3n: Haga click aqu\u00ed\u2026","rel":"","context":"En \u00ab20101\u00bb","block_context":{"text":"20101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/20101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/03\/restaurante-japan-tico-alajuela-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3710,"url":"https:\/\/costaricainfolink.com\/restaurantes\/el-chante-vegano\/","url_meta":{"origin":5970,"position":3},"title":"Restaurante El Chante Vegano","author":"Restaurantes Costa Rica","date":"28 abril 2014","format":false,"excerpt":"Click the following link to read this page in English: El Chante Vegano Restaurant El Chante Vegano est\u00e1 ubicado en el coraz\u00f3n de la ciudad de Alajuela, y ofrece todo un mundo gastr\u00f3nomico para vegetarianos y veganos amantes de buenos y sofisticados sabores. [portfolio_slideshow id=3720] Todos los platillos que El\u2026","rel":"","context":"En \u00ab20101\u00bb","block_context":{"text":"20101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/20101\/"},"img":{"alt_text":"Restaurante El Chante Vegano Alajuela, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/04\/el-chante-vegano-restaurante-alajuela-costa-rica-logo-e1398439293575.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":49,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bella-verona-pizzeria-bar-y-restaurante\/","url_meta":{"origin":5970,"position":4},"title":"Pizzeria, Bar y Restaurante Bella Verona en Alajuela, Costa Rica","author":"Restaurantes Costa Rica","date":"16 abril 2009","format":false,"excerpt":"Click here to read this page in English Hotel, Pizzeria, Bar y Restaurante italiano, ubicado en el Molino de Florencia, carretera a La Fortuna de San Carlos, Costa Rica es una excelente opci\u00f3n para disfrutar del verdadero sabor italiano, cuando se encuentre por la zona. [portfolio_slideshow id=2334] El Restaurante, Bar\u2026","rel":"","context":"En \u00abAlajuela\u00bb","block_context":{"text":"Alajuela","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/alajuela\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/bella-verona-san-carlos-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8290,"url":"https:\/\/costaricainfolink.com\/restaurantes\/arepera-to-go\/","url_meta":{"origin":5970,"position":5},"title":"Arepera To Go","author":"Restaurantes Costa Rica","date":"28 septiembre 2019","format":false,"excerpt":"Direcci\u00f3n 300 m Oeste del Super \"La Canastica\" por la via 124, Local 1 A la par de la Lavander\u00eda Total Laundry. Distrito: Gu\u00e1cima, cant\u00f3n: Alajuela, provincia: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20105. \u00a0\u00a0 Horario De Martes a Domingo de 11am a 9pm. Lunes de 6pm a\u2026","rel":"","context":"En \u00ab20105\u00bb","block_context":{"text":"20105","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/20105\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/09\/arepera-to-go-guacima-alajuela-costa-rica-comida-venezolana-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/09\/arepera-to-go-guacima-alajuela-costa-rica-comida-venezolana-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/09\/arepera-to-go-guacima-alajuela-costa-rica-comida-venezolana-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/09\/arepera-to-go-guacima-alajuela-costa-rica-comida-venezolana-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=5970"}],"version-history":[{"count":23,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5970\/revisions"}],"predecessor-version":[{"id":9322,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/5970\/revisions\/9322"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=5970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=5970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=5970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}