{"id":6806,"date":"2018-08-09T06:44:37","date_gmt":"2018-08-09T11:44:37","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/?p=6806"},"modified":"2021-04-06T05:43:36","modified_gmt":"2021-04-06T10:43:36","slug":"marisqueria-rancho-santa-barbara","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","title":{"rendered":"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara"},"content":{"rendered":"<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622699369\">+506 2269-9369<\/a> Servicio a domicilio ( express ).<\/p>\n<h2>Horario<\/h2>\n<p>De Martes a Domingo de 12md a 8pm.<\/p>\n<h2>Direcci\u00f3n<\/h2>\n<p>150 metros oeste del parque de Santa Barbara, sobre Av 2 entre calles 4 y 6. <strong>Distrito<\/strong>: Santa Barbara, <strong>cant\u00f3n<\/strong>: Santa Barbara, <strong>provincia<\/strong>: Heredia. C\u00f3digo postal de la zona: 40401.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u1hfupt\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante Marisquer\u00eda Rancho Santa Barbara, Heredia, Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/goo.gl\/maps\/zK2kx48kJ7u\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante Marisquer\u00eda Rancho Santa Barbara, Heredia, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<ul>\n<li>M\u00fasica en vivo todos los S\u00e1bados en el Restaurante.<\/li>\n<li>Lunes Karaoke a partir de las 7pm en el area del Bar.<\/li>\n<li>50% de descuento en consumo para el cumplea\u00f1ero. Aplican Restricciones.<\/li>\n<\/ul>\n<h1>MEN\u00da<\/h1>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#ejecutivo\">Ejecutivo<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#entradas\">Entradas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#arroces\">Arroces<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#pescado\">Pescado<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#combosinfantiles\">Combos Infantiles<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#bocas\">Bocas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#carnesypollo\">Carnes Y Pollo<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#especialidades\">Especialidades<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#camarones\">Camarones<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#menuliviano\">Men\u00fa Liviano<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#postres\">Postres<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#bebidasnaturales\">Bebidas Naturales<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#cervezascocteles\">Cervezas \/ Cocteles<\/a><\/p>\n<p id=\"ejecutivo\"><strong>ALMUERZO EJECUTIVO<\/strong>&nbsp;\u20a13800<br \/>\nDe Lunes a Viernes. Incluye bebida natural, plato fuerte y postre.<\/p>\n<h1 id=\"entradas\">Entradas<\/h1>\n<p><strong>Ceviche de Pescado<\/strong>&nbsp;\u20a13600<\/p>\n<p><strong>Ceviche de Camarones<\/strong>&nbsp;\u20a14500<\/p>\n<p><strong>Ceviche de Mixto<\/strong>&nbsp;\u20a14500<\/p>\n<p><strong>Salpic\u00f3n de Mariscos<\/strong>&nbsp;\u20a14500<\/p>\n<p><strong>Chuchecas<\/strong>&nbsp;\u20a14500<\/p>\n<p><strong>Sopa de Mariscos<\/strong>&nbsp;\u20a14500<\/p>\n<h1 id=\"arroces\">Arroces<\/h1>\n<p><strong>Arroz a la Marinera<\/strong>&nbsp;medio \u20a14700 entero&nbsp;\u20a16500<br \/>\n<a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica\/\" rel=\"attachment wp-att-6814\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6814\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?fit=1920%2C1441&amp;ssl=1\" data-orig-size=\"1920,1441\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Arroz a la Marinera, Restaurante Marisqueria Rancho Santa Barbara, Heredia, Costa Rica\" data-image-description=\"&lt;p&gt;Arroz a la Marinera, Restaurante Marisqueria Rancho Santa Barbara, Heredia, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?fit=1024%2C769&amp;ssl=1\" class=\"aligncenter wp-image-6814\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=600%2C450&#038;ssl=1\" alt=\"\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=1024%2C769&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/arroz-a-la-marinera-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Arroz con Pollo<\/strong>&nbsp;medio \u20a14400 entero&nbsp;\u20a16500<\/p>\n<p><strong>Arroz Mixto<\/strong>&nbsp;medio \u20a14700 entero&nbsp;\u20a1650<\/p>\n<p><strong>Arroz Canton\u00e9s<\/strong>&nbsp;medio \u20a14600 entero&nbsp;\u20a165000<\/p>\n<p><strong>Arroz Ranchero<\/strong>&nbsp;medio \u20a14600 entero&nbsp;\u20a16500<\/p>\n<p><strong>Arroz con Camar\u00f3n Mediano<\/strong>&nbsp;medio \u20a14700 entero&nbsp;\u20a16500<\/p>\n<p><strong>Arroz con Camar\u00f3n Peque\u00f1o<\/strong>&nbsp;entero&nbsp;\u20a17500<\/p>\n<h1 id=\"pescado\">Pescado<\/h1>\n<p><strong>Filet Empanizado<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet Al Ajillo<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet a la plancha<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet a la Mantequilla<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet en Salsa de Tomate<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Filet Princesa<\/strong>&nbsp;\u20a16500<\/p>\n<p><strong>Filet al Camar\u00f3n<\/strong>&nbsp;\u20a16500<\/p>\n<p><strong>Pescado Entero Frito o Empanizado<\/strong>&nbsp;\u20a1seg\u00fan peso<\/p>\n<p><strong>Pescado Entero Frito o Empanizado Relleno<\/strong>&nbsp;\u20a1seg\u00fan peso<\/p>\n<h1 id=\"combosinfantiles\">Combos Infantiles<\/h1>\n<p><strong>Cada uno con un valor de \u20a13800. Acompa\u00f1ado de refresco natural en agua y un postre especial.<\/strong><\/p>\n<ol>\n<li><strong>Fajitas de Pollo Empanizadas<\/strong><\/li>\n<li><strong>Fajitas de Pescado Empanizadas<\/strong><\/li>\n<li><strong>Arroz con Pollo<\/strong><\/li>\n<\/ol>\n<h1 id=\"bocas\">Bocas<\/h1>\n<p><strong>Lomo o Pollo a la Plancha<\/strong>&nbsp;\u20a13800<br \/>\nEn Salsa Jalape\u00f1a o Monteverde.<\/p>\n<p><strong>Arroz Canton\u00e9s<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Arroz Ranchero<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Arroz con Camar\u00f3n<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Arroz Marinera<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Papas a la Francesa<\/strong>&nbsp;Peq. \u20a13500 Grnd. \u20a12400<\/p>\n<p><strong>Ceviche de Corvina<\/strong>&nbsp;\u20a12300<\/p>\n<p><strong>Ceviche de Camar\u00f3n o Mixto<\/strong>&nbsp;\u20a12700<\/p>\n<p><strong>Chuchecas o Salpic\u00f3n de Mariscos<\/strong>&nbsp;\u20a12700<\/p>\n<p><strong>Costilla BBQ<\/strong>&nbsp;\u20a13900<\/p>\n<p><strong>Chifrijo<\/strong>&nbsp;\u20a13700<\/p>\n<p><strong>Chicharr\u00f3n<\/strong>&nbsp;\u20a13900<\/p>\n<p><strong>Nachos ( Pollo o Carne Mexicana )<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>4 Alitas ( Salsa Jalape\u00f1a o Ajillo )<\/strong>&nbsp;\u20a12600<\/p>\n<p><strong>Alitas ( Bufalo, Mostaza Miel, BBQ )<\/strong>&nbsp;6 und. \u20a13900&nbsp;12 und. \u20a17800<\/p>\n<p><strong>Patac\u00f3n Arreglado<\/strong>&nbsp;\u20a12500<\/p>\n<p><strong>Consome de Pollo<\/strong>&nbsp;\u20a12400<\/p>\n<p><strong>Plato Surtido de Carnes<\/strong>&nbsp;\u20a19200<\/p>\n<p><strong>Surtido Ranchero<\/strong>&nbsp;\u20a14900<\/p>\n<p><strong>Sopa de Mariscos<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Filet de Corvina Empanizado<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Fajitas de Pollo o Corvina Empanizadas<\/strong>&nbsp;\u20a13500<\/p>\n<p><strong>Aros de Cebolla<\/strong>&nbsp;\u20a13500<\/p>\n<h1 id=\"carnesypollo\">Carnes y Pollo<\/h1>\n<p><strong>Lomo Monteverde<\/strong>&nbsp;\u20a16800<br \/>\n<a href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica\/\" rel=\"attachment wp-att-6817\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6817\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?fit=1920%2C1440&amp;ssl=1\" data-orig-size=\"1920,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Lomo Monteverde, Restaurante Marisqueria Rancho Santa Barbara, Heredia, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?fit=1024%2C768&amp;ssl=1\" class=\"aligncenter wp-image-6817\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=600%2C450&#038;ssl=1\" alt=\"Lomo Monteverde, Restaurante Marisqueria Rancho Santa Barbara, Heredia, Costa Rica\" width=\"600\" height=\"450\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=560%2C420&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=260%2C195&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?resize=160%2C120&amp;ssl=1 160w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/08\/lomo-monteverde-restaurante-marisqueria-rancho-santa-barbara-heredia-costa-rica.jpg?w=1920&amp;ssl=1 1920w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Lomo Encebollado o a la Plancha<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Lomo Salsa de Hongos<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Lomo Salsa Jalape\u00f1a<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Pollo Monteverde<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Pollo a la Plancha<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Pollo Salsa Jalape\u00f1a<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Pollo en Salsa de Hongos<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Casado con Lomo, Pollo o Filet de Pescado Empanizado<\/strong>&nbsp;\u20a14500<\/p>\n<h1 id=\"especialidades\">Especialidades<\/h1>\n<p><strong>Mariscada al Ajillo<\/strong>&nbsp;\u20a17500<\/p>\n<p><strong>Mariscada a la Mantequilla<\/strong>&nbsp;\u20a17500<\/p>\n<p><strong>Mariscada en Salsa Jalape\u00f1a<\/strong>&nbsp;\u20a17500<\/p>\n<p><strong>Mariscada en Salsa de Tomate<\/strong>&nbsp;\u20a17500<\/p>\n<p><strong>Spaghetti con Pollo o Mariscos<\/strong>&nbsp;\u20a17500<br \/>\nEn salsa de tomate o blanca<\/p>\n<h1 id=\"camarones\">Camarones<\/h1>\n<p><strong>Camarones Empanizados<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<p><strong>Camarones Al Ajillo<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<p><strong>Camarones a la Mantequilla<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<p><strong>Camarones en Salsa de Tomate<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<p><strong>Camarones en Salsa de Tomate<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<p><strong>Camarones Especiales de la Casa<\/strong>&nbsp;Peq. \u20a15100 Med.&nbsp;\u20a17500<\/p>\n<h1 id=\"menuliviano\">Men\u00fa Liviano<\/h1>\n<p><strong>Ensalada de Palmito<\/strong>&nbsp;\u20a14500<\/p>\n<p><strong>Ensalada de Camarones Medianos<\/strong>&nbsp;\u20a17500<\/p>\n<p><strong>Lomo a la Plancha<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Pollo a la Plancha<\/strong>&nbsp;\u20a16800<\/p>\n<p><strong>Filet de Corvina a la Plancha<\/strong>&nbsp;\u20a14950<\/p>\n<p><strong>Arroz a la Jardinera<\/strong>&nbsp;\u20a15850<\/p>\n<h1 id=\"postres\">Postres<\/h1>\n<p><strong>Tres Leches<\/strong>&nbsp;\u20a11900<\/p>\n<p><strong>Flan de Coco<\/strong>&nbsp;\u20a11900<\/p>\n<p><strong>Pedacito de Cielo<\/strong>&nbsp;\u20a11900<\/p>\n<h1 id=\"bebidasnaturales\">Bebidas Naturales<\/h1>\n<p><strong>Bebidas Naturales en Agua<\/strong>&nbsp;\u20a11300<br \/>\nFresa, limonada, guanabana, pi\u00f1a, t\u00e9 fr\u00edo.<\/p>\n<p><strong>Bebidas Naturales en Leche<\/strong>&nbsp;\u20a11500<br \/>\nFresa, guanabana, pi\u00f1a.<\/p>\n<p><strong>Bebidas Gaseosas<\/strong>&nbsp;\u20a11350<br \/>\nCoca Cola regular y light, Ginger Ale, Fresca, Soda, Fanta.<\/p>\n<p><strong>Limonada Hierbabuena<\/strong>&nbsp;\u20a12100<\/p>\n<p><strong>Limonada Hierbabuena con Jengibre<\/strong>&nbsp;\u20a12100<\/p>\n<p><strong>Limonada Hierbabuena con Fresa<\/strong>&nbsp;\u20a12100<\/p>\n<p><strong>Pi\u00f1a con Hierbabuena<\/strong>&nbsp;\u20a12100<\/p>\n<p><strong>Smoothie de Fresa o Guanabana<\/strong>&nbsp;\u20a12700<\/p>\n<p><strong>Pi\u00f1a Colada Sin Licor<\/strong>&nbsp;\u20a12600<\/p>\n<p><strong>Jugo de Lim\u00f3n, Tomate o Naranja<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>Leche Evaporada<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>Jugo de Ar\u00e1ndano<\/strong>&nbsp;\u20a11500<\/p>\n<h1 id=\"cervezascocteles\">Cervezas \/ Cocteles<\/h1>\n<p><strong>Cerveza Imperial Draft<\/strong>&nbsp;Peq. \u20a11400 Grnd. \u20a12200 Pichel \u20a16100<\/p>\n<p><strong>Imperial<\/strong>&nbsp;\u20a11500<br \/>\nCl\u00e1sica, Light, Silver, Cero<\/p>\n<p><strong>Pilsen, Rock Lim\u00f3n<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>Bavaria<\/strong>&nbsp;\u20a12300<br \/>\nGold, Dark, Light<\/p>\n<p><strong>Corona, Smirnoff, Heineken<\/strong>&nbsp;\u20a12300<\/p>\n<p><strong>Balde 6 Cervezas<\/strong>&nbsp;\u20a1consultar precio<br \/>\nConsulte precio y cervezas participantes en la promoci\u00f3n con el mesero.<\/p>\n<p><strong>Pasi\u00f3n de Rancho<\/strong>&nbsp;\u20a12600<\/p>\n<p><strong>Isla del Coco<\/strong>&nbsp;\u20a12500<\/p>\n<p><strong>Margarita<\/strong>&nbsp;\u20a13300<\/p>\n<p><strong>Blue Hawaian<\/strong>&nbsp;\u20a13550<\/p>\n<p><strong>Margarita Especial<\/strong>&nbsp;\u20a13500<\/p>\n<p><b>Saltamontes<\/b>&nbsp;\u20a13500<\/p>\n<p><strong>Pi\u00f1a Colada<\/strong>&nbsp;\u20a13800<\/p>\n<p><strong>Tequila Sunrise<\/strong>&nbsp;\u20a13300<\/p>\n<p><strong>Bloody Mary<\/strong>&nbsp;\u20a13350<\/p>\n<p><strong>Sangr\u00eda<\/strong>&nbsp;\u20a12500<\/p>\n<h2>FACEBOOK<\/h2>\n<div class=\"fb-page\" data-href=\"https:\/\/www.facebook.com\/RanchoStaB\/\" data-tabs=\"timeline\" data-width=\"500\" data-height=\"200\" data-small-header=\"true\" data-adapt-container-width=\"true\" data-hide-cover=\"true\" data-show-facepile=\"false\">\n<blockquote class=\"fb-xfbml-parse-ignore\" cite=\"https:\/\/www.facebook.com\/RanchoStaB\/\"><p><a href=\"https:\/\/www.facebook.com\/RanchoStaB\/\">Rancho Santa B\u00e1rbara<\/a><\/p><\/blockquote>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Tel\u00e9fono +506 2269-9369 Servicio a domicilio ( express ). Horario De Martes a Domingo de 12md a 8pm. Direcci\u00f3n 150 metros oeste del parque de Santa Barbara, sobre Av 2 entre calles 4 y 6. Distrito: Santa Barbara, cant\u00f3n: Santa Barbara, provincia: Heredia. C\u00f3digo postal de la zona: 40401. M\u00fasica en vivo todos los S\u00e1bados &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#more-6806\" aria-label=\"Leer m\u00e1s sobre Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[214,3,74],"tags":[],"class_list":["post-6806","post","type-post","status-publish","format-standard","hentry","category-214","category-heredia","category-santa-barbara","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario<\/title>\n<meta name=\"description\" content=\"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario\" \/>\n<meta property=\"og:description\" content=\"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-09T11:44:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-06T10:43:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara\",\"datePublished\":\"2018-08-09T11:44:37+00:00\",\"dateModified\":\"2021-04-06T10:43:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/\"},\"wordCount\":756,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"articleSection\":[\"40401\",\"Heredia\",\"Santa B\u00e1rbara\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/\",\"name\":\"Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"datePublished\":\"2018-08-09T11:44:37+00:00\",\"dateModified\":\"2021-04-06T10:43:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\",\"contentUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/ubicacion-waze.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/marisqueria-rancho-santa-barbara\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario","description":"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario","og_description":"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2018-08-09T11:44:37+00:00","article_modified_time":"2021-04-06T10:43:36+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara","datePublished":"2018-08-09T11:44:37+00:00","dateModified":"2021-04-06T10:43:36+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/"},"wordCount":756,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","articleSection":["40401","Heredia","Santa B\u00e1rbara"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/","name":"Restaurante Marisquer\u00eda Rancho Santa Barbara - Men\u00fa, Tel\u00e9fono, Horario","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","datePublished":"2018-08-09T11:44:37+00:00","dateModified":"2021-04-06T10:43:36+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Restaurante Marisquer\u00eda Rancho Santa Barbara en Heredia, Costa Rica. Servicio a domicilio, tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#primaryimage","url":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg","contentUrl":"https:\/\/costaricainfolink.com\/ubicacion-waze.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/marisqueria-rancho-santa-barbara\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Marisquer\u00eda Rancho Santa B\u00e1rbara"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1LM","jetpack-related-posts":[{"id":1623,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-pianos\/","url_meta":{"origin":6806,"position":0},"title":"Bar y Restaurante Pianos","author":"Restaurantes Costa Rica","date":"27 julio 2012","format":false,"excerpt":"Horario: De Martes a Domingo de 2 p.m. a 12 mn. Karaoke Viernes de 7pm a 11pm. Lunes Cerrado MEN\u00da Ubicaci\u00f3n: 1.5 km noreste de la plaza de Birr\u00ed, distrito: Jes\u00fas, cant\u00f3n: Santa B\u00e1rbara, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40404 Coordenadas para GPS: 10.065206,-84.128408 (10\u00b003'54.74\"N, 84\u00b007'42.27\"W) Tel\u00e9fono: +506 2269-8051\u2026","rel":"","context":"En \u00ab40404\u00bb","block_context":{"text":"40404","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40404\/"},"img":{"alt_text":"Mirador Pianos Bar y Restaurante en Birri, Santa Barbara, Heredia, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/07\/mirador-pianos-bar-restaurante-birri-santa-barbara-heredia-costa-rica-300x207.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1274,"url":"https:\/\/costaricainfolink.com\/restaurantes\/el-banco-de-los-mariscos\/","url_meta":{"origin":6806,"position":1},"title":"Restaurante El Banco de los Mariscos","author":"Restaurantes Costa Rica","date":"1 junio 2012","format":false,"excerpt":"Horario: De Lunes a S\u00e1bados de 11:30 a.m. a 10 p.m. Domingos de 11:30 a.m. a 9 p.m. Ubicaci\u00f3n: 600m al oeste del costado suroeste de la Iglesia de Santa B\u00e1rbara, distrito: San Pedro, cant\u00f3n: Santa Barbara, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40402. Coordenadas para GPS:\u2026","rel":"","context":"En \u00ab40402\u00bb","block_context":{"text":"40402","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40402\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/02\/el-banco-de-los-mariscos-restaurante-costa-rica-logo4.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":11379,"url":"https:\/\/costaricainfolink.com\/restaurantes\/sognos-cafe\/","url_meta":{"origin":6806,"position":2},"title":"Sognos Caf\u00e9","author":"Restaurantes Costa Rica","date":"23 enero 2023","format":false,"excerpt":"Tel\u00e9fono +506 2215-4276, WhatsApp 8831-4221 Horario Abierto de Lunes a Domingo de 8am a 630pm. Direcci\u00f3n 125 metros norte de la Estaci\u00f3n de bomberos, esquinero, entre avenida 5 y calle. Distrito: Santo Domingo, cant\u00f3n: Santo Domingo, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40301. \u00a0\u00a0 MEN\u00da Desayunos \u00b7\u2026","rel":"","context":"En \u00ab40301\u00bb","block_context":{"text":"40301","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40301\/"},"img":{"alt_text":"Sognos Cafe en Santo Domingo Heredia Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/sognos-cafe-santo-domingo-heredia-costa-rica-1.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":68,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-las-orquideas\/","url_meta":{"origin":6806,"position":3},"title":"Bar y Restaurante Las Orqu\u00eddeas","author":"Restaurantes Costa Rica","date":"29 abril 2009","format":false,"excerpt":"Horario: De Lunes a S\u00e1bados de 8a.m. a 10p.m. Domingos de 8a.m. a 6p.m. Ubicaci\u00f3n: 2km al norte del puente peatonal de San Luis, sobre la carretera a Guapiles, distrito: San Jose, cant\u00f3n: San Isidro, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40602. Coordeandas para GPS: 10.0237415,-84.0257073 (10\u00b001'25.47\u2026","rel":"","context":"En \u00ab40602\u00bb","block_context":{"text":"40602","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40602\/"},"img":{"alt_text":"Centro de Convenciones, Bar y Las Restaurante Orqu\u00eddeas Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/04\/las-orquideas-restaurante-centro-convenciones-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8840,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tratoria-il-gusto-toscano\/","url_meta":{"origin":6806,"position":4},"title":"Trattor\u00eda il gusto Toscano","author":"Restaurantes Costa Rica","date":"24 octubre 2020","format":false,"excerpt":"Tel\u00e9fonos: +506 8885-7494, +506 8873-7227 Horario: de Martes a Viernes de 8am a 9pm. S\u00e1bados y Domingos de 8am a 7pm. Lunes cerrado. Direcci\u00f3n: Villa Tremedal en Santa Elena, distrito: San Jos\u00e9, cant\u00f3n: San Isidro, provincia: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40602. \u00a0\u00a0 Men\u00fa Entradas \u00b7 Pizzas\u2026","rel":"","context":"En \u00ab40602\u00bb","block_context":{"text":"40602","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40602\/"},"img":{"alt_text":"Restaurante Trattor\u00eda il gusto Toscano en Santa Elena, San Isidro, Heredia, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/restaurante-trattoria-il-gusto-toscano-santa-elena-san-isidro-heredia-costa-rica-1-300x264.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1940,"url":"https:\/\/costaricainfolink.com\/restaurantes\/pollos-raymi\/","url_meta":{"origin":6806,"position":5},"title":"Pollos RAYMI","author":"Restaurantes Costa Rica","date":"17 septiembre 2012","format":false,"excerpt":"Ubicaci\u00f3n: 150 oeste de Ferreteria El Lagar, distrito: San Antonio, cant\u00f3n: Bel\u00e9n, provincia: Heredia, Costa Rica. C\u00f3digo postal: 40701 Coordenadas para GPS: 9.979734,-84.183383 (9\u00b058'47.04\"N, 84\u00b011'00.18\"W) Servicio a domicilio a todo Bel\u00e9n (express)\u00a0\u20a1800 Tel\u00e9fono: +506 2239-2725 +506 4030-5777 Horario: todos los dias de 11 a.m. a 10 p.m. Men\u00fa Mapa con\u2026","rel":"","context":"En \u00ab40701\u00bb","block_context":{"text":"40701","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/40701\/"},"img":{"alt_text":"Restaurante Pollos RAYMI en Bel\u00e9n, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/pollos-raymi-heredia-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=6806"}],"version-history":[{"count":17,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6806\/revisions"}],"predecessor-version":[{"id":9785,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6806\/revisions\/9785"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=6806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=6806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=6806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}