{"id":6858,"date":"2018-09-02T07:35:04","date_gmt":"2018-09-02T12:35:04","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/?p=6858"},"modified":"2023-03-21T05:13:51","modified_gmt":"2023-03-21T10:13:51","slug":"spoon","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","title":{"rendered":"Spoon"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"6865\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/spoon-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?fit=323%2C125&amp;ssl=1\" data-orig-size=\"323,125\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Spoon Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?fit=323%2C125&amp;ssl=1\" class=\"alignright size-full wp-image-6865\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=323%2C125&#038;ssl=1\" alt=\"Spoon Costa Rica\" width=\"323\" height=\"125\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?w=323&amp;ssl=1 323w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=300%2C116&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=260%2C101&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?resize=160%2C62&amp;ssl=1 160w\" sizes=\"auto, (max-width: 323px) 100vw, 323px\" \/><\/p>\n<h2>Tel\u00e9fono Servicio a Domicilio ( express )<\/h2>\n<p><a href=\"tel:+50622596000\">+506 2259-6000<\/a><\/p>\n<h1><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#menu\">MEN\u00da<\/a><\/h1>\n<h2>Ubicaciones<\/h2>\n<p align=\"center\">ALAJUELA: <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#plazarealalajuela\">Plaza Real<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#citymall\">City Mall<\/a> &#8211; SAN JOS\u00c9: <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#laureles\">Los Laureles<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#distrito4\">Distrito 4<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#multiplazaescazu\">Multiplaza Escaz\u00fa<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#escazuvillage\">Escaz\u00fa Village<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#sabana\">Sabana<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#pavas\">Pavas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#clinicabiblica\">Cl\u00ednica B\u00edblica<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#avenidacentral\">Avenida Central<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#callecentral\">Calle Central<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#yoses\">Yoses<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#mallsanpedro\">Mall San Pedro<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#antares\">Antares<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#plazalincoln\">Plaza Lincoln<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#plazadelsol\">Plaza del Sol<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#zapote\">Zapote<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#multiplazadeleste\">Multiplaza del Este<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#multicentro\">Multicentro<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#elcristo\">El Cristo<\/a> &#8211; HEREDIA: <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#sanfrancisco\">San Francisco<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#plazaheredia\">Plaza Heredia<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#paseodelasflores\">Paseo de las Flores<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#realcariari\">Real Cariari<\/a> &#8211; CARTAGO: <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#ciudaddeleste\">Ciudad del Este<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#terramall\">Terramall<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#paseometropoli\">Paseo Metr\u00f3poli<\/a><\/p>\n<h2 id=\"laureles\">Plaza Los Laureles<\/h2>\n<p>Del Centro Comercial Paco 350 metros este. <strong>Distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0mpy3q\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza Laureles en San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/Q6bxsKEGWCD2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza Laureles en San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>T\u00e9lefono<\/h2>\n<p><a href=\"tel:+50622282300\">+506 2228-2300<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Domingo a Jueves de 7:00 a.m. a 8:45 p.m. Viernes y S\u00e1bado de 7:00 a.m. a 9:45 p.m.<\/p>\n<h1 id=\"plazarealalajuela\">Plaza Real Alajuela<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p><strong>distrito<\/strong>: Alajuela, <strong>cant\u00f3n<\/strong>: Alajuela, <strong>provincia<\/strong>: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0gyf3v\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza Real Alajuela Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/uEzcBxKN79k\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza Real Alajuela Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50624309489\">+506 2430-9489<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes de 9:00 a.m. a 9:00 p.m. S\u00e1bado y Domingo de 8:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"citymall\">City Mall Alajuela<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>City Mall, <strong>distrito<\/strong>: Alajuela, <strong>cant\u00f3n<\/strong>: Alajuela, <strong>provincia<\/strong>: Alajuela, Costa Rica. C\u00f3digo postal de la zona: 20101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0gtrnu\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon City Mall Alajuela Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/k93Pi67ZynR2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon City Mall Alajuela Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fonos<\/h2>\n<p><a href=\"tel:+50642005342\">+506 4200-5342<\/a> \/ <a href=\"tel:+50642005341\">+506 4200-5341<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo de 9:00 a.m. a 9:00 p.m<\/p>\n<h1 id=\"distrito4\">Distrito 4<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Distrito 4, <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0scrzh\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Distrito 4 San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/UEVhwuXTM4u\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Distrito 4 San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622280525\">+506 2228-0525<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Jueves de 8:00 a.m. a 9:00 p.m.<br \/>\nViernes y S\u00e1bado de 8:00 a.m. a 10:00 p.m.<br \/>\nDomingo de 8:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"multiplazaescazu\">Multiplaza Escaz\u00fa<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Multiplaza V Etapa <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t4hs8\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Multiplaza San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/qJHYyDd7QSD2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Multiplaza San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062201-5720\">+506 2201-5720<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Domingo a Jueves: 10:00 a.m. a 9:00 p.m.<br \/>\nViernes y S\u00e1bado: 10:00 a.m. a 10:00 p.m.<\/p>\n<h1 id=\"escazuvillage\">Escaz\u00fa Village<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>En Escaz\u00fa Village, contiguo a la helader\u00eda estaci\u00f3n, detr\u00e1s de Walmart. <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t86kz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Escazu Village San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/wpaQc9w3MXN2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Escazu Village San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062208-8815\">+506 2208-8815<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 7:00 a.m. a 8:30 p.m.<\/p>\n<h1 id=\"sabana\">Sabana<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>100 oeste de la Contralor\u00eda, contiguo al AMPM de Sabana <strong>distrito<\/strong>: Mata Redonda, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10108.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t86kz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Sabana en San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/Pvs3twyGXS32\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Sabana en San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062290-3693\">+506 2290-3693<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes de 7:00 a.m. a 8:00 p.m.<br \/>\nS\u00e1bado de 8:00 a.m. a 7:00 p.m.<br \/>\nDomingo 9:00 a.m. a 6:00 p.m.<\/p>\n<h1 id=\"pavas\">Pavas<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Diagonal a Plaza Rohrmoser <strong>distrito<\/strong>: Pavas, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10109.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0tc9e1\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Pavas en San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/wHvjdfhpzVT2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Pavas en San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062296-6165\">+506 2296-6165<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes: 7:00 a.m. a 9:00 p.m.<br \/>\nS\u00e1bado y Domingo: 8:00 a.m. a 8:00 p.m.<\/p>\n<h1 id=\"sanfrancisco\">San Francisco<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>De la Gasolinera NASA, 500 m oeste y 23 m al sur. Centro Comercial Multiflores, <strong>distrito<\/strong>: San Francisco, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0v6zhh\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon San Franscisco de Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/Zzkpj7PMWPo\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon San Francisco de Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622617405\">+506 2261-7405<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Domingo a Jueves: 8:00 a.m. a 9:00 p.m.<br \/>\nViernes y S\u00e1bado: 8:00 a 10:00 p.m.<\/p>\n<h1 id=\"plazaheredia\">Plaza Heredia<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Plaza Heredia, <strong>distrito<\/strong>: Heredia, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0vgxxe\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/Ki9diF1swbq\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062263-2159\">+506 2263-2159<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 9:00 a.m. a 8:00 p.m.<\/p>\n<h1 id=\"paseodelasflores\">Paseo de las Flores<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Paseo de las Flores, <strong>distrito<\/strong>: San Francisco, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0y18ky\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Paseo de las Flores San Francisco Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/zhBsZxvMKKG2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Paseo de las Flores San Francisco Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062237-2980\">+506 2237-2980<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes de 10:00 a.m. a 9:00 p.m.<br \/>\nS\u00e1bado y Domingo de 9:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"realcariari\">Real Cariari<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Real Cariari, <strong>distrito<\/strong>: Ulloa, <strong>cant\u00f3n<\/strong>: Heredia, <strong>provincia<\/strong>: Heredia, Costa Rica. C\u00f3digo postal de la zona: 40104.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0ubuk9\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Real Cariari Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/XpPBk8A4sHz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Real Cariari Heredia Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062589-1232\">+506 2589-1232<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 9:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"clinicabiblica\">Cl\u00ednica B\u00edblica<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Edificio Omega, \u00e1rea del Food Court, sobre Calle 2, entre Avenidas 14 y 16, <strong>distrito<\/strong>: Hospital, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10103.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0qxq97\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Clinica Biblica San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/D6ccE6jVdzn\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Clinica Biblica San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622582741\">+506 2258-2741<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes: 7:00 a.m. a 8:00 p.m.<br \/>\nS\u00e1bado: 7:30 a.m. a 3:00 p.m.<br \/>\nDomingo: Cerrado<\/p>\n<h1 id=\"avenidacentral\">Avenida Central<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>De la Plaza de la Cultura, 25 metros este, sobre avenida central, entre calles 5 y 7 <strong>distrito<\/strong>: Carmen, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0wb3sr\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Avenida Central San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/RFSjxu1vEqn\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Avenida Central San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622238236\">+506 2223-8236<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Viernes de 7:00 a.m. a 8:00 p.m.<br \/>\nS\u00e1bado 9:00 a.m. a 8:00 p.m.<br \/>\nDomingo 10:00 a.m. a 7:00 p.m.<\/p>\n<h1 id=\"callecentral\">Calle Central<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>100 m norte del Teatro Melico Salazar, Avenida central, calle central, <strong>distrito<\/strong>: Merced, <strong>cant\u00f3n<\/strong>: San Jos\u00e9, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10102.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0w8rmt\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon avenida y calle Central San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/krLGeyqQpQo\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon avenida y calle central San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622218851\">+506 2221-8851<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Jueves 6:30 a.m. a 9:00 p.m.<br \/>\nViernes de 6:30 a.m. a 9:00 p.m.<br \/>\nS\u00e1bado de 7:00 a.m a 9:00 p.m.<br \/>\nDomingo de 7:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"yoses\">Yoses<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Del ICE en San Pedro 125 metros oeste, en Plaza Vivo <strong>distrito<\/strong>: San Pedro, <strong>cant\u00f3n<\/strong>: Montes de Oca, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11501.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rpyzq\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Yoses Vivo Plaza San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/oerY1Kf8vpQ2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Yoses Vivo Plaza San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50625241128\">+506 2524-1128<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 7:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"mallsanpedro\">Mall San Pedro<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Mall San Pedro, 2 piso <strong>distrito<\/strong>: San Pedro, <strong>cant\u00f3n<\/strong>: Montes de Oca, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11501.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0x0rv4\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Mall San Pedro Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/j2yhS3hdbV92\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Mall San Pedro Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622834548\">+506 2283-4548<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 10:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"antares\">Plaza Antares<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Plaza Antares, diagonal a la rotonda de La Bandera <strong>distrito<\/strong>: Mercedes, <strong>cant\u00f3n<\/strong>: Montes de Oca, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11503.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0x30rc\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza Antares Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/7FxzM1sxB3k\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza Antares Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622251117\">+506 2225-1117<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo de 9:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"plazalincoln\">Plaza Liconln<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Plaza Liconln, <strong>distrito<\/strong>: San Vicente, <strong>cant\u00f3n<\/strong>: Moravia, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11401.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0xjxuk\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza Liconln San Vicente Moravia San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/5RvgHs7dm532\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza Liconln San Vicente Moravia San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50625199561\">+506 2519-9561<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo de 10:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"plazadelsol\">Plaza del Sol<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Plaza del Sol <strong>distrito<\/strong>: Curridabat, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rx6sf\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Plaza del Sol Curridabat San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/XFFxtmAxBW82\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Plaza del Sol Curridabat San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+50622241304\">+506 2224-1304<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a S\u00e1bado de 9:00 a.m. a 8:00 p.m.<br \/>\nDomingo: 9:30 a.m. a 7:30 p.m.<\/p>\n<h1 id=\"zapote\">Zapote<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Frente al Registro Nacional <strong>distrito<\/strong>: Curridabat, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rmtdd\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Curridabat San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/9gdjVceSZGm\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Curridabat San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fonos<\/h2>\n<p><a href=\"tel:+5062224-7408\">+506 2224-7408<\/a>, <a href=\"tel:+50622832042\">+506 2283-2042<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 7:00 a.m. a 9:30 p.m.<\/p>\n<h1 id=\"multiplazadeleste\">Multiplaza del Este<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Multiplaza del Este, <strong>distrito<\/strong>: Curridabat, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11801.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0rmwch\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Multiplaza del Este San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/uQPWhWmSQEG2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Multiplaza del Este San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062253-4781\">+506 2253-4781<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Domingo a Jueves de 9:00 a.m. a 9:30 p.m.<br \/>\nViernes y S\u00e1bado de 9:00 a.m. a 10:00 p.m.<\/p>\n<h1 id=\"elcristo\">El Cristo<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Contiguo al Cristo de Sabanilla, <strong>distrito<\/strong>: Sabanilla, <strong>cant\u00f3n<\/strong>: Montes de Oca, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11502.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0xfpzz\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon El Cristo Sabanilla Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/pXyug6uNFJr\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon El Cristo Sabanilla Montes de Oca San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fonos<\/h2>\n<p><a href=\"tel:+5062273-4621\">+506 2273-4621<\/a>, <a href=\"tel:+5062273-4711\">+506 2273-4711<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo: 8:00 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"ciudaddeleste\">Ciudad del Este<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>En Centro Comercial Ciudad del Este, calle la marina, contiguo a la Art\u00edstica, <strong>distrito<\/strong>: S\u00e1nchez, <strong>cant\u00f3n<\/strong>: Curridabat, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 11803.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u225u3y\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Ciudad del Este, Sanchez, Curridabat, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/sHbCkkLEbbS2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Ciudad del Este, Sanchez, Curridabat, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5064702-9470\">+506 4702-9470<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a viernes 10:00 am a 10:00 pm<br \/>\nS\u00e1bados y Domingos: 9:00 am a 10:00 pm<\/p>\n<h1 id=\"terramall\">Terramall<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Terramall, <strong>distrito<\/strong>: San Diego, <strong>cant\u00f3n<\/strong>: La Uni\u00f3n, <strong>provincia<\/strong>: Cartago, Costa Rica. C\u00f3digo postal de la zona: 30302.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u22defy\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Terramall, San Diego, La Union, Cartago Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/GfRefX6FWHF2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Terramall, San Diego, La Union, Cartago Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062278-6833\">+506 2278-6833<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Jueves: 10:00 a.m. a 9:00 p.m.<br \/>\nViernes a Domingo de 10:00 a.m. a 10:00 p.m.<\/p>\n<h1 id=\"paseometropoli\">Paseo Metr\u00f3poli<\/h1>\n<h2>Ubicaci\u00f3n<\/h2>\n<p>Centro Comercial Paseo Metr\u00f3poli, <strong>distrito<\/strong>: Guadalupe, <strong>cant\u00f3n<\/strong>: Cartago, <strong>provincia<\/strong>: Cartago, Costa Rica. C\u00f3digo postal de la zona: 30106.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u21u5w2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Spoon Paseo Metropoli, Guadalupe, Cartago Costa Rica\" width=\"50\" height=\"50\" \/><\/a><a href=\"https:\/\/goo.gl\/maps\/DUQEhqucqPM2\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Spoon Paseo Metropoli, Guadalupe, Cartago Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>Tel\u00e9fono<\/h2>\n<p><a href=\"tel:+5062573-3726\">+506 2573-3726<\/a><\/p>\n<h2>Horario<\/h2>\n<p>Lunes a Domingo de 10:30 a.m. a 9:00 p.m.<\/p>\n<h1 id=\"menu\">MEN\u00da<\/h1>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#desayunos\">Desayunos<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#entradas\">Entradas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#sopas\">Sopas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#panarabesywraps\">Pan \u00c1rabes y Wraps<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#sandwiches\">S\u00e1ndwiches<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#casados\">Casados<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#especialidades\">Especialidades<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#ninos\">Ni\u00f1os<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#bebidas\">Bebidas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#blendz\">Blendz<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#frozzenlattes\">Frozzenlattes<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#naturales\">Naturales<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#tortasybocadillos\">Tortas y bocadillos<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#fit\">Fit<\/a><\/p>\n<h1 id=\"desayunos\">desayunos Spoon<\/h1>\n<p><strong>Pan Arabe de Pinto<\/strong>\u00a0\u20a13200<br \/>\nAdicional de natilla por\u00a0\u20a1300.<\/p>\n<p><strong>Hac\u00e9 tu desayuno<\/strong>\u00a0\u20a13100<br \/>\nEscog\u00e9 1 de las siguientes opciones.<\/p>\n<ul>\n<li>Gallo pinto<\/li>\n<li>2 huevos fritos o revueltos. *<\/li>\n<li>Omelette de jam\u00f3n y queso. *<\/li>\n<\/ul>\n<p>* Incluye tostadas.<\/p>\n<p>1 Bebida<\/p>\n<ul>\n<li>Caf\u00e9 negro 8 oz \/ leche 8 oz<\/li>\n<li>Jugo de naranja 8 oz<\/li>\n<li>T\u00e9 negro \/ leche 8 oz<\/li>\n<li>Capuccino 8 oz<\/li>\n<\/ul>\n<p>Agreg\u00e1 un acompa\u00f1amiento por solo\u00a0\u20a1690 adicionales: * queso con tortilla * tostadas * maduros.<\/p>\n<h1>desayunos completos<\/h1>\n<p>Incluyen gallo pinto, tortillas o tostadas, natilla, jugo de naranja 8 oz y caf\u00e9 negro o con leche 8oz. 1 refill incluido en caf\u00e9 negro o con leche.<\/p>\n<p><strong>Desayuno completo con huevos<\/strong>\u00a0\u20a14400<br \/>\nFritos o revueltos.<\/p>\n<p><strong>Desayuno completo con Omelette de Jam\u00f3n y Queso<\/strong>\u00a0\u20a14750<\/p>\n<h2>Omelettes<\/h2>\n<p>\u20a12950 Incluyen tostadas<\/p>\n<p><strong>Vegetariano<\/strong><br \/>\nSolo claras de huevo o huevo entero, mantequilla, chile morr\u00f3n, hongos, queso mozarella, tomate.<\/p>\n<p><strong>Jam\u00f3n y queso<\/strong><\/p>\n<h1 id=\"entradas\">entradas<\/h1>\n<p><strong>Pizza personal de jam\u00f3n y queso<\/strong>\u00a0\u20a11850<\/p>\n<p><strong>Tique\u00f1os con salsa tamarindo<\/strong>\u00a0\u20a12500<br \/>\n5 unidades.<\/p>\n<p><strong>Hummus de Garbanzo<\/strong>\u00a0\u20a12500<\/p>\n<p><strong>Rollos primavera de jam\u00f3n de pavo<\/strong>\u00a0\u20a13250<\/p>\n<p><strong>Rollos primavera de Salm\u00f3n<\/strong>\u00a0\u20a13950<\/p>\n<p><strong>Chifrijo Spoon personal<\/strong>\u00a0\u20a13950<\/p>\n<h1 id=\"sopas\">sopas<\/h1>\n<p><strong>Sopa Mexicana<\/strong>\u00a0\u20a13950<br \/>\nAguacate, pollo, tortilla tostada y queso.<\/p>\n<p><strong>Sopa Negra Estilo Spoon<\/strong>\u00a0\u20a13950<br \/>\nAguacate, huevo duro picado, tortilla tostada y arroz.<\/p>\n<p><strong>Crema de Ayote<\/strong>\u00a0\u20a13950<\/p>\n<p><strong>Crema de tomate<\/strong>\u00a0\u20a13950<\/p>\n<h1 id=\"panarabesywraps\">pan \u00e1rabes y wraps<\/h1>\n<p>\u20a14750 Incluyen papas<\/p>\n<p><strong>Pan \u00c1rabe con Jam\u00f3n de Pavo y Aguacate<\/strong><\/p>\n<p><strong>Pan \u00c1rabe de Falafel y Hummus<\/strong><\/p>\n<p><strong>Wrap Pollo Grill<\/strong><\/p>\n<p>Agreg\u00e1 tu bebida* gaseosa o fruta natural por un precio especial de\u00a0\u20a11300<\/p>\n<p>O tambi\u00e9n pod\u00e9s agregar un blend por un precio especial de \u20a11750<\/p>\n<p>* bebida gaseosa de 16oz o fruta ntaural en agua 16 oz: maracuy&#8217;\u00e1, mora con jengibre, guan\u00e1bana con menta, pitahaya con maracuy\u00e1 o fruta de temporada.<\/p>\n<h1 id=\"sandwiches\">S\u00e1ndwiches<\/h1>\n<p>Incluyen papas bravas<\/p>\n<p><strong>Escog\u00e9 el tama\u00f1o de pan<\/strong>: Baguetinos, Pan Trenza, Pan L\u00e1piz ( grande ).<\/p>\n<p><strong>Jam\u00f3n y Queso<\/strong> baguetino \u20a12000 med\u00a0\u20a13800 gnde\u00a0\u20a14500<\/p>\n<p><strong>Roast Beef<\/strong>\u00a0baguetino \u20a12000 med\u00a0\u20a13800 gnde\u00a0\u20a14500<\/p>\n<p><strong>Pollo<\/strong>\u00a0baguetino \u20a12000 med\u00a0\u20a13800 gnde\u00a0\u20a14500<\/p>\n<p><strong>Pollo y tres quesos<\/strong>\u00a0baguetino \u20a12400 med\u00a0\u20a14300 gnde\u00a0\u20a14950<\/p>\n<h1 id=\"casados\">Casados Spoon<\/h1>\n<p>incluyen bebida: bebida gaseosa de 16 oz o fruta natural en agua 16 oz. Maracuy\u00e1, mora con jengibre, guan\u00e1bana con menta, pitahaya con maracuy\u00e1 o fruta de temporada.<\/p>\n<p><strong>Carne mechada<\/strong>\u00a0\u20a15450<br \/>\nArroz, frijoles, pl\u00e1tanos maduros, picadillo de pl\u00e1tano con chorizo, ensalada verde y bebida.<\/p>\n<p><strong>Fajitas de pollo<\/strong>\u00a0\u20a15550<br \/>\nArroz, frijoles, pl\u00e1tanos maduros, picadillo de pl\u00e1tano con chorizo, ensalada verde y bebida.<\/p>\n<p><strong>Pescado<\/strong>\u00a0\u20a15550<br \/>\nArroz, frijoles, pl\u00e1tanos maduros, picadillo de pl\u00e1tano con chorizo, ensalada verde y bebida.<\/p>\n<p><strong>Casado de arroz con pollo<\/strong>\u00a0\u20a15450<br \/>\nAcompa\u00f1ado de papas bravas, frijoles molidos, pl\u00e1tanos maduros y ensalada verde.<\/p>\n<p><strong>Chifrijo Spoon Grande<\/strong>\u00a0\u20a15950<br \/>\nIncluye bebida<\/p>\n<h1 id=\"especialidades\"><em>especialidades<\/em><\/h1>\n<p>2 acompa\u00f1amientos, 1 de cada tipo: guarnici\u00f3n vegetales, papas, ensalada verde, pur\u00e9 de papa, arroz blanco.<\/p>\n<p><strong>Pescado a la Plancha<\/strong>\u00a0\u20a15950<\/p>\n<p><strong>Pechugas Rellenas<\/strong>\u00a0\u20a17150<\/p>\n<p><strong>Salm\u00f3n en salsa lim\u00f3n, alcaparras y eneldo<\/strong>\u00a0\u20a18650<\/p>\n<p><strong>Lomito en Salsa de Hongos<\/strong>\u00a0\u20a18950<\/p>\n<p><strong>Punta de Lomito Salteadas<\/strong>\u00a0\u20a19250<\/p>\n<p><strong>Ravioli espinaca y ricotta en salsa de tomate<\/strong>\u00a0\u20a15950<\/p>\n<p><strong>Arroz con palmito<\/strong>\u00a0\u20a15950<\/p>\n<p><strong>Lasagna de Pollo con Salsa Blanca<\/strong>\u00a0\u20a15950<\/p>\n<p><strong>Lasagna de Carne<\/strong>\u00a0\u20a15950<\/p>\n<p>Agreg\u00e1 tu bebida* gaseosa o fruta natural por un precio especial de\u00a0\u20a11300<\/p>\n<p>O tambi\u00e9n pod\u00e9s agregar un blend por un precio especial de \u20a11750<\/p>\n<p>* bebida gaseosa de 16oz o fruta ntaural en agua 16 oz: maracuy&#8217;\u00e1, mora con jengibre, guan\u00e1bana con menta, pitahaya con maracuy\u00e1 o fruta de temporada.<\/p>\n<h1 id=\"ninos\">men\u00fa infantil<\/h1>\n<p>\u20a14400 Incluyen papas fritas**, alfajo y refreso natural o gaseosa.<\/p>\n<ol>\n<li>Pizza personal.<\/li>\n<li>* Deditos de pescado.<\/li>\n<li>Pechuga a la plancha<\/li>\n<\/ol>\n<p>* Por naturaleza este producto podr\u00eda tener fragmentos de espinas.<br \/>\n** Pod\u00e9s cambiarlo por pur\u00e9 de papa o arroz blanco.<\/p>\n<h1 id=\"bebidas\">bebidas<\/h1>\n<h2>caf\u00e9s<\/h2>\n<p><strong>Caf\u00e9 Espresso<\/strong>\u00a0\u20a11000<\/p>\n<p><strong>Caf\u00e9 Espresso doble<\/strong>\u00a0\u20a11400<\/p>\n<p><strong>Caf\u00e9 filtrado 8 oz negro o en leche<\/strong>\u00a0\u20a11500<\/p>\n<p><strong>Capuccino 8 oz<\/strong>\u00a0\u20a11700<\/p>\n<p><strong>Latte 8 oz<\/strong>\u00a0\u20a11800<br \/>\nTradicional, Mocha, Caramel, Vainilla, Vainilla Light, Crema Irlandesa<\/p>\n<p><strong>Coconut Mocha 12 oz<\/strong>\u00a0\u20a12250<\/p>\n<h1>t\u00e9s<\/h1>\n<h2>Calientes<\/h2>\n<p><strong>T\u00e9 Negro 8 oz<\/strong>\u00a0\u20a11400<\/p>\n<p><strong>T\u00e9 con Leche 8 oz<\/strong>\u00a0\u20a11500<\/p>\n<p><strong>T\u00e9 de Sabores 8 oz<\/strong>\u00a0\u20a11500<\/p>\n<p><strong>T\u00e9 Chai 12 oz<\/strong>\u00a0\u20a12200<\/p>\n<h2>Fr\u00edos<\/h2>\n<p><strong>T\u00e9 Frutos Rojos 16 oz<\/strong>\u00a0\u20a11650<\/p>\n<h2>bebidas calientes<\/h2>\n<p><strong>Chocolate 8 oz<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Chocolate 12 oz<\/strong>\u00a0\u20a12200<\/p>\n<p><strong>Chocolate 12 oz<\/strong>\u00a0\u20a12650<\/p>\n<h1 id=\"blendz\">blendz 16 oz<\/h1>\n<p><strong>Sand\u00eda con lim\u00f3n<\/strong>\u00a0\u20a11900<\/p>\n<p><strong>Limon con Hierbabuena<\/strong>\u00a0\u20a12225<\/p>\n<p><strong>Manzana verde con albahaca<\/strong>\u00a0\u20a12225<\/p>\n<p><strong>Mango, maracuy\u00e1 y naranja<\/strong>\u00a0\u20a12375<\/p>\n<p><strong>Frutas Mixtas<\/strong>\u00a0\u20a12375<\/p>\n<p><strong>Mandarina<\/strong>\u00a0\u20a12450<\/p>\n<h1 id=\"frozzenlattes\">frozzenlattes<\/h1>\n<p>a base de caf\u00e9<\/p>\n<p><strong>Cappuccino Frozzen 10 oz<\/strong>\u00a0\u20a11700<\/p>\n<p><strong>Capuccino Frozzen 16 oz<\/strong>\u00a0\u20a12700<\/p>\n<h2>bebidas naturales en agua<\/h2>\n<p><strong>Pitahaya con maracuy\u00e1<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Guan\u00e1bana con menta<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Mora con Jengibre<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Fruta de Temporada<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Maracuy\u00e1<\/strong>\u00a0\u20a11800<\/p>\n<h2>otros<\/h2>\n<p><strong>Agua destilada<\/strong>\u00a0\u20a11125<\/p>\n<p><strong>T\u00e9 fr\u00edo 16 oz<\/strong>\u00a0\u20a11500<\/p>\n<p><strong>Jugo de Naranja 12 oz<\/strong>\u00a0\u20a11650<\/p>\n<p><strong>Soda italiana de frutos silvestres<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Refresco Gaseoso 16 oz<\/strong>\u00a0\u20a11800<\/p>\n<p><strong>Gaseosa en botella 600ml<\/strong>\u00a0\u20a11900<\/p>\n<h1 id=\"tortasybocadillos\">tortas y bocadillos<\/h1>\n<h2>porci\u00f3n de postres<\/h2>\n<p><strong>Flan de coco<\/strong>\u00a0\u20a12250<\/p>\n<p><strong>Flan de Tres Leches<\/strong>\u00a0\u20a12950<\/p>\n<p><strong>Pie de Lim\u00f3n<\/strong>\u00a0\u20a12950<\/p>\n<p><strong>Tres Leches<\/strong>\u00a0\u20a12950<\/p>\n<h2>porci\u00f3n de cheese cake fr\u00edo<\/h2>\n<p><strong>Maracuy\u00e1 <span style=\"color: #00ccff;\">fit<\/span><\/strong>\u00a0\u20a12950<\/p>\n<p><strong>Fresas<\/strong>\u00a0\u20a12950<\/p>\n<h2>tortas y queques<\/h2>\n<p><strong>Melocot\u00f3n<\/strong>\u00a0\u20a13200<\/p>\n<p><strong>Churchill<\/strong>\u00a0\u20a13200<\/p>\n<p><strong>Chilena<\/strong>\u00a0\u20a13200<\/p>\n<p><strong>Zanahoria<\/strong>\u00a0\u20a13300<\/p>\n<p><strong>Yogurt y Berries\u00a0<\/strong>\u20a11500<\/p>\n<p><strong>Chocolate<\/strong>\u00a0\u20a13300<\/p>\n<p><strong>Chocofresa<\/strong>\u00a0\u20a13300<\/p>\n<h2>queque seco<\/h2>\n<p><strong>Seco con Pasas<\/strong>\u00a0\u20a11750<\/p>\n<p><strong>Seco Lim\u00f3n<\/strong>\u00a0\u20a11750<\/p>\n<p><strong>Seco Zanahoria<\/strong>\u00a0\u20a11850<\/p>\n<h2>bocadillos salados<\/h2>\n<p><strong>Empanadas Peque\u00f1as<\/strong>\u00a0\u20a1825<br \/>\nPollo \/ Tres quesos<\/p>\n<p><strong>Arrollado de Jam\u00f3n<\/strong>\u00a0\u20a1850<\/p>\n<p><strong>Pa\u00f1uelo de espinaca y queso<\/strong>\u00a0\u20a1850<\/p>\n<p><strong>Sombrero de Palmito<\/strong>\u00a0\u20a1850<\/p>\n<p><strong>Enchilada de papa y carne<\/strong>\u00a0\u20a1875<\/p>\n<p><strong>Pastel de Esp\u00e1rragos<\/strong>\u00a0\u20a1875<\/p>\n<p><strong>Empanadas grandes<\/strong>\u00a0\u20a11465<br \/>\nPollo &#8211; Pollo y Hongos &#8211; Carne<\/p>\n<p><strong>Pastel personal palmito<\/strong>\u00a0\u20a11650<\/p>\n<p><strong>Arreglado de Carne<\/strong>\u00a0\u20a12700<\/p>\n<h2>bocadillos dulces<\/h2>\n<p><strong>Alfajor mini<\/strong>\u00a0\u20a1700<\/p>\n<p><strong>Arrollado de leche condensada mini<\/strong>\u00a0\u20a1700<\/p>\n<p><strong>Chicloso<\/strong>\u00a0\u20a1700<\/p>\n<p><strong>Canastitas<\/strong>\u00a0\u20a1700<br \/>\nLim\u00f3n, fresa o cereza.<\/p>\n<p><strong>Tartaleta de manzana<\/strong>\u00a0\u20a1725<\/p>\n<p><strong>Costilla de Leche Condensada<\/strong>\u00a0\u20a1825<\/p>\n<p><strong>Alfajor Mediano<\/strong>\u00a0\u20a1885<\/p>\n<p><strong>Cajeta<\/strong>\u00a0\u20a1885<\/p>\n<p><strong>Cocada<\/strong>\u00a0\u20a1885<\/p>\n<p><strong>Tartaleta<\/strong>\u00a0\u20a11325<br \/>\nLim\u00f3n, fresa o cereza.<\/p>\n<p><strong>Brownie de fudge<\/strong>\u00a0\u20a11390<\/p>\n<p><strong>Crocante de Nuez<\/strong>\u00a0\u20a11900<\/p>\n<h1>Spoon Coffee Time<\/h1>\n<p>Por\u00a0\u20a1400 agranda tu Cappuccino a 12 oz.<\/p>\n<p><strong>Capuccino 8 oz + Porci\u00f3n de queque seco<\/strong>\u00a0\u20a12370<\/p>\n<p><strong>Cappuccino 8 oz + 2 bocadillos peque\u00f1os \u00f3 1 bocadillo grande<\/strong>\u00a0\u20a12450<br \/>\n<span style=\"letter-spacing: 0.05em;\">Promoci\u00f3n v\u00e1lida para bocadillos seleccionados, ver condiciones en punto de venta.<\/span><\/p>\n<p><strong>Cappuccino 8 oz + Arreglado<\/strong>\u00a0\u20a13100<br \/>\nIncluye 1 refill de caf\u00e9 negro o con leche.<\/p>\n<h1 id=\"fit\"><span style=\"color: #00ccff;\">men\u00fa fit<\/span><\/h1>\n<p>Si est\u00e1s buscando una opci\u00f3n baja en calor\u00edas, te presentamos el men\u00fa fit avalado por nuestra nutricionista Kathryn Von Saalfeld. Todos estos productos contienen 550 kcal o menos.<\/p>\n<p><strong>Omelette Vegetariano<\/strong><br \/>\n430 kcal ( 2 carb + 1\/2 veg + 3 prot + 2 gr )<\/p>\n<p><strong>Sopa Mexicana<\/strong><br \/>\n440 kcal ( 2 1\/2 carb + 1 veg + 2 1\/2 prot + 2 1\/2 gr )<\/p>\n<p><strong>Sopa Negra<\/strong><br \/>\n470 kcal ( 3 1\/2 carb + 1 veg + 1\/2 prot + 3 gr )<\/p>\n<p><strong>Rollo Primavera de Jam\u00f3n de Pavo<\/strong><br \/>\n220 kcal ( 1 carb + 1 veg + 1 oz prot + 1 gr )<\/p>\n<p><strong>Rollos Primavera de Salm\u00f3n<\/strong><br \/>\n245 kcal ( 2 carb + 1\/2 veg + 1\/2 prot + 1 gr )<\/p>\n<p><strong>Wrap de Pollo Grill ( con aderezo liviano )<br \/>\n<\/strong>Convert\u00ed en opci\u00f3n fit al cambiar tus papas al romero por ensalada personal ( sin papa rallada ni aderezo )<br \/>\n545 kcal ( 3 1\/2 carb + 3 veg + 2 prot + 2 gr )<\/p>\n<p><strong>Pan \u00c1rabe con Jam\u00f3n de Pavo y Aguacate<br \/>\nConvert\u00ed en opci\u00f3n fit al cambiar tus papas al romero por ensalada personal ( sin papa rallada ni aderezo )<\/strong><br \/>\n465 kcal ( 2 1\/2 carb + 3 prot + 2 veg + 2 gr )<\/p>\n<p><strong>Ensalada Mediterr\u00e1nea con Quinoa y Pollo *<\/strong><br \/>\n385 kcal ( 1 carb + 3 1\/2 prot + 2 veg + 1gr )<\/p>\n<p><strong>Ensalada de Pollo Grill<\/strong><br \/>\nSin chaoming. 280 kcal ( 4 prot + 1 veg + 1gr )<\/p>\n<p><strong>T\u00e9 fr\u00edo<\/strong>\u00a05 kcal ( libre )<\/p>\n<p><b>Limonada con hierbabuena<\/b>\u00a05 kcal ( libre )<\/p>\n<p><strong>Mora con Jengibre<\/strong>\u00a045 kcal ( 1 frut )<\/p>\n<p><strong>Guan\u00e1bana con Menta<\/strong>\u00a0100 kcal ( 1 1\/2 libre )<\/p>\n<p><strong>Pitahaya con Maracuy\u00e1<\/strong>\u00a0160 kcal ( 2 1\/2 frut )<\/p>\n<p><em>Estas bebidas pueden considerarse como opci\u00f3n fit, siempre y cuando se soliciten sin az\u00facar o con el edulcorante de su gusto.<\/em><\/p>\n<p><strong>Cheesecake de Maracuy\u00e1 ( porci\u00f3n )<\/strong><br \/>\n190 kcal ( 1\/2 carb + 1 frut + 1\/2 lact + 1gr )<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel\u00e9fono Servicio a Domicilio ( express ) +506 2259-6000 MEN\u00da Ubicaciones ALAJUELA: Plaza Real &#8211; City Mall &#8211; SAN JOS\u00c9: Los Laureles &#8211; Distrito 4 &#8211; Multiplaza Escaz\u00fa &#8211; Escaz\u00fa Village &#8211; Sabana &#8211; Pavas &#8211; Cl\u00ednica B\u00edblica &#8211; Avenida Central &#8211; Calle Central &#8211; Yoses &#8211; Mall San Pedro &#8211; Antares &#8211; Plaza Lincoln &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Spoon\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#more-6858\" aria-label=\"Leer m\u00e1s sobre Spoon\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[87,113,207,172,212,98,176,148,143,218,111,99,134,220,150,78,8,39,160,102,69,175,28,221,3,208,222,173,224,171,170,149,40,219,223,151,26,53,177,217,159],"tags":[251],"class_list":["post-6858","post","type-post","status-publish","format-standard","hentry","category-87","category-113","category-207","category-172","category-212","category-98","category-176","category-148","category-143","category-218","category-111","category-99","category-134","category-220","category-150","category-78","category-alajuela","category-cafe","category-carmen-san-jose","category-cartago","category-curridabat","category-desamparados","category-escazu","category-guadalupe-cartago","category-heredia","category-hospital","category-la-union","category-mata-redonda","category-merced","category-mercedes","category-montes-de-oca","category-moravia","category-pavas","category-sabanilla-montes-de-oca","category-san-diego","category-san-francisco","category-san-jose","category-san-pedro","category-san-rafael-escazu","category-san-vicente","category-sanchez","tag-san-jose-costa-rica-restaurantes","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google<\/title>\n<meta name=\"description\" content=\"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google\" \/>\n<meta property=\"og:description\" content=\"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-02T12:35:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T10:13:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Spoon\",\"datePublished\":\"2018-09-02T12:35:04+00:00\",\"dateModified\":\"2023-03-21T10:13:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/\"},\"wordCount\":2424,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/spoon-costa-rica.png\",\"keywords\":[\"San Jose Costa Rica Restaurantes\"],\"articleSection\":[\"10101\",\"10102\",\"10103\",\"10108\",\"10109\",\"10203\",\"10301\",\"11401\",\"11501\",\"11502\",\"11801\",\"11803\",\"20101\",\"30106\",\"40103\",\"40104\",\"Alajuela\",\"Caf\u00e9\",\"Carmen\",\"Cartago\",\"Curridabat\",\"Desamparados\",\"Escaz\u00fa\",\"Guadalupe\",\"Heredia\",\"Hospital\",\"La Uni\u00f3n\",\"Mata Redonda\",\"Merced\",\"Mercedes\",\"Montes de Oca\",\"Moravia\",\"Pavas\",\"Sabanilla\",\"San Diego\",\"San Francisco\",\"San Jos\u00e9\",\"San Pedro\",\"San Rafael\",\"San Vicente\",\"S\u00e1nchez\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/\",\"name\":\"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/spoon-costa-rica.png\",\"datePublished\":\"2018-09-02T12:35:04+00:00\",\"dateModified\":\"2023-03-21T10:13:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/spoon-costa-rica.png?fit=323%2C125&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/spoon-costa-rica.png?fit=323%2C125&ssl=1\",\"width\":323,\"height\":125,\"caption\":\"Spoon Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/spoon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spoon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google","description":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","og_locale":"es_ES","og_type":"article","og_title":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google","og_description":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2018-09-02T12:35:04+00:00","article_modified_time":"2023-03-21T10:13:51+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"23 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Spoon","datePublished":"2018-09-02T12:35:04+00:00","dateModified":"2023-03-21T10:13:51+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/"},"wordCount":2424,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png","keywords":["San Jose Costa Rica Restaurantes"],"articleSection":["10101","10102","10103","10108","10109","10203","10301","11401","11501","11502","11801","11803","20101","30106","40103","40104","Alajuela","Caf\u00e9","Carmen","Cartago","Curridabat","Desamparados","Escaz\u00fa","Guadalupe","Heredia","Hospital","La Uni\u00f3n","Mata Redonda","Merced","Mercedes","Montes de Oca","Moravia","Pavas","Sabanilla","San Diego","San Francisco","San Jos\u00e9","San Pedro","San Rafael","San Vicente","S\u00e1nchez"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/","name":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Ubicaciones WAZE y mapas de Google","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png","datePublished":"2018-09-02T12:35:04+00:00","dateModified":"2023-03-21T10:13:51+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Spoon - Men\u00fa, Horario, Tel\u00e9fonos, Direcciones, Ubicaciones WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/spoon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?fit=323%2C125&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/spoon-costa-rica.png?fit=323%2C125&ssl=1","width":323,"height":125,"caption":"Spoon Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/spoon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Spoon"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s5i3XU-spoon","jetpack-related-posts":[{"id":3745,"url":"https:\/\/costaricainfolink.com\/restaurantes\/cosi-costa-rica\/","url_meta":{"origin":6858,"position":0},"title":"Restaurante Cos\u00ec","author":"Restaurantes Costa Rica","date":"8 mayo 2014","format":false,"excerpt":"Men\u00fa Restaurante Cos\u00ec Restaurante Cos\u00ec Multiplaza Escaz\u00fa: Direcci\u00f3n: centro comercial Multiplaza en Escaz\u00fa, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Coordenadas para GPS: 9.944760,-84.152504 (9\u00b056'41.13\"N, 84\u00b009'09.01\"W) Tel\u00e9fono: +506 4031-6441 Horario: De Domingo a Jueves de 11 a.m. a 9 p.m. Viernes y S\u00e1bado\u2026","rel":"","context":"En \u00ab11503\u00bb","block_context":{"text":"11503","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/11503\/"},"img":{"alt_text":"Restaurante Cos\u00ec Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2014\/05\/restaurante-cosi-costa-rica-logo-e1399074442747.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5398,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-modesta\/","url_meta":{"origin":6858,"position":1},"title":"La Modesta","author":"Restaurantes Costa Rica","date":"20 febrero 2017","format":false,"excerpt":"NEGOCIO CERRADO Tel\u00e9fono: +506 7293-7360 Horario: De Lunes a Viernes de 9am a 7pm. S\u00e1bados de 9am a 1pm. Domingo cerrado. Direcci\u00f3n De la salida a Multiplaza Escaz\u00fa en la autopista Prospero Fern\u00e1ndez, 800 mts norte frente a Crossfit 506, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante La Modesta, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/restaurante-la-modesta-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1245,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tacobar\/","url_meta":{"origin":6858,"position":2},"title":"TacoBar","author":"Restaurantes Costa Rica","date":"22 julio 2012","format":false,"excerpt":"Restaurante TacoBar en Santa Ana: Ubicaci\u00f3n: 350m al norte de la Cruz Roja, frente de Mas x Menos en Santa Ana, distrito: Santa Ana, cant\u00f3n: Santa Ana, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10901. Coordenadas para GPS: 9.937425,-84.188756 (9\u00b056'14.73\"N, 84\u00b011'19.52\"W) Tel\u00e9fono: +506 2282-4863 Horario: de Lunes\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/01\/taco-bar-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1788,"url":"https:\/\/costaricainfolink.com\/restaurantes\/gelateria-da-noi\/","url_meta":{"origin":6858,"position":3},"title":"Gelateria Da Noi","author":"Restaurantes Costa Rica","date":"27 agosto 2012","format":false,"excerpt":"Click the following link to read this page in English: Da Noi Gelateria El Caf\u00e9 y Gelateria Da Noi, que significa \u201cDonde nosotros\u201d en italiano, es una gelater\u00eda artesanal italiana que abri\u00f3 sus puertas en el a\u00f1o 2008 en San Jos\u00e9, gracias al sue\u00f1o de Elena Barnab\u00f3 y Marcello Polinaris,\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Gelateria Da Noi en Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/da-noi-gelateria-cafe-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9067,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bottega-privee\/","url_meta":{"origin":6858,"position":4},"title":"Bottega Priv\u00e9e","author":"Restaurantes Costa Rica","date":"15 noviembre 2020","format":false,"excerpt":"Horario De Lunes a Viernes de 12md a 9pm. Sabados y Domingos de 12md a 7pm. Bottega Priv\u00e9e Escaz\u00fa Tel\u00e9fono: +506 4001-7752 Direcci\u00f3n: en Momemtum Escaz\u00fa, sobre ruta 27, frente a Multiplaza. Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. \u00a0\u00a0 Bottega\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante Italiano Bottega Privee en Escazu, Pinares y City Mall","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/11\/restaurante-italiano-bottega-privee-escazu-pinares-city-mall-costa-rica-1-300x292.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6157,"url":"https:\/\/costaricainfolink.com\/restaurantes\/plaza-espana\/","url_meta":{"origin":6858,"position":5},"title":"Restaurante Plaza Espa\u00f1a","author":"Restaurantes Costa Rica","date":"10 diciembre 2017","format":false,"excerpt":"Ubicaci\u00f3n: De la Iglesia Cat\u00f3lica 300 metros oeste y 100 Sur. Distrito: San Antonio, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10202. Horario: Martes, Mi\u00e9rcoles y Jueves de 6pm a 1030 pm. Viernes de 12md a 3pm y de 6pm a 1030pm. S\u00e1bado de 12md\u2026","rel":"","context":"En \u00ab10202\u00bb","block_context":{"text":"10202","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10202\/"},"img":{"alt_text":"Restaurante Plaza Espa\u00f1a en San Antonio, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/12\/restaurante-plaza-espana-san-antonio-escazu-san-jose-costa-rica-1-300x145.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=6858"}],"version-history":[{"count":83,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6858\/revisions"}],"predecessor-version":[{"id":11978,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/6858\/revisions\/11978"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=6858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=6858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=6858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}