{"id":7178,"date":"2018-11-14T22:15:32","date_gmt":"2018-11-15T03:15:32","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/?p=7178"},"modified":"2023-02-14T07:59:56","modified_gmt":"2023-02-14T12:59:56","slug":"outback-steakhouse","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/","title":{"rendered":"Outback Steakhouse Costa Rica"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7189\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&amp;ssl=1\" data-orig-size=\"610,260\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Restaurante Outback Steakhouse en Plaza Itskatzu San Rafael, Escazu, San Jose, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&amp;ssl=1\" class=\"alignright wp-image-7189\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?resize=399%2C170&#038;ssl=1\" alt=\"Restaurante Outback Steakhouse en Plaza Itskatzu San Rafael, Escazu, San Jose, Costa Rica\" width=\"399\" height=\"170\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?w=610&amp;ssl=1 610w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?resize=300%2C128&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?resize=560%2C239&amp;ssl=1 560w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?resize=260%2C111&amp;ssl=1 260w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?resize=160%2C68&amp;ssl=1 160w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<h1>Horario<\/h1>\n<p>De Domingo a Mi\u00e9rcoles de 11am a 1030pm.<br \/>\nDe Jueves a S\u00e1bado de 11am a 11pm.<\/p>\n<h1>Tel\u00e9fono:<br \/>\n<a href=\"tel:+50640000247\">+506 4000-0247<\/a><\/h1>\n<h1>Direcci\u00f3n<\/h1>\n<p>Plaza Itskatz\u00fa, <strong>distrito<\/strong>: San Rafael, <strong>cant\u00f3n<\/strong>: Escaz\u00fa, <strong>provincia<\/strong>: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t4nn9\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Outback Steakhouse Plaza Itskatzu San Rafael Escazu San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a><a href=\"https:\/\/goo.gl\/maps\/LWgooU9akps\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Outback Steakhouse Plaza Itskatzu San Rafael Escazu San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<h1>Men\u00fa<\/h1>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#aussietizers\">aussietizers<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#salads\">salads<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#steaks\">steaks<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#favorites\">favorites<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#combos\">combos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#fromthesea\">from the sea<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#soupsandsides\">soups and sides<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#sandwichesandhandhelds\">sandwiches and handhelds<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#desserts\">desserts<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#kidsmenu\">kids menu<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#happyhour\">happy hour<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#beer\">beer<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#cocktails\">cocktails<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#beverages\">beverages<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#butchercuts\">butcher cuts<\/a><\/p>\n<h2 id=\"aussietizers\">AussieTizers<\/h2>\n<p><strong>Bloomin&#8217; Onion<\/strong> \u20a14900<br \/>\nLa original de Outback. Nuestra cebolla especial tallada a mano, cocinada hasta dorar y lista para sumergir en nuestro aderezo especial bloom. <em>*Sujeto a disponibilidad.<\/em><\/p>\n<p><strong>Beef Carpaccio<\/strong>&nbsp;1.5oz \u20a14900 4.5oz \u20a19900<br \/>\nFinas lonjas de res acompa\u00f1adas de salsa chimichurri y queso parmesano. Servido con una ensalada de ar\u00fagula y tostadas de ajonjol\u00ed.<\/p>\n<p><strong>Aussie Cheese Fries<\/strong>&nbsp;Orden regular \u20a16900 Orden peque\u00f1a \u20a14900<br \/>\nPapas Aussie cubiertas con quesos Monterrey Jack y Cheddar, pedacitos de tocino y servidas con aderezo ranch.<\/p>\n<p><strong>BBQ Mini Ribs<\/strong>&nbsp;\u20a19900<br \/>\nCostillas ahumadas y cocidas, ba\u00f1adas con salsa barbacoa asi\u00e1tica y rociadas con semillas de ajonjol\u00ed. Servidas con Papas Aussie.<\/p>\n<p><strong>Coconut Shrimp<\/strong>&nbsp;\u20a18900<br \/>\nCamarones cubiertos con coco rallado, fritos hasta dorar. Servidos con nuestra mermelada especial de naranja.<\/p>\n<p><strong>Kookabura Wings<\/strong>&nbsp;Orden Regular \u20a19900 Orden Peque\u00f1a&nbsp;\u20a16900<br \/>\nAlitas de pollo sazonadas en una mezcla de especias secretas y servidas con nuestro cremoso aderezo Blue Cheese, bastones de apio y zanahoria. Se pueden pedir con salsa suave, media o picante.<\/p>\n<p><strong>Crispy Fried Mushrooms<\/strong>&nbsp;\u20a16900<br \/>\nHongos ligeramente empanizados y fritos, servidos con aderezo ranch picante.<\/p>\n<p><strong>Crispy Calamari<\/strong>&nbsp;\u20a18900<br \/>\nCalamares sazonados, ligeramente empanizados y fritos hasta un dorado tierno y crujiente. Servidos con salsa marinara.<\/p>\n<p><strong>Grilled Shrimp on the Barbie<\/strong>&nbsp;\u20a18900<br \/>\nCamarones ligeramente condimentados y cocidos delicadamente a la parrilla. Servidos con aderezo remoulade.<\/p>\n<p><strong>Shrimp and Avocado Ceviche<\/strong>&nbsp;\u20a16900<br \/>\nCamarones, aguacate, cebolla, tomate y culantro marinado en jugo de lim\u00f3n fresco. Decorado con jalape\u00f1os y servido con tortillas de ma\u00edz y lim\u00f3n fresco.<\/p>\n<h1 id=\"salads\">Signature Salads<\/h1>\n<p><strong>Caesar Salad<\/strong><br \/>\nCrujiente lechuga romana y crotones reci\u00e9n hechos, con nuestro aderezo Caesar de la casa acompa\u00f1ado con la opci\u00f3n de su preferncia.<\/p>\n<ul>\n<li><strong>Camarones a la parrilla<\/strong>&nbsp;\u20a19900<\/li>\n<li><strong>Pollo a la Parrilla<\/strong>&nbsp;\u20a17900<\/li>\n<li><strong>Sirloin<\/strong>&nbsp;\u20a19900<\/li>\n<li><strong>Salm\u00f3n<\/strong>&nbsp;\u20a16900<\/li>\n<\/ul>\n<p><strong>Aussie Chicken Cobb Salad<\/strong>&nbsp;\u20a17900<br \/>\nPechuga de pollo a la parrilla o empanizada a mano, dorada y crujiente. Sobre una cama de lechuga, queso Monterrey Jack y Cheddar, tocino, huevo, tomate, crotones y servido con el aderezo de su elecci\u00f3n.<\/p>\n<p><strong>Tropical Mango Chicken Salad<\/strong>&nbsp;\u20a18900<br \/>\nLechugas mixtas, zanahoria, tomate, huevo, quesos mixtos y pepinos. Acompa\u00f1ado de una pechuga de pollo en trozos, mango fresco y tiras crujientes de tortilla. Servido con su elecci\u00f3n de aderezo.<\/p>\n<p><strong>Steakhouse Salad<\/strong>&nbsp;\u20a18900<br \/>\nSirloin sellado con una ensalada verde mixta, pasta Aussie Crunch, tomate, cebolla morada, pecanas con canela y vinagreta de Blue Cheese.<\/p>\n<h1 id=\"steaks\">Signature Steaks<\/h1>\n<p>Agregue una ensalada de la Casa o Caesar por&nbsp;\u20a12900<\/p>\n<p><strong>Outback Special<\/strong><br \/>\nNuestro Sirloin especial es sazonado con especias de la casa y sellado a la perfecci\u00f3n.<\/p>\n<ul>\n<li><strong>6 oz<\/strong>&nbsp;\u20a110900<\/li>\n<li><strong>8 oz<\/strong>&nbsp;\u20a113900<\/li>\n<li><strong>12 oz<\/strong>&nbsp;\u20a116900<\/li>\n<\/ul>\n<p><strong>Ribeye<\/strong>&nbsp;12oz \u20a118900<br \/>\nEl corte de los amantes de la carne de res. Balanceado y jugoso. Escoja su opci\u00f3n de cocci\u00f3n, a la parrilla o sazonado a la plancha.<\/p>\n<p><strong>Prime Rib<\/strong>&nbsp;10 oz \u20a116900 12&nbsp;oz \u20a119900<br \/>\nUn corte a mano Prime Rib sazonado y sellado a la perfecci\u00f3n. O pida nuestro Prime Rib asado original. Servidos con nuestro traidicionla au jus.<\/p>\n<p><strong>VIctoria&#8217;s Filet<\/strong>&nbsp;10 oz \u20a116900 8&nbsp;oz \u20a120900<br \/>\nEl m\u00e1s tierno y jugoso filete de corte grueso.<\/p>\n<p><strong>New York Strip<\/strong>&nbsp;12&nbsp;oz \u20a117900<br \/>\nUn corte grueso tipo New York Strip sellado con nuestro sazonador secreto.<\/p>\n<p><strong>Arrachera<\/strong>&nbsp;10 oz \u20a117900<br \/>\nChurrasco estilo mexicano sazonado y tierno, cocido a la parrilla y servido con salsa chimichurri.<\/p>\n<p><strong>Le gustar\u00eda un corte m\u00e1s grande? Pregunte por nuestra disponibilidad.<\/strong><\/p>\n<h2>ADD-ONS<\/h2>\n<p><strong>Cola de Langosta<\/strong>&nbsp;\u20a19900<\/p>\n<p><strong>Cebollas Salteadas<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Blue Cheese<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Hongos Salteados<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Salsa Chimichurri<\/strong>&nbsp;\u20a11600<\/p>\n<p><strong>Camarones a la parrilla<\/strong>&nbsp;\u20a15900<\/p>\n<h1 id=\"favorites\">Outback Favorites<\/h1>\n<p><strong>Alice Springs Chicken<\/strong>&nbsp;\u20a19900<br \/>\nPechuga de pollo a la parrilla con hongos salteados, fajitas de tocino, quesos Monterrey Jack y Cheddar derretidos encima, acompa\u00f1ada de salsa mostaza miel. Servida con Papas Aussie.<\/p>\n<p><strong>BBQ Ribs<\/strong>&nbsp;Orden Regular \u20a117900 Orden Grande \u20a117900<br \/>\nCostillas suculentas y jugosas, cada una fue ahumada y cocida a la perfecci\u00f3n con nuestra salsa barbacoa especial. Servidas con Papas Aussie.<\/p>\n<p><strong>Fajitas<\/strong><br \/>\nSazonadas y a la parrilla, servidas en un sart\u00e9n caliente sobre una cama de chile dulce y cebolla. Acompa\u00f1adas de quesos Monterrey Jack y Cheddar, natilla, pico de gallo de aguacate, torillas y arroz piaf.<\/p>\n<ul>\n<li><strong>Pollo<\/strong> \u20a19900<\/li>\n<li><strong>Churrasco<\/strong>&nbsp;\u20a113900<\/li>\n<li><strong>Camar\u00f3n<\/strong> \u20a112900<\/li>\n<li><strong>Mixto<\/strong> \u20a112900<\/li>\n<\/ul>\n<p><strong>Toowoomba Pasta<\/strong>&nbsp;\u20a19900<br \/>\nCamarones a la parrilla, hongos y queso parmesano con pasta fetuccini y una liviana salsa cremosa de queso parmesano.<\/p>\n<p><strong>Chicken on the Barbie<\/strong>&nbsp;\u20a18900<br \/>\nPechuga de pollo sazonada a la parrilla, servida con salsa barbacoa y vegetales al vapor.<\/p>\n<p><strong>No Rules Pasta<\/strong>&nbsp;\u20a17500<br \/>\nPasta fetuccini acompa\u00f1ada de una salsa cremosa de queso parmesano.<\/p>\n<ul>\n<li><strong>Vegetales<\/strong>&nbsp;\u20a18900<\/li>\n<li><strong>Camar\u00f3n<\/strong>&nbsp;\u20a110900<\/li>\n<li><strong>Pollo<\/strong> \u20a19900<\/li>\n<li><strong>Mixto<\/strong> \u20a19900<\/li>\n<\/ul>\n<p><strong>Aussie Steak Skewer<\/strong>&nbsp;\u20a112900<br \/>\nPinchos de carne a la parrilla con cebolla morda, chile dulce, champi\u00f1ones y tomate cherry. Servido sobre una cama de nuestro arroz especial Tasmania, con salsa demiglace.<\/p>\n<p><strong>Diablo Steak Skewer<\/strong>&nbsp;\u20a112900<br \/>\nPinchos de carne a la parrilla con cebolla morada, chile dulce, champi\u00f1oines y tomate cherry. Servido sobre una cama de nuestro arroz frito con una salsa picante de diablo.<\/p>\n<h1 id=\"combos\">Specialty Cuts &amp; Combos<\/h1>\n<p><strong>Toowoomba Topped Fillet<\/strong>&nbsp;6oz \u20a121900 8oz \u20a125900<br \/>\nCamarones y hongos salteados con una liviana salsa cremosa de queso parmesano, servidos sobre un jugoso filete sazonado y sellado. Servido con uno de sus acompa\u00f1amientos favoritos.<\/p>\n<p><strong>Sirloin and BBQ Ribs<\/strong>&nbsp;\u20a119900<br \/>\nNuestro SIrloin de 6oz especial acompa\u00f1ado con 14oz de costillas ahumadas en salsa barbacoa. Servido con Papas Aussie.<\/p>\n<p><strong>BBQ Mixed Grill<\/strong>&nbsp;\u20a118900<br \/>\nPollo a la parrilla con nuestra salsa barbacosa especial, jugosas BBQ Ribs y camarones cubiertos con coco, fritos hasta dorar. Servido con Papas Aussie.<\/p>\n<p><strong>Steak and Lobster Tail<\/strong><br \/>\nUn tierno y jugoso corte de res con una suculenta cola de langosta sazonada y cocida al vapor. Servido con dos de sus acompa\u00f1amientos favoritos. Escoja el corte de su preferencia.<\/p>\n<ul>\n<li><strong>Strip 8 oz<\/strong>&nbsp;\u20a127900<\/li>\n<li><strong>Ribeye 10 oz<\/strong>&nbsp;\u20a129900<\/li>\n<li><strong>Sirloin 8 oz<\/strong>&nbsp;\u20a126900<\/li>\n<\/ul>\n<h1 id=\"fromthesea\">From the Sea<\/h1>\n<p>Agregue una ensalada de la Casa o Caesar por&nbsp;\u20a12900.<\/p>\n<p><strong>Salm\u00f3n<\/strong>&nbsp;\u20a114900<br \/>\nFilet de salm\u00f3n servido con vegetales al vapor y cocinado a su gusto. Sazonado y a la parrilla o Pepper Crusted, cubierto con pimienta gruesa y con una salsa de mantequilla y lim\u00f3n.<\/p>\n<p><strong>Caj\u00fan Tuna Steak con tropical Mango Salsa<\/strong>&nbsp;\u20a115900<br \/>\nFilete de at\u00fan fresco, sazonado con especias caj\u00fan y sellado a la perfecci\u00f3n. Cubierto con una salsa de mango y servido con arroz pilaf y verduras de temporada.<\/p>\n<p><strong>Fish of the Day<\/strong>&nbsp;\u20a112900<br \/>\nFilete de corvina, fresco, sazonado y a la parrilla, servido con vegetales al vapor.<\/p>\n<ul>\n<li>Toowoomba Topping \u20a15900<\/li>\n<\/ul>\n<p><strong>Fish Tacos<\/strong>&nbsp;\u20a19900<br \/>\nPescado a la parrilla, ensalada de repollo y salsa de mango servido sobre dos tortillas de harina calientes. Acompa\u00f1ados con pico de gallo y Papas Aussie.<\/p>\n<p><strong>No Rules Shrimp Tacos<\/strong>&nbsp;\u20a19900<br \/>\nDos tortillas de harina rellenas con camarones a la parrilla, ensalada de repollo, salsa de cilantro y lim\u00f3n. Acompa\u00f1ados con pico de gallo y salsa de mango. Se sirve con Papas Aussie.<\/p>\n<h1 id=\"soupsandsides\">Freshly Made Soups and Sides<\/h1>\n<p><strong>Vegetales al Vapor<\/strong>&nbsp;\u20a11900<\/p>\n<p><strong>Papas Aussie<\/strong>&nbsp;\u20a11900<\/p>\n<p><strong>Papa Horneada<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Arroz Pilaf<\/strong>&nbsp;\u20a12500<\/p>\n<p><strong>Arroz Tasmania<\/strong>&nbsp;\u20a12500<\/p>\n<p><strong>Pur\u00e9 de Papa<\/strong>&nbsp;\u20a12500<\/p>\n<p><strong>Corn on the Cob<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Esparragos de la Parrilla<\/strong>&nbsp;\u20a13900<\/p>\n<p><strong>Sopa del D\u00eda<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Cebolla Francesa<\/strong>&nbsp;\u20a13900<\/p>\n<p>Signature Side Salads<\/p>\n<p><strong>Ensalada Caesar<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Ensalada de la Casa<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Ensalada Mixta<\/strong>&nbsp;\u20a12900<\/p>\n<p><strong>Ensalada con Camar\u00f3n<\/strong>&nbsp;\u20a16900<\/p>\n<h1 id=\"sandwichesandhandhelds\">Sandwiches and Handhelds<\/h1>\n<p><strong>Grilled California Chicken Sandwich<\/strong>&nbsp;\u20a18900<br \/>\nPechuga de pollo a la parrilla ligeramente sazonada, con tocina, lechuga, tomate, alioli y aguacate. Servida con Papas Aussie.<\/p>\n<p><strong>Philly Prime Rib Cheesesteak<\/strong>&nbsp;\u20a18900<br \/>\nPrime Rib con cebolla caramelizada, chile dulce asado, queso derretido servido en nuestro pan especial de trigo miel. Acompa\u00f1ado con Papas Aussie.<\/p>\n<p><strong>No Rules Burger<\/strong>&nbsp;\u20a112900<br \/>\nUna hamburguesa hecha para guerreros, comience con nuestra carne angus premium y escoja sus opciones favoritas. Servida con Papas Aussie.<\/p>\n<p><strong>The Outback Burger<\/strong>&nbsp;\u20a18900<br \/>\nHamburguesa con lechuga, tomate, cebolla, pepinillo y mostaza. Servida con Papas Aussie.<\/p>\n<p><strong>Bloomin&#8217; Burger<\/strong>&nbsp;\u20a18900<br \/>\nHamburguesa servida con p\u00e9taos de Bloomin&#8217; Onion\u00ae, queso americano, lechuga, tomate y nuestra famosa salsa bloom. Servida con Papas Aussie.<\/p>\n<p><strong>Bacon Cheeseburger<\/strong>&nbsp;\u20a18900<br \/>\nUna hamburguesa con tocino, queso americano, pepinillos, cebolla, mayonesa, lechuga y tomate. Servida con Papas Aussie.<\/p>\n<p><strong>Opciones<\/strong><br \/>\nHongos Salteados<br \/>\nQueso suizo<br \/>\nQueso Americano<br \/>\nTocineta<br \/>\nLechuga<br \/>\nTomate<br \/>\nCebolla Cruda<br \/>\nCebolla Salteada<br \/>\nPepinillos<br \/>\nP\u00e9talos de Bloomin&#8217; Onion<br \/>\nAderezo Blue Cheese<br \/>\nAderezo Caesar<br \/>\nAderezo Bloom<br \/>\nAderezo Ranch<br \/>\nAderezo Mostaza Miel<br \/>\nSalsa Alioli<br \/>\nSalsa BBQ<br \/>\nSalsa de Tomate<br \/>\nMayonesa<br \/>\nMostaza<br \/>\nGuacamole<\/p>\n<h1 id=\"desserts\">Desserts<\/h1>\n<p><strong>Chocolate Thunder from Down Under<\/strong>&nbsp;\u20a16900<br \/>\nUn brownie de chocolate y pecanas extra grande, coronado con un sabroso helado de vainilla, ba\u00f1ado con nuestra salsa de chocolate tibia y cubierto con crema chantilly y chocolate rallado.<\/p>\n<p><strong>Cheesecake<\/strong>&nbsp;\u20a14900<br \/>\nPastel de queso estilo New York con salsa de frambuesa, caramelo o chocolate de la casa.<\/p>\n<p><strong>Dessert Duo<\/strong>&nbsp;\u20a16900<br \/>\nUna combinaci\u00f3n de una porci\u00f3n de Chocolate Thunder from Down Under y Cheesecake.<br \/>\nO escoja una porci\u00f3n individual de cualquiera&nbsp;\u20a14900.<\/p>\n<p><strong>Cinnamon Oblivion<\/strong>&nbsp;\u20a16900<br \/>\nHelado de vainilla coronado con manzanas en salsa de canela tibia, crotones de canela, pecanas, salsa de caramelo y crema chantilly.<\/p>\n<p><strong>Mini Milkshakes<\/strong>&nbsp;\u20a12900<br \/>\nHelado premium de vainilla mezclado a la perfecci\u00f3n, coronado con crema chantilly y servido en una botella hecha a la antigua. Seleccione entre Chocolate, Vainilla, Fresa y OREO\u00ae.<\/p>\n<p><strong>Classic Key Lime Mini Parfait<\/strong>&nbsp;\u20a13500<br \/>\nTrozos peque\u00f1os de galleta colocadas en capas con relleno de pie de lim\u00f3n. Acompa\u00f1ado de un gajo peque\u00f1o de lim\u00f3n.<\/p>\n<p><strong>Chocolate OREO Mini Parfait<\/strong>&nbsp;\u20a13500<br \/>\nCremoso mousse de chocolate y galleta OREO\u00ae en trozos, colocada en capas cubierto con una cremosa salsa de chocolate tibia.<\/p>\n<p><strong>Strawberry Shortcake Mini Parfait<\/strong>&nbsp;\u20a13500<br \/>\nCapas de fresas maceradas, pastel de vainilla, relleno de parfait, cubierto con crema batida y almendras.<\/p>\n<p><strong>*Algunos de estos productos contienen nueces.<\/strong><\/p>\n<h1 id=\"kidsmenu\">Kids MENU<\/h1>\n<p>Todos los platos incluyen un jugo Del Valle y Aussie Fries.<br \/>\n( Excepto para la Pasta y Mini Milkshakes )<\/p>\n<p><strong>Kids Chicken Fingers<\/strong>&nbsp;\u20a14900<\/p>\n<p><strong>Kids Burger<\/strong>&nbsp;\u20a14900<\/p>\n<p><strong>Kids Mac &#8216;N Cheese<\/strong>&nbsp;\u20a15900<\/p>\n<p><strong>Kids Steak Medallions<\/strong>&nbsp;\u20a16900<\/p>\n<p><strong>Kids Pasta<\/strong>&nbsp;\u20a14900<\/p>\n<p><strong>Kids Ribs<\/strong>&nbsp;\u20a16900<\/p>\n<p><strong>Kids Fish and Chips<\/strong>&nbsp;\u20a14900<\/p>\n<p><strong>Mini Milkshakes<\/strong>&nbsp;\u20a12900<\/p>\n<h1 id=\"happyhour\">GET HAPPY<\/h1>\n<p><strong>BILLABONG HOUR<\/strong>&nbsp;de Lunes a Viernes de 4pm a 8pm.<br \/>\n2&#215;1 en Imperial Draft, Cocteles y Licores.<\/p>\n<h1 id=\"beer\">BEER<\/h1>\n<p>LOCAL<\/p>\n<p><strong>Bavaria Dark, Gold, Light<\/strong><\/p>\n<p><strong>Heineken<\/strong><\/p>\n<p><strong>Imperial, Light<\/strong><\/p>\n<p><strong>Pilsen<\/strong><\/p>\n<p>IMPORTS<\/p>\n<p><strong>Budweiser<\/strong><\/p>\n<p><strong>Corona<\/strong><\/p>\n<p><strong>Miller Light<\/strong><\/p>\n<p><strong>Stella Artois<\/strong><\/p>\n<h1>ARTESANAL<\/h1>\n<p><strong>Libertas<\/strong><\/p>\n<p><strong>Segua<\/strong><\/p>\n<p><strong>Malacrianza<\/strong><\/p>\n<p><strong>Escalante<\/strong><\/p>\n<h1>DRAFT<\/h1>\n<p><strong>Imperial<\/strong><\/p>\n<p><strong>Escalante<\/strong><\/p>\n<h1 id=\"cocktails\">Specialty Cocktails<\/h1>\n<p><strong>Gold Coast &#8216;Rita<\/strong>&nbsp;\u20a14900<br \/>\nLa margarita tradicional con Tequila Sauza Gold. Disfrutela frozen o en las rocas con un toque de sal ( o sin sal, no hay problema.<br \/>\nPru\u00e9bela Down Under adicionando un shote extra de Tequila Sauza Gold y un toque de Cointreau.&nbsp;\u20a16900<\/p>\n<p><strong>Sydne&#8217;s Cosmo<\/strong>&nbsp;\u20a15900<br \/>\nUna deliciosa combinaci\u00f3n de Vodka Smirnoff, Cointreau y jugo de cranberry con un toque de lim\u00f3n, mezclada a mano y servida bien fr\u00eda.<\/p>\n<p><strong>The Wallaby Darne<\/strong>&nbsp;\u20a16500<br \/>\nEl famoso bellini Australiano de melocot\u00f3n. Sienta en su boca el cosquilleo de est\u00e1 combinaci\u00f3n helada de melocot\u00f3n, champagne, Vodka Smirnoff y Dekuper Peachtree Schapps.<\/p>\n<p><strong>Classic Mojito<\/strong>&nbsp;\u20a14900<br \/>\nUna refrescante mezcla de Ron Bacardi Blanco, hojas frescas de hierbabuena, az\u00facar y soda. Con un toque de lim\u00f3n y menta.<\/p>\n<p><strong>Long Island Iced Tea<\/strong>&nbsp;\u20a16500<br \/>\nEl coctel cl\u00e1sico hecho con Vodka Smirnoff, Ron Bacardi Blanco, Gin Gordon&#8217;s, triple sec y sabor fresco a c\u00edtrico con un toque de Coca Cola.<\/p>\n<p><strong>Classic Caipirinha<\/strong>&nbsp;\u20a14900<br \/>\n\u00a1Un Coctel cl\u00e1sico de Suram\u00e9rica! Lim\u00f3n fresco y az\u00facar mezclados con un toque de cacha\u00e7a.<\/p>\n<p><strong>Strawberry Peach Sangr\u00eda<\/strong>&nbsp;\u20a16900<br \/>\nPur\u00e9 de fresas y melocotones mezclados con Malibu ron de pi\u00f1a, zinfnadel blanco, jugo de pi\u00f1a y adornado con fresas y limones en rodajas frescas.<\/p>\n<h1 id=\"beverages\">Spirit Free BEVERAGES<\/h1>\n<h2>COLD BEVERAGES<\/h2>\n<p>\u20a12800<br \/>\nRefill gratis en gaseosas y t\u00e9 fr\u00edo regular<br \/>\nSpritzer de Sabores<br \/>\nMango, Kiwi, Mel\u00f3n, Manzana<\/p>\n<p>T\u00e9 Fr\u00edo<\/p>\n<p>Agua Gasificada<\/p>\n<p>Agua Embotellada<\/p>\n<p><strong>Cherry Limeade<\/strong>&nbsp;\u20a13500<br \/>\nCerezas dulces, lim\u00f3n y un toque de Sprite hacen la mezcla perfecta para una bebida refrescante.<\/p>\n<h2>HOT BEVERAGES<\/h2>\n<p><strong>Caf\u00e9 Americano<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>Capuccino<\/strong>&nbsp;\u20a11900<\/p>\n<p><strong>Espresso<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>T\u00e9 Caliente<\/strong>&nbsp;\u20a11500<\/p>\n<p><strong>Chocolate<\/strong>&nbsp;\u20a11900<\/p>\n<h1 id=\"butchercuts\">Outback Butcher Cuts<\/h1>\n<p><strong>Chargrilled Bone &#8211; IN Ribeye<\/strong>&nbsp;18oz \u20a127900<br \/>\nJugoso Ribeye con hueso cocido a la parrilla. Servido con dos acompa\u00f1amientos.<\/p>\n<p><strong>T BONE<\/strong>&nbsp;20 oz \u20a133900<br \/>\nLa combinaci\u00f3n perfecta hecha para los aficionados del corte tipo NY y Filet. Servido con dos acompa\u00f1amientos.<\/p>\n<p><strong>Smoky Bacon Bourbon Ribeye<\/strong>&nbsp;18oz \u20a127900<br \/>\nRibeye con hueso, marinado en bourbon ahumado y crujiente tocineta. Servido con dos acompa\u00f1amientos.<\/p>\n<p><strong>RECOMEDANCI\u00d3N DE VINO<br \/>\nCabernet Sauvignon, Chocal\u00e1n, Chile.<br \/>\n<\/strong>Sabor afrutado y especiado, caracter\u00edsticos del Cabernet. Profundas notas de cerezas negras, casis, pimienta y matices de roble persistente.<br \/>\nCopa \u20a15900 Botella&nbsp;\u20a122900<\/p>\n<p><strong>Tomahawk Bone-IN Ribeye<\/strong>&nbsp;35oz \u20a177900<br \/>\nCubierto con mantequilla de ajo asado. Servido con dos acompa\u00f1amientos. ( para compartir )<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horario De Domingo a Mi\u00e9rcoles de 11am a 1030pm. De Jueves a S\u00e1bado de 11am a 11pm. Tel\u00e9fono: +506 4000-0247 Direcci\u00f3n Plaza Itskatz\u00fa, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. Men\u00fa aussietizers \u00b7 salads \u00b7 steaks \u00b7 favorites \u00b7 combos \u00b7 from the sea \u00b7 soups &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Outback Steakhouse Costa Rica\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#more-7178\" aria-label=\"Leer m\u00e1s sobre Outback Steakhouse Costa Rica\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[98,28,26,177],"tags":[250],"class_list":["post-7178","post","type-post","status-publish","format-standard","hentry","category-98","category-escazu","category-san-jose","category-san-rafael-escazu","tag-restaurantes-en-escazu","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-15T03:15:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T12:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Outback Steakhouse Costa Rica\",\"datePublished\":\"2018-11-15T03:15:32+00:00\",\"dateModified\":\"2023-02-14T12:59:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/\"},\"wordCount\":2172,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg\",\"keywords\":[\"Restaurantes en Escazu\"],\"articleSection\":[\"10203\",\"Escaz\u00fa\",\"San Jos\u00e9\",\"San Rafael\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/\",\"name\":\"Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg\",\"datePublished\":\"2018-11-15T03:15:32+00:00\",\"dateModified\":\"2023-02-14T12:59:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&ssl=1\",\"width\":610,\"height\":260,\"caption\":\"Restaurante Outback Steakhouse en Plaza Itskatzu San Rafael, Escazu, San Jose, Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/outback-steakhouse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Outback Steakhouse Costa Rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n","description":"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/","og_locale":"es_ES","og_type":"article","og_title":"Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n","og_description":"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2018-11-15T03:15:32+00:00","article_modified_time":"2023-02-14T12:59:56+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Outback Steakhouse Costa Rica","datePublished":"2018-11-15T03:15:32+00:00","dateModified":"2023-02-14T12:59:56+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/"},"wordCount":2172,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg","keywords":["Restaurantes en Escazu"],"articleSection":["10203","Escaz\u00fa","San Jos\u00e9","San Rafael"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/","name":"Outback Steakhouse Costa Rica - Men\u00fa, Horario, Direcci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg","datePublished":"2018-11-15T03:15:32+00:00","dateModified":"2023-02-14T12:59:56+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Outback Steakhouse Costa Rica en San Rafael, Escazu, San Jose. Men\u00fa, tel\u00e9fono, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/11\/restaurante-outback-steakhouse-escazu-san-jose-costa-rica.jpg?fit=610%2C260&ssl=1","width":610,"height":260,"caption":"Restaurante Outback Steakhouse en Plaza Itskatzu San Rafael, Escazu, San Jose, Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/outback-steakhouse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Outback Steakhouse Costa Rica"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1RM","jetpack-related-posts":[{"id":5398,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-modesta\/","url_meta":{"origin":7178,"position":0},"title":"La Modesta","author":"Restaurantes Costa Rica","date":"20 febrero 2017","format":false,"excerpt":"NEGOCIO CERRADO Tel\u00e9fono: +506 7293-7360 Horario: De Lunes a Viernes de 9am a 7pm. S\u00e1bados de 9am a 1pm. Domingo cerrado. Direcci\u00f3n De la salida a Multiplaza Escaz\u00fa en la autopista Prospero Fern\u00e1ndez, 800 mts norte frente a Crossfit 506, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante La Modesta, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/restaurante-la-modesta-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":360,"url":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-y-restaurante-il-panino\/","url_meta":{"origin":7178,"position":1},"title":"Caf\u00e9 y Restaurante Il Panino","author":"Restaurantes Costa Rica","date":"3 febrero 2011","format":false,"excerpt":"Horario: De Lunes a Jueves de 8 a.m. a 12 a.m. Viernes y S\u00e1bados 8 a.m. a 1 a.m. Domingos de 9 a.m. a 12 a.m Direcci\u00f3n: Multicentro Paco en Escaz\u00fa, en el cruce de Guachipel\u00edn, carretera vieja a Santa Ana. Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Restaurante Il Panino Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/il-panino-restaurante-cafe-costa-rica-logo.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":538,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samurai-fusion\/","url_meta":{"origin":7178,"position":2},"title":"Restaurante Samurai Fusion","author":"Restaurantes Costa Rica","date":"20 diciembre 2012","format":false,"excerpt":"El Restaurante Samurai Fusion, como su nombre lo indica, propone una fusi\u00f3n entre la traidicional comida japonesa y un acento que remite a la gastronom\u00eda de otras culturas; el restaurante est\u00e1 ubicado en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Todo en el Restaurante Samurai es simplemente genial, el ambiente\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/11\/samurai-fusion-restaurante-escazu-costa-rica-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5836,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tacos-bowls-tabows\/","url_meta":{"origin":7178,"position":3},"title":"Tacos &#038; Bowls TABOWS","author":"Restaurantes Costa Rica","date":"13 agosto 2017","format":false,"excerpt":"Direcci\u00f3n: Centro comercial Boulevard, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Horario: De Lunes a Viernes de 8am a 4pm. S\u00e1bados de 9am a 330pm. Domingos cerrado. Tel\u00e9fono: +506 2201-6423 ACEPTAMOS TARJETAS VISA, MASTERCARD Y AMERICAN EXPRESS RECOMENDACIONES DEL CHEF DESAYUNOS PARFAIT BOWL\u00a0\u20a12500\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante Tacos & Bowls TABOWS en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/08\/tacos-bowls-san-rafael-escazu-san-jose-costa-rica-1-300x148.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6413,"url":"https:\/\/costaricainfolink.com\/restaurantes\/4th-wave-cafe\/","url_meta":{"origin":7178,"position":4},"title":"4th WAVE Caf\u00e9 y Restaurante","author":"Restaurantes Costa Rica","date":"4 marzo 2018","format":false,"excerpt":"Direcci\u00f3n: Metroplaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Tel\u00e9fono: +506 2289 4849 Horario: De Lunes a Viernes de 7am a 7pm. S\u00e1bados de 10am a 4pm. Domingos cerrado. MEN\u00da DESAYUNOS De 7am a 10am. Especial del D\u00eda\u00a0\u20a12000 2 huevos al gusto, gallo\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"4th Wave Caf\u00e9 y Restaurante en Metroplaza San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1001,"url":"https:\/\/costaricainfolink.com\/restaurantes\/damalfi\/","url_meta":{"origin":7178,"position":5},"title":"Restaurante D&#8217;amalfi","author":"Restaurantes Costa Rica","date":"6 diciembre 2012","format":false,"excerpt":"Restaurante Cerrado Click the following link to read this page in English: D'amalfi Restaurant El Restaurante D'amalfi es el aut\u00e9ntico restaurante de comida italiana a cargo del reconocido Chef Giuseppe Galuppo, mejor conocido como Chef Pino, ubicado en Escaz\u00fa, el cual abri\u00f3 sus puertas en el a\u00f1o 2010. [portfolio_slideshow id=2406]\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=7178"}],"version-history":[{"count":19,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7178\/revisions"}],"predecessor-version":[{"id":11628,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7178\/revisions\/11628"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=7178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=7178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=7178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}