{"id":7926,"date":"2019-05-29T07:31:05","date_gmt":"2019-05-29T12:31:05","guid":{"rendered":"https:\/\/www.costaricainfolink.com\/restaurantes\/?p=7926"},"modified":"2023-02-14T07:57:34","modified_gmt":"2023-02-14T12:57:34","slug":"jerah","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","title":{"rendered":"Restaurante Jerah"},"content":{"rendered":"<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"7945\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/restaurante-jerah-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&amp;ssl=1\" data-orig-size=\"1012,532\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Restaurante Jerah Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&amp;ssl=1\" class=\"alignright wp-image-7945\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?resize=399%2C210&#038;ssl=1\" alt=\"Restaurante Jerah Costa Rica\" width=\"399\" height=\"210\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?resize=300%2C158&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?resize=768%2C404&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?w=1012&amp;ssl=1 1012w\" sizes=\"auto, (max-width: 399px) 100vw, 399px\" \/><\/p>\n<h1>Jerah Jac\u00f3<\/h1>\n<h2>Tel\u00e9fono<br><a href=\"tel:+50683592067\">+506 8359-2067<\/a><\/h2>\n<h2>Horario<\/h2>\n<p>De Martes a Domingo de 530pm a 10pm.<br>Lunes cerrado.<\/p>\n<h2>Direcci\u00f3n<\/h2>\n<p>Sobre calle Anita, entre Bar Isaga y Jac\u00f3 Bl\u00fa, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1eydnuhd\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Restaurante Jerah Jaco, Garabito, Puntarenas, Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/goo.gl\/maps\/fhKhcAcrJiTMSGJZA\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante Jerah Jaco, Garabito, Puntarenas, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n\n\n<h2 class=\"wp-block-heading\">Men\u00fa Jerah Jac\u00f3<\/h2>\n\n\n\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#ensaladasyentradas\">Ensaladas y Entradas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#arrolladosdeprimavera\">Arrollados de Primavera<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#nuestrassopas\">Nuestras Sopas<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#platosfuertes\">Platos Fuertes<\/a> &#8211; <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#loscurries\">Los Curries<\/a><\/p>\n<p>Muchas gracias por visitarnos. Esperamos que disfrute su estad\u00eda con nosotros. Le vamos a preparar su plato preferido lleno de aromas usando solamente ingredientes frescos y org\u00e1nicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestros precios incluyen impuestos de 13%  y servicio de 10%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aceptamos colones y $USD, solamente efectivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Disfruta de nuestros t\u00e9s helados, los preparamos aqu\u00ed en casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si quiere llevarse su comida, solo le ofrecemos usando contenedores biodegradables o reusables a un precio de 500 colones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Buen Provecho y Pura Vida!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"ensaladasyentradas\">Ensaladas y Entradas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ensalada Pawpaw<\/strong> \u20a13500<br>Papayas semi maduras, aromatizadas con salsa de pescado, az\u00facar integral, tomates, limones, ajo, chilis, culantro y man\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Alitas de Pollo Fritas<\/strong> \u20a14400<br>Alitas fritas servidas con salsa realmente picantes. Inf\u00f3rmenos si las prefiere menos picantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Satay Gai &#8211; Pincho de Pollito<\/strong> \u20a14400<br>3 filetes de pollo en pinchos, asados y servidos con salsa de man\u00ed hecha en casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"arrolladosdeprimavera\">Po Piad Tod &#8211; Arrollados de Primavera<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Los arrollados primavera ( Po Pia Tod en tailand\u00e9s ) los preparamos fresquitos aqu\u00ed en nuestra cocina. El chef los llena con repollo chino, zanahorias, culantor y viene servido con salsas agridulces y picantes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pollo \u20a14600<\/li>\n\n\n\n<li>Pescado \u20a15200<\/li>\n\n\n\n<li>Camarones \u20a15200<\/li>\n\n\n\n<li>Vegetales \u20a14600<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Una porci\u00f3n incluye 3 crujientes arrollados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"nuestrassopas\">Nuestras Sopas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tom Khai Gai<\/strong> \u20a14600<br>Sopa cl\u00e1sica de Tailandia, preparado con leche de coco, ceboll\u00edn, jengibre, limoncollo, culantro, tomates, hojas de cal kaffir, cebollas, setas, galangal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tom Yum Gung<\/strong> \u20a15200<br>Tambi\u00e9n una sopa cl\u00e1sica en Tailandia que se prepara con camarones, tomates, limoncillo, hojas de cal kaffir, jengibre, culantro, cebollas, cebollines, setas y galangal.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"platosfuertes\">Platos Fuertes<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guay Tiau<\/strong><br>Plato nacional de Tailandia. Sopa con fideos de arroz servido en un taz\u00f3n, con ceboll\u00edn, apio, albahaca, culantro, jengibre, limoncillo y man\u00ed.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guay Tiau Heng<\/strong><br>Fideos de arroz en aceite de ajo y salsa de ostra ( para vegetarianos puede ser con Salsa Hoisin ),  servido con ceboll\u00edn, apio, albahaca, culantro, jegibre y man\u00ed.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pollo  \u20a110000<\/li>\n\n\n\n<li>Cerdo  \u20a110500<\/li>\n\n\n\n<li>Carne  \u20a110500<\/li>\n\n\n\n<li>Camarones  \u20a111000<\/li>\n\n\n\n<li>Vegetales \u20a110000<\/li>\n\n\n\n<li>Vegetales &amp; Tofu  \u20a110500<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pad Krathiam Prikthai<\/strong><br>Frescos vegetales salteados con ajo, salsa de ostra ( salsa hoising para vegetarianos \/ veganos ), chili, culantro fresco, servido con arroz blanco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Khao Phad<\/strong><br>Arroz frito con huevitos fritos, vegetales frescos y culantro, con salsa agridulce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Phad Bami<\/strong><br>Fideos ( huevo ) servidos con huevitos fritos, vegetales frescos y culantro, con salsa agridulce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Phad Si-Eju<\/strong><br>Fideos de arroz servidos con huevitos fritos, vegetales frescos y culantro, con salsa agridulce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Pad Thai<\/strong><br>Fideos de arroz servidos con huevitos fritos y una salsa de tamarindo ducle, con vegetales frescos y culantro.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pollo \u20a110000<\/li>\n\n\n\n<li>Cerdo \u20a110500<\/li>\n\n\n\n<li>Carne \u20a110500<\/li>\n\n\n\n<li>Camarones \u20a111000<\/li>\n\n\n\n<li>Vegetales \u20a110000 <\/li>\n\n\n\n<li>Vegetales &amp; Tofu \u20a110500<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"loscurries\">Los Curries<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Verde<\/strong><br>Preparada con chili verde, limoncillo, ajo, sal, galangal, extracto de camarones ( preparado con camarones y sal ), c\u00e1scara de la cal de kaffir, semillas de culantro, pimienta negra, comino, c\u00farcuma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bastante picante!!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Rojo<\/strong><br>Preparado con chili seco rojo, limoncillo, sal, pimienta negra, chalote, galangal, extracto de camarones ( preparado con camarones y sal ), c\u00e1scara de la cal de kaffir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pica, pero ya no tanto&#8230;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Amarillo<\/strong><br>Preparado con ajo, limoncillo, sal, chalote, galangal, chili seco rojo, semillas de culantro, c\u00e1scara de la cal de kaffir, polvo de curry, comino, canela, c\u00farcuma, cardamomo, raspada de nuez moscada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco picante<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los curries vienen preparados con vegetales en leche de coco con un mont\u00f3n de hierbas fresquitas y arroz.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pollo &nbsp;\u20a110000<\/li>\n\n\n\n<li>Cerdo &nbsp;\u20a110500<\/li>\n\n\n\n<li>Carne &nbsp;\u20a110500<\/li>\n\n\n\n<li>Camarones &nbsp;\u20a111000<\/li>\n\n\n\n<li>Vegetales &nbsp;\u20a110000<\/li>\n\n\n\n<li>Vegetales &amp; Tofu &nbsp;\u20a110500<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Jerah Jac\u00f3 Tel\u00e9fono+506 8359-2067 Horario De Martes a Domingo de 530pm a 10pm.Lunes cerrado. Direcci\u00f3n Sobre calle Anita, entre Bar Isaga y Jac\u00f3 Bl\u00fa, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61101. &nbsp;&nbsp; Men\u00fa Jerah Jac\u00f3 Ensaladas y Entradas &#8211; Arrollados de Primavera &#8211; Nuestras Sopas &#8211; Platos Fuertes &#8211; Los &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Jerah\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#more-7926\" aria-label=\"Leer m\u00e1s sobre Restaurante Jerah\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[92,229,73,42],"tags":[],"class_list":["post-7926","post","type-post","status-publish","format-standard","hentry","category-92","category-garabito","category-jaco","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario<\/title>\n<meta name=\"description\" content=\"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario\" \/>\n<meta property=\"og:description\" content=\"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-29T12:31:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T12:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica-300x158.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Jerah\",\"datePublished\":\"2019-05-29T12:31:05+00:00\",\"dateModified\":\"2023-02-14T12:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/\"},\"wordCount\":608,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/restaurante-jerah-costa-rica-300x158.jpg\",\"articleSection\":[\"61101\",\"Garabito\",\"Jac\u00f3\",\"Puntarenas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/\",\"name\":\"Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/restaurante-jerah-costa-rica-300x158.jpg\",\"datePublished\":\"2019-05-29T12:31:05+00:00\",\"dateModified\":\"2023-02-14T12:57:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&ssl=1\",\"width\":1012,\"height\":532,\"caption\":\"Restaurante Jerah Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/jerah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Jerah\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario","description":"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario","og_description":"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2019-05-29T12:31:05+00:00","article_modified_time":"2023-02-14T12:57:34+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica-300x158.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Jerah","datePublished":"2019-05-29T12:31:05+00:00","dateModified":"2023-02-14T12:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/"},"wordCount":608,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica-300x158.jpg","articleSection":["61101","Garabito","Jac\u00f3","Puntarenas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","name":"Restaurante Jerah Costa Rica - Men\u00fa, Tel\u00e9fono, Horario","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica-300x158.jpg","datePublished":"2019-05-29T12:31:05+00:00","dateModified":"2023-02-14T12:57:34+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Restaurante Jerah en Jac\u00f3 y San Rafael de Escaz\u00fa Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/jerah\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica.jpg?fit=1012%2C532&ssl=1","width":1012,"height":532,"caption":"Restaurante Jerah Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Jerah"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s5i3XU-jerah","jetpack-related-posts":[{"id":11509,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mikkonos-greek-tavern\/","url_meta":{"origin":7926,"position":0},"title":"MIKKONOS GREEK TAVERN","author":"Restaurantes Costa Rica","date":"31 enero 2023","format":false,"excerpt":"Direcci\u00f3n En Centro Comercial Jac\u00f3 Walk, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Tel\u00e9fono +506 8823 7000 Horario Lunes, Mi\u00e9rcoles, Jueves, Viernes, S\u00e1bado y Domingo de 12md a 9pm. Martes cerrado. MEN\u00da Quinoa Bowl \u20a16450 Quinoa org\u00e1nica, kale, lechuga, tomate, pan artesanal,\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"MIKKONOS GREEK TAVERN JAC\u00d3 WALK COSTA RICA","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/MIKKONOS-GREEK-TAVERN-JACO-WALK-COSTA-RICA-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2943,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-surf-dogs\/","url_meta":{"origin":7926,"position":1},"title":"Bar y Restaurante Surf Dogs","author":"Restaurantes Costa Rica","date":"16 abril 2013","format":false,"excerpt":"CERRADO El Bar y Restaurante Surf Dogs Costa Rica es un bar surfo, con un ambiente agradable para relajarse y simplemente pasarla bien con tus amigos o familiares, situado muy convenientemente en medio de la avenida principal en Jac\u00f3, Costa Rica. Surf Dogs abri\u00f3 sus puertas en enero del 2012\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8965,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-gata-flora\/","url_meta":{"origin":7926,"position":2},"title":"La Gata Flora","author":"Restaurantes Costa Rica","date":"9 noviembre 2020","format":false,"excerpt":"Direcci\u00f3n: de Herrradura 1km Hacia Jaco contiguo a Sof\u00eda Market a mano izquierda. Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Tel\u00e9fono: +506 4703-0707 MEN\u00da Hamburguesas \u00b7 Sandwich \u00b7 PIZZA \u00b7 A la parrilla \u00b7 Platos Fuertes \u00b7 ENSALADAS \u00b7 Pollo a la\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"La Gata Flora restaurante y pizzer\u00eda en Jac\u00f3, Puntarenas, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/11\/restaurante-pizzeria-la-gata-flora-jaco-puntarenas-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":10152,"url":"https:\/\/costaricainfolink.com\/restaurantes\/marys-diner-jaco-beach\/","url_meta":{"origin":7926,"position":3},"title":"Mary&#8217;s Diner Jac\u00f3 Beach","author":"Restaurantes Costa Rica","date":"8 octubre 2021","format":false,"excerpt":"Tel\u00e9fono: +506 2643-4265 Horario: De Lunes a Domingo de 7:30am a 2:30pm. CERRADO los Martes Direcci\u00f3n: Centro Comercial Ure\u00f1a local # 1, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 MENU Desayunos \u00b7 Almuerzos \u00b7 Ensaladas \u00b7 Men\u00fa de Ni\u00f1os \u00b7 Bebidas DESAYUNOS\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Mary's Diner Jac\u00f3 Beach Costa Rica-logo","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/10\/restaurante-marys-diner-jaco-costa-rica-300x194.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8401,"url":"https:\/\/costaricainfolink.com\/restaurantes\/malecon\/","url_meta":{"origin":7926,"position":4},"title":"Restaurante Malec\u00f3n","author":"Restaurantes Costa Rica","date":"25 noviembre 2019","format":false,"excerpt":"Direcci\u00f3n Frente a la playa, al lado de Rio Copey, sobre calle El Boh\u00edo. Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Tel\u00e9fono+506 2643 3916 Horario Lunes, Mi\u00e9rcoles, Jueves, Viernes, S\u00e1bado y Domingo de 11am a 10pm. Martes cerrado. Men\u00fa Entradas \u00b7 Especiales\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Restaurante Malec\u00f3n Jac\u00f3 Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/11\/restaurante-malecon-jaco-costa-rica-2-1-300x114.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8595,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samudios-sunset-restobar\/","url_meta":{"origin":7926,"position":5},"title":"Samudio&#8217;s Sunset Restobar","author":"Restaurantes Costa Rica","date":"18 agosto 2020","format":false,"excerpt":"Tel\u00e9fono: +506 8928-6266Horario: Mi\u00e9rcoles cerrado. Lunes, Martes, Jueves y Viernes de 12md. a 10pm. S\u00e1bados y Domingos de 7am a 7pm. Direcci\u00f3n: Frente a la playa, segundo piso de Restaurante El Malec\u00f3n, calle el boh\u00edo. Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Samudios Sunset Restobar Jac\u00f3 Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/08\/restaurante-bar-samudios-jaco-costa-rica-1-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=7926"}],"version-history":[{"count":23,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7926\/revisions"}],"predecessor-version":[{"id":11627,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/7926\/revisions\/11627"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=7926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=7926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=7926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}