{"id":81,"date":"2009-05-25T16:42:06","date_gmt":"2009-05-25T21:42:06","guid":{"rendered":"http:\/\/www.costaricainfolink.com\/restaurantes\/?p=81"},"modified":"2016-03-27T08:23:32","modified_gmt":"2016-03-27T13:23:32","slug":"la-paila-casera","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","title":{"rendered":"Restaurante La Paila Casera"},"content":{"rendered":"<h3>Click the following link to read this page in English: <a href=\"https:\/\/costaricainfolink.com\/restaurants\/la-paila-casera-restaurant\/\">La Paila Casera Restaurant<\/a><\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"82\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/restaurante-la-paila-casera-limon-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&amp;ssl=1\" data-orig-size=\"260,265\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&amp;ssl=1\" class=\"aligncenter wp-image-82\" title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?resize=139%2C131&#038;ssl=1\" alt=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" width=\"139\" height=\"131\" \/><\/p>\n<p>Restaurante de comida caribe\u00f1a, ubicado en Puerto Viejo de Talamanca en la Costa del Caribe, directamente en Punta Uva, Lim\u00f3n, Costa Rica. Cuenta con parqueo, excelente servicio y rapidez.<\/p>\n<p><strong>Tel\u00e9fono:<\/strong> <a href=\"callto:+5062759-9047\">+506 2759-9047<\/a><br \/>\n<strong>Coordenadas para GPS:<\/strong>9.637281,-82.691414 (9\u00b038&#8217;14.21&#8243;N, 82\u00b041&#8217;29.09&#8243;W)<\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/mapa-con-la-direccion-del-restaurante-la-paila-casera\/\">Haga click aqu\u00ed para ver la direcci\u00f3n al Restaurante La Paila Casera en Lim\u00f3n, Costa Rica.<\/a><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"88\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/restaurante-la-paila-casera-limon-costa-rica-21\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-21.jpg?fit=219%2C156&amp;ssl=1\" data-orig-size=\"219,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-21.jpg?fit=219%2C156&amp;ssl=1\" class=\"alignnone size-full wp-image-88\" title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-21.jpg?resize=219%2C156&#038;ssl=1\" alt=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" width=\"219\" height=\"156\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"89\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/restaurante-la-paila-casera-limon-costa-rica-11\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-11.jpg?fit=208%2C156&amp;ssl=1\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-11.jpg?fit=208%2C156&amp;ssl=1\" class=\"alignnone size-full wp-image-89\" title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-11.jpg?resize=208%2C156&#038;ssl=1\" alt=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" width=\"208\" height=\"156\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"90\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/restaurante-la-paila-casera-limon-costa-rica-31\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-31.jpg?fit=208%2C156&amp;ssl=1\" data-orig-size=\"208,156\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;}\" data-image-title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-31.jpg?fit=208%2C156&amp;ssl=1\" class=\"alignnone size-full wp-image-90\" title=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica-31.jpg?resize=208%2C156&#038;ssl=1\" alt=\"Restaurante La Paila Casera, Punta Uva, Puerto Viejo de Talamanca, Lim\u00f3n, Costa Rica\" width=\"208\" height=\"156\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Click the following link to read this page in English: La Paila Casera Restaurant Restaurante de comida caribe\u00f1a, ubicado en Puerto Viejo de Talamanca en la Costa del Caribe, directamente en Punta Uva, Lim\u00f3n, Costa Rica. Cuenta con parqueo, excelente servicio y rapidez. Tel\u00e9fono: +506 2759-9047 Coordenadas para GPS:9.637281,-82.691414 (9\u00b038&#8217;14.21&#8243;N, 82\u00b041&#8217;29.09&#8243;W) Haga click aqu\u00ed para &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante La Paila Casera\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#more-81\" aria-label=\"Leer m\u00e1s sobre Restaurante La Paila Casera\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[15,16,17,18],"tags":[21],"class_list":["post-81","post","type-post","status-publish","format-standard","hentry","category-caribena","category-de-playa","category-limon","category-puerto-viejo","tag-anadir-etiqueta-nueva","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante La Paila Casera Costa Rica<\/title>\n<meta name=\"description\" content=\"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante La Paila Casera Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-25T21:42:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-27T13:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante La Paila Casera\",\"datePublished\":\"2009-05-25T21:42:06+00:00\",\"dateModified\":\"2016-03-27T13:23:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/\"},\"wordCount\":76,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/restaurante-la-paila-casera-limon-costa-rica.jpg\",\"keywords\":[\"A\u00f1adir etiqueta nueva\"],\"articleSection\":[\"Caribe\u00f1a\",\"De playa\",\"Lim\u00f3n\",\"Puerto Viejo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/\",\"name\":\"Restaurante La Paila Casera Costa Rica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/restaurante-la-paila-casera-limon-costa-rica.jpg\",\"datePublished\":\"2009-05-25T21:42:06+00:00\",\"dateModified\":\"2016-03-27T13:23:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2009\\\/05\\\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&ssl=1\",\"width\":\"260\",\"height\":\"265\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/la-paila-casera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante La Paila Casera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante La Paila Casera Costa Rica","description":"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante La Paila Casera Costa Rica","og_description":"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2009-05-25T21:42:06+00:00","article_modified_time":"2016-03-27T13:23:32+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante La Paila Casera","datePublished":"2009-05-25T21:42:06+00:00","dateModified":"2016-03-27T13:23:32+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/"},"wordCount":76,"commentCount":0,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg","keywords":["A\u00f1adir etiqueta nueva"],"articleSection":["Caribe\u00f1a","De playa","Lim\u00f3n","Puerto Viejo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/","name":"Restaurante La Paila Casera Costa Rica","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg","datePublished":"2009-05-25T21:42:06+00:00","dateModified":"2016-03-27T13:23:32+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Informaci\u00f3n del Restaurante La Paila Casera Costa Rica en Talamanca, Limon: ubicaci\u00f3n, horario, mapa con direcci\u00f3n, coordenadas para GPS, fotos y m\u00e1s.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/restaurante-la-paila-casera-limon-costa-rica.jpg?fit=260%2C265&ssl=1","width":"260","height":"265"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/la-paila-casera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante La Paila Casera"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-1j","jetpack-related-posts":[{"id":6995,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tamara\/","url_meta":{"origin":81,"position":0},"title":"Restaurante Caribe\u00f1o Tamara","author":"Restaurantes Costa Rica","date":"24 septiembre 2018","format":false,"excerpt":"Horario Abierto todos los d\u00edas de 1130am a 10pm. Tel\u00e9fonos +506 2750-0148, +506 8712-5150 Direcci\u00f3n 200 metros este del Banco de Costa Rica en Puerto Viejo, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. MEN\u00da Entradas \u00b7 Platos Fuertes \u00b7 Otros \u00b7 Bebidas \u00b7\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"Restaurante Tamara en Limon, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/09\/restaurante-tamara-limon-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3091,"url":"https:\/\/costaricainfolink.com\/restaurantes\/cafeteria-bread-chocolate\/","url_meta":{"origin":81,"position":1},"title":"Restaurante y Cafeter\u00eda Bread &#038; Chocolate","author":"Restaurantes Costa Rica","date":"22 septiembre 2013","format":false,"excerpt":"Horario: De Martes a S\u00e1bados de 6:30 a.m. a 6:30 p.m. Domingos de 6:30 a.m. a 2:30 p.m. Lunes cerrado. Tel\u00e9fono: +506 2750-0723 MEN\u00da Direcci\u00f3n: 50 m sur de Caf\u00e9 Viejo en Puerto Viejo, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. Coordenadas para\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"Restaurante y Cafeter\u00eda Bread and Chocolate en Puerto Viejo de Lim\u00f3n, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/09\/bread-and-chocolate-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":120,"url":"https:\/\/costaricainfolink.com\/restaurantes\/le-numu\/","url_meta":{"origin":81,"position":2},"title":"Restaurante Le Numu","author":"Restaurantes Costa Rica","date":"28 mayo 2009","format":false,"excerpt":"Click the following link to read this page in English: Le Numu Restaurant El Restaurante Le Numu del Hotel Le Cam\u00e9l\u00e9on Boutique Resort es la m\u00e1s lujosa y exquisita experiencia que se puede tener en la costa Caribe en Cocles, en Puerto Viejo de Talamanca, a tan s\u00f3lo 15 km\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"Restaurante Le Numu Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/hotel-le-cameleon-puerto-viejo-limon-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3138,"url":"https:\/\/costaricainfolink.com\/restaurantes\/stashus-con-fusion\/","url_meta":{"origin":81,"position":3},"title":"Restaurante Stashu&#8217;s Con Fusion","author":"Restaurantes Costa Rica","date":"17 octubre 2013","format":false,"excerpt":"Horario: Abierto de Jueves a Martes de 5 p.m. a 10 p.m. Tel\u00e9fono: +506 2750-0530 Direcci\u00f3n: 200 m Sur del pueblo sobre la calle principal, justo al lado del Restaurante Elena Brown en Puerto Viejo, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. Coordenadas\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"Restaurante Stashu's Con Fusion en Cahuita, Talamanca, Lim\u00f3n, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/10\/stashus-con-fusion-restaurante-limon-costa-rica.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1811,"url":"https:\/\/costaricainfolink.com\/restaurantes\/outback-jacks-australian-roadkill-grill\/","url_meta":{"origin":81,"position":4},"title":"Restaurante Outback Jacks Australian Roadkill Grill","author":"Restaurantes Costa Rica","date":"6 septiembre 2012","format":false,"excerpt":"Click the following link to read this page in English: Outback Jack's Restaurant El Restaurante y Bar de playa Outback Jacks Costa Rica, naci\u00f3 gracias al sue\u00f1o de \"Outback Jack\", un peregrino que andaba de paseo (walkabout) alrededor del mundo, creando una tormenta de sabores con su comida australiana, cuando\u2026","rel":"","context":"En \u00ab70403\u00bb","block_context":{"text":"70403","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/70403\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/08\/outback-jacks-australian-roadkill-grill-restaurante-costa-rica-logo2.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]},{"id":112,"url":"https:\/\/costaricainfolink.com\/restaurantes\/maxis\/","url_meta":{"origin":81,"position":5},"title":"Restaurante Maxis","author":"Restaurantes Costa Rica","date":"27 mayo 2009","format":false,"excerpt":"Restaurante Maxis en Manzanillo, Lim\u00f3n: Ubicaci\u00f3n: sobre la carretera principal en Manzanillo centro junto a la playa, distrito: Cahuita, cant\u00f3n: Talamanca, provincia: Lim\u00f3n, Costa Rica. C\u00f3digo postal de la zona: 70403. Coordenadas para GPS: 9.632503,-82.657817 (9\u00b037'57.01\"N, 82\u00b039'28.14\"W) Tel\u00e9fono: +506 2798-3740 \/ +506 2759-9073 Horario: todos los d\u00edas de 11 a.m.\u2026","rel":"","context":"En \u00ab10901\u00bb","block_context":{"text":"10901","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10901\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2009\/05\/maxis-restaurante-manzanillo-limon-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/81","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=81"}],"version-history":[{"count":17,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/81\/revisions"}],"predecessor-version":[{"id":4478,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/81\/revisions\/4478"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=81"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=81"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}