{"id":8755,"date":"2020-10-14T20:14:29","date_gmt":"2020-10-15T01:14:29","guid":{"rendered":"https:\/\/costaricainfolink.com\/restaurantes\/?p=8755"},"modified":"2023-02-14T07:55:17","modified_gmt":"2023-02-14T12:55:17","slug":"invictus","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","title":{"rendered":"Invictus Restaurant &#038; Sports Bar"},"content":{"rendered":"<p><strong><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica\/#main\" rel=\"attachment wp-att-8803\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8803\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&amp;ssl=1\" data-orig-size=\"400,400\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Invictus Restaurant &amp;#038; Sports Bar San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Telefono, horario, menu, direccion, ubicacion WAZE y mapas de Google\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&amp;ssl=1\" class=\"alignright size-medium wp-image-8803\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?resize=300%2C300&#038;ssl=1\" alt=\"Invictus Restaurant &amp; Sports Bar San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Telefono, horario, menu, direccion, ubicacion WAZE y mapas de Google\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?w=400&amp;ssl=1 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Tel\u00e9fono<\/strong>: <a href=\"tel:+50640015287\">+506 40015287<\/a><\/p>\n<p><strong>WhatsApp:<\/strong> <a href=\"https:\/\/wa.me\/50663620197\">6362-0197<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong>: Ruta 121, 90 metros noroeste del centro comercial paco, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0mpfvk\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Invictus Restaurant &amp; Sports Bar San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/g.page\/Invictus-restaurant-Sport-Bar?share\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Invictus Restaurant &amp; Sports Bar San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n<p>Desayuno, Almuerzo, After office Sports, reuniones, cena.<\/p>\n<p><strong>Horario<\/strong>: De Lunes a Viernes de 11am a 10pm. S\u00e1bados y Domingos de 8am a 9pm.<\/p>\n<p>MEN\u00da<\/p>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#bocas\">Bocas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#entradas\">Entradas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#sopasycremas\">Sopas y Cremas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#ensaladas\">Ensaladas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#pastasyrisottos\">Pastas y Risottos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#pizzas\">PIZZAS<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#hamburguesas\">Hamburguesas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#sandwiches\">Sandwiches<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#platos\">Platos<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#nuestrogrill\">Nuestro Grill<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#pequenos\">Para los peque\u00f1os<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#postres\">Postres<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#bebidas\">Bebidas<\/a><\/p>\n<h2 id=\"bocas\">Bocas<\/h2>\n<p><strong>Aros de Calamar<\/strong> \u20a14200<br>Aros del delicioso molusco empanizados y acompa\u00f1ados de papel de arroz y mayones de la casa.<\/p>\n<p><strong>Vegetales Tempura<\/strong> \u20a14100<br>Bocados de vegetales al estilo tempura en salsa Teriyaki.<\/p>\n<p><strong>Camarones aj\u00ed<\/strong> \u20a14900<br>Deliciosos camarones finamente empanizados y servidos con mayones de aj\u00ed.<\/p>\n<p><strong>Gajos de papa<\/strong> \u20a13490<br>Tradicionales gajos de papas fritas servidos con inigualable dip de cebolla.<\/p>\n<p><strong>Dedos de pollo<\/strong> \u20a14400<br>Trozos de pollo frito empanizado servidos con Mayones de la casa.<\/p>\n<p><strong>Dedos de queso<\/strong> \u20a14500<br>Deliciosos sticks de queso mozarella empanizados.<\/p>\n<p><strong>Papas a la frances<\/strong> \u20a12450<br>Crujientes gajos de papa fritas.<\/p>\n<p><strong>Teque\u00f1os<\/strong> \u20a13700<br>Exquisitos rollitos de queso envueltos en masa de harina de trigo.<\/p>\n<p><strong>Patacones<\/strong> \u20a15400<br>Ricos patacones acompa\u00f1ados con guacamole, pico de gallo y frijoles molidos.<\/p>\n<p><strong>Nachos de Carne<\/strong> \u20a15800<br>Carne molida sazonada a la mexicana sobre una cama de tortillas y queso derretido.<\/p>\n<p><strong>Palitos de Yuca<\/strong> \u20a13950<br>Sticks de yuca frita servidos con aderezo de natilla, tocineta y puerros.<\/p>\n<p><strong>Croquetas Invictus<\/strong> \u20a14800<br>Crujientes y deliciosas esferas fritas empanizadas rellenas de cremoso risotto.<\/p>\n<p><strong>Tacos<\/strong> \u20a14950<br>Popular plato de la gastronom\u00eda mexicana en sus versiones de: Carne, Pollo o Pescado.<\/p>\n<p><strong>Alitas de Pollo<\/strong> 6 piezas \u20a14600 12 piezas \u20a17850<br>Excelente alitas de pollo de corte profundo en la salsa de su elecci\u00f3n: BBQ o Buffalo.<\/p>\n<p><strong>Chips de Vegetales<\/strong> \u20a14100<br>Plat\u00f3n de chips de vegetales servidos con dip de cebolla, natilla y tocineta, frijoles molidos y guacamole.<\/p>\n<h2 id=\"entradas\">ENTRADAS<\/h2>\n<p><strong>Gyosas Fritas<\/strong> \u20a15200<br>Delicioso platillo de la gastronom\u00eda japonesa servidas con salsa ponz\u00fa en versiones de Camar\u00f3n, pollo o vegetales.<\/p>\n<p><strong>Carpaccio<\/strong> \u20a15600<br>Excelente aperitivo veneciano en versiones de Pulpo, Salm\u00f3n o Lomito.<\/p>\n<p><strong>Ceviche<\/strong> \u20a15600<\/p>\n<h2 id=\"sopasycremas\">Sopas y Cremas<\/h2>\n<p><strong>Crema de tomate<\/strong> \u20a15200<br>Crema a base de tomate fresco con un toque de ajo y albahaca.<\/p>\n<p><strong>Crema de ayote<\/strong> \u20a14900<br>Receta preparada en casa on Ayote Saz\u00f3n y condimentos de primera.<\/p>\n<p><strong>Crema de hongos<\/strong> \u20a15200 media porci\u00f3n \u20a13100<\/p>\n<p><strong>Crema de vegetales<\/strong> \u20a14900 media porci\u00f3n \u20a12900<\/p>\n<p><strong>Sopa Azteca<\/strong> \u20a15400 media porci\u00f3n \u20a13200.<\/p>\n<h2 id=\"ensaladas\">Ensaladas<\/h2>\n<p><strong>Ensalada Cesar<\/strong> \u20a14750<\/p>\n<p><strong>Cesar con Camarones<\/strong> \u20a16750<\/p>\n<p><strong>Caesar con Pollo<\/strong> \u20a16450<\/p>\n<p><strong>Ensalada Capresa<\/strong> \u20a14560<\/p>\n<p><strong>Green Salad<\/strong> \u20a13900<\/p>\n<h2 id=\"pastasyrisottos\">Pastas y Risottos<\/h2>\n<p>Pasta seleccionada: Penne, Fetuccini o Spaghetti con la salsa de su elecci\u00f3n. \u20a16950<\/p>\n<p><strong>Napolitana<\/strong><br><strong>Bolognesa<\/strong><br><strong>Pesto<\/strong><br><strong>Cuatro Quesos<\/strong><br><strong>Gorgonzola<\/strong><\/p>\n<p><strong>Lasagna<\/strong> Pollo \u20a13900 Carne \u20a16600 Vegetales \u20a15900<\/p>\n<p><strong>Risotto a lo invictus<\/strong> \u20a19600<br>Delicioso plato del norte de Italia. Arroz de consistencia cremosa preparado en caldo y acompa\u00f1ado con su elecci\u00f3n de: Hongos, Salm\u00f3n o Camar\u00f3n.<\/p>\n<h2 id=\"pizzas\">PIZZAS<\/h2>\n<p><strong>Margarita<\/strong> \u20a16450<br>Queso mozzarella, tomate y albahaca sobre nuestra deliciosa salsa de la casa.<\/p>\n<p><strong>Hawaiana<\/strong> \u20a16750<br>Jam\u00f3n, queso mozarella, trozos de pi\u00f1a sobre salsa de la casa.<\/p>\n<p><strong>Pepperoni<\/strong> \u20a16850<br>Queso mozzarella y pepperoni sobre la salsa para pizza de la casa.<\/p>\n<p><strong>Jamon y Hongos<\/strong> \u20a16850<br>Jam\u00f3n, champi\u00f1ones, queso mozzarella y salsa para pizza.<\/p>\n<p><strong>Vegetariana<\/strong> \u20a16600<br>Queso mozzarella, vegetales y salsa para pizza hecha en casa.<\/p>\n<p><strong>Gourmet<\/strong> \u20a17200<br>Construya su pizza a gusto: 3 ingredientes a escoger: cebolla, chile dulce, jam\u00f3n, pepperoni, tocineta, hongos, ma\u00edz dulce, aceitunas negras o carne molida.<\/p>\n<h2 id=\"hamburguesas\">Hamburguesas<\/h2>\n<p>Todas nuestra hamburguesas vienen con un acompa\u00f1amiento a elegir: ensalada de repollo, papas fritas, aros de cebolla o elote.<\/p>\n<p><strong>First Burger<\/strong> \u20a16450<br>150gr de carne, lechuga, tomate, cebolla, queso cheddar, pepinilos, tocineta.<\/p>\n<p><strong>Basil Burger<\/strong> \u20a16700<br>150gr de carne, lechuga, jam\u00f3n, tomate, hongos, espinaca, tocineta, queso suizo y aderezo de albahaca.<\/p>\n<p><strong>Invictus Burger<\/strong> \u20a16950<br>150 gr de carne , tomate cherry, huevo, queso mozzarella, lechuga, aro de cebolla.<\/p>\n<p><strong>Honey Burger<\/strong> \u20a16450<br>150gr de carne, lechuga, tomate deshidratado, mozzarella frito, hongos, aderezo miel mostaza.<\/p>\n<p><strong>Chicken burger<\/strong> \u20a16200<br>Pechuga de pollo, lechuga, tomate, tocineta, cebolla morada, salsa t\u00e1rtara.<\/p>\n<p><strong>Tartar Burger<\/strong> \u20a16450<br>150 gr de carne, lechuga, tomate, tocineta, cebolla morada, salsa t\u00e1rtara.<\/p>\n<p><strong>Beyond Burger<\/strong> \u20a18250<br>Torta <strong><em>Beyond Meat<\/em><\/strong> vegetariana, lechuga, tomate, hongos, cebolla morada, salsa t\u00e1rtara y queso cheddar.<\/p>\n<h2 id=\"sandwiches\">Sandwiches<\/h2>\n<p><strong>Caprese<\/strong> \u20a15450<br>Queso mozzarella, tomate y salsa pesto con un toque de aceite de oliva y albahaca.<\/p>\n<p><strong>Lomo<\/strong> \u20a15950<br>Carne de res, hongos, huevo, mostaza china, cebolla.<\/p>\n<p><strong>Vegetales<\/strong> \u20a15500<br>Lechuga, hongos salteados, tomate, berenjena empanizada.<\/p>\n<p><strong>Roast Beef<\/strong> \u20a15600<br>Roast beef, tomate, lechuga, espinaca y cebolla caramelizada.<\/p>\n<p><strong>Jam\u00f3n y Queso<\/strong> \u20a15600<br>Jam\u00f3n, queso mozzarella, tomate, lechuga.<\/p>\n<p><strong>Pollo<\/strong> \u20a15600<br>Pollo, queso mozzarella, tomate y salsa pesto.<\/p>\n<p><strong>Club House<\/strong> \u20a15950<br>Pollo, tomate, lechuga, huevo, tocineta con aderezo especial, servido en pan cuadrado.<\/p>\n<h2 id=\"platos\">Platos<\/h2>\n<p>Los acompa\u00f1amientos para su elecci\u00f3n son los siguientes: papas mini al romero, arroz, pur\u00e9, vegetales salteados, vegetales al vapor o papa asada con adereo de natilla, puerro y tocineta.<\/p>\n<p><strong>Lomito Chief<\/strong> \u20a19900<br>Corte de lomito de primera ba\u00f1ado en la salsa de su preferencia: gorgonzola, hongos o espinaca y con dos acompa\u00f1amientos a elegir.<\/p>\n<p><strong>Brocheta barrenada<\/strong> Pollo \u20a18700 Carne \u20a19300<br>260gr de carne o pollo a su elecci\u00f3n, presentados en dados barrenados con cebolla y chile dulce.<\/p>\n<p><strong>Pollo Cordon Bleu<\/strong> \u20a17400<br>Pechuga de pollo envuelta sobre jam\u00f3n y queso, empanizada y frita.<\/p>\n<p><strong>Pollo Gratinado<\/strong> \u20a17200<br>Pechuga de pollo cubierta de queso y gratinada al horno, presentada con dos acompa\u00f1amientos a elegir.<\/p>\n<p><strong>Pollo Gorgonzola<\/strong> \u20a17400<br>Pechuga de pollo gratinada cubierta con salsa de espinaca y queso gorgonzola.<\/p>\n<p><strong>Pollo en Salsa de Mora<\/strong> \u20a17600<br>Pechuga de pollo ba\u00f1ada en una salsa de mora y un toque de vino tinto, servida con dos acompa\u00f1amientos de su elecci\u00f3n.<\/p>\n<p><strong>Saute Fajitas<\/strong> Pollo \u20a17200 Carne \u20a19300 Mixta \u20a18900<br>Delicioso plato Tex-Mex con vegetales salteados, pico de gallo, guacamole y frijoles, servidas con tortillas.<\/p>\n<p><strong>Tacos Mexicanos<\/strong> Pollo \u20a15900 Carne \u20a16300 Camar\u00f3n \u20a16900<\/p>\n<p><b>Quesadilla<\/b> Pollo \u20a15900 Carne \u20a16200 Mixta \u20a15200<\/p>\n<p><strong>Corvina al ajillo<\/strong> \u20a19600<br>Filet de Corvina 200gr condimentado al ajillo y preparado al sart\u00e9n en su salsa.<\/p>\n<p><strong>Corvina a lo Macho<\/strong> \u20a110800<br>Corvina coronada con mejillones, camarones, almejas, ba\u00f1ada en salsa pomodoro o bechamel con selecci\u00f3n de dos acompa\u00f1antes: papa asada, pur\u00e9 de papas, papas mini o vegetales.<\/p>\n<p><strong>Grilled Salmon<\/strong> \u20a19200<br>180 gr de salm\u00f3n cocinado a la parrilla y dos acompa\u00f1amientos a elegir.<\/p>\n<p><strong>At\u00fan Miel Naranja<\/strong> \u20a19900<br>150gr de at\u00fan cocinado a la plancha y ba\u00f1ado en un agridulce de miel y naranaja, presentado con dos acompa\u00f1amientos a elegir.<\/p>\n<p><strong>Costillas de cerdo<\/strong> \u20a16900<br>Costillas de cerdo ba\u00f1adas en salsa BBQ horneadas en proceso lento, servidas con dos acompa\u00f1amientos de su elecci\u00f3n.<\/p>\n<p><strong>Half St. Louis Ribs<\/strong> \u20a114000<br>1\/2 rack de tiernas costillas St. Louis en salsa&nbsp; BBQ de la casa y dos acompa\u00f1amientos de su elecci\u00f3n.<\/p>\n<p><strong>St. Louis Rack<\/strong> \u20a124500<br>Rack de costillas St. Louis en salsa BBQ de la casa y dos acompa\u00f1amientos de su elecci\u00f3n.<\/p>\n<h2 id=\"nuestrogrill\">Nuestro Grill<\/h2>\n<p><strong>Choice Rib Eye<\/strong> \u20a112900<br>300gr de excelente Rib Eye Angus Choice al grill con selecci\u00f3n de dos acompa\u00f1antes: papa asada, pur\u00e9 de papas, papas mini, vegetales salteados, tomate al grill.<\/p>\n<p><strong>Shirt Steak<\/strong> \u20a110800<br>200 gr de deliciosa Entra\u00f1a Choice al grill con selecci\u00f3n de dos acompa\u00f1antes: papa asada, pur\u00e9 de papas, papas mini, vegetales salteados, tomate al grill.<\/p>\n<h2 id=\"pequenos\">Para los peque\u00f1os<\/h2>\n<p><strong>Dedos de Pollo<\/strong> \u20a14500<\/p>\n<p><strong>Kids Burger<\/strong> \u20a14500<\/p>\n<p><strong>Pasta corta o larga<\/strong> \u20a14000<\/p>\n<p><strong>Pizza Margarita Kids<\/strong> \u20a14000<\/p>\n<h2 id=\"postres\">Postres<\/h2>\n<p><strong>Flan de Vainilla<\/strong> \u20a12500<\/p>\n<p><strong>Tiramis\u00fa<\/strong> \u20a12800<\/p>\n<p><strong>Salami de Chocolate<\/strong> \u20a13500<\/p>\n<p><strong>Semifredo de Turr\u00f3n<\/strong> \u20a13500<\/p>\n<p><strong>Pie de Manzana<\/strong> \u20a12800<\/p>\n<p><strong>Cheesecake<\/strong> \u20a12900<\/p>\n<p><strong>Copa de Helado<\/strong> \u20a12100<\/p>\n<h2 id=\"bebidas\">Bebidas<\/h2>\n<p><strong>Jugos Naturales<\/strong> \u20a11950<br><strong>Gaseosas<\/strong> \u20a11800<br><strong>Agua<\/strong> \u20a11200<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tel\u00e9fono: +506 40015287 WhatsApp: 6362-0197 Direcci\u00f3n: Ruta 121, 90 metros noroeste del centro comercial paco, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. &nbsp;&nbsp; Desayuno, Almuerzo, After office Sports, reuniones, cena. Horario: De Lunes a Viernes de 11am a 10pm. S\u00e1bados y Domingos de 8am a 9pm. &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Invictus Restaurant &#038; Sports Bar\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#more-8755\" aria-label=\"Leer m\u00e1s sobre Invictus Restaurant &#038; Sports Bar\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[98,28,26,177],"tags":[250],"class_list":["post-8755","post","type-post","status-publish","format-standard","hentry","category-98","category-escazu","category-san-jose","category-san-rafael-escazu","tag-restaurantes-en-escazu","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Invictus Restaurant &amp; Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n<\/title>\n<meta name=\"description\" content=\"Invictus Restaurant &amp; Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Invictus Restaurant &amp; Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Invictus Restaurant &amp; Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-15T01:14:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-14T12:55:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Invictus Restaurant &#038; Sports Bar\",\"datePublished\":\"2020-10-15T01:14:29+00:00\",\"dateModified\":\"2023-02-14T12:55:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/\"},\"wordCount\":1201,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg\",\"keywords\":[\"Restaurantes en Escazu\"],\"articleSection\":[\"10203\",\"Escaz\u00fa\",\"San Jos\u00e9\",\"San Rafael\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/\",\"name\":\"Invictus Restaurant & Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg\",\"datePublished\":\"2020-10-15T01:14:29+00:00\",\"dateModified\":\"2023-02-14T12:55:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Invictus Restaurant & Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&ssl=1\",\"width\":400,\"height\":400,\"caption\":\"Invictus Restaurant & Sports Bar San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Telefono, horario, menu, direccion, ubicacion WAZE y mapas de Google\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/invictus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invictus Restaurant &#038; Sports Bar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Invictus Restaurant & Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n","description":"Invictus Restaurant & Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","og_locale":"es_ES","og_type":"article","og_title":"Invictus Restaurant & Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n","og_description":"Invictus Restaurant & Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2020-10-15T01:14:29+00:00","article_modified_time":"2023-02-14T12:55:17+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Invictus Restaurant &#038; Sports Bar","datePublished":"2020-10-15T01:14:29+00:00","dateModified":"2023-02-14T12:55:17+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/"},"wordCount":1201,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg","keywords":["Restaurantes en Escazu"],"articleSection":["10203","Escaz\u00fa","San Jos\u00e9","San Rafael"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/","name":"Invictus Restaurant & Sports Bar - Men\u00fa, Tel\u00e9fono, Horario, Ubicaci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica-300x300.jpg","datePublished":"2020-10-15T01:14:29+00:00","dateModified":"2023-02-14T12:55:17+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Invictus Restaurant & Sports Bar en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Men\u00fa, direcci\u00f3n, tel\u00e9fono, horario, WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/invictus\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/10\/invictus-restaurant-sports-bar-san-rafael-escazu-san-jose-costa-rica.jpg?fit=400%2C400&ssl=1","width":400,"height":400,"caption":"Invictus Restaurant & Sports Bar San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Telefono, horario, menu, direccion, ubicacion WAZE y mapas de Google"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/invictus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Invictus Restaurant &#038; Sports Bar"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s5i3XU-invictus","jetpack-related-posts":[{"id":5398,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-modesta\/","url_meta":{"origin":8755,"position":0},"title":"La Modesta","author":"Restaurantes Costa Rica","date":"20 febrero 2017","format":false,"excerpt":"NEGOCIO CERRADO Tel\u00e9fono: +506 7293-7360 Horario: De Lunes a Viernes de 9am a 7pm. S\u00e1bados de 9am a 1pm. Domingo cerrado. Direcci\u00f3n De la salida a Multiplaza Escaz\u00fa en la autopista Prospero Fern\u00e1ndez, 800 mts norte frente a Crossfit 506, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante La Modesta, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/restaurante-la-modesta-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":360,"url":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-y-restaurante-il-panino\/","url_meta":{"origin":8755,"position":1},"title":"Caf\u00e9 y Restaurante Il Panino","author":"Restaurantes Costa Rica","date":"3 febrero 2011","format":false,"excerpt":"Horario: De Lunes a Jueves de 8 a.m. a 12 a.m. Viernes y S\u00e1bados 8 a.m. a 1 a.m. Domingos de 9 a.m. a 12 a.m Direcci\u00f3n: Multicentro Paco en Escaz\u00fa, en el cruce de Guachipel\u00edn, carretera vieja a Santa Ana. Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Restaurante Il Panino Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/il-panino-restaurante-cafe-costa-rica-logo.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5836,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tacos-bowls-tabows\/","url_meta":{"origin":8755,"position":2},"title":"Tacos &#038; Bowls TABOWS","author":"Restaurantes Costa Rica","date":"13 agosto 2017","format":false,"excerpt":"Direcci\u00f3n: Centro comercial Boulevard, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Horario: De Lunes a Viernes de 8am a 4pm. S\u00e1bados de 9am a 330pm. Domingos cerrado. Tel\u00e9fono: +506 2201-6423 ACEPTAMOS TARJETAS VISA, MASTERCARD Y AMERICAN EXPRESS RECOMENDACIONES DEL CHEF DESAYUNOS PARFAIT BOWL\u00a0\u20a12500\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante Tacos & Bowls TABOWS en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/08\/tacos-bowls-san-rafael-escazu-san-jose-costa-rica-1-300x148.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6413,"url":"https:\/\/costaricainfolink.com\/restaurantes\/4th-wave-cafe\/","url_meta":{"origin":8755,"position":3},"title":"4th WAVE Caf\u00e9 y Restaurante","author":"Restaurantes Costa Rica","date":"4 marzo 2018","format":false,"excerpt":"Direcci\u00f3n: Metroplaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Tel\u00e9fono: +506 2289 4849 Horario: De Lunes a Viernes de 7am a 7pm. S\u00e1bados de 10am a 4pm. Domingos cerrado. MEN\u00da DESAYUNOS De 7am a 10am. Especial del D\u00eda\u00a0\u20a12000 2 huevos al gusto, gallo\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"4th Wave Caf\u00e9 y Restaurante en Metroplaza San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":538,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samurai-fusion\/","url_meta":{"origin":8755,"position":4},"title":"Restaurante Samurai Fusion","author":"Restaurantes Costa Rica","date":"20 diciembre 2012","format":false,"excerpt":"El Restaurante Samurai Fusion, como su nombre lo indica, propone una fusi\u00f3n entre la traidicional comida japonesa y un acento que remite a la gastronom\u00eda de otras culturas; el restaurante est\u00e1 ubicado en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Todo en el Restaurante Samurai es simplemente genial, el ambiente\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/11\/samurai-fusion-restaurante-escazu-costa-rica-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1001,"url":"https:\/\/costaricainfolink.com\/restaurantes\/damalfi\/","url_meta":{"origin":8755,"position":5},"title":"Restaurante D&#8217;amalfi","author":"Restaurantes Costa Rica","date":"6 diciembre 2012","format":false,"excerpt":"Restaurante Cerrado Click the following link to read this page in English: D'amalfi Restaurant El Restaurante D'amalfi es el aut\u00e9ntico restaurante de comida italiana a cargo del reconocido Chef Giuseppe Galuppo, mejor conocido como Chef Pino, ubicado en Escaz\u00fa, el cual abri\u00f3 sus puertas en el a\u00f1o 2010. [portfolio_slideshow id=2406]\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/8755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=8755"}],"version-history":[{"count":25,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/8755\/revisions"}],"predecessor-version":[{"id":11626,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/8755\/revisions\/11626"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=8755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=8755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=8755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}