{"id":9389,"date":"2021-03-14T18:36:12","date_gmt":"2021-03-14T23:36:12","guid":{"rendered":"https:\/\/costaricainfolink.com\/restaurantes\/?p=9389"},"modified":"2021-03-18T11:11:40","modified_gmt":"2021-03-18T16:11:40","slug":"ridiculous-burgers","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/","title":{"rendered":"Ridiculous Burgers"},"content":{"rendered":"<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/ridiculous-burgers-jaco-costa-rica-logo\/#main\" rel=\"attachment wp-att-9391\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9391\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/ridiculous-burgers-jaco-costa-rica-logo\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&amp;ssl=1\" data-orig-size=\"272,272\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"ridiculous-burgers-jaco-costa-rica-logo\" data-image-description=\"&lt;p&gt;Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&amp;ssl=1\" class=\"alignright wp-image-9391\" title=\"Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?resize=214%2C214&#038;ssl=1\" alt=\"Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica\" width=\"214\" height=\"214\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?w=272&amp;ssl=1 272w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?resize=150%2C150&amp;ssl=1 150w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n<p><strong>Horario<\/strong>: Todos los d\u00edas de 11:30 a 24:00. Servicio de recogida y\/o entrega de 12:00 a 24:00.<\/p>\n<p><strong>T\u00e9lefono<\/strong>: <a href=\"tel:+50626431010\">+506 2643-1010<\/a><\/p>\n<p><strong>Direcci\u00f3n<\/strong>: Avenida Pastor Diaz (Avenida Principal de Jac\u00f3) entre Calle Hicaco y Calle Alice, Jac\u00f3, Puntaranas, Costa Rica. C\u00f3digo postal de la zona: 61101.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1eydmc48\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica\" width=\"50\" height=\"50\"><\/a>&nbsp;&nbsp;<a href=\"https:\/\/g.page\/RidiculousBurgers?share\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica\" width=\"50\" height=\"50\"><\/a><\/p>\n\n<h2>MEN\u00da<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#bebidas\">Bebidas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#cervezasvinoslicores\">Cervezas, Vinos y Licores<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#coctelesnormales\">Cocteles Normales<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#coctelesgigantes\">Cocteles Gigantes<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#sinalcohol\">Sin Alcohol<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#shots\">Shots<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#shotsespeciales\">Shots Especiales<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#sixpackshots\">Six Pack Shots<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#chemistry\">Chemistry<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#ensaladas\">Ensaladas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#hamburguesas\">Hamburguesas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#premiumburgers\">Premium Burgers<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#sides\">Sides<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#aliolis\">Aliolis<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#menudeni\u00f1os\">Men\u00fa de Ni\u00f1os<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#challenge1\">Challenge #1<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#challenge2\">Challenge #2<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#challenge3\">Challenge #3<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#challenge4\">Challenge #4<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#cafefrio\">Caf\u00e9 Fr\u00edo<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#cafe\">Caf\u00e9<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#crazyshakes\">Crazy Shakes<\/a><\/p>\n<h2 id=\"bebidas\">BEBIDAS<\/h2>\n<p>Limonada con Hierba Buena \u20a12090<br>Pi\u00f1a y Albahaca \u20a12090<br>T\u00e9 Fr\u00edo de la casa \u20a11356<br>Agua \u20a11576<br>Coca Cola \u20a11576<br>Coca Cola Light \u20a11576<br>Fresca \u20a11576<br>Ginger Ale \u20a11576<br>Soda \u20a11576<br>T\u00f3nica \u20a11576<br>Fanta Naranja \u20a11576<br>T\u00e9 Fr\u00edo \u20a11576<\/p>\n<h2 id=\"cervezasvinoslicores\">CERVEZAS, VINOS Y LICORES<\/h2>\n<p>Imperial \u20a11808<br>Craft Beer \u20a13164<br>Cerveza Importada \u20a13390<br>Copa de Vino de la Casa \u20a14955<br>Contamos con licores Premium a tu elecci\u00f3n \u20a17345<\/p>\n<h2 id=\"coctelesnormales\">COCTELES NORMALES<\/h2>\n<p>Margarita, Pi\u00f1a Colada, Bloddy Merry, Gintonic de Pepino, Mojito Mediterr\u00e1neo, Mojito de Maracuy\u00e1 \u20a14520<\/p>\n<h2 id=\"coctelesgigantes\">COCTELES GIGANTES<\/h2>\n<p><strong>Recomendados para compartir en pareja<\/strong><\/p>\n<p><strong>Sexy Pink 55oz \u20a117876<\/strong><br>Una combinaci\u00f3n de Tequila, Vodka y Ron de frutos rojos y pi\u00f1a colada, simplemente una delicia!<\/p>\n<p><strong>Mimosa 25oz \u20a115961<\/strong><br>Un litro de vino espumante con frutos frescos del bosque y de sprite y jugo de naranja.<\/p>\n<p><strong>Coronita 55oz \u20a115961<\/strong><br>Margarita de la casa con una Corona michelada super refrescante.<\/p>\n<p><strong>Bloddy Merry 25oz \u20a115961<\/strong><br>Jugo de tomate, jugo de lim\u00f3n, pimienta, sal, vodka y Lian Perry.<\/p>\n<p><strong>Ridiculous Drink 55oz \u20a117876<\/strong><br>Vodka, Blue Curacao, pi\u00f1a, jugo de naranja, splash de jugo de ar\u00e1ndano y Ron Malib\u00fa.<\/p>\n<p><strong>Special X 55oz \u20a116672<\/strong><br>Al gusto del bartender.<\/p>\n<h2 id=\"sinalcohol\">SIN ALCOHOL<\/h2>\n<p><strong>Pi\u00f1a Colada 55 oz \u20a111492<\/strong><br>Una pi\u00f1a colada virgen con banano y coco. Sabores caribe\u00f1os.<\/p>\n<p><strong>Limonada con Fresa \u20a111492<\/strong><br>Limonada con burbujas y fresas, perfecta para el clima tropical.<\/p>\n<h2 id=\"shots\">SHOTS<\/h2>\n<p>Patr\u00f3n \u20a16780<br>Don Julio \u20a16215<br>Baileys \u20a14520<br>Grey Goose \u20a15650<br>Flor de Ca\u00f1a \u20a15537<\/p>\n<h2 id=\"shotsespeciales\">SHOTS ESPECIALES<\/h2>\n<p>Bob Marley \u20a15085<br>Beauty and the Beast \u20a15085<br>Shit on the Grass \u20a15085<br>Pap\u00e1 Pitufo \u20a15085<br>Red Snapper \u20a15085<br>RedBull Jagger \u20a16780<\/p>\n<h2 id=\"sixpackshots\">SIX PACK SHOTS<\/h2>\n<p><strong>Algo \u00fanico para compartir \u20a116893<\/strong><br>Black Russian<br>White Russian<br>Tequila Sunrise<br>Mamadita<br>Luna Azul<br>Claro de Luna<\/p>\n<h2 id=\"chemistry\">CHEMISTRY<\/h2>\n<p>Un juego de qu\u00edmica de shots, una combinaci\u00f3n de 12 licores grandiosos. Una locura TOTAL! \u20a122487<\/p>\n<h2 id=\"ensaladas\">ENSALADAS<\/h2>\n<p><strong>Del Mar \u20a18475<\/strong><br>Una fiesta de mariscos para los amantes del mar, en una cama de lechuga, calamares, camarones, pescado completamente frescos del pac\u00edfico, salteados con mantequilla y ajo, cebolla morada, tomate cherry y un aderezo c\u00edtrico. La mejor combinaci\u00f3n!<\/p>\n<p><strong>Asi\u00e1tica \u20a18475<\/strong><br>At\u00fan aleta amarilla o Salm\u00f3n fresco sellado de la mejor calidad, acompa\u00f1ado con lonjas de aguacate, jengibre, pepinos, remolacha en vinagreta de la casa, cebolla morada sobre cama de lechuga americana, un delicioso aderezo de soya y tahini al estilo japon\u00e9s con sabores c\u00edtricos. Una fusi\u00f3n asi\u00e1tica que no podr\u00e1s olvidar!<\/p>\n<p><strong>Tropical \u20a17006<\/strong><br>Kale y lechuga americana, queso blanco en cuadros, hongos, ar\u00e1ndanos, fresas, mango, nueces, cebollas moradas, aderezo de yogurt natural con una reducci\u00f3n de bals\u00e1mico y az\u00facar moreno.<\/p>\n<p><strong>Capresse \u20a16215<\/strong><br>Una cama de lechuga fresca con tomates de la mejor calidad, cebolla bals\u00e1mica, hongos silvestres frescos, deliciosas rebanadas de queso Boconchinni de b\u00faffalo, albahaca y alioli bals\u00e1mico.<\/p>\n<p><strong>Mexicana \u20a17797<\/strong><br>Fajitas de lomo de exportaci\u00f3n, frijoles caseros, cuadros de queso cheddar, pico de gallo, guacamole, chile jalape\u00f1o, natilla casera y nuestro delicioso aderezo de chipotle en una cama de lechuga. \u00danica y diferente para los amantes del picante. La mejor al estilo mexicano.<\/p>\n<p><strong>Pollo \u20a17797<\/strong><br>Deliciosos trozos de pollo a la parrilla de la mejor calidad, linjas de tocineta crocantes, gajos de naranja, tomates cherry y nuestro aderezo alioli de mostaza dulce sobre una cama de lechuga. Un manjar para los que gustan comer sano.<\/p>\n<h2 id=\"hamburguesas\">HAMBURGUESAS<\/h2>\n<p><strong>Cl\u00e1sica Americana \u20a14508<\/strong><br>Deliciosa torta de carne artesanal, lechuga fresca, cebolla morada en vinagreta, tomate con nuestra salsa secreta Rid\u00edcula.<\/p>\n<p><strong>Hamburguesa con Queso \u20a15085<\/strong><br>Deliciosa torta de carne artesanal, lechuga fresca, tomates, cebolla morada en vinagreta, queso mozzarella frsco y aderezo secreto de la casa. Un deleite para los amantes del buen queso.<\/p>\n<p><strong>Jac\u00f3 \u20a16768<\/strong><br>Delciosa torta de carne artesanal, con sabores nacionales, alioli a base de salsa Lizano, pl\u00e1tanos maduros, frijoles molidos, cebolla morada, lechuga fresca y tomate. Una experiencia Tica!<\/p>\n<p><strong>Chili Pollo \u20a16765<\/strong><br>Delicioso filet de pollo, alioli de sriracha, pimientos rojos asados, lechuga fresca, cebolla morada, cebolla salteada, tomates y queso mozzarella.<\/p>\n<p><strong>Pollo \u20a15638<\/strong><br>Delicioso filet de pollo marinado con hierbas frescas, alioli de vegetales rostizados, cebolla bals\u00e1mica y tomate. Al mejor estilo mediterr\u00e1neo.<\/p>\n<p><strong>Hawaiana \u20a16768<\/strong><br>Carne o pollo a escoger, con una deliciosa rodaja de pi\u00f1a a la parrilla, alioli de mango, lechuga, tomate, cebolla morada, cubierto con aros de cebolla, Un manjar en tu boca.<\/p>\n<p><strong>Texas \u20a17898<\/strong><br>Deliciosa torta de carne de res artesanal a la parrilla, aros de cebolla, tocineta, salsa BBQ, queso americano, lechuga, tomate, cebolla morada y alioli de sriracha.<\/p>\n<p><strong>Mexican \u20a16768<\/strong><br>Deliciosa torta de carne artesanal, queso americano, guacamole, pico de gallo, doritos, lechuga, tomate, cebolla morada y alioli de chipotle.<\/p>\n<p><strong>Tocino \u20a17898<\/strong><br>Deliciosa torta de carne, tocineta, cebolla morada marinada en vinagreta, lechuga, tomate, alioli de aguacate, chipotle y huevo frito.<\/p>\n<p><strong>Kiwi \u20a17898<\/strong><br>Deliciosa torta de carne con queso americano, remolacha, salsa de tomate, cebolla morada, tomate y huevo frito. Al mejor estilo de Nueva Zelanda.<\/p>\n<p><strong>Conejo \u20a17898<\/strong><br>Torta de conejo a la plancha, tomate caramelizado, tocineta, lechuga, tomate, cebolla morada, alioli de vegetales rostizados.<\/p>\n<p><strong>Buffalo \u20a17898<\/strong><br>Excepcional torta de B\u00faffalo de pastoreo, cebolla caramelizada, lechuga, tomate, cebolla morarda, queso mozzarella y alioli de la casa.<\/p>\n<p><strong>Cordero \u20a17898<\/strong><br>Torta de Cordero con queso mozzarella, jalea de menta, lechuga, tomate, cebolla morada, pimientos rojos, cebolla salteada y alioli Rid\u00edculo.<\/p>\n<p><strong>Amor \u20a18927<\/strong><br>Torta de Camar\u00f3n empanizada en coco, lonjas de aguacate, pi\u00f1a a la parrilla, aros de cebolla, queso mozzarella, lechuga, tomate, cebolla morada con alioli de maracuy\u00e1. Una hamburguesa llena de pasi\u00f3n!<\/p>\n<p><strong>Nada \u20a14508<\/strong><br>Baja en calor\u00edas y libre de gluten, carne o filet de pollo a elegir, queso mozzarella, pepino, cebolla morada en vinagreta, tomate envuelta en lechugas frescas.<\/p>\n<p><strong>Salm\u00f3n \u20a19605<\/strong><br>Salm\u00f3n de primera calidad, lechuga, tomate, cebolla morada, pepinos en vinagreta y alioli de eneldo.<\/p>\n<p><strong>At\u00fan \u20a17684<\/strong><br>At\u00fan aleta amarilla fresco, aguacate, lechuga, cebolla morada, tomate y nuestro alioli asi\u00e1tico a base de soya y tahini.<\/p>\n<p><strong>Langosta \u20a111288<\/strong><br>Langostas frescas del pac\u00edfico, cebolla caramelizada, aguacate, alioli de vegetales rostizados, lechuga, tomate, cebolla morada y alioli de tomillo y coco.<\/p>\n<p><strong>Mar &amp; Tierra \u20a114678<\/strong><br>Delicioso corte de entra\u00f1a, camarones salteados en mantequilla y ajo, alioli de vegetales rostizados, lechuga, tomate, cebolla morada y queso mozzarella.<\/p>\n<p><strong>Dorado \u20a16667<\/strong><br>Filete de pescado con una base de mantequilla y ajo, tomate, aderezo a base de coco y tomillo, lechuga, cebolla morada y aguacate.<\/p>\n<p><strong>Quinoa \u20a16215<\/strong><br>Impresionante torta vegetariana elaborada a base de quinoa y frijoles. Lechuga, tomate, cebolla morada, alioli de eneldo, hummus, hongos salteados y rodajas de zuquinni a la parrilla.<\/p>\n<p><strong>Argentina \u20a18475<\/strong><br>Corte de entra\u00f1a, chimichurri, queso mozarella, tomate, cebolla morada, lechuga alioli a base de vino tinto.<\/p>\n<p><strong>Hongos Portobello \u20a16768<\/strong><br>Deliciosa torta hecha de hongos portobello silvestre de la mejor calidad, queso mozzarella, hummus de garbanzos, lechuga, tomate, zuquinni a la parrilla, cebollas caramelizadas y alioli vegetariano especial.<\/p>\n<p><strong>Pescado y Papas \u20a16768<\/strong><br>Tres deliciosas porciones de Dorado empanizado, acompa\u00f1ado con papas fritas y salsa t\u00e1rtara.<\/p>\n<h2 id=\"premiumburgers\">PREMIUM BURGERS<\/h2>\n<p><strong>El Rey \u20a116893<\/strong><br>Hamburguesa de Rib Eye Premium de 250gr de la mejor calidad, cocida a la parrilla, queso mozzarella derretido, aros de cebolla, lechuga, tomate, cebolla morada y cebolla salteada, chiles morrones y hongos, adobada con steak sauce original y alioli de vegetales rostizados.<\/p>\n<p><strong>Gutbusters \u20a115763<\/strong><br>Una hamburguesa realmente grande con seis tortas de carne, tocineta, queso americano, huevo frito, vegetales y nuestra deliciosa salsa Rid\u00edcula.<\/p>\n<p><strong>Bomba \u20a110113<\/strong><br>Deliciosa torta de carne envuelta en tocineta rellena de quesos diferentes, una explosi\u00f3n de sabores secretos, con lechuga, tomate y cebolla morada. Una verdadera Bomba de sabor con nuestra salsa Rid\u00edcula.<\/p>\n<p><strong>Wagyu USD $111<\/strong><br>Corte de Wagyu carne Japonesa, lechuga, tomate, cebolla morada en vinagreta, pepinillos artesanales, queso mozzarella, cebollas caramelizadas, hongos salteados y alioli de vegetales rostizados.<\/p>\n<p><strong>Wagyu &amp; Caviar USD $563<\/strong><br>Una extravagante hamburguesa con delicioso Caviar y carne de Wagyu de alta calidad con una mezcla \u00fanica de sabores incre\u00edbles con alioli de vegetales y nuestro delicioso pan gourmet.<\/p>\n<p><strong>Caviar &amp; Salm\u00f3n USD $450<\/strong><br>El Orgullo del Mar, una fusi\u00f3n \u00fanica de delicioso caviar y salm\u00f3n fresco con lechuga, tomate, aguacate, remolacha, cebolla morada y nuestro alioli especial en pan artesanal.<\/p>\n<h2 id=\"sides\">SIDES<\/h2>\n<p>Papas de Camote \u20a12260<br>Aros de Cebolla \u20a12260<br>Papas Fritas \u20a11356<\/p>\n<h2 id=\"aliolis\">ALIOLIS<\/h2>\n<p>Sriracha, Eneldo, Vegetales Rostizados, Cebolla Dulce, Vino Tinto, Lizano, T\u00e1rtara, Sambal, Ridiculous, Albahaca, Coco Tomillo, Maracuy\u00e1, Mango, Asi\u00e1tico, Mostaza Dulce, Bals\u00e1mico, BBQ, Chipotle.<\/p>\n<h2 id=\"menudeni\u00f1os\">MEN\u00da DE NI\u00d1OS<\/h2>\n<p><strong>Fish &amp; Chips \u20a14463<\/strong><br>Una pieza de pescado, papas fritas y t\u00e9 fr\u00edo.<\/p>\n<p><strong>Quesohamburguesa \u20a14463<\/strong><br>Hamburguesa de queso peque\u00f1a con papas fritas y t\u00e9 fr\u00edo.<\/p>\n<h2 id=\"challenge1\">CHALLENGE #1<\/h2>\n<p><strong>Monster Burger \u20a122588<\/strong><br>Si logras comer nuestra hamburguesa m\u00e1s grande con papas en 30 minutos es GRATIS!<\/p>\n<h2 id=\"challenge2\">CHALLENGE #2<\/h2>\n<p><strong>Inferno Burger \u20a116837<\/strong><br>Come nuestra Hamburguesa Inferno con los chiles Carolina Reaper m\u00e1s picantes del mundo, papas fritas y dos tragos especiales de Chiliguaro en 15 minutos y es GRATIS!<\/p>\n<h2 id=\"challenge3\">CHALLENGE #3<\/h2>\n<p><strong>Speed Burger \u20a111288<\/strong><br>Todos los S\u00e1bados tendremos una competencia de comida de hamburguesas! La persona que coma una QuesoHamburguesa doble con papas fritas y Coca Cola, gana una comida gratis.<\/p>\n<h2 id=\"challenge4\">CHALLENGE #4<\/h2>\n<p><strong>Costa Rica Largest Coffee \u20a19040<\/strong><br>Beba el caf\u00e9 m\u00e1s grande del Costa Rica en 15 minutos y es GRATIS.<\/p>\n<h2 id=\"cafefrio\">CAF\u00c9 FR\u00cdO<\/h2>\n<p>Tradicional \u20a14022<br>Coco \u20a14022<br>Marshmellow \u20a14022<br>Peanut Butter \u20a14022<br>Cereza \u20a14022<\/p>\n<h2 id=\"cafe\">CAF\u00c9<\/h2>\n<p>Americano \u20a11356<br>Caf\u00e9 con Leche \u20a11469<br>Capuccino \u20a11751<br>Latte \u20a12147<br>Expresso \u20a11582<br>Machiatto \u20a11638<br>T\u00e9 de Menta, Verde y Manzanilla \u20a11469<\/p>\n<h2 id=\"crazyshakes\">CRAZY SHAKES<\/h2>\n<p><strong>Come Galletas \u20a14350<\/strong><br>Helado de vainilla, galletas oreo, crema batida, galleta especial, M&amp;M&#8217;s y mucho m\u00e1s.<\/p>\n<p><strong>Chocolate \u20a14350<\/strong><br>Helado, chocolate l\u00edquido, crema batida, M&amp;M&#8217;s, dona y muffin.<\/p>\n<p><strong>Fresa \u20a14350<\/strong><br>Helado, fresas silvestres, crema batida, M&amp;M&#8217;s, dona y muffin.<\/p>\n<p><strong>Vainilla \u20a14350<\/strong><br>Helado de vainilla, leche evaporada, crema batida, M&amp;M&#8217;s, dona, muffin y nueces.<\/p>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Horario: Todos los d\u00edas de 11:30 a 24:00. Servicio de recogida y\/o entrega de 12:00 a 24:00. T\u00e9lefono: +506 2643-1010 Direcci\u00f3n: Avenida Pastor Diaz (Avenida Principal de Jac\u00f3) entre Calle Hicaco y Calle Alice, Jac\u00f3, Puntaranas, Costa Rica. C\u00f3digo postal de la zona: 61101. &nbsp;&nbsp; MEN\u00da Bebidas \u00b7 Cervezas, Vinos y Licores \u00b7 Cocteles Normales &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Ridiculous Burgers\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#more-9389\" aria-label=\"Leer m\u00e1s sobre Ridiculous Burgers\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[229,73,42],"tags":[],"class_list":["post-9389","post","type-post","status-publish","format-standard","hentry","category-garabito","category-jaco","category-puntarenas","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-14T23:36:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-18T16:11:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Ridiculous Burgers\",\"datePublished\":\"2021-03-14T23:36:12+00:00\",\"dateModified\":\"2021-03-18T16:11:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/\"},\"wordCount\":1637,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ridiculous-burgers-jaco-costa-rica-logo.jpg\",\"articleSection\":[\"Garabito\",\"Jac\u00f3\",\"Puntarenas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/\",\"name\":\"Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ridiculous-burgers-jaco-costa-rica-logo.jpg\",\"datePublished\":\"2021-03-14T23:36:12+00:00\",\"dateModified\":\"2021-03-18T16:11:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&ssl=1\",\"width\":272,\"height\":272,\"caption\":\"Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/ridiculous-burgers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ridiculous Burgers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n","description":"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/","og_locale":"es_ES","og_type":"article","og_title":"Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n","og_description":"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2021-03-14T23:36:12+00:00","article_modified_time":"2021-03-18T16:11:40+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Ridiculous Burgers","datePublished":"2021-03-14T23:36:12+00:00","dateModified":"2021-03-18T16:11:40+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/"},"wordCount":1637,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg","articleSection":["Garabito","Jac\u00f3","Puntarenas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/","name":"Ridiculous Burgers Jac\u00f3 - Men\u00fa, Horario, Direcci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg","datePublished":"2021-03-14T23:36:12+00:00","dateModified":"2021-03-18T16:11:40+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Ridiculous Burgers Jac\u00f3, Costa Rica. Men\u00fa, ubicaci\u00f3n WAZE y mapas de Google, direcci\u00f3n, horario.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/03\/ridiculous-burgers-jaco-costa-rica-logo.jpg?fit=272%2C272&ssl=1","width":272,"height":272,"caption":"Ridiculous Burgers, Jac\u00f3, Puntarenas, Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/ridiculous-burgers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Ridiculous Burgers"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-2rr","jetpack-related-posts":[{"id":2943,"url":"https:\/\/costaricainfolink.com\/restaurantes\/bar-y-restaurante-surf-dogs\/","url_meta":{"origin":9389,"position":0},"title":"Bar y Restaurante Surf Dogs","author":"Restaurantes Costa Rica","date":"16 abril 2013","format":false,"excerpt":"CERRADO El Bar y Restaurante Surf Dogs Costa Rica es un bar surfo, con un ambiente agradable para relajarse y simplemente pasarla bien con tus amigos o familiares, situado muy convenientemente en medio de la avenida principal en Jac\u00f3, Costa Rica. Surf Dogs abri\u00f3 sus puertas en enero del 2012\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2013\/04\/surf-dogs-restaurante-jaco-costa-rica-logo2.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":10152,"url":"https:\/\/costaricainfolink.com\/restaurantes\/marys-diner-jaco-beach\/","url_meta":{"origin":9389,"position":1},"title":"Mary&#8217;s Diner Jac\u00f3 Beach","author":"Restaurantes Costa Rica","date":"8 octubre 2021","format":false,"excerpt":"Tel\u00e9fono: +506 2643-4265 Horario: De Lunes a Domingo de 7:30am a 2:30pm. CERRADO los Martes Direcci\u00f3n: Centro Comercial Ure\u00f1a local # 1, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 MENU Desayunos \u00b7 Almuerzos \u00b7 Ensaladas \u00b7 Men\u00fa de Ni\u00f1os \u00b7 Bebidas DESAYUNOS\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Mary's Diner Jac\u00f3 Beach Costa Rica-logo","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/10\/restaurante-marys-diner-jaco-costa-rica-300x194.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8595,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samudios-sunset-restobar\/","url_meta":{"origin":9389,"position":2},"title":"Samudio&#8217;s Sunset Restobar","author":"Restaurantes Costa Rica","date":"18 agosto 2020","format":false,"excerpt":"Tel\u00e9fono: +506 8928-6266Horario: Mi\u00e9rcoles cerrado. Lunes, Martes, Jueves y Viernes de 12md. a 10pm. S\u00e1bados y Domingos de 7am a 7pm. Direcci\u00f3n: Frente a la playa, segundo piso de Restaurante El Malec\u00f3n, calle el boh\u00edo. Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Samudios Sunset Restobar Jac\u00f3 Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2020\/08\/restaurante-bar-samudios-jaco-costa-rica-1-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7926,"url":"https:\/\/costaricainfolink.com\/restaurantes\/jerah\/","url_meta":{"origin":9389,"position":3},"title":"Restaurante Jerah","author":"Restaurantes Costa Rica","date":"29 mayo 2019","format":false,"excerpt":"Jerah Jac\u00f3 Tel\u00e9fono+506 8359-2067 Horario De Martes a Domingo de 530pm a 10pm.Lunes cerrado. Direcci\u00f3n Sobre calle Anita, entre Bar Isaga y Jac\u00f3 Bl\u00fa, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Men\u00fa Jerah Jac\u00f3 Ensaladas y Entradas - Arrollados de Primavera - Nuestras Sopas\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"Restaurante Jerah Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2019\/05\/restaurante-jerah-costa-rica-300x158.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11336,"url":"https:\/\/costaricainfolink.com\/restaurantes\/diablo-burger\/","url_meta":{"origin":9389,"position":4},"title":"Diablo Burger","author":"Restaurantes Costa Rica","date":"16 enero 2023","format":false,"excerpt":"Direcci\u00f3n En Centro Comercial Jac\u00f3 Walk. Distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: \u00a0\u00a0 Tel\u00e9fono +506 8823-7000 Horario Lunes, Mi\u00e9rcoles, Jueves, Viernes, S\u00e1bado y Domingo de 12md a 9pm. Martes cerrado. MEN\u00da Burgers \u00b7 Sides \u00b7 Extras \u00b7 Ni\u00f1os \u00b7 Refrescos \u00b7 Limonadas \u00b7\u2026","rel":"","context":"En \u00abGarabito\u00bb","block_context":{"text":"Garabito","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/por-ubicacion\/puntarenas\/garabito\/"},"img":{"alt_text":"Restaurante Diablo Burger Jac\u00f3 Costa Rica, wood fired grill, 100% black angus beef","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/restaurante-diablo-burger-jaco-costa-rica-wood-fired-grill-100-black-angus-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":11509,"url":"https:\/\/costaricainfolink.com\/restaurantes\/mikkonos-greek-tavern\/","url_meta":{"origin":9389,"position":5},"title":"MIKKONOS GREEK TAVERN","author":"Restaurantes Costa Rica","date":"31 enero 2023","format":false,"excerpt":"Direcci\u00f3n En Centro Comercial Jac\u00f3 Walk, distrito: Jac\u00f3, cant\u00f3n: Garabito, provincia: Puntarenas, Costa Rica. C\u00f3digo postal de la zona: 61101. \u00a0\u00a0 Tel\u00e9fono +506 8823 7000 Horario Lunes, Mi\u00e9rcoles, Jueves, Viernes, S\u00e1bado y Domingo de 12md a 9pm. Martes cerrado. MEN\u00da Quinoa Bowl \u20a16450 Quinoa org\u00e1nica, kale, lechuga, tomate, pan artesanal,\u2026","rel":"","context":"En \u00ab61101\u00bb","block_context":{"text":"61101","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/61101\/"},"img":{"alt_text":"MIKKONOS GREEK TAVERN JAC\u00d3 WALK COSTA RICA","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2023\/01\/MIKKONOS-GREEK-TAVERN-JACO-WALK-COSTA-RICA-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=9389"}],"version-history":[{"count":26,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9389\/revisions"}],"predecessor-version":[{"id":9694,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9389\/revisions\/9694"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=9389"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=9389"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=9389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}