{"id":9901,"date":"2021-05-03T08:39:26","date_gmt":"2021-05-03T13:39:26","guid":{"rendered":"https:\/\/costaricainfolink.com\/restaurantes\/?p=9901"},"modified":"2021-05-06T07:56:26","modified_gmt":"2021-05-06T12:56:26","slug":"tiquicia-divina","status":"publish","type":"post","link":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/","title":{"rendered":"Restaurante Tiquicia Divina"},"content":{"rendered":"<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica\/#main\" rel=\"attachment wp-att-9905\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9905\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&amp;ssl=1\" data-orig-size=\"612,612\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&amp;ssl=1\" class=\"alignright size-medium wp-image-9905\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?resize=300%2C300&#038;ssl=1\" alt=\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\" width=\"300\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?w=612&amp;ssl=1 612w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<h2>Tel\u00e9fono: <a href=\"tel:+50622892456\">+506 2289 2456<\/a><\/h2>\n<p><strong>Direcci\u00f3n<\/strong>: 800 metros sur de la Rotonda de Multiplaza, en Golden Plaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203.<\/p>\n<p><a href=\"https:\/\/waze.com\/ul\/hd1u0t14g5\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-waze.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n WAZE de Playa Colonia en Bahia Ballena, Osa, Puntarenas, Costa Rica\" width=\"50\" height=\"50\" \/><\/a>\u00a0\u00a0<a href=\"https:\/\/goo.gl\/maps\/UCYwgZaLueLYXtKc7\" target=\"_blank\" rel=\"noopener\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/ubicacion-mapas-de-google.jpg?resize=50%2C50&#038;ssl=1\" alt=\"Ubicaci\u00f3n Mapas de Google de Restaurante Tiquicia Divina en Golden Plaza, San Rafael, Escazu, San Jose Costa Rica\" width=\"50\" height=\"50\" \/><\/a><\/p>\n<h2>MEN\u00da<\/h2>\n<p><a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#desayuno\">Desayuno<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#entradas\">Entradas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#sopas\">Sopas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#ensaladas\">Ensaladas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#menuejecutivo\">Menu Ejecutivo<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#platosfuertes\">Platos Fuertes<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#guarnicionesticas\">Guarniciones Ticas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#tablitascampesinas\">Tablitas Campesinas<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#menude\u00f1i\u00f1os\">Menu de Ni\u00f1os<\/a> \u00b7 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#postres\">Postres<\/a><\/p>\n<h2 id=\"desayuno\">Desayuno<\/h2>\n<p><strong data-rich-text-format-boundary=\"true\">Buenos dias Tiquicia<\/strong> \u20a13700 <a href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica\/#main\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9977\" data-permalink=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica\/#main\" data-orig-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?fit=1440%2C1440&amp;ssl=1\" data-orig-size=\"1440,1440\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Gallo Pinto Tiquicia Divina, Restaurante Escazu, San Jose, Costa Rica\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?fit=1024%2C1024&amp;ssl=1\" class=\"alignnone wp-image-9977\" src=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?resize=25%2C25&#038;ssl=1\" alt=\"Gallo Pinto Tiquicia Divina, Restaurante Escazu, San Jose, Costa Rica\" width=\"25\" height=\"25\" srcset=\"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/gallo-pinto-tiquicia-divina-restaurante-escazu-costa-rica.jpg?w=1440&amp;ssl=1 1440w\" sizes=\"auto, (max-width: 25px) 100vw, 25px\" \/><\/a><br data-rich-text-line-break=\"true\" \/>Gallo pinto, 2 huevos al gusto, salchich\u00f3n, pl\u00e1tanos maduros y natilla. Acompa\u00f1ado de 2 rodajas de pan baguete o tortillas caseras. ( Incluye caf\u00e9 o agua dulce ).<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Tamal de cerdo<\/strong> \u20a11300.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Orden de Gallo Pinto<\/strong> \u20a11200<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Huevos al gusto<\/strong> \u20a11000<br data-rich-text-line-break=\"true\" \/>Orden de huevos al gusto, acompa\u00f1ados de tortillas caseras o pan baguette.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Tortilla ali\u00f1ada<\/strong> \u20a12300<br data-rich-text-line-break=\"true\" \/>Tortilla con 3 quesos, acompa\u00f1ada de natilla.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Chorreada<\/strong> \u20a11800<br data-rich-text-line-break=\"true\" \/>Chorreada de ma\u00edz, acompa\u00f1ada de queso molido o natilla.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Frutas de temporada<\/strong> \u20a11500<br data-rich-text-line-break=\"true\" \/>Mixto de frutas frescas, acompa\u00f1adas de yogurt y granola.<\/p>\n<h2 id=\"entradas\">Entradas<\/h2>\n<p><strong data-rich-text-format-boundary=\"true\">Enyucado Tiquicia<\/strong> \u20a12700<br \/>Dos enyucados rellenos de carne mechada o 3 quesos ticos.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Chile relleno tico<\/strong> \u20a12500<br \/>Chile dulce relleno de carne molida sazonada envuelto en huevo, acompa\u00f1ado de salsa de tomate natural.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Chile relleno vegetariano<\/strong> \u20a12700<br \/>Chile dulce relleno de champi\u00f1ones frescos salteados al vino y queso mascarpone.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pl\u00e1tano Maduro con queso<\/strong> \u20a12300<br \/>Medio platano maduro frito con 3 quesos ticos.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Patacones Mixtos<\/strong> \u20a13100<br \/>Patacones de platano verde o maduro servidos con frijoles molidos, pico de gallo o guacamole a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Gallo<\/strong> \u20a12600<br \/>Gallo de Salchichon o chorizo. Servidos en tortillas caseras y acompa\u00f1ados de ensalada de repollo y pico de gallo.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Ceviche Tico<\/strong> \u20a13500<br \/>Pescado de temporada 100% nacional y de pesca responsable, ali\u00f1ado con lim\u00f3n y especies. Acompa\u00f1ado de chips frescos de pl\u00e1tano verde o galleta soda.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Ceviche Porte\u00f1o<\/strong> \u20a14200<br \/>Ceviche mixto de pescado y camar\u00f3n, ali\u00f1ado con lim\u00f3n y especies. Acompa\u00f1ado de chips o galleta soda.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Chicharr\u00f3n de Pulpo<\/strong> \u20a14450<br \/>Frescos tent\u00e1culos de pulpo a la parrilla, servidos con papas salteadas con ajo y perejil y salsa de la casa.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Gallos Mixtos<\/strong> \u20a12650<br \/>Gallos de picadillos del d\u00eda servidos con tortillas caseras.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">El infaltable<\/strong> \u20a11300<br \/>Tradicional tamal con carne de cerdo, arroz, vegetales, guisantes y garbanzos.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Elotico<\/strong> \u20a11400<br \/>Delicioso elote grano blanco ba\u00f1ado con mantequilla.<\/p>\n<h2 id=\"sopas\">Sopas<\/h2>\n<p><strong data-rich-text-format-boundary=\"true\">Sopa de la Abuela<\/strong> \u20a13600<br \/>Exquisita sopa de pollo con verduras, acompa\u00f1ada de arroz blanco.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">La tradicional Sopa Negra<\/strong> \u20a13500<br \/>Caldo de frijoles negros con cujlantro y huevo duro, acompa\u00f1ado de arroz blanco.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">La mechuda<\/strong> \u20a13750<br \/>Sustancia de carne mechada con especies, acompa\u00f1ada de arroz blanco y de banano verde de la casa.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Olla de carne<\/strong> \u20a14800<br \/>Deliciosa sopa elaborada con caldo de tres tipos de carnes de res y verduras frescas, acompa\u00f1ada de arroz blanco. ( Solo lunes y Jueves )<\/p>\n<h2 id=\"ensaladas\">Ensaladas<\/h2>\n<p><strong data-rich-text-format-boundary=\"true\">Ensalada de palmito<\/strong> \u20a13100<br \/>Lechugas mixtas con tomate, pepino, zanahoria y palmito mezclados con la vinagreta del chef.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Ensalada de la casa<\/strong> \u20a13400<br \/>Lechugas mixtas con tomate, pepino, zanahoria, cebolla morada, ma\u00edz dulce y aguacate.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Ensalada Tiquicia<\/strong> \u20a13950<br \/>Lechugas mixtas con tomte, pepino, zanahoria, cebolla morada, ma\u00edz dulce, aguacate y pollo sazonado a la parrilla.<\/p>\n<h2 id=\"menuejecutivo\">MEN\u00da EJECUTIVO<\/h2>\n<p>Horario: de 11am a 230pm. Preguntar por el plato invitado de la semana. Incluye entrada del d\u00eda, bebida natural y postre.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Casado de la casa<\/strong> \u20a14500<br \/>Servido con chuleta de cerco, lomito encebollado, filet de pollo, pescado de temporada al gusto o carne mechada en salsa. Acompa\u00f1ado de arroz, frijoles arreglados, pl\u00e1tanos maduros y picadillo del d\u00eda.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Arroz con pollo<\/strong> \u20a14500<br \/>Acompa\u00f1ado de frijoles molidos y papas tostadas, ensalada rusa o ensalada mixta a elegir.<\/p>\n<h2 id=\"platosfuertes\">Platos Fuertes<\/h2>\n<p><strong data-rich-text-format-boundary=\"true\">Lomito San Jos\u00e9<\/strong> \u20a18900<br \/>Lomito de res a la parrilla ba\u00f1ada en salsa de hongos, acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Entra\u00f1a Divina<\/strong> \u20a18600<br \/>Corte nacional de entra\u00f1a, acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Arroz Gianna<\/strong> \u20a17500<br \/>Delicioso arroz con camarones salteados y sazonados con hierbas del chef acompa\u00f1ado de papas semilla al ajo y perejil y ensalada mixta.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Lomito N\u00edkolas<\/strong> \u20a18500<br \/>Corte de lomito de res a la parrilla con salsa chimichurri, acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pescado de mi Tierra<\/strong> \u20a17200<br \/>Filet de pescado de temporada 100% nacional al gusto. Acompa\u00f1ado de 2 guarniciones ticas a elegir. Empanizado al ajillo o a la mantequilla.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Sopa Porte\u00f1a<\/strong> \u20a18100<br \/>Exquisita sopa con fondo de pescado y mariscos frescos de temporada en salsa de tomate natural, acompa\u00f1ada de arroz blanco.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Arroz Gianna<\/strong> \u20a17500<br \/>Delicioso arroz con camarones salteados y sazonados con hierbas del chef acompa\u00f1ado de papas semila al ajo y perejil y ensalada mixta.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Patacon Tiquicia&#8230; el chineado!!<\/strong> \u20a13500<br \/>Patac\u00f3n de pl\u00e1tano maduro con carne mechada, frijoles molidos, queso turrialba y salsa de la casa.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">At\u00fan del chef<\/strong> \u20a18400<br \/>At\u00fan a las hierbas en espejo de jengibre, acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pescado Entero<\/strong> \u20a17700<br \/>Pescado de temporada frito, sazonado con la mezcla especial del chef, acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pasta Manuel Antonio<\/strong> \u20a18500<br \/>Delicioso linguini en salsa blanca con camarones medianos acompa\u00f1ados de pan de ajo.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pasta Tilar\u00e1n<\/strong> \u20a17400<br \/>Pasta a elegir en una deliciosa salsa de tomate natural coronada con fajitas de lomito de res a la plancha, acompa\u00f1ados de pan de ajo.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">El Vegetariano<\/strong> \u20a16500<br \/>Pasta o arroz salteado con vegetales frescos de temporada, acompa\u00f1ados de pan de ajo o ensalada.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">El que todos conocemos&#8230; Chifrijo!!<\/strong> \u20a15200<br \/>Canasta de tortilla con arroz, frijoles tiernos, mixto de chicharr\u00f3n, pico de gallo, aguacate y picos de tortillas.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">El muy nuestro&#8230; Vigor\u00f3n<\/strong> \u20a14500<br \/>Repollo fresco, yuca sancochada, chicharr\u00f3n de carne, pico de gallo y chicharr\u00f3n tostado.<\/p>\n<p><strong data-rich-text-format-boundary=\"true\">Pinchos Tiquicia<\/strong><br \/>Acompa\u00f1ado de 2 guarniciones ticas a elegir.<\/p>\n<ul>\n<li><strong data-rich-text-format-boundary=\"true\">Mar y Tierra<\/strong> \u20a19500<\/li>\n<li><strong data-rich-text-format-boundary=\"true\">Lomito<\/strong> \u20a18700<\/li>\n<li><strong data-rich-text-format-boundary=\"true\">Pollo<\/strong> \u20a16300<\/li>\n<\/ul>\n<h2 id=\"guarnicionesticas\">Guarniciones Ticas<\/h2>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Arroz Blanco<\/strong> \u20a1700<br><strong>Frijoles arreglados<\/strong> \u20a1800<br><strong>Picos de tortillas<\/strong> \u20a1500<br><strong>Pico de gallo<\/strong> \u20a1650<br><strong>Guacamole<\/strong> \u20a11100<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Yuca Frita<\/strong> \u20a1850<br><strong>Vegetales mixtos salteados<\/strong> \u20a11000<br><strong>Ensalada mixta<\/strong> \u20a1900<br><strong>Ensalada de repollo<\/strong> \u20a1800<br><strong>Picadillo del d\u00eda<\/strong> \u20a1850<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><strong>Banano verde de la casa<\/strong> \u20a1700<br><strong>Pure de papa<\/strong> \u20a1850<br><strong>Papas Fritas<\/strong> \u20a1900<br><strong>Patacones verdes<\/strong> \u20a11000<br><strong>Patacones maduros<\/strong> \u20a11000<\/p>\n<\/div>\n<\/div>\n\n\n<h2 id=\"tablitascampesinas\">Tablitas Campesinas<\/h2>\n<p><strong>Fiesta Tiquicia<\/strong> \u20a120500<br \/>Tabla mixta de fajitas de pollo, fajitas de res, trozos de chicharr\u00f3n y 2 picaadillos del d\u00eda. Acompa\u00f1ados de pico de gallo, guacamole, ensalada de repollo, yuca frita, patacones y tortillas caseras. ( 4 personas )<\/p>\n<p><strong>Patacones Divinos<\/strong> \u20a115700<br \/>Tabla de patacones de pl\u00e1tano verde, maduros o mixtos. Acompa\u00f1ados de carne mechada, frijoles arreglados, guacamole, pico de gallo y salsa de la casa. ( 4 personas ).<\/p>\n<h2 id=\"menudeni\u00f1os\">Men\u00fa de Ni\u00f1os<\/h2>\n<p><strong>Dedos empanizados<\/strong> \u20a12700<br \/>Dedos de pollo o pescado empanizados a elegir, acompa\u00f1ado de papas fritas.<\/p>\n<p><strong>Mini casado<\/strong> \u20a12400<br \/>Fajitas de carne o pollo a la plancha, acompa\u00f1ados de arroz blanco, frijoles arreglados, pl\u00e1tano maduro o picadillo.<\/p>\n<h2 id=\"postres\">Postres<\/h2>\n<p><strong>Arroz con Leche<\/strong> \u20a11500<br \/><strong>Helado de sorbetera con barquillos<\/strong> \u20a11600<br \/><strong>Flan Isla del Coco<\/strong> \u20a11950<br \/><strong>Ensalada de frutas con gelatina y helado<\/strong> \u20a12000<br \/><strong>Postres del chef<\/strong> \u20a12300<br \/>Sabores: Cas, maracuy\u00e1 o mango, sujetos a disponibilidad.<\/p>","protected":false},"excerpt":{"rendered":"<p>Tel\u00e9fono: +506 2289 2456 Direcci\u00f3n: 800 metros sur de la Rotonda de Multiplaza, en Golden Plaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa Rica. C\u00f3digo postal de la zona: 10203. \u00a0\u00a0 MEN\u00da Desayuno \u00b7 Entradas \u00b7 Sopas \u00b7 Ensaladas \u00b7 Menu Ejecutivo \u00b7 Platos Fuertes \u00b7 Guarniciones Ticas \u00b7 Tablitas Campesinas \u00b7 Menu &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"Restaurante Tiquicia Divina\" class=\"read-more button\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#more-9901\" aria-label=\"Leer m\u00e1s sobre Restaurante Tiquicia Divina\">Ver Restaurante<\/a><\/p>\n","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[98,28,26,177,6],"tags":[],"class_list":["post-9901","post","type-post","status-publish","format-standard","hentry","category-98","category-escazu","category-san-jose","category-san-rafael-escazu","category-tipica-costarricense","infinite-scroll-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n<\/title>\n<meta name=\"description\" content=\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/\" \/>\n<meta property=\"og:site_name\" content=\"Restaurantes Costa Rica\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/costaricainfolink\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-03T13:39:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-06T12:56:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg\" \/>\n<meta name=\"author\" content=\"Restaurantes Costa Rica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@costaricatwitt\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Restaurantes Costa Rica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/\"},\"author\":{\"name\":\"Restaurantes Costa Rica\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"headline\":\"Restaurante Tiquicia Divina\",\"datePublished\":\"2021-05-03T13:39:26+00:00\",\"dateModified\":\"2021-05-06T12:56:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/\"},\"wordCount\":1095,\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg\",\"articleSection\":[\"10203\",\"Escaz\u00fa\",\"San Jos\u00e9\",\"San Rafael\",\"T\u00edpica Costarricense\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/\",\"name\":\"Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg\",\"datePublished\":\"2021-05-03T13:39:26+00:00\",\"dateModified\":\"2021-05-06T12:56:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\"},\"description\":\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/costaricainfolink.com\\\/restaurantes\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&ssl=1\",\"width\":612,\"height\":612,\"caption\":\"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/tiquicia-divina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Restaurante Tiquicia Divina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#website\",\"url\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/\",\"name\":\"Restaurantes Costa Rica\",\"description\":\"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/costaricainfolink.com\\\/restaurantes\\\/#\\\/schema\\\/person\\\/c621c7c259addb15cb59745d5936b36f\",\"name\":\"Restaurantes Costa Rica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g\",\"caption\":\"Restaurantes Costa Rica\"},\"sameAs\":[\"https:\\\/\\\/costaricainfolink.com\",\"https:\\\/\\\/www.facebook.com\\\/costaricainfolink\",\"https:\\\/\\\/www.instagram.com\\\/costaricainfolink\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/costa-rica-info-link\",\"https:\\\/\\\/x.com\\\/costaricatwitt\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/CostaRicaInfoLinkcom\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n","description":"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/","og_locale":"es_ES","og_type":"article","og_title":"Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n","og_description":"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","og_url":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/","og_site_name":"Restaurantes Costa Rica","article_author":"https:\/\/www.facebook.com\/costaricainfolink","article_published_time":"2021-05-03T13:39:26+00:00","article_modified_time":"2021-05-06T12:56:26+00:00","og_image":[{"url":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg","type":"","width":"","height":""}],"author":"Restaurantes Costa Rica","twitter_card":"summary_large_image","twitter_creator":"@costaricatwitt","twitter_misc":{"Escrito por":"Restaurantes Costa Rica","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#article","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/"},"author":{"name":"Restaurantes Costa Rica","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"headline":"Restaurante Tiquicia Divina","datePublished":"2021-05-03T13:39:26+00:00","dateModified":"2021-05-06T12:56:26+00:00","mainEntityOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/"},"wordCount":1095,"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg","articleSection":["10203","Escaz\u00fa","San Jos\u00e9","San Rafael","T\u00edpica Costarricense"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/","url":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/","name":"Restaurante Tiquicia Divina en Escaz\u00fa - Men\u00fa, Tel\u00e9fono, Direcci\u00f3n","isPartOf":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#primaryimage"},"image":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#primaryimage"},"thumbnailUrl":"https:\/\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica-300x300.jpg","datePublished":"2021-05-03T13:39:26+00:00","dateModified":"2021-05-06T12:56:26+00:00","author":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f"},"description":"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Tel\u00e9fono, men\u00fa, horario, direcci\u00f3n, ubicaci\u00f3n WAZE y mapas de Google.","breadcrumb":{"@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#primaryimage","url":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&ssl=1","contentUrl":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2021\/05\/restaurante-tiquicia-divina-san-rafael-escazu-san-jo-costa-rica.jpg?fit=612%2C612&ssl=1","width":612,"height":612,"caption":"Restaurante Tiquicia Divina en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica"},{"@type":"BreadcrumbList","@id":"https:\/\/costaricainfolink.com\/restaurantes\/tiquicia-divina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/costaricainfolink.com\/restaurantes\/"},{"@type":"ListItem","position":2,"name":"Restaurante Tiquicia Divina"}]},{"@type":"WebSite","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#website","url":"https:\/\/costaricainfolink.com\/restaurantes\/","name":"Restaurantes Costa Rica","description":"Telefonos, horario, mapa con direccion, coordenadas para GPS, ubicacion, fotos, sitio web.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costaricainfolink.com\/restaurantes\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/costaricainfolink.com\/restaurantes\/#\/schema\/person\/c621c7c259addb15cb59745d5936b36f","name":"Restaurantes Costa Rica","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c7b0d923dbcfd314affe09456117ffd232f8b22901cede5d6bc23366e5299e9?s=96&d=mm&r=g","caption":"Restaurantes Costa Rica"},"sameAs":["https:\/\/costaricainfolink.com","https:\/\/www.facebook.com\/costaricainfolink","https:\/\/www.instagram.com\/costaricainfolink\/","https:\/\/www.linkedin.com\/company\/costa-rica-info-link","https:\/\/x.com\/costaricatwitt","https:\/\/www.youtube.com\/c\/CostaRicaInfoLinkcom"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5i3XU-2zH","jetpack-related-posts":[{"id":5398,"url":"https:\/\/costaricainfolink.com\/restaurantes\/la-modesta\/","url_meta":{"origin":9901,"position":0},"title":"La Modesta","author":"Restaurantes Costa Rica","date":"20 febrero 2017","format":false,"excerpt":"NEGOCIO CERRADO Tel\u00e9fono: +506 7293-7360 Horario: De Lunes a Viernes de 9am a 7pm. S\u00e1bados de 9am a 1pm. Domingo cerrado. Direcci\u00f3n De la salida a Multiplaza Escaz\u00fa en la autopista Prospero Fern\u00e1ndez, 800 mts norte frente a Crossfit 506, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante La Modesta, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/02\/restaurante-la-modesta-san-rafael-escazu-san-jose-costa-rica-300x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":360,"url":"https:\/\/costaricainfolink.com\/restaurantes\/cafe-y-restaurante-il-panino\/","url_meta":{"origin":9901,"position":1},"title":"Caf\u00e9 y Restaurante Il Panino","author":"Restaurantes Costa Rica","date":"3 febrero 2011","format":false,"excerpt":"Horario: De Lunes a Jueves de 8 a.m. a 12 a.m. Viernes y S\u00e1bados 8 a.m. a 1 a.m. Domingos de 9 a.m. a 12 a.m Direcci\u00f3n: Multicentro Paco en Escaz\u00fa, en el cruce de Guachipel\u00edn, carretera vieja a Santa Ana. Distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9, Costa\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Caf\u00e9 y Restaurante Il Panino Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2010\/07\/il-panino-restaurante-cafe-costa-rica-logo.gif?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5836,"url":"https:\/\/costaricainfolink.com\/restaurantes\/tacos-bowls-tabows\/","url_meta":{"origin":9901,"position":2},"title":"Tacos &#038; Bowls TABOWS","author":"Restaurantes Costa Rica","date":"13 agosto 2017","format":false,"excerpt":"Direcci\u00f3n: Centro comercial Boulevard, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Horario: De Lunes a Viernes de 8am a 4pm. S\u00e1bados de 9am a 330pm. Domingos cerrado. Tel\u00e9fono: +506 2201-6423 ACEPTAMOS TARJETAS VISA, MASTERCARD Y AMERICAN EXPRESS RECOMENDACIONES DEL CHEF DESAYUNOS PARFAIT BOWL\u00a0\u20a12500\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"Restaurante Tacos & Bowls TABOWS en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2017\/08\/tacos-bowls-san-rafael-escazu-san-jose-costa-rica-1-300x148.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6413,"url":"https:\/\/costaricainfolink.com\/restaurantes\/4th-wave-cafe\/","url_meta":{"origin":9901,"position":3},"title":"4th WAVE Caf\u00e9 y Restaurante","author":"Restaurantes Costa Rica","date":"4 marzo 2018","format":false,"excerpt":"Direcci\u00f3n: Metroplaza, distrito: San Rafael, cant\u00f3n: Escaz\u00fa, provincia: San Jos\u00e9. C\u00f3digo postal de la zona: 10203. Tel\u00e9fono: +506 2289 4849 Horario: De Lunes a Viernes de 7am a 7pm. S\u00e1bados de 10am a 4pm. Domingos cerrado. MEN\u00da DESAYUNOS De 7am a 10am. Especial del D\u00eda\u00a0\u20a12000 2 huevos al gusto, gallo\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"4th Wave Caf\u00e9 y Restaurante en Metroplaza San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2018\/03\/4th-wave-cafe-restaurante-san-rafael-escazu-san-jose-costa-rica.png?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":538,"url":"https:\/\/costaricainfolink.com\/restaurantes\/samurai-fusion\/","url_meta":{"origin":9901,"position":4},"title":"Restaurante Samurai Fusion","author":"Restaurantes Costa Rica","date":"20 diciembre 2012","format":false,"excerpt":"El Restaurante Samurai Fusion, como su nombre lo indica, propone una fusi\u00f3n entre la traidicional comida japonesa y un acento que remite a la gastronom\u00eda de otras culturas; el restaurante est\u00e1 ubicado en San Rafael, Escaz\u00fa, San Jos\u00e9, Costa Rica. Todo en el Restaurante Samurai es simplemente genial, el ambiente\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2012\/11\/samurai-fusion-restaurante-escazu-costa-rica-logos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1001,"url":"https:\/\/costaricainfolink.com\/restaurantes\/damalfi\/","url_meta":{"origin":9901,"position":5},"title":"Restaurante D&#8217;amalfi","author":"Restaurantes Costa Rica","date":"6 diciembre 2012","format":false,"excerpt":"Restaurante Cerrado Click the following link to read this page in English: D'amalfi Restaurant El Restaurante D'amalfi es el aut\u00e9ntico restaurante de comida italiana a cargo del reconocido Chef Giuseppe Galuppo, mejor conocido como Chef Pino, ubicado en Escaz\u00fa, el cual abri\u00f3 sus puertas en el a\u00f1o 2010. [portfolio_slideshow id=2406]\u2026","rel":"","context":"En \u00ab10203\u00bb","block_context":{"text":"10203","link":"https:\/\/costaricainfolink.com\/restaurantes\/category\/codigo-postal\/10203\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/costaricainfolink.com\/restaurantes\/wp-content\/uploads\/2011\/08\/damalfi-restaurante-costa-rica-logo.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/comments?post=9901"}],"version-history":[{"count":36,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9901\/revisions"}],"predecessor-version":[{"id":9980,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/posts\/9901\/revisions\/9980"}],"wp:attachment":[{"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/media?parent=9901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/categories?post=9901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/costaricainfolink.com\/restaurantes\/wp-json\/wp\/v2\/tags?post=9901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}